{"id":9677,"date":"2021-06-30T00:00:00","date_gmt":"2021-06-29T16:00:00","guid":{"rendered":"https:\/\/instantkarmamag.com\/article\/the-spirit-of-goa-rang-reng-waterfall\/"},"modified":"2024-07-03T16:46:14","modified_gmt":"2024-07-03T08:46:14","slug":"o-espirito-de-goa-tocou-a-cachoeira-reng-2","status":"publish","type":"article","link":"https:\/\/instantkarmamag.com\/pt\/artigo\/o-espirito-de-goa-tocou-a-cachoeira-reng-2\/","title":{"rendered":"O Esp\u00edrito de Goa Rang Reng"},"content":{"rendered":"<div id=\"bsf_rt_marker\"><\/div><p style=\"text-align: left;\"><span class=\"markedContent\"><span dir=\"ltr\">M<\/span><span dir=\"ltr\">ade cresceu em <\/span><span dir=\"ltr\">Banjar Gitgit, norte <\/span><span dir=\"ltr\">da cidade de Gianyar, Bali. <\/span><span dir=\"ltr\">A selva, o rio e a cachoeira <\/span><span dir=\"ltr\">por Goa Rang Reng s\u00e3o<\/span><span dir=\"ltr\"> sua segunda casa. Como filho da natureza, ele conhece cada pedra e folha. <\/span><\/span><\/p>\n<p style=\"text-align: left;\"><span class=\"markedContent\"><span dir=\"ltr\">Curiosos e atentos, ouvimos a sua hist\u00f3ria \u00fanica de cria\u00e7\u00e3o do novo atrativo tur\u00edstico e os rituais que ainda hoje s\u00e3o realizados pelas gentes desta aldeia. Percebe-se imediatamente que Made \u00e9 uma pessoa emp\u00e1tica e espiritual que est\u00e1 fortemente ligada a este lugar. A M\u00e3e Natureza \u00e9 sua professora.<\/span><\/span><\/p>\n<p><span class=\"markedContent\"><span dir=\"ltr\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-3279 size-full\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2021\/07\/Screenshot-2021-07-01-at-04-07-02-IK-magz-5-print-final-pdf.png\" alt=\"esp\u00edrito de goa tocou cachoeira reng bali gianyar ubud cerim\u00f4nia do ciclo da vida melukat viagens indon\u00e9sia\" width=\"214\" height=\"214\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2021\/07\/Screenshot-2021-07-01-at-04-07-02-IK-magz-5-print-final-pdf.png 214w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2021\/07\/Screenshot-2021-07-01-at-04-07-02-IK-magz-5-print-final-pdf-150x150.png 150w\" sizes=\"auto, (max-width: 214px) 100vw, 214px\" \/><\/span><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span class=\"markedContent\"><span dir=\"ltr\">No dia 20 de maio de 2015, quando <\/span><span dir=\"ltr\">Made estava meditando na caverna <\/span><span dir=\"ltr\">de Rang Reng pr\u00f3ximo \u00e0 cachoeira, <\/span><span dir=\"ltr\">de repente ele teve a ideia de fazer <\/span><span dir=\"ltr\">algo louco:<\/span><\/span><\/p>\n<h3 style=\"text-align: center;\"><em><strong><span class=\"markedContent\"><span dir=\"ltr\">Ele queria partir uma pedra enorme e <\/span><span dir=\"ltr\">jogue-o no rio para bloque\u00e1-lo.<\/span><\/span><\/strong><\/em><\/h3>\n<p><span class=\"markedContent\"><span dir=\"ltr\">Ent\u00e3o, ele perguntou aos seus amigos da aldeia <\/span><span dir=\"ltr\">se eles quisessem ajud\u00e1-lo com isso. <\/span><span dir=\"ltr\">Finalmente, ele convenceu muitos deles <\/span><span dir=\"ltr\">que se a cachoeira principal fosse <\/span><span dir=\"ltr\">bloqueado, criaria um pool e <\/span><span dir=\"ltr\">ent\u00e3o a cachoeira estaria fluindo <\/span><span dir=\"ltr\">sobre mais pedras. Portanto, ser\u00e1 <\/span><span dir=\"ltr\">ser mais bonito do que antes.<\/span><\/span><\/p>\n<h6><\/h6>\n<h6><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-27751 size-full\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/10\/WhatsApp-Image-2023-10-04-at-02.08.35.jpg\" alt=\"esp\u00edrito de goa tocou cachoeira reng bali gianyar ubud cerim\u00f4nia do ciclo da vida melukat viagens indon\u00e9sia\" width=\"664\" height=\"556\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/10\/WhatsApp-Image-2023-10-04-at-02.08.35.jpg 664w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/10\/WhatsApp-Image-2023-10-04-at-02.08.35-300x251.jpg 300w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/10\/WhatsApp-Image-2023-10-04-at-02.08.35-624x523.jpg 624w\" sizes=\"auto, (max-width: 664px) 100vw, 664px\" \/><\/h6>\n<h2><span class=\"markedContent\"><span dir=\"ltr\">Como surgiu o nome Rang Reng <\/span><span dir=\"ltr\">sobre:<\/span><\/span><\/h2>\n<p><span class=\"markedContent\"><span dir=\"ltr\">Outra vez, Made foi o pr\u00f3ximo <\/span><span dir=\"ltr\">na caverna, ele conheceu um menino. <\/span><span dir=\"ltr\">Este menino disse a ele que a caverna era <\/span><span dir=\"ltr\">&#039;Rang Reng&#039;, que significa surpreendente <\/span><span dir=\"ltr\">lindo mas assustador ao mesmo <\/span><span dir=\"ltr\">tempo. Portanto, o nome do <\/span><span dir=\"ltr\">caverna \u00e9 Rang Reng. <\/span><\/span><\/p>\n<p><span class=\"markedContent\"><span dir=\"ltr\">Made disse que nunca tinha visto <\/span><span dir=\"ltr\">esse garoto antes, e nunca tinha conhecido <\/span><span dir=\"ltr\">ele desde ent\u00e3o.<\/span><span dir=\"ltr\">Ele perguntou a seus vizinhos se eles sabiam <\/span><span dir=\"ltr\">aquele garotinho que veio at\u00e9 ele naquela <\/span><span dir=\"ltr\">dia. Mas ningu\u00e9m parecia saber <\/span><span dir=\"ltr\">ele. <\/span><\/span><\/p>\n<p>&nbsp;<\/p>\n<h3 style=\"text-align: center;\"><span class=\"markedContent\"><span dir=\"ltr\">Made acredita verdadeiramente que este <\/span><span dir=\"ltr\">menino misterioso era o esp\u00edrito do <\/span><span dir=\"ltr\">caverna em si.<\/span><\/span><\/h3>\n<p><span class=\"markedContent\"><span dir=\"ltr\">O povo de Banjar Gitgit em <\/span><span dir=\"ltr\">Gianyar v\u00e3o para a Caverna de Goa <\/span><span dir=\"ltr\">Rang Reng se eles tiverem uma situa\u00e7\u00e3o terr\u00edvel <\/span><span dir=\"ltr\">sentimento ou pesadelo, para fazer o ritual <\/span><span dir=\"ltr\">limpeza, chamada &#039;melukat&#039;. <\/span><\/span><\/p>\n<h3><span class=\"markedContent\"><span dir=\"ltr\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-27752 size-full\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/10\/WhatsApp-Image-2023-10-04-at-02.08.36.jpg\" alt=\"esp\u00edrito de goa tocou cachoeira reng bali gianyar ubud cerim\u00f4nia do ciclo da vida melukat viagens indon\u00e9sia\" width=\"656\" height=\"385\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/10\/WhatsApp-Image-2023-10-04-at-02.08.36.jpg 656w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/10\/WhatsApp-Image-2023-10-04-at-02.08.36-300x176.jpg 300w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/10\/WhatsApp-Image-2023-10-04-at-02.08.36-624x366.jpg 624w\" sizes=\"auto, (max-width: 656px) 100vw, 656px\" \/><\/span><\/span><\/h3>\n<h3><\/h3>\n<h3><span class=\"markedContent\"><span dir=\"ltr\">Goa Rang Reng tamb\u00e9m \u00e9 \u00fanico porque <\/span><span dir=\"ltr\">logo antes da caverna, dois rios est\u00e3o <\/span><span dir=\"ltr\">vindo juntos. <\/span><\/span><\/h3>\n<p><span class=\"markedContent\"><span dir=\"ltr\">Eles simbolizam o <\/span><span dir=\"ltr\">energias femininas e masculinas. <\/span><span dir=\"ltr\">Depois disso, o rio entra na caverna <\/span><span dir=\"ltr\">que representa o \u00fatero. Estes dois <\/span><span dir=\"ltr\">os rios s\u00e3o testemunhas do amor verdadeiro.<\/span><\/span><\/p>\n<p><span class=\"markedContent\"><span dir=\"ltr\">Quando uma garota quer ter certeza de que ela <\/span><span dir=\"ltr\">namorado a ama, ela vai para isso <\/span><span dir=\"ltr\">lugar com o namorado. Um menino que <\/span><span dir=\"ltr\">s\u00f3 quer se divertir com a garota <\/span><span dir=\"ltr\">nunca vou dizer a ela neste lugar que <\/span><span dir=\"ltr\">ele a ama se n\u00e3o for sincero.<\/span><\/span><\/p>\n<p>&nbsp;<\/p>\n<blockquote>\n<h3 style=\"text-align: center;\"><em><span class=\"markedContent\"><span dir=\"ltr\">\u00c9 o seu ciclo de vida.<\/span><\/span><\/em><\/h3>\n<\/blockquote>\n<p><span class=\"markedContent\"><span dir=\"ltr\">Mas se um garoto disser \u00e0 namorada que ele <\/span><span dir=\"ltr\">a ama, ela sabe que \u00e9 verdade, <\/span><span dir=\"ltr\">porque ningu\u00e9m dir\u00e1 a mentira <\/span><span dir=\"ltr\">naquele lugar. Ningu\u00e9m!<\/span><\/span><\/p>\n<p><span class=\"markedContent\"><span dir=\"ltr\">\u00c9 claro que na vida balinesa existem <\/span><span dir=\"ltr\">muitas cerim\u00f4nias importantes. Ainda, <\/span><span dir=\"ltr\">para as pessoas aqui, \u00e9 vital que <\/span><span dir=\"ltr\">o mesmo lugar onde eles admitem seus <\/span><span dir=\"ltr\">amor, eles tamb\u00e9m v\u00e3o acabar depois do <\/span><span dir=\"ltr\">crema\u00e7\u00e3o. <\/span><\/span><\/p>\n<p><a href=\"https:\/\/www.google.com\/maps\/place\/Goa+Rang+Reng+Waterfall\/@-8.5153614,115.3307974,15z\/data=!4m2!3m1!1s0x0:0x972abf684b06f39f?sa=X&amp;ved=2ahUKEwj2kJOzksDxAhVjyDgGHYvHCQkQ_BIwGHoECEoQBQ\" target=\"_blank\" rel=\"noopener\">VAI L\u00c1 -&gt; LOCALIZA\u00c7\u00c3O DO MAPAS<\/a><\/p>\n<p>Nosso amigo e Made est\u00e1 ansioso para mostrar a voc\u00ea sua linda casa. Sua profunda conex\u00e3o com a beleza natural de Banjar Gitgit \u00e9 verdadeiramente inspiradora.<\/p>\n<p>Sua hist\u00f3ria nos leva a uma viagem pelo cora\u00e7\u00e3o m\u00edstico de Bali, onde a selva, o rio e a cachoeira de Goa Rang Reng servem de pano de fundo para sua not\u00e1vel hist\u00f3ria. O conhecimento \u00edntimo de Made de cada pedra e folha deste lugar encantador \u00e9 uma prova de seu profundo v\u00ednculo com a M\u00e3e Natureza.<\/p>\n<p>Para o povo de Banjar Gitgit, a Caverna de Goa Rang Reng \u00e9 mais do que apenas uma atra\u00e7\u00e3o tur\u00edstica; \u00e9 um lugar sagrado para limpeza ritual, conhecido como &#039;melukat&#039;. Aqui, eles buscam consolo em sentimentos terr\u00edveis e pesadelos.<\/p>\n<p>O <a href=\"https:\/\/instantkarmamag.com\/pt\/artigo\/origem-de-ubud\/\" target=\"_blank\" rel=\"noopener\">converg\u00eancia de dois rios<\/a> diante da caverna, simbolizando as energias femininas e masculinas, cria uma poderosa met\u00e1fora para o amor. Os casais v\u00eam aqui para afirmar o seu amor, sabendo que este solo sagrado n\u00e3o deixa espa\u00e7o para falsidades.<\/p>\n<p>\u00c9 uma prova do v\u00ednculo duradouro entre a humanidade e a beleza encantadora da natureza selvagem de Bali\u2026<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Leia a sua hist\u00f3ria \u00fanica de cria\u00e7\u00e3o da nova atra\u00e7\u00e3o tur\u00edstica de Goa Rang Reng e os rituais que ainda s\u00e3o realizados pelas pessoas desta aldeia.<\/p>","protected":false},"author":214,"featured_media":10756,"comment_status":"open","ping_status":"closed","template":"","meta":{"footnotes":""},"categories":[270],"tags":[342],"section":[385,395],"interest":[199,377,400],"_magazine":[343],"class_list":["post-9677","article","type-article","status-publish","has-post-thumbnail","hentry","category-explore","tag-342","section-explore","section-places","interest-expeditions","interest-sightseeing","interest-things-to-do","_magazine-343"],"_links":{"self":[{"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/article\/9677","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/article"}],"about":[{"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/types\/article"}],"author":[{"embeddable":true,"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/users\/214"}],"replies":[{"embeddable":true,"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/comments?post=9677"}],"version-history":[{"count":0,"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/article\/9677\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/media\/10756"}],"wp:attachment":[{"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/media?parent=9677"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/categories?post=9677"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/tags?post=9677"},{"taxonomy":"section","embeddable":true,"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/section?post=9677"},{"taxonomy":"interest","embeddable":true,"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/interest?post=9677"},{"taxonomy":"_magazine","embeddable":true,"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/_magazine?post=9677"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}<!-- This website is optimized by Airlift. Learn more: https://airlift.net. Template:. Learn more: https://airlift.net. Template: 6a3c9e6bc6af5a91495580da. Config Timestamp: 2026-06-25 03:19:51 UTC, Cached Timestamp: 2026-09-02 03:40:00 UTC -->