{"id":38352,"date":"2025-09-15T09:28:01","date_gmt":"2025-09-15T01:28:01","guid":{"rendered":"https:\/\/instantkarmamag.com\/?post_type=article&#038;p=38352"},"modified":"2025-09-22T09:55:57","modified_gmt":"2025-09-22T01:55:57","slug":"visite-denpasar-um-renascimento-cultural-com-htl-psr","status":"publish","type":"article","link":"https:\/\/instantkarmamag.com\/pt\/artigo\/visite-denpasar-um-renascimento-cultural-com-htl-psr\/","title":{"rendered":"Visite Denpasar \u2013 Um renascimento cultural com HTL PSR"},"content":{"rendered":"<div id=\"bsf_rt_marker\"><\/div>\n<p class=\"wp-block-paragraph\">A tens\u00e3o n\u00e3o \u00e9 te\u00f3rica. \u00c9 vis\u00edvel em estruturas de a\u00e7o, atalhos paradoxais e penhascos em ru\u00ednas. \u00c9 ouvida em conversas entre artistas, arquitetos, gar\u00e7ons, pol\u00edticos e vizinhos.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bali est\u00e1 sendo constru\u00edda continuamente, muitas vezes sem planejamento. A superf\u00edcie da ilha est\u00e1 se tornando cada vez mais fina.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>O HTL PSR se encaixa propositalmente nessa tens\u00e3o.&nbsp;&nbsp;<\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>O edif\u00edcio abriga um caf\u00e9-bar, escrit\u00f3rios criativos, espa\u00e7o para exposi\u00e7\u00f5es, local na cobertura e programas culturais rotativos.&nbsp;<\/strong><\/h3>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"684\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2025\/09\/ADL00847-1-1024x684.jpg\" alt=\"\" class=\"wp-image-38360\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2025\/09\/ADL00847-1-1024x684.jpg 1024w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2025\/09\/ADL00847-1-300x200.jpg 300w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2025\/09\/ADL00847-1-768x513.jpg 768w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2025\/09\/ADL00847-1-1536x1026.jpg 1536w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2025\/09\/ADL00847-1-2048x1368.jpg 2048w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2025\/09\/ADL00847-1-18x12.jpg 18w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">N\u00e3o se tratava de uma constru\u00e7\u00e3o. Era uma escava\u00e7\u00e3o. Um retorno. Desbastado \u00e0 m\u00e3o. O que emergiu \u00e9 uma casa cultural que faz mais do que vender uma vers\u00e3o de Bali. Ela participa dela.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Denpasar n\u00e3o precisa de renascimento. A cidade nunca morreu. Apenas foi exclu\u00edda da narrativa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O HTL PSR foi inaugurado em mar\u00e7o de 2025 na Jalan Gajah Mada, a hist\u00f3rica art\u00e9ria comercial da ilha, a ainda n\u00e3o oficial Chinatown de Bali, entre barracas de tecidos e cafeterias hist\u00f3ricas e new wave.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c9 usado diariamente \u2013 por moradores, por transeuntes, por h\u00f3spedes que ficam muito tempo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>O Kafe Jago fica no t\u00e9rreo.&nbsp;<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"684\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2025\/09\/ADL00825-1-1024x684.jpg\" alt=\"\" class=\"wp-image-38362\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2025\/09\/ADL00825-1-1024x684.jpg 1024w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2025\/09\/ADL00825-1-300x200.jpg 300w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2025\/09\/ADL00825-1-768x513.jpg 768w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2025\/09\/ADL00825-1-1536x1026.jpg 1536w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2025\/09\/ADL00825-1-2048x1368.jpg 2048w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2025\/09\/ADL00825-1-18x12.jpg 18w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">O local parece mais com algo em Bangkok ou Jacarta: elegante, divertido, com design inovador e constru\u00eddo quase inteiramente com material reciclado.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Os m\u00f3veis, as prateleiras e o bar foram feitos sob medida pela equipe interna.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O card\u00e1pio \u00e9 indo-franc\u00eas: crepes, petiscos, pratos especiais experimentais e sobremesas. Os coquet\u00e9is s\u00e3o intensos e vibrantes. Arak substitui as doses habituais, e s\u00f3 h\u00e1 bebidas indon\u00e9sias nas prateleiras. A clientela se aglomera silenciosamente e depois fica at\u00e9 tarde.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>No andar de cima opera a Equipe de Design.&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A equipe cuida das experi\u00eancias de marca, da narrativa, do design espacial e da produ\u00e7\u00e3o. \u00c9 aqui que o HTL PSR foi concebido e onde projetos externos s\u00e3o realizados. O est\u00fadio tamb\u00e9m funciona como galeria e espa\u00e7o para eventos. As exposi\u00e7\u00f5es com curadoria se revezam mensalmente. Convidados entram, amigos saem.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>H\u00e1 um terra\u00e7o tamb\u00e9m.&nbsp;<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"684\" height=\"1024\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2025\/09\/ADL00801-1-684x1024.jpg\" alt=\"\" class=\"wp-image-38363\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2025\/09\/ADL00801-1-684x1024.jpg 684w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2025\/09\/ADL00801-1-200x300.jpg 200w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2025\/09\/ADL00801-1-768x1150.jpg 768w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2025\/09\/ADL00801-1-1026x1536.jpg 1026w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2025\/09\/ADL00801-1-1368x2048.jpg 1368w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2025\/09\/ADL00801-1-8x12.jpg 8w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2025\/09\/ADL00801-1-scaled.jpg 1710w\" sizes=\"auto, (max-width: 684px) 100vw, 684px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Sempre aberto. Frequentemente ativo. As madrugadas se estendem para a dan\u00e7a. At\u00e9 agora: uma noite de funk-soul s\u00f3 com discos de vinil, um bar na cobertura com coquet\u00e9is rotativos, um clube noturno com cinco pratos que reuniu assistentes sociais com artistas e m\u00fasicos para falar sobre cuidado, terapia e resist\u00eancia criativa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As obras de arte da recente exposi\u00e7\u00e3o <em>Sinestesia<\/em> permanecem em exposi\u00e7\u00e3o. Todas as pe\u00e7as est\u00e3o \u00e0 venda, e a renda ser\u00e1 revertida para a continuidade das oficinas de arte inclusiva.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">VISIT DPS \u00e9 a pr\u00f3xima exposi\u00e7\u00e3o: participativa, realista e aberta a todos \u2014 de planejadores urbanos a comerciantes de pasar. Ela observa, escuta e prop\u00f5e maneiras de preservar a mem\u00f3ria, evoluindo significativamente com o tempo. O lan\u00e7amento come\u00e7a com uma sess\u00e3o de vinil no terra\u00e7o e um jantar em mesas compridas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O HTL PSR reflete e amplifica a cultura que j\u00e1 existe \u2013 <em>aquele raramente visto em Canggu ou Uluwatu<\/em>.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A vida local, vivida e cont\u00ednua, que ainda se desenrola em mercados, ruas, quarteir\u00f5es e resid\u00eancias estudantis.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Denpasar nunca desapareceu. A hist\u00f3ria apenas mudou para outro lugar.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Agora est\u00e1 mudando de volta.<\/p>\n\n\n\n<h4 class=\"wp-block-heading has-text-align-center\"><strong>O HTL PSR est\u00e1 aberto. Est\u00e1 funcionando. <\/strong><\/h4>\n\n\n\n<h4 class=\"wp-block-heading has-text-align-center\"><strong>Suba as escadas.<\/strong><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Instagram <a href=\"https:\/\/instagram.com\/htlpsr.id\" target=\"_blank\" rel=\"noopener\">@htlpsr.id<\/a>&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Link do MAPS<\/strong><br><a href=\"https:\/\/www.google.com\/maps\/place\/HTL+PSR+%2B+KAFE+JAGO\/@-8.6554992,115.2135502,17z\/data=!4m15!1m8!3m7!1s0x2dd23fbf5bf569af:0xe60b92fd10a4c4e0!2sHTL+PSR+%2B+KAFE+JAGO!8m2!3d-8.6555691!4d115.2135417!10e5!16s%2Fg%2F11w97sj_n8!3m5!1s0x2dd23fbf5bf569af:0xe60b92fd10a4c4e0!8m2!3d-8.6555691!4d115.2135417!16s%2Fg%2F11w97sj_n8?entry=ttu&amp;g_ep=EgoyMDI1MDgyNS4wIKXMDSoASAFQAw%3D%3D\" target=\"_blank\" rel=\"noopener\">https:\/\/www.google.com<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>","protected":false},"excerpt":{"rendered":"<p>Bali est\u00e1 sendo constru\u00edda continuamente, muitas vezes sem planejamento. A superf\u00edcie da ilha est\u00e1 se tornando cada vez mais fina.<\/p>\n<p>O HTL PSR se encaixa propositalmente nessa tens\u00e3o.\u00a0\u00a0<\/p>","protected":false},"author":223,"featured_media":38357,"comment_status":"open","ping_status":"closed","template":"","meta":{"footnotes":""},"categories":[270],"tags":[427],"section":[385,395],"interest":[425,380,372,378,400],"_magazine":[426],"class_list":["post-38352","article","type-article","status-publish","has-post-thumbnail","hentry","category-explore","tag-427","section-explore","section-places","interest-art","interest-creative","interest-eco","interest-social","interest-things-to-do","_magazine-426"],"_links":{"self":[{"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/article\/38352","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/article"}],"about":[{"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/types\/article"}],"author":[{"embeddable":true,"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/users\/223"}],"replies":[{"embeddable":true,"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/comments?post=38352"}],"version-history":[{"count":4,"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/article\/38352\/revisions"}],"predecessor-version":[{"id":38368,"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/article\/38352\/revisions\/38368"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/media\/38357"}],"wp:attachment":[{"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/media?parent=38352"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/categories?post=38352"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/tags?post=38352"},{"taxonomy":"section","embeddable":true,"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/section?post=38352"},{"taxonomy":"interest","embeddable":true,"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/interest?post=38352"},{"taxonomy":"_magazine","embeddable":true,"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/_magazine?post=38352"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}<!-- This website is optimized by Airlift. Learn more: https://airlift.net. Template:. Learn more: https://airlift.net. Template: 6a3c9e6bc6af5a91495580da. Config Timestamp: 2026-06-25 03:19:51 UTC, Cached Timestamp: 2026-09-02 08:58:26 UTC -->