{"id":32411,"date":"2023-07-12T19:10:06","date_gmt":"2023-07-12T11:10:06","guid":{"rendered":"https:\/\/instantkarmamag.com\/?post_type=article&#038;p=32411"},"modified":"2024-07-02T17:33:29","modified_gmt":"2024-07-02T09:33:29","slug":"andrea-hirata-laskar-pelangi-2","status":"publish","type":"article","link":"https:\/\/instantkarmamag.com\/pt\/artigo\/andrea-hirata-laskar-pelangi-2\/","title":{"rendered":"Andrea Hirata \u2013 Autora de Laskar Pelangi"},"content":{"rendered":"<div id=\"bsf_rt_marker\"><\/div><p><span data-contrast=\"none\">Andrea Hirata tornou-se um renomado autor indon\u00e9sio das profundezas da discrimina\u00e7\u00e3o e da pobreza atrav\u00e9s de seu trabalho seminal <a href=\"https:\/\/amzn.to\/4aMlrME\" target=\"_blank\" rel=\"noopener\">livro Laskar Pelangi<\/a> \u2013 \u201cThe Rainbow Troops\u201d, que conta a hist\u00f3ria da sua inf\u00e2ncia em Belitung, onde a educa\u00e7\u00e3o era escassa e a opress\u00e3o corporativa era grande.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335559738&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"none\">\u201cThe Rainbow Troops\u201d foi traduzido para mais de 30 idiomas e adaptado para um filme. <\/span><\/p>\n<p><span data-contrast=\"none\">Isto<\/span><span data-contrast=\"none\"> tornou-se<a href=\"https:\/\/www.imdb.com\/title\/tt1301264\/\" target=\"_blank\" rel=\"noopener\"><strong> o filme indon\u00e9sio mais visto de todos os tempos<\/strong><\/a>, sendo visto por 5 milh\u00f5es de telespectadores durante sua exibi\u00e7\u00e3o teatral, <\/span><span data-contrast=\"none\">aumentando ainda mais a consci\u00eancia global da heran\u00e7a cultural de Belitung.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335559738&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<h2><span data-contrast=\"none\">Hirata n\u00e3o \u00e9 apenas um autor de best-sellers<\/span><\/h2>\n<p><span data-contrast=\"none\">Ele tamb\u00e9m \u00e9 conhecido por suas contribui\u00e7\u00f5es ao patrim\u00f4nio cultural de <a href=\"https:\/\/instantkarmamag.com\/pt\/artigo\/belitung-o-paraiso-mais-proximo\/\">Ilha Belitung<\/a>d. <\/span><span data-contrast=\"none\">Em 2009, fundou o Museu KATA Andrea Hirata, que apresenta o rico patrim\u00f3nio cultural e hist\u00f3rico da ilha. O museu tamb\u00e9m funciona como centro de promo\u00e7\u00e3o da literatura e das artes.\u00a0<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"none\">Nesta entrevista, Andrea compartilha sua jornada, lutas e conselhos para quem busca seus sonhos.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335559738&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-32419 size-large\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2024\/04\/andrea-hirata-1-4-663x1024.jpg\" alt=\"andrea hirata laskar pelangi\" width=\"663\" height=\"1024\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2024\/04\/andrea-hirata-1-4-663x1024.jpg 663w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2024\/04\/andrea-hirata-1-4-194x300.jpg 194w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2024\/04\/andrea-hirata-1-4-768x1187.jpg 768w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2024\/04\/andrea-hirata-1-4-994x1536.jpg 994w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2024\/04\/andrea-hirata-1-4-1325x2048.jpg 1325w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2024\/04\/andrea-hirata-1-4-scaled.jpg 1656w\" sizes=\"auto, (max-width: 663px) 100vw, 663px\" \/><\/p>\n<h3>Como voc\u00ea enfrentou os desafios retratados em seu livro Laskar Pelangi?<\/h3>\n<p><i><span data-contrast=\"none\"><strong>Desamparo aprendido<\/strong> foi o maior desafio para mim e meus amigos de inf\u00e2ncia. Discrimina\u00e7\u00e3o \u2013 como descrevi em The Rainbow Troops \u2013 <\/span><\/i><i><span data-contrast=\"auto\">imposta pela mineradora de estanho \u2013 foi t\u00e3o grande que criou uma hegemonia em nossa cultura e o motor de nossa vida social. <\/span><\/i><\/p>\n<p><i><span data-contrast=\"auto\">Isso resultou em baixa autoestima, desconfian\u00e7a e sentimento entre n\u00f3s, nativos, que acredit\u00e1vamos que algo progressista e pr\u00f3spero nunca nos pertenceria. <\/span><\/i><\/p>\n<p><i><span data-contrast=\"auto\">Pens\u00e1vamos que n\u00e3o t\u00ednhamos capacidade para aprender e ser educados. <strong>N\u00f3s fomos rotulados<\/strong> como coolies, o nosso futuro era inevit\u00e1vel, e todos se tornariam mineiros de estanho, como todos os homens da nossa aldeia, gera\u00e7\u00e3o ap\u00f3s gera\u00e7\u00e3o.<\/span><\/i><i><span data-contrast=\"none\"> A educa\u00e7\u00e3o nunca fez parte dos nossos planos.<\/span><\/i><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335559738&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><strong>Em seu livro Laskar Pelangi, a hist\u00f3ria gira em torno da descoberta das pr\u00f3prias habilidades e potencialidades e do enfrentamento dos obst\u00e1culos e desafios da vida.<\/strong><\/p>\n<h3>Como voc\u00ea descobriu seu potencial?<\/h3>\n<p><i><span data-contrast=\"none\">Atrav\u00e9s do instinto, coragem e uma atitude positiva. Nossa comunidade era t\u00e3o isolada e sem instru\u00e7\u00e3o naquela \u00e9poca. Nem sab\u00edamos que uma empresa que explora os nossos recursos naturais \u2013 especialmente uma empresa estatal \u2013 tem uma responsabilidade social corporativa. <\/span><\/i><\/p>\n<p><i><span data-contrast=\"none\">N\u00e3o sab\u00edamos que os nossos direitos humanos b\u00e1sicos, como o acesso \u00e0 educa\u00e7\u00e3o, estavam a ser violados. Meus instintos me disseram que algo estava muito errado. Essa \u00e9 uma das raz\u00f5es pelas quais escrevi meu primeiro romance.<\/span><\/i><\/p>\n<p><i><span data-contrast=\"none\">Lembro-me de quando tinha 16 anos, deixei minha aldeia natal e fui para Jacarta e fiz biscates l\u00e1, administrando lojas e como oper\u00e1rio de f\u00e1brica. Lembro-me de me sentar uma noite e come\u00e7ar a digitar. <\/span><\/i><\/p>\n<p><i><span data-contrast=\"none\">Sem perceber, depois de tr\u00eas semanas, havia escrito 800 p\u00e1ginas. Eu nunca tinha escrito um conto antes. Esse \u00e9 meu primeiro romance, The Rainbow Troops. N\u00e3o porque eu seja um escritor brilhante, mas porque tinha muitas coisas para contar desde a minha inf\u00e2ncia e como \u00e9ramos maltratados pelas autoridades, incluindo a empresa estatal. <\/span><\/i><\/p>\n<p><i><span data-contrast=\"none\">Minha escrita foi motivada pela minha pura inten\u00e7\u00e3o de dizer a todos que o que aconteceu conosco na Ilha Belitung naquela \u00e9poca n\u00e3o deveria acontecer novamente. Mas voc\u00ea sabe o que? Isso ainda est\u00e1 acontecendo em muitos cantos do mundo.<\/span><\/i><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-32414 size-large\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2024\/04\/1museumkatanadreahirata8-2-1024x547.jpg\" alt=\"andrea hirata laskar pelangi\" width=\"1024\" height=\"547\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2024\/04\/1museumkatanadreahirata8-2-1024x547.jpg 1024w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2024\/04\/1museumkatanadreahirata8-2-2048x1095.jpg 2048w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2024\/04\/1museumkatanadreahirata8-2-300x160.jpg 300w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2024\/04\/1museumkatanadreahirata8-2-768x410.jpg 768w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2024\/04\/1museumkatanadreahirata8-2-1536x821.jpg 1536w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<h3>A vida \u00e9 uma jornada emocionante cheia de aventuras que nos trazem desafios.<\/h3>\n<p><b><span data-contrast=\"none\">Em Laskar Pelangi, a hist\u00f3ria \u00e9 sobre uni\u00e3o, determina\u00e7\u00e3o e apoio para que todos possam realizar seus sonhos.<\/span><\/b><\/p>\n<p><b><span data-contrast=\"none\">Para quem ainda n\u00e3o leu seus livros, qual o seu melhor conselho para perseguir e alcan\u00e7ar seus objetivos e sonhos?<\/span><\/b> <span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335559738&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><i><span data-contrast=\"none\">Assuma a responsabilidade, esse seria o meu conselho. Acredito que assumir responsabilidades \u00e9 a raiz de todas as virtudes. Aprender \u00e9 f\u00e1cil, mas s\u00f3 se pode alcan\u00e7ar algo se for respons\u00e1vel pelo futuro, pelas coisas boas que pode fazer, pelo bem que pode dar aos outros, pelas oportunidades que tem e por tudo o que lhe \u00e9 dado, incluindo o talento. .<\/span><\/i><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<h3>Quando voc\u00ea est\u00e1 longe de Belitung, do que voc\u00ea mais sente falta?<\/h3>\n<p><i><span data-contrast=\"none\">Sinto falta dos meus amigos da escola, dos meus professores, das pessoas nos caf\u00e9s, de toda a fam\u00edlia e da m\u00fasica malaia.<\/span><\/i><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335559738&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<h3>Voc\u00ea tem um lugar favorito em Belitung que poucas pessoas conhecem?<\/h3>\n<p><i><span data-contrast=\"none\">Vivemos em um mundo cada vez mais sim\u00e9trico. O que um sabe, o outro sabe numa fra\u00e7\u00e3o de segundo. \u00c9 um mundo chato sem segredos, haha! O turismo paisag\u00edstico ainda domina em todos os lugares. <\/span><\/i><\/p>\n<p><i><span data-contrast=\"none\">Mas as t\u00edpicas barracas de caf\u00e9 malaias em East Belitung proporcionam um destino cultural fascinante e raramente s\u00e3o visitadas por turistas. Ou talvez voc\u00ea esteja interessado em conhecer o Andrea Hirata Words Museum, o primeiro museu liter\u00e1rio da Indon\u00e9sia, inaugurado em 2009 em East Belitung.<\/span><\/i><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><b><span data-contrast=\"none\">Como Belitung se transformou ao longo do tempo e o sucesso de Laskar Pelangi impactou as mudan\u00e7as?<\/span><\/b><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335559738&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><i><span data-contrast=\"auto\">O impacto de Laskar Pelangi foi significativo em Belitung. O turismo aumentou 1800% \u2013 Talvez seja por causa do romance e tamb\u00e9m porque a hist\u00f3ria da beleza da ilha de Belitung foi transformada em filme. O acesso \u00e0 educa\u00e7\u00e3o \u00e9 melhor agora e as cr\u00edticas do romance \u00e0 empresa estatal refor\u00e7aram a responsabilidade social corporativa.<\/span><\/i><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335559738&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<h3>Voc\u00ea pode compartilhar um pouco mais sobre o seu museu liter\u00e1rio em Belitung?<\/h3>\n<p><i><span data-contrast=\"auto\">Em 2009, criei o Museu Andrea Hirata Kata na minha aldeia em East Belitung para incentivar o interesse pela leitura entre os jovens de Belitung, em particular, e da Indon\u00e9sia, em geral. Dentro est\u00e1 <\/span><\/i><i><span data-contrast=\"none\">uma biblioteca e um museu liter\u00e1rio com uma das maiores cole\u00e7\u00f5es de literatura malaia.<\/span><\/i><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-32415 size-large\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2024\/04\/Iandrea-hirata-museum-1024x768.jpg\" alt=\"andrea hirata laskar pelangi\" width=\"1024\" height=\"768\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2024\/04\/Iandrea-hirata-museum-1024x768.jpg 1024w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2024\/04\/Iandrea-hirata-museum-300x225.jpg 300w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2024\/04\/Iandrea-hirata-museum-768x576.jpg 768w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2024\/04\/Iandrea-hirata-museum-1536x1152.jpg 1536w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2024\/04\/Iandrea-hirata-museum-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p><b><span data-contrast=\"none\">Qual \u00e9 a sua defini\u00e7\u00e3o de turismo respons\u00e1vel e como \u00e9 melhor praticado em Belitung?<\/span><\/b><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335559738&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><i><span data-contrast=\"auto\">Acho que em Belitung ou em qualquer outro lugar<\/span><\/i><i><span data-contrast=\"none\">, o turismo \u00e9 uma forma ideal de envolver o cora\u00e7\u00e3o e a mente. O turismo promove e preserva a cultura e proporciona educa\u00e7\u00e3o e esclarecimento ao mesmo tempo que \u00e9 agrad\u00e1vel.<\/span><\/i><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335559738&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<h3>Algum conselho para quem mora em \u00e1reas remotas e quer ser escritor?<\/h3>\n<p><i><span data-contrast=\"auto\">Leia e tenha coragem de experimentar coisas novas e ouse responder a todos os desafios<\/span><\/i><span data-contrast=\"auto\">. <\/span><\/p>\n<p>&nbsp;<\/p>\n<blockquote>\n<h2 style=\"text-align: center;\"><span data-contrast=\"auto\"><em>Cada cria\u00e7\u00e3o tem seu destino, basta escrev\u00ea-lo. <\/em><\/span><\/h2>\n<h2 style=\"text-align: center;\"><span data-contrast=\"auto\"><em>O futuro pertence aos corajosos. <\/em> <\/span><\/h2>\n<p>&nbsp;<\/p><\/blockquote>\n<p><i><span data-contrast=\"auto\">N\u00e3o tenho forma\u00e7\u00e3o em educa\u00e7\u00e3o ou reda\u00e7\u00e3o e n\u00e3o sou um escritor com muita experi\u00eancia. Um jornal australiano me chamou de escritor acidental, concordo com isso.<\/span><\/i><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><b><span data-contrast=\"none\">Como escritor indon\u00e9sio, \u00e9 importante envolver elementos culturais e tradi\u00e7\u00f5es de <\/span><\/b><b><span data-contrast=\"auto\">o local de origem do escritor?<\/span><\/b><span data-contrast=\"none\">\u202f<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335559738&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><i><span data-contrast=\"none\">Isso \u00e9 muito importante. Infelizmente, os temas culturais e educacionais s\u00e3o bastante raros para os escritores indon\u00e9sios. Principalmente, eles est\u00e3o mais interessados em temas de estilo de vida e quest\u00f5es urbanas.<\/span><\/i><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335559738&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-32413 size-large\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2024\/04\/1museumkataandreahirata-depan-4-1024x628.jpg\" alt=\"andrea hirata laskar pelangi\" width=\"1024\" height=\"628\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2024\/04\/1museumkataandreahirata-depan-4-1024x628.jpg 1024w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2024\/04\/1museumkataandreahirata-depan-4-1536x942.jpg 1536w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2024\/04\/1museumkataandreahirata-depan-4-300x184.jpg 300w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2024\/04\/1museumkataandreahirata-depan-4-768x471.jpg 768w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2024\/04\/1museumkataandreahirata-depan-4-2048x1257.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<h3>Quais temas voc\u00ea acha fascinantes e por qu\u00ea?<\/h3>\n<p><i><span data-contrast=\"none\">Educa\u00e7\u00e3o, esse \u00e9 o meu tema principal. Quando eu era crian\u00e7a, a Ilha Belitung supria a maior parte da necessidade mundial de estanho. No entanto, as crian\u00e7as malaias de Belitung frequentavam uma escola t\u00e3o pobre e tortuosa que poderia ruir a qualquer momento \u2013 fic\u00e1vamos nervosos sempre que chovia e o vento soprava.<\/span><\/i><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335559738&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2 style=\"text-align: center;\"><i><span data-contrast=\"none\">A educa\u00e7\u00e3o tornou-se uma coisa muito pessoal.<\/span><\/i><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335559738&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/h2>\n<p>&nbsp;<\/p>\n<p><b><span data-contrast=\"none\">Voc\u00ea tem algum conselho para aspirantes a escritores que est\u00e3o apenas come\u00e7ando?<\/span><\/b><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335559738&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><i><span data-contrast=\"none\">Recomendo ler o m\u00e1ximo poss\u00edvel, ser ousado na escrita e experimentar diferentes g\u00eaneros e estilos. N\u00e3o se preocupe em ser perfeito e n\u00e3o se compare a outros escritores. Cada escritor tem uma voz e um estilo \u00fanicos, e esse desenvolvimento leva<\/span><\/i><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335559738&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><i><span data-contrast=\"none\">tempo e pr\u00e1tica. Al\u00e9m disso, n\u00e3o tenha medo de buscar feedback e cr\u00edticas de<\/span><\/i><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335559738&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><i><span data-contrast=\"none\">outros, pois pode ajudar a melhorar sua escrita.<\/span><\/i><span data-contrast=\"none\">\u202f<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335559738&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<h3>Quais s\u00e3o seus livros e autores favoritos?<\/h3>\n<p><i><span data-contrast=\"none\">Tenho muitos autores favoritos, mas alguns dos meus her\u00f3is incluem Truman Capote, Antonio Skarmeta, Jane Smiley, John Barrend, Harper Lee e James Allan McPherson. A Sangue Frio, de Capote, e O Velho e o Mar, de Hemingway, s\u00e3o meus livros favoritos de todos os tempos. <\/span><\/i><\/p>\n<p><i><span data-contrast=\"none\">A capacidade de Capote de escrever n\u00e3o-fic\u00e7\u00e3o convincente \u00e9 inspiradora, enquanto o estilo de escrita simples, mas poderoso, de Hemingway sempre ressoa em mim.<\/span><\/i><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335559738&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<h3>Voc\u00ea est\u00e1 trabalhando em algum projeto atualmente?<\/h3>\n<p><i><span data-contrast=\"none\">H\u00e1 alguns meses, fui inspirado por meu primeiro conto, \u201cDry Season\u201d, publicado pela Washington Square Review Literary Magazine, NYU. Agora estou escrevendo minha primeira cole\u00e7\u00e3o de contos.<\/span><\/i><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335559738&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span data-contrast=\"none\">Obrigado, Andrea, pela entrevista. <\/span><\/p>\n<p><span data-contrast=\"none\">Esperamos ansiosamente por mais livros inspiradores seus.\u00a0<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335559738&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335559738&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<h3 style=\"text-align: center;\"><span data-contrast=\"none\"><a href=\"https:\/\/amzn.to\/4aMlrME\" target=\"_blank\" rel=\"noopener\">Obtenha Laskar Pelangi \u201cAs Tropas Arco-\u00cdris\u201d<\/a> por Andrea Hirata<\/span><\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-32416 size-medium\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2024\/04\/The-Rainbow-Troops-American-edition-290x300.jpg\" alt=\"andrea hirata laskar pelangi\" width=\"290\" height=\"300\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2024\/04\/The-Rainbow-Troops-American-edition-290x300.jpg 290w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2024\/04\/The-Rainbow-Troops-American-edition-768x793.jpg 768w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2024\/04\/The-Rainbow-Troops-American-edition-991x1024.jpg 991w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2024\/04\/The-Rainbow-Troops-American-edition-1487x1536.jpg 1487w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2024\/04\/The-Rainbow-Troops-American-edition.jpg 1600w\" sizes=\"auto, (max-width: 290px) 100vw, 290px\" \/><\/p>\n<h3><span data-contrast=\"none\">Siga no Instagram <a href=\"https:\/\/www.instagram.com\/hirataandrea\/\" target=\"_blank\" rel=\"noopener\">@hirataandrea<\/a><\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335559738&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/h3>\n<p><span data-contrast=\"none\">\u202f<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335559738&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>Os romances de Andrea Hirata, como \u201cLaskar Pelangi\u201d (As Tropas do Arco-\u00cdris) e \u201cSang Pemimpi\u201d (O Sonhador), colocaram Belitung no mapa liter\u00e1rio e chamaram a aten\u00e7\u00e3o para a cultura e as tradi\u00e7\u00f5es \u00fanicas da ilha.<\/p>","protected":false},"author":214,"featured_media":32417,"comment_status":"open","ping_status":"closed","template":"","meta":{"footnotes":""},"categories":[273],"tags":[],"section":[388],"interest":[380,381,378],"_magazine":[364],"class_list":["post-32411","article","type-article","status-publish","has-post-thumbnail","hentry","category-people","section-people","interest-creative","interest-empowerment","interest-social","_magazine-364"],"_links":{"self":[{"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/article\/32411","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/article"}],"about":[{"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/types\/article"}],"author":[{"embeddable":true,"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/users\/214"}],"replies":[{"embeddable":true,"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/comments?post=32411"}],"version-history":[{"count":0,"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/article\/32411\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/media\/32417"}],"wp:attachment":[{"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/media?parent=32411"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/categories?post=32411"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/tags?post=32411"},{"taxonomy":"section","embeddable":true,"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/section?post=32411"},{"taxonomy":"interest","embeddable":true,"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/interest?post=32411"},{"taxonomy":"_magazine","embeddable":true,"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/_magazine?post=32411"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}<!-- This website is optimized by Airlift. Learn more: https://airlift.net. Template:. Learn more: https://airlift.net. Template: 6a3c9e6bc6af5a91495580da. Config Timestamp: 2026-06-25 03:19:51 UTC, Cached Timestamp: 2026-09-02 07:25:54 UTC -->