{"id":28644,"date":"2023-11-29T21:54:40","date_gmt":"2023-11-29T13:54:40","guid":{"rendered":"https:\/\/instantkarmamag.com\/?post_type=article&#038;p=28644"},"modified":"2024-02-09T18:34:52","modified_gmt":"2024-02-09T10:34:52","slug":"as-montanhas-sagradas-de-kintamani","status":"publish","type":"article","link":"https:\/\/instantkarmamag.com\/pt\/artigo\/as-montanhas-sagradas-de-kintamani\/","title":{"rendered":"As Montanhas Sagradas de Kintamani\u00a0"},"content":{"rendered":"<div id=\"bsf_rt_marker\"><\/div><p><span data-contrast=\"auto\">Kintamani. Um frio<\/span><span data-contrast=\"none\"> escapar f<\/span><span data-contrast=\"auto\">do calor tropical dos seus destinos costeiros normais na ilha. A vista do topo \u00e9 o objetivo: o Monte Batur, de 1.717 metros de altura, ideal para caminhantes casuais. Ainda \u00e9 uma caminhada desafiadora, especialmente no escuro, mas l\u00e1 de baixo voc\u00ea pode ver as lanternas dos caminhantes anteriores serpenteando at\u00e9 o cume. Voc\u00ea n\u00e3o vai se perder.\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-30948 size-large\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/11\/mount-batur-kintamani-1024x683.jpg\" alt=\"Monte Batur Kintamani\" width=\"1024\" height=\"683\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/11\/mount-batur-kintamani-1024x683.jpg 1024w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/11\/mount-batur-kintamani-300x200.jpg 300w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/11\/mount-batur-kintamani-768x512.jpg 768w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/11\/mount-batur-kintamani.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<h2><span data-contrast=\"auto\">Uma vez no topo, \u00e9 lindo. <\/span><\/h2>\n<p><span data-contrast=\"auto\">O sol nasce emanando seus raios saud\u00e1veis, abrindo as vistas verdejantes ao redor (e voc\u00ea pode ser saudado por macacos), al\u00e9m da vista das outras montanhas - o Monte Abang, mais alto, e se o c\u00e9u estiver limpo, Gunung Agung em Karangasem, a leste - e o impressionante lago Batur em forma de meia-lua. Manh\u00e3 bem passada.\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">\u00c9 uma vis\u00e3o fascinante, mas cuidado, pois Batur e Abang <\/span><span data-contrast=\"none\">s\u00e3o vulc\u00f5es ativos<\/span><span data-contrast=\"auto\">, que entrou em erup\u00e7\u00e3o em 1800 e formou a caldeira do Lago <\/span><span data-contrast=\"none\">Batur. Nos dias de hoje, <\/span><span data-contrast=\"auto\">as pessoas visitam Kintamani mais pelos caf\u00e9s. As estruturas minimalistas de vidro a partir das quais os clientes podem aproveitar os terra\u00e7os e tirar selfies com as montanhas e o lago.\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Tamb\u00e9m \u00e9 muito flagrante que no futuro o alpinismo possa ser totalmente proibido pelo governo devido a comportamentos question\u00e1veis de turistas estrangeiros que sentem a necessidade de se exporem num local que os balineses consideram sagrado.\u00a0\u00a0\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Novamente, devemos estar sempre atentos e conscientes dos costumes e da cultura local antes de visitar um lugar estrangeiro. E isso inclui escalar as montanhas de Bali. Mas que significado especial isso tem para os balineses<\/span><span data-contrast=\"none\"> Hindu?<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<h3>Alto e poderoso<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-30950 size-large\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/11\/Kintamanni-Pura-Puncak-Penulisan-1024x683.jpg\" alt=\"Kintamanni Pura Puncak Penulisan\" width=\"1024\" height=\"683\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/11\/Kintamanni-Pura-Puncak-Penulisan-1024x683.jpg 1024w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/11\/Kintamanni-Pura-Puncak-Penulisan-300x200.jpg 300w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/11\/Kintamanni-Pura-Puncak-Penulisan-768x512.jpg 768w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/11\/Kintamanni-Pura-Puncak-Penulisan.jpg 1500w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<h2><span data-contrast=\"auto\">As montanhas s\u00e3o locais sagrados em Bali. <\/span><\/h2>\n<p><span data-contrast=\"auto\">O terreno elevado representa o lar dos deuses ancestrais e do pr\u00f3prio Deus supremo, Ida Sanghyang Widhi Wasa.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">O templo de montanha mais famoso de Bali \u00e9 o Templo Besakih, no sop\u00e9 da montanha Agung. Mas Kintamani tamb\u00e9m possui um templo de montanha historicamente importante: Pura Puncak Penulisan, na colina Penulisan. O templo, a oeste de Batur, foi constru\u00eddo durante a idade do bronze de Bali (600 aC \u2013 800 dC) e funciona n\u00e3o apenas para fins cerimoniais, mas tamb\u00e9m como local de medita\u00e7\u00e3o para sacerdotes.\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">\u00c9 uma jornada ascendente de 300 degraus que leva a sete terra\u00e7os onde se encontram diferentes templos, sendo o templo mais alto (Pura Puncak Penulisan) adornado com artefatos megal\u00edticos e est\u00e1tuas. A estrutura do templo, tamb\u00e9m conhecida como Pura Tegeh Kahuripan, pretendia simbolizar uma montanha. Representando a ascens\u00e3o do ser humano aos c\u00e9us.\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Se desejar visitar, \u00e9 aconselh\u00e1vel<\/span><span data-contrast=\"none\"> contratar <\/span><span data-contrast=\"auto\">de um guia tur\u00edstico que possa lhe dizer a maneira correta de se comportar e como se vestir adequadamente ao visitar um templo.\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<h2>\u00c9 preciso uma aldeia<\/h2>\n<h3>Aldeia Trunyan<\/h3>\n<p><span data-contrast=\"none\">A aldeia que fica na costa leste de <\/span><span data-contrast=\"none\">lago Batur <\/span><span data-contrast=\"none\">habitada pelo povo Bali Mula (ou tamb\u00e9m frequentemente referido como Bali Aga), o povo original <\/span><span data-contrast=\"none\">povos ind\u00edgenas em Bali. Como as pessoas<\/span><span data-contrast=\"none\"> em Sulawesi do Sul, aqui a tribo exp\u00f5e os mortos em um espa\u00e7o aberto sob a m\u00edstica \u00e1rvore Trunyan. \u00c9 aconselh\u00e1vel ir com um guia a Trunyan para que voc\u00ea conhe\u00e7a os pr\u00f3s e contras.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<h3><strong>Aldeia Penglipuran<\/strong><\/h3>\n<figure id=\"attachment_30952\" aria-describedby=\"caption-attachment-30952\" style=\"width: 1024px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-30952 size-large\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/11\/desa-penglipuran-kintamani-1024x683.jpg\" alt=\"Kintamani desa penglipuran\" width=\"1024\" height=\"683\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/11\/desa-penglipuran-kintamani-1024x683.jpg 1024w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/11\/desa-penglipuran-kintamani-300x200.jpg 300w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/11\/desa-penglipuran-kintamani-768x512.jpg 768w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/11\/desa-penglipuran-kintamani.jpg 1500w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption id=\"caption-attachment-30952\" class=\"wp-caption-text\">Foto de I Komang Sumadi Arta<\/figcaption><\/figure>\n<p><span data-contrast=\"none\">Embora n\u00e3o esteja nas proximidades da \u00e1rea de Batur, a vila de Panglipuran \u00e9 imperd\u00edvel quando voc\u00ea est\u00e1 na regi\u00e3o de Kintamani-Bangli. A vila foi eleita uma das tr\u00eas vilas mais limpas do mundo e \u00e9 bastante pitoresca, com belos jardins tropicais e casas sustentadas por bambu. Voc\u00ea pode parar em uma das casas para saborear os pratos locais (como os vegetais cozidos no vapor com molho de amendoim).<\/span><i><span data-contrast=\"none\">tipat cantok<\/span><\/i><span data-contrast=\"none\">ou a refrescante bebida \u00e0 base de ervas<\/span><i><span data-contrast=\"none\">hahaha cem<\/span><\/i><span data-contrast=\"none\">cem).<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-30953 size-large\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/11\/Kintamani-Herbal-Drink-loloh-cem-cem-1024x683.jpg\" alt=\"Bebida de ervas Kintamani loloh cem cem\" width=\"1024\" height=\"683\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/11\/Kintamani-Herbal-Drink-loloh-cem-cem-1024x683.jpg 1024w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/11\/Kintamani-Herbal-Drink-loloh-cem-cem-300x200.jpg 300w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/11\/Kintamani-Herbal-Drink-loloh-cem-cem-768x512.jpg 768w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/11\/Kintamani-Herbal-Drink-loloh-cem-cem.jpg 1500w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p><span data-contrast=\"none\"> E, como forma perfeita de mergulhar no estilo de vida aut\u00eantico de Bali, voc\u00ea pode reservar uma estadia em uma das casas.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>Podemos escalar montanhas para conquistar (e tirar fotos preciosas), mas para os balineses \u00e9 para nos sentirmos mais pr\u00f3ximos da natureza e dos seus deuses.\u00a0<\/p>","protected":false},"author":46,"featured_media":30949,"comment_status":"open","ping_status":"closed","template":"","meta":{"footnotes":""},"categories":[270],"tags":[368],"section":[385],"interest":[199],"_magazine":[328],"class_list":["post-28644","article","type-article","status-publish","has-post-thumbnail","hentry","category-explore","tag-368","section-explore","interest-expeditions","_magazine-328"],"_links":{"self":[{"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/article\/28644","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/article"}],"about":[{"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/types\/article"}],"author":[{"embeddable":true,"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/comments?post=28644"}],"version-history":[{"count":0,"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/article\/28644\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/media\/30949"}],"wp:attachment":[{"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/media?parent=28644"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/categories?post=28644"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/tags?post=28644"},{"taxonomy":"section","embeddable":true,"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/section?post=28644"},{"taxonomy":"interest","embeddable":true,"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/interest?post=28644"},{"taxonomy":"_magazine","embeddable":true,"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/_magazine?post=28644"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}<!-- This website is optimized by Airlift. Learn more: https://airlift.net. Template:. Learn more: https://airlift.net. Template: 6a3c9e6bc6af5a91495580da. Config Timestamp: 2026-06-25 03:19:51 UTC, Cached Timestamp: 2026-09-02 02:28:33 UTC -->