{"id":26391,"date":"2023-07-03T15:29:47","date_gmt":"2023-07-03T07:29:47","guid":{"rendered":"https:\/\/instantkarmamag.com\/?post_type=article&#038;p=26391"},"modified":"2024-02-28T15:47:30","modified_gmt":"2024-02-28T07:47:30","slug":"festival-folclorico-de-ubud-2023","status":"publish","type":"article","link":"https:\/\/instantkarmamag.com\/pt\/artigo\/festival-folclorico-de-ubud-2023\/","title":{"rendered":"Festival Folcl\u00f3rico de Ubud 2023"},"content":{"rendered":"<div id=\"bsf_rt_marker\"><\/div><h3>Festival Folcl\u00f3rico de Ubud 2023<\/h3>\n<p><span data-contrast=\"auto\">Durante o evento de tr\u00eas dias do Ubud Folkfest 2023, os participantes tiveram a oportunidade de mergulhar numa celebra\u00e7\u00e3o vibrante de m\u00fasica, arte e Culture. Al\u00e9m de apresenta\u00e7\u00f5es musicais cativantes, o festival contou com apresenta\u00e7\u00f5es de dan\u00e7a tradicional ao vivo, sess\u00f5es de pintura art\u00edstica ao vivo, uma exposi\u00e7\u00e3o de arte, um mercado de arte, uma loja de discos e atividades envolventes para crian\u00e7as.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span data-contrast=\"auto\">O primeiro dia do UFF (Ubud Folkfest) 2023 foi animado por 9 performers e 2 dan\u00e7as tradicionais. N\u00e3o s\u00f3 a m\u00fasica folk \u00e9 apresentada, mas tamb\u00e9m a m\u00fasica mundial e a m\u00fasica experimental de fus\u00e3o tradicional. Al\u00e9m de m\u00fasicos e artistas de Bali, tamb\u00e9m houve apresenta\u00e7\u00f5es de muitos m\u00fasicos e artistas convidados de fora de Bali.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">O segundo dia do Ubud Folkfest 2023 abriu com um talk show sobre a cena musical e o fen\u00f4meno de muitos grandes festivais realizados em Bali ap\u00f3s o fim da Pandemia. O talk show contou com Rudolf Dethu e Anom Darsana como palestrantes. Come\u00e7ou com uma exibi\u00e7\u00e3o cativante do trailer do filme \u201cPulau Plastik\u201d, destacando a quest\u00e3o da polui\u00e7\u00e3o pl\u00e1stica. Al\u00e9m disso, uma apresenta\u00e7\u00e3o em v\u00eddeo sobre conscientiza\u00e7\u00e3o ambiental foi conduzida por Gede Robi da Navicula Band. Os participantes demonstraram grande entusiasmo e participaram ativamente neste envolvente talk show.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span data-contrast=\"auto\">Ap\u00f3s o talk show, os dois palcos do UFF 2023 se alternaram com apresenta\u00e7\u00f5es de dez m\u00fasicos, e o final do dia foi encerrado em alta vibe com m\u00fasicas de Hip-hop, Reggae e Drum n Bass do DJ Cbee.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">O \u00faltimo dia da UFF 2023, abriu com Atividades Infantis gratuitas, das 10h \u00e0s 16h. Algumas das oficinas e atividades gratuitas inclu\u00edram oficinas de confec\u00e7\u00e3o de fantoches de sombra, encaderna\u00e7\u00e3o, escultura em madeira, colora\u00e7\u00e3o, confec\u00e7\u00e3o de decora\u00e7\u00f5es e pintura facial para as crian\u00e7as.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">\u00c0s 17h, o \u00faltimo dia do Ubud Folkfest 2023 abriu com uma apresenta\u00e7\u00e3o e exibi\u00e7\u00e3o de v\u00eddeos sobre as artes culturais tradicionais da Indon\u00e9sia em colabora\u00e7\u00e3o com arte de instala\u00e7\u00e3o e mapeamento visual multim\u00eddia.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Terminada a apresenta\u00e7\u00e3o e exibi\u00e7\u00e3o do v\u00eddeo, seguiu-se a Open Stage Session, que permitiu a qualquer pessoa apresentar a sua arte musical em palco, nessa tarde a Open Stage Session foi animada por Cellomano, Zoey And Zac, Lyze e Andy Sixstring. Cada artista apresentou performances musicais cativantes, encantando os visitantes do festival com seu talento e deixando uma impress\u00e3o duradoura.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Ap\u00f3s a Sess\u00e3o Palco Aberto, o palco foi novamente animado pela colabora\u00e7\u00e3o de v\u00e1rios grandes m\u00fasicos que realizaram extraordin\u00e1rias performances musicais, teatrais e de pintura ao vivo.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Getzhamani, Metallesa, Anda Perdana, Reza Achman e Agus Salim s\u00e3o os artistas por tr\u00e1s da colabora\u00e7\u00e3o \u201cSOULJAM\u201d, que conseguiram hipnotizar os visitantes do Ubud Folkfest 2023 durante 2,5 horas com as suas performances colaborativas.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Ap\u00f3s a atua\u00e7\u00e3o not\u00e1vel do SOULJAM, o palco do UFF 2023 foi instantaneamente energizado pela m\u00fasica hip-hop de ELF Tranzporter, o \u00fanico rapper a agraciar o evento com seu estilo \u00fanico.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span data-contrast=\"auto\">No geral, o UFF 2023 correu bem e de forma surpreendente, e saudamos a UFF por dar espa\u00e7o aos m\u00fasicos e por seu compromisso em fornecer uma plataforma para m\u00fasicos talentosos que podem n\u00e3o ter alcan\u00e7ado amplo reconhecimento, mas possuem proezas musicais excepcionais. A dedica\u00e7\u00e3o do festival em apresentar esses artistas \u00e9 louv\u00e1vel e contribui para o sucesso geral e a singularidade da UFF.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span data-contrast=\"auto\">N\u00e3o se trata de quantas pessoas comparecem ou quantos ingressos s\u00e3o vendidos, mas a satisfa\u00e7\u00e3o de ser uma plataforma de m\u00fasicos de qualidade e raramente expostos \u00e9 uma honra para os fundadores e organizadores do UFF 2023.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span data-contrast=\"auto\">Portanto, uma sauda\u00e7\u00e3o final aos Fundadores e a toda equipe UFF 2023. Al\u00e9m disso, todas as performances, artistas tradicionais, pintores e todos os lojistas do mercado que participaram do Ubud Folkfest 2023.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><span data-contrast=\"auto\">Nos vemos no Ubud Folkfest 2024!<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/h3>\n<h3><span data-contrast=\"auto\">N\u00f3s te amamos!<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/h3>\n<p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Confira e siga o Instagram deles: <a href=\"https:\/\/www.instagram.com\/ubudfolkfest\/\" target=\"_blank\" rel=\"noopener\"><span class=\"atwho-query\">ubudfol<\/span>kfest<\/a><\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>Durante o evento de tr\u00eas dias do Ubud Folkfest 2023, os participantes tiveram a oportunidade de mergulhar numa celebra\u00e7\u00e3o vibrante de m\u00fasica, arte e Culture<\/p>","protected":false},"author":1,"featured_media":31929,"comment_status":"open","ping_status":"closed","template":"","meta":{"footnotes":""},"categories":[272,273],"tags":[365],"section":[394],"interest":[380,378,400],"_magazine":[366],"class_list":["post-26391","article","type-article","status-publish","has-post-thumbnail","hentry","category-artsy","category-people","tag-365","section-review","interest-creative","interest-social","interest-things-to-do","_magazine-366"],"_links":{"self":[{"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/article\/26391","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/article"}],"about":[{"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/types\/article"}],"author":[{"embeddable":true,"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/comments?post=26391"}],"version-history":[{"count":0,"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/article\/26391\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/media\/31929"}],"wp:attachment":[{"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/media?parent=26391"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/categories?post=26391"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/tags?post=26391"},{"taxonomy":"section","embeddable":true,"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/section?post=26391"},{"taxonomy":"interest","embeddable":true,"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/interest?post=26391"},{"taxonomy":"_magazine","embeddable":true,"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/_magazine?post=26391"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}<!-- This website is optimized by Airlift. Learn more: https://airlift.net. Template:. Learn more: https://airlift.net. Template: 6a3c9e6bc6af5a91495580da. Config Timestamp: 2026-06-25 03:19:51 UTC, Cached Timestamp: 2026-09-02 22:41:20 UTC -->