{"id":19612,"date":"2022-11-04T06:37:17","date_gmt":"2022-11-03T22:37:17","guid":{"rendered":"https:\/\/instantkarmamag.com\/?post_type=article&#038;p=19612"},"modified":"2024-02-05T02:42:39","modified_gmt":"2024-02-04T18:42:39","slug":"maes-de-rua-de-bali","status":"publish","type":"article","link":"https:\/\/instantkarmamag.com\/pt\/artigo\/maes-de-rua-de-bali\/","title":{"rendered":"M\u00e3es da rua de Bali"},"content":{"rendered":"<div id=\"bsf_rt_marker\"><\/div><p align=\"LEFT\"><b>A fundadora do Bali Street Mums, Kim Farr, conta uma hist\u00f3ria comovente sobre as crian\u00e7as que salvaram. <\/b><\/p>\n<p align=\"LEFT\">Acontece que a pequena Wayan Duri e seu irm\u00e3o foram levados \u00e0s ruas por uma gangue para mendigar e vender len\u00e7os de papel. Sua m\u00e3e morreu de c\u00e2ncer e seu pai ficou paralisado. Ele recebia $4 por dia pelo trabalho dos filhos. O marido da irm\u00e3 mais velha de Wayan comandava a gangue.<\/p>\n<p align=\"LEFT\">Ele e um grupo de homens pegavam crian\u00e7as de fam\u00edlias pobres nas montanhas, prometendo dinheiro aos pais, e depois levavam todas as crian\u00e7as para as ruas para mendigar durante 10 horas por dia. As crian\u00e7as eram trancadas em um quarto e alimentadas com uma refei\u00e7\u00e3o por dia.<\/p>\n<p align=\"LEFT\">A gangue amea\u00e7ou levar Wayan embora e, em troca, a organiza\u00e7\u00e3o de caridade teve que pagar-lhes 1.000.000 de rupias por semana. Eles mantiveram Wayan seguro nessas condi\u00e7\u00f5es por mais de um m\u00eas, at\u00e9 que a pol\u00edcia foi envolvida.<\/p>\n<p align=\"LEFT\">Wayan sofria de fortes dores de cabe\u00e7a constantes por causa da infec\u00e7\u00e3o ocular. Teve que ser removido. Bali Street Mums reuniu dinheiro suficiente para a cirurgia e encontrou uma maneira de fazer um olho artificial para Wayan.<\/p>\n<h3 align=\"LEFT\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-19617 size-large\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/11\/6BA0CF96-AAAE-4DB6-8D17-946CCB1B636F-1-768x1024.jpeg\" alt=\"m\u00e3es de rua de bali\" width=\"768\" height=\"1024\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/11\/6BA0CF96-AAAE-4DB6-8D17-946CCB1B636F-1-768x1024.jpeg 768w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/11\/6BA0CF96-AAAE-4DB6-8D17-946CCB1B636F-1-225x300.jpeg 225w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/11\/6BA0CF96-AAAE-4DB6-8D17-946CCB1B636F-1-1152x1536.jpeg 1152w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/11\/6BA0CF96-AAAE-4DB6-8D17-946CCB1B636F-1-1536x2048.jpeg 1536w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/11\/6BA0CF96-AAAE-4DB6-8D17-946CCB1B636F-1-624x832.jpeg 624w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/11\/6BA0CF96-AAAE-4DB6-8D17-946CCB1B636F-1.jpeg 1920w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/h3>\n<h3 align=\"LEFT\">Esta hist\u00f3ria resume a maioria das coisas que as m\u00e3es de Bali Street fazem. As mulheres das aldeias empobrecidas nas montanhas pegam nos seus filhos e v\u00e3o para as ruas urbanas mendigar.<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-19626 size-large\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/11\/55273615-F2D3-4E16-AC6E-5C76465B2ACD-1024x908.jpeg\" alt=\"m\u00e3es de rua de bali\" width=\"1024\" height=\"908\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/11\/55273615-F2D3-4E16-AC6E-5C76465B2ACD-1024x908.jpeg 1024w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/11\/55273615-F2D3-4E16-AC6E-5C76465B2ACD-300x266.jpeg 300w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/11\/55273615-F2D3-4E16-AC6E-5C76465B2ACD-768x681.jpeg 768w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/11\/55273615-F2D3-4E16-AC6E-5C76465B2ACD-624x553.jpeg 624w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/11\/55273615-F2D3-4E16-AC6E-5C76465B2ACD.jpeg 1212w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p align=\"LEFT\">As crian\u00e7as muitas vezes s\u00e3o sequestradas, traficadas e abusadas. As m\u00e3es da rua de Bali salvam as pessoas dessas circunst\u00e2ncias. Eles fornecem refei\u00e7\u00f5es, ajuda m\u00e9dica e abrigo, se necess\u00e1rio. Sua casa segura parece um lugar divertido, e se n\u00e3o se conhece a hist\u00f3ria das crian\u00e7as e mulheres que moram l\u00e1.<\/p>\n<h2 style=\"text-align: center;\" align=\"LEFT\">\u00c9 f\u00e1cil presumir que se trata de um clube extracurricular. As crian\u00e7as est\u00e3o ocupadas brincando, desenhando e fazendo a li\u00e7\u00e3o de casa. Eles n\u00e3o t\u00eam medo de estranhos e correm para seus bra\u00e7os para um abra\u00e7o.<u> <\/u><\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-19623 size-large\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/11\/DSC01633-1-1024x683.jpg\" alt=\"m\u00e3es de rua de bali\" width=\"1024\" height=\"683\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/11\/DSC01633-1-1024x683.jpg 1024w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/11\/DSC01633-1-300x200.jpg 300w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/11\/DSC01633-1-768x512.jpg 768w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/11\/DSC01633-1-1536x1024.jpg 1536w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/11\/DSC01633-1-2048x1366.jpg 2048w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/11\/DSC01633-1-624x416.jpg 624w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p align=\"LEFT\">A casa segura est\u00e1 localizada perto das favelas, onde as pessoas t\u00eam muito pouco dinheiro para alimentar adequadamente os seus filhos e mand\u00e1-los para a escola. A organiza\u00e7\u00e3o de caridade tamb\u00e9m os ajuda. As crian\u00e7as l\u00e1 est\u00e3o <a href=\"https:\/\/instantkarmamag.com\/pt\/artigo\/atrofiando-a-face-da-pobreza-2\/\">sofrendo de desnutri\u00e7\u00e3o<\/a> e doen\u00e7as.<\/p>\n<p align=\"LEFT\">Todos os dias eles podem tomar um caf\u00e9 da manh\u00e3 nutritivo e almo\u00e7ar na casa segura, al\u00e9m de educa\u00e7\u00e3o e escola l\u00fadica. Para essas crian\u00e7as das favelas quentes e empoeiradas, a casa segura e o pequeno parquinho s\u00e3o um santu\u00e1rio.<\/p>\n<p align=\"LEFT\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-19621 size-large\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/11\/DSC01659-1-683x1024.jpg\" alt=\"m\u00e3es de rua de bali\" width=\"683\" height=\"1024\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/11\/DSC01659-1-683x1024.jpg 683w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/11\/DSC01659-1-200x300.jpg 200w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/11\/DSC01659-1-768x1152.jpg 768w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/11\/DSC01659-1-1024x1536.jpg 1024w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/11\/DSC01659-1-1366x2048.jpg 1366w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/11\/DSC01659-1-624x936.jpg 624w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/11\/DSC01659-1.jpg 1707w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/><\/p>\n<h4 align=\"LEFT\"><b>Kim nos contou mais algumas hist\u00f3rias sobre as circunst\u00e2ncias horr\u00edveis em que algumas crian\u00e7as se encontram e como Bali Street Mums as est\u00e1 ajudando e apoiando.<\/b><\/h4>\n<h3 style=\"text-align: center;\"><b>Komang e Ketut Anih <\/b><\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-19618 size-full\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/11\/069E4246-AB3A-4D21-AB5B-113124934583.jpeg\" alt=\"m\u00e3es de rua de bali\" width=\"720\" height=\"900\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/11\/069E4246-AB3A-4D21-AB5B-113124934583.jpeg 720w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/11\/069E4246-AB3A-4D21-AB5B-113124934583-240x300.jpeg 240w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/11\/069E4246-AB3A-4D21-AB5B-113124934583-624x780.jpeg 624w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><\/p>\n<p>O padrasto e a m\u00e3e os enviaram \u00e0s ruas para mendigar assim que puderam andar. Eles trabalhavam 12 horas dia e noite, correndo at\u00e9 os carros implorando por dinheiro.<\/p>\n<p>Certo dia, encontramos Komang sozinho nas ruas. Seu padrasto abusou sexualmente dela e n\u00f3s a levamos ao hospital onde ela foi operada.<\/p>\n<p>A fam\u00edlia dela fugiu da cabana nas favelas e n\u00e3o conseguimos encontrar sua irm\u00e3 mais nova, Ketut Anih. Patrulhamos as ruas durante seis meses e finalmente a encontramos. Ela estava desnutrida e muito doente. N\u00f3s a levamos de volta para a casa segura, onde ela se reencontrou com sua irm\u00e3 mais velha!<\/p>\n<p>Conseguimos descobrir a nova localiza\u00e7\u00e3o do padrasto e estamos trabalhando com a pol\u00edcia para conden\u00e1-lo.<\/p>\n<p align=\"LEFT\"><b>Wayan Wisnu\u00a0<\/b><\/p>\n<p align=\"LEFT\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-19619 size-large\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/11\/DD2FA7DD-DE71-46E7-BBCB-471A1A83ED08-1024x696.jpeg\" alt=\"m\u00e3es de rua de bali\" width=\"1024\" height=\"696\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/11\/DD2FA7DD-DE71-46E7-BBCB-471A1A83ED08-1024x696.jpeg 1024w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/11\/DD2FA7DD-DE71-46E7-BBCB-471A1A83ED08-300x204.jpeg 300w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/11\/DD2FA7DD-DE71-46E7-BBCB-471A1A83ED08-768x522.jpeg 768w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/11\/DD2FA7DD-DE71-46E7-BBCB-471A1A83ED08-624x424.jpeg 624w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/11\/DD2FA7DD-DE71-46E7-BBCB-471A1A83ED08.jpeg 1322w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p align=\"LEFT\">Ele veio at\u00e9 a casa segura para nos perguntar se seus dois filhos poderiam ingressar em nossa escolinha. Ele \u00e9 pai solteiro, sua esposa morreu durante o nascimento de sua filha. Wayan trabalha em canteiros de obras e ganha cerca de $5 por dia.<\/p>\n<p align=\"LEFT\">Durante o confinamento em Bali, ele n\u00e3o conseguiu encontrar trabalho. Ajudamos a fam\u00edlia com alimentos, rem\u00e9dios, gasolina para a scooter e dinheiro para alugar o barraco de um c\u00f4modo.<\/p>\n<p align=\"LEFT\">Wayan agora tem trabalho e todas as manh\u00e3s ele deixa as crian\u00e7as na Casa Segura para refei\u00e7\u00f5es, estudos e cuidados, enquanto trabalha e depois as pega no final do dia. Ele \u00e9 o pai mais gentil e cuida muito bem de seus filhos.<\/p>\n<p align=\"LEFT\"><b>Alya e Anissa<\/b>\u00a0foram encontrados trancados em um barraco na favela. Nosso seguran\u00e7a e assistente social patrulham regularmente as favelas. H\u00e1 quatro meses, eles foram avisados por alguns vizinhos que ouviram as meninas chorando.<\/p>\n<p align=\"LEFT\">Ambas as meninas foram vendidas pelo pai para uma fam\u00edlia que filmava crian\u00e7as para sites de pedofilia. As meninas agora moram na casa segura e recebem aconselhamento.<\/p>\n<p align=\"LEFT\">A assistente de bem-estar da nossa menina, Angel, divide um quarto com elas para que, se as meninas acordarem \u00e0 noite, ela esteja l\u00e1 para ajud\u00e1-las.<\/p>\n<p align=\"LEFT\">A iniciativa mais recente \u00e9 a cria\u00e7\u00e3o de uma empresa onde as mulheres possam trabalhar em vez de mendigar.<\/p>\n<h2 style=\"text-align: center;\" align=\"LEFT\">Todo mundo sabe:<\/h2>\n<h2 style=\"text-align: center;\" align=\"LEFT\">Se voc\u00ea der um peixe a um homem, voc\u00ea o alimentar\u00e1 por um dia \u2013 mas se voc\u00ea ensinar um homem a pescar, voc\u00ea o alimentar\u00e1 por toda a vida.<\/h2>\n<p style=\"text-align: left;\" align=\"LEFT\">Agora as mulheres t\u00eam a oportunidade de trabalhar e serem remuneradas como todas as outras pessoas, apenas com um pouco de ajuda e incentivo.<\/p>\n<p align=\"LEFT\">Bali \u00e9 o para\u00edso na Terra, desde que voc\u00ea siga rigorosamente um roteiro tur\u00edstico. Mas mesmo se voc\u00ea fizer isso, voc\u00ea encontrar\u00e1 pessoas necessitadas. D\u00ea-lhes uma m\u00e3o amiga, se puder e tiver vontade. Se nos unirmos, poderemos fazer de Bali o para\u00edso para todos.<\/p>\n<h3>DOE AQUI<\/h3>\n<h3 align=\"LEFT\"><a href=\"https:\/\/balistreetmums.org\/\" target=\"_blank\" rel=\"noopener\">balistreetmums.org<\/a><\/h3>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h2 align=\"LEFT\">Recomenda\u00e7\u00f5es para quem quiser ajudar:<\/h2>\n<h3 align=\"LEFT\"><strong>Em primeiro lugar, certifique-se de ter energia e recursos materiais suficientes para caridade.<\/strong><\/h3>\n<p align=\"LEFT\">Deve vir da abund\u00e2ncia, da compaix\u00e3o e de um desejo genu\u00edno de ajudar, n\u00e3o da culpa e da pena.<\/p>\n<h3 align=\"LEFT\"><strong>N\u00e3o d\u00ea dinheiro para mendigos nas ruas.<\/strong><\/h3>\n<p align=\"LEFT\">Normalmente, o dinheiro arrecadado nas ruas vai para pais abusivos e outros parentes que exploram crian\u00e7as. N\u00e3o ajuda a melhorar as suas vidas, muitas vezes \u00e9 o contr\u00e1rio.<\/p>\n<h3 align=\"LEFT\">Em vez disso, doe para institui\u00e7\u00f5es de caridade.<\/h3>\n<p align=\"LEFT\">Se voc\u00ea estiver preocupado com a forma como seu dinheiro est\u00e1 sendo gasto, poder\u00e1 solicitar um relat\u00f3rio. Se for uma organiza\u00e7\u00e3o como a Bali Street Mums voc\u00ea pode ir direto para o esconderijo e ver o que acontece l\u00e1. Doe em <a href=\"http:\/\/balistreetmums.org\" target=\"_blank\" rel=\"noopener\">balistreetmums.org<\/a><\/p>\n<h3 align=\"LEFT\">Se voc\u00ea vir um mendigo na rua, entre em contato com Bali Street Mums e conte-lhes sobre isso.<\/h3>\n<p align=\"LEFT\">Eles far\u00e3o todo o poss\u00edvel para encontrar os mendigos e ajud\u00e1-los. O problema que estas pessoas t\u00eam pode ser mais profundo do que apenas a falta de dinheiro, por isso necessitam de uma abordagem sistem\u00e1tica como ajuda m\u00e9dica, psicol\u00f3gica ou jur\u00eddica, podem precisar de asilo ou de qualquer outra coisa em que o nosso dinheiro n\u00e3o os ajude.<\/p>\n<p align=\"LEFT\"><a href=\"https:\/\/www.instagram.com\/balistreetmums_project\/\" target=\"_blank\" rel=\"noopener\">@balistreetmums_project<\/a> \u00e9 a p\u00e1gina do Instagram do Bali Street Mums, onde voc\u00ea pode inform\u00e1-los sobre pessoas que podem precisar de sua ajuda.<\/p>\n<h3 align=\"LEFT\">Uma das maneiras mais f\u00e1ceis de ajudar as m\u00e3es de rua de Bali \u00e9 comprar algo em sua barraca no La Brisa Sunday Market.<\/h3>\n<p align=\"LEFT\">Em vez de implorar por dinheiro, essas mulheres vendem lindas bonecas e acess\u00f3rios. Depois de comprar algo deles, voc\u00ea n\u00e3o apenas apoia eficientemente as m\u00e3es e seus filhos, mas tamb\u00e9m ganha uma pequena lembran\u00e7a.<\/p>\n<p align=\"LEFT\">","protected":false},"excerpt":{"rendered":"<p>A fundadora da Bali Street Mums, Kim Farr, conta uma hist\u00f3ria comovente sobre as crian\u00e7as que salvaram. Descobriu-se que a pequena Wayan Duri e seu irm\u00e3o foram levados \u00e0s ruas por uma gangue para mendigar e vender len\u00e7os de papel. Sua m\u00e3e morreu de c\u00e2ncer e seu pai ficou paral\u00edtico. Ele recebia $4 por [\u2026]<\/p>","protected":false},"author":40,"featured_media":19625,"comment_status":"open","ping_status":"closed","template":"","meta":{"footnotes":""},"categories":[275],"tags":[359,78,286],"section":[387],"interest":[381,378],"_magazine":[357],"class_list":["post-19612","article","type-article","status-publish","has-post-thumbnail","hentry","category-impact","tag-359","tag-bali","tag-yayasan","section-impact","interest-empowerment","interest-social","_magazine-357"],"_links":{"self":[{"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/article\/19612","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/article"}],"about":[{"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/types\/article"}],"author":[{"embeddable":true,"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/users\/40"}],"replies":[{"embeddable":true,"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/comments?post=19612"}],"version-history":[{"count":0,"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/article\/19612\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/media\/19625"}],"wp:attachment":[{"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/media?parent=19612"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/categories?post=19612"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/tags?post=19612"},{"taxonomy":"section","embeddable":true,"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/section?post=19612"},{"taxonomy":"interest","embeddable":true,"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/interest?post=19612"},{"taxonomy":"_magazine","embeddable":true,"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/_magazine?post=19612"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}<!-- This website is optimized by Airlift. Learn more: https://airlift.net. Template:. Learn more: https://airlift.net. Template: 6a3c9e6bc6af5a91495580da. Config Timestamp: 2026-06-25 03:19:51 UTC, Cached Timestamp: 2026-09-02 17:10:21 UTC -->