{"id":17838,"date":"2022-10-13T09:56:49","date_gmt":"2022-10-13T01:56:49","guid":{"rendered":"https:\/\/instantkarmamag.com\/?post_type=online&#038;p=17838"},"modified":"2024-10-28T00:00:44","modified_gmt":"2024-10-27T16:00:44","slug":"o-restaurante-gourmet-kelusa","status":"publish","type":"article","link":"https:\/\/instantkarmamag.com\/pt\/artigo\/o-restaurante-gourmet-kelusa\/","title":{"rendered":"The Kelusa \u2013 Restaurante Gourmet em Ubud"},"content":{"rendered":"<div id=\"bsf_rt_marker\"><\/div><h2 align=\"CENTER\"><span lang=\"en-ID\"><i><b>Um charmoso restaurante em Ubud com uma atmosfera agrad\u00e1vel<\/b><\/i><\/span><\/h2>\n<p align=\"JUSTIFY\"><span style=\"color: #000000;\"><span style=\"font-family: Arial, serif;\"><span style=\"font-size: medium;\"><span lang=\"en-ID\">H\u00e1 uma infinidade de lugares para escolher <a href=\"https:\/\/instantkarmamag.com\/pt\/destino\/bali-island-tours\/\">na Ilha dos Deuses<\/a> quando se trata de op\u00e7\u00f5es para comer fora. Quer se trate de um bistr\u00f4 moderno e aconchegante ou de um restaurante gourmet 5 estrelas em Ubud, sempre se pode elogiar a experi\u00eancia gastron\u00f4mica l\u00e1. <\/span><\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Arial, serif;\"><span style=\"font-size: medium;\"><span lang=\"en-ID\">\u00c9 uma raridade, no entanto, descobrir um lugar como o Kelusa que atende praticamente aqueles que desejam desfrutar de experi\u00eancias gastron\u00f4micas cl\u00e1ssicas e modernas que, embora possam ser descritas como vanguardistas, ainda s\u00e3o acess\u00edveis e inclusivas para todos que t\u00eam encontrei casa em<\/span><\/span><\/span><\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"color: #000000;\"><span style=\"font-family: Arial, serif;\"><span style=\"font-size: medium;\"><span lang=\"en-ID\">Que tal um restaurante que mant\u00e9m uma abordagem culin\u00e1ria cl\u00e1ssica, mas consegue de alguma forma apresentar formas modernas e sofisticadas de servi-los em suas mesas? Que tal um local id\u00edlico onde artistas e pessoas criativas possam se conhecer e formar conex\u00f5es e muito mais por meio de eventos mensais regulares, cuidadosamente elaborados para os vision\u00e1rios?<\/span><\/span><\/span><\/span><\/p>\n<h3><span style=\"color: #000000;\"><span style=\"font-family: Arial, serif;\"><span style=\"font-size: medium;\"><span lang=\"en-ID\">Localizado em Ubud, Bali, o The Kelusa \u00e9 uma joia culin\u00e1ria cercada pela exuberante e serena floresta tropical de Payangan.<\/span><\/span><\/span><\/span><\/h3>\n<p align=\"JUSTIFY\"><span style=\"color: #000000;\"><span style=\"font-family: Arial, serif;\"><span style=\"font-size: medium;\"><span lang=\"en-ID\">A pitoresca floresta tornou-se um elemento constante entre as fotos enviadas pelos viajantes de Bali, tornando a experi\u00eancia gastron\u00f4mica no The Kelusa n\u00e3o apenas satisfazendo seu apetite, mas tamb\u00e9m maravilhosa.<\/span><\/span><\/span><\/span><\/p>\n<p align=\"JUSTIFY\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-17842 size-large\" src=\"https:\/\/i0.wp.com\/instantkarmamag.com\/wp-content\/uploads\/2022\/10\/the-kelusa_pan-seared-baramundi-02-scaled-1.jpg?fit=768%2C1024&amp;ssl=1\" alt=\"\" width=\"768\" height=\"1024\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/10\/the-kelusa_pan-seared-baramundi-02-scaled-1.jpg 1920w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/10\/the-kelusa_pan-seared-baramundi-02-scaled-1-225x300.jpg 225w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/10\/the-kelusa_pan-seared-baramundi-02-scaled-1-768x1024.jpg 768w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/10\/the-kelusa_pan-seared-baramundi-02-scaled-1-1152x1536.jpg 1152w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/10\/the-kelusa_pan-seared-baramundi-02-scaled-1-1536x2048.jpg 1536w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/p>\n<p align=\"JUSTIFY\"><span style=\"color: #000000;\"><span style=\"font-family: Arial, serif;\"><span style=\"font-size: medium;\"><span lang=\"en-ID\">A experi\u00eancia gastron\u00f4mica do Kelusa atende at\u00e9 os gourmets mais exigentes, oferecendo pratos cuidadosamente elaborados, divididos em duas se\u00e7\u00f5es: exclusivos \u2013 pratos indon\u00e9sios modernos com um toque especial \u2013 e cl\u00e1ssicos.\u00a0<\/span><\/span><\/span><\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"color: #000000;\"><span style=\"font-family: Arial, serif;\"><span style=\"font-size: medium;\"><span lang=\"en-ID\">A sele\u00e7\u00e3o de pratos exclusivos inclui <\/span><\/span><\/span><\/span><strong><span style=\"color: #000000;\"><span style=\"font-family: Arial, serif;\"><span style=\"font-size: medium;\"><span lang=\"en-ID\"><i>Sambal seja Tongkol<\/i><\/span><\/span><\/span><\/span><\/strong><span style=\"color: #000000;\"><span style=\"font-family: Arial, serif;\"><span style=\"font-size: medium;\"><span lang=\"en-ID\">, que \u00e9 uma salada de atum com chalota, capim-lim\u00e3o, pimenta e manjeric\u00e3o local, <\/span><\/span><\/span><\/span><strong><span style=\"color: #000000;\"><span style=\"font-family: Arial, serif;\"><span style=\"font-size: medium;\"><span lang=\"en-ID\"><i>Cakalang Woku <\/i><\/span><\/span><\/span><\/span><\/strong><span style=\"color: #000000;\"><span style=\"font-family: Arial, serif;\"><span style=\"font-size: medium;\"><span lang=\"en-ID\">(atum grelhado, caldo de a\u00e7afr\u00e3o picante, alho-por\u00f3 carbonizado e tomate confitado) e variedade de sobremesas incluem os favoritos de todos os tempos <\/span><\/span><\/span><\/span><strong><span style=\"color: #000000;\"><span style=\"font-family: Arial, serif;\"><span style=\"font-size: medium;\"><span lang=\"en-ID\"><i>Gethuk <\/i><\/span><\/span><\/span><\/span><\/strong><span style=\"color: #000000;\"><span style=\"font-family: Arial, serif;\"><span style=\"font-size: medium;\"><span lang=\"en-ID\">(mandioca doce, creme de baunilha, crumble de nozes e sorvete de baunilha).<\/span><\/span><\/span><\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"color: #000000;\"><span style=\"font-family: Arial, serif;\"><span style=\"font-size: medium;\"><span lang=\"en-ID\">Como mencionado anteriormente, o The Kelusa tamb\u00e9m oferece pratos cl\u00e1ssicos da <\/span><\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Arial, serif;\"><span style=\"font-size: medium;\"><span lang=\"en-ID\"><i>Melanzane\u00a0<\/i><\/span><\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Arial, serif;\"><span style=\"font-size: medium;\"><span lang=\"en-ID\">(berinjela, tomate, mussarela queimada, r\u00facula selvagem e bals\u00e2mico), para <\/span><\/span><\/span><\/span><strong><span style=\"color: #000000;\"><span style=\"font-family: Arial, serif;\"><span style=\"font-size: medium;\"><span lang=\"en-ID\"><i>Barramundi Tostado na Panela<\/i><\/span><\/span><\/span><\/span><\/strong><span style=\"color: #000000;\"><span style=\"font-family: Arial, serif;\"><span style=\"font-size: medium;\"><span lang=\"en-ID\"> (bolo de polenta, cogumelos selvagens, espinafres salteados e beurre noir) e sobremesas cl\u00e1ssicas como <\/span><\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Arial, serif;\"><span style=\"font-size: medium;\"><span lang=\"en-ID\"><i><strong>Semifrio<\/strong> <\/i><\/span><\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Arial, serif;\"><span style=\"font-size: medium;\"><span lang=\"en-ID\">(manteiga de amendoim, pipoca de caramelo, tuile de am\u00eandoa e calda de chocolate) e <\/span><\/span><\/span><\/span><strong><span style=\"color: #000000;\"><span style=\"font-family: Arial, serif;\"><span style=\"font-size: medium;\"><span lang=\"en-ID\"><i>P\u00eara escalfada <\/i><\/span><\/span><\/span><\/span><\/strong><span style=\"color: #000000;\"><span style=\"font-family: Arial, serif;\"><span style=\"font-size: medium;\"><span lang=\"en-ID\">(cranberry condimentado, staranise, creme de chantilly e biscoitos amanteigados).<\/span><\/span><\/span><\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"color: #000000;\"><span style=\"font-family: Arial, serif;\"><span style=\"font-size: medium;\"><span lang=\"en-ID\">Os pais com filhos pequenos n\u00e3o precisam se preocupar com os filhos, pois o Chef Iwan do Kelusa preparou um menu especial pensado para eles. <\/span><\/span><\/span><\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"color: #000000;\"><span style=\"font-family: Arial, serif;\"><span style=\"font-size: medium;\"><span lang=\"en-ID\">Os conhecedores de vinhos finos podem escolher qual vinho satisfaz seu paladar na adega do Samsara, enquanto os amantes de coquet\u00e9is ir\u00e3o, sem d\u00favida, desfrutar de uma variedade de coquet\u00e9is incr\u00edveis que The Kelusa oferece, que incluem a assinatura: <\/span><\/span><\/span><\/span><strong><span style=\"color: #000000;\"><span style=\"font-family: Arial, serif;\"><span style=\"font-size: medium;\"><span lang=\"en-ID\"><i>Pipoca azeda<\/i><\/span><\/span><\/span><\/span><\/strong><span style=\"color: #000000;\"><span style=\"font-family: Arial, serif;\"><span style=\"font-size: medium;\"><span lang=\"en-ID\">, uma deliciosa bebida ideal para antes\/depois do almo\u00e7o, feita com uma divertida mistura de pipoca e Vodka sour.\u00a0<\/span><\/span><\/span><\/span> <span style=\"color: #000000;\"><span style=\"font-family: Arial, serif;\"><span style=\"font-size: medium;\"><span lang=\"en-ID\">A variedade de coquet\u00e9is e mocktails do Kelusa reflete as cores fascinantes e os produtos org\u00e2nicos frescos de Bali.<\/span><\/span><\/span><\/span><\/p>\n<p align=\"JUSTIFY\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-17840 size-large\" src=\"https:\/\/i0.wp.com\/instantkarmamag.com\/wp-content\/uploads\/2022\/10\/samsara-ubud-the-kelusa-bar-pop-corn-sour-scaled-1.jpg?fit=683%2C1024&amp;ssl=1\" alt=\"\" width=\"683\" height=\"1024\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/10\/samsara-ubud-the-kelusa-bar-pop-corn-sour-scaled-1.jpg 1709w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/10\/samsara-ubud-the-kelusa-bar-pop-corn-sour-scaled-1-200x300.jpg 200w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/10\/samsara-ubud-the-kelusa-bar-pop-corn-sour-scaled-1-768x1150.jpg 768w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/10\/samsara-ubud-the-kelusa-bar-pop-corn-sour-scaled-1-684x1024.jpg 684w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/10\/samsara-ubud-the-kelusa-bar-pop-corn-sour-scaled-1-1025x1536.jpg 1025w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/10\/samsara-ubud-the-kelusa-bar-pop-corn-sour-scaled-1-1367x2048.jpg 1367w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/><\/p>\n<p align=\"JUSTIFY\"><span style=\"color: #000000;\"><span style=\"font-family: Arial, serif;\"><span style=\"font-size: medium;\"><span lang=\"en-ID\">Al\u00e9m dos pratos gourmet na selva de Ubud, o The Kelusa se esfor\u00e7a para se tornar um centro para todas as pessoas criativas e vision\u00e1rios de toda a ilha se conhecerem e se divertirem. Os eventos mensais do local s\u00e3o projetados para viajantes globais que chamam Bali de sua casa, para que possam desfrutar de boa comida e bebidas enquanto mant\u00eam sua criatividade fluindo, proporcionando uma atmosfera segura e feliz.<\/span><\/span><\/span><\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"color: #000000;\"><span style=\"font-family: Arial, serif;\"><span style=\"font-size: medium;\"><span lang=\"en-ID\">A serenidade das florestas circundantes e dos interiores tropicais naturais apenas contribuem para o charme do The Kelusa, al\u00e9m dos pratos gourmet que celebram a rica e diversificada hist\u00f3ria culin\u00e1ria da culin\u00e1ria indon\u00e9sia. Em suma, o The Kelusa abre as suas portas e o seu objetivo \u00e9 garantir a cada h\u00f3spede uma experi\u00eancia epicurista com culin\u00e1ria cl\u00e1ssica preparada de forma moderna e sofisticada.<\/span><\/span><\/span><\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"color: #000000;\"><span style=\"font-family: Arial, serif;\"><span style=\"font-size: medium;\"><span lang=\"en-ID\">O Diretor Geral da PT Samsara Raga Internasional, Bayu Sarwono, dono do The Kelusa e do resort Samsara Ubud, disse que a vis\u00e3o deles \u00e9 ser a primeira coisa que vem \u00e0 mente das pessoas quando pensam em um <a href=\"https:\/\/instantkarmamag.com\/pt\/artigo\/a-culinary-journey-ubud\/\">op\u00e7\u00e3o de jantar em Ubud<\/a> para a culin\u00e1ria indon\u00e9sia, onde toques modernos encontram tradi\u00e7\u00f5es e heran\u00e7a cultural.<\/span><\/span><\/span><\/span><\/p>\n<h4 align=\"JUSTIFY\"><span lang=\"en-ID\">\u201d<\/span><span style=\"color: #000000;\"><span style=\"font-family: Arial, serif;\"><span style=\"font-size: medium;\"><span lang=\"en-ID\">Al\u00e9m disso, queremos criar um local que valorize a inclus\u00e3o, a inova\u00e7\u00e3o e a conex\u00e3o com a natureza e o entorno.<\/span><\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Arial, serif;\"><span style=\"font-size: medium;\"><span lang=\"en-ID\">\u201d <\/span><\/span><\/span><\/span><\/h4>\n<p align=\"JUSTIFY\"><span style=\"color: #000000;\"><span style=\"font-family: Arial, serif;\"><span style=\"font-size: medium;\"><span lang=\"en-ID\">\u2013 disse, mencionando que qualidade e humildade s\u00e3o as palavras que descrevem a filosofia da Kelusa.<\/span><\/span><\/span><\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"color: #000000;\"><span style=\"font-family: Arial, serif;\"><span style=\"font-size: medium;\"><span lang=\"en-ID\">Bayu disse que o The Kelusa se esfor\u00e7a para promover a culin\u00e1ria local e otimizar o uso de produtos locais.<\/span><\/span><\/span><\/span><\/p>\n<h4 align=\"JUSTIFY\"><span style=\"color: #000000;\">\u201c<span style=\"font-family: Arial, serif;\"><span style=\"font-size: medium;\"><span lang=\"en-ID\">Queremos tamb\u00e9m manter a sustentabilidade e capacitar o talento local e fomentar a inova\u00e7\u00e3o\u201d, acrescentou.<\/span><\/span><\/span><\/span><\/h4>\n<p align=\"JUSTIFY\"><span style=\"color: #000000;\"><span style=\"font-family: Arial, serif;\"><span style=\"font-size: medium;\"><span lang=\"en-ID\">O Kelusa abre diariamente das 07h00 \u00e0s 22h30.<\/span><\/span><\/span><\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"color: #000000;\"><span style=\"font-family: Arial, serif;\"><span style=\"font-size: medium;\"><span lang=\"en-ID\">Local na rede Internet:<\/span><\/span><\/span><\/span><a href=\"https:\/\/www.samsaraubud.com\/en\/bali\/ubud\/luxury\/resort\/villas\/dining\" target=\"_blank\" rel=\"noopener\"><span style=\"font-family: Arial, serif;\"><span style=\"font-size: medium;\"><span lang=\"en-ID\">samsaraubud.com<\/span><\/span><\/span><\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Um restaurante charmoso em Ubud com uma atmosfera agrad\u00e1vel. H\u00e1 uma infinidade de op\u00e7\u00f5es gastron\u00f4micas na Ilha dos Deuses. Seja um bistr\u00f4 moderno e aconchegante ou um restaurante gourmet 5 estrelas em Ubud, voc\u00ea sempre pode se deliciar com a experi\u00eancia gastron\u00f4mica. \u00c9 [\u2026]<\/p>","protected":false},"author":135,"featured_media":17839,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"categories":[313],"tags":[],"section":[395],"interest":[196,399],"_magazine":[],"class_list":["post-17838","article","type-article","status-publish","has-post-thumbnail","hentry","category-review","section-places","interest-luxury","interest-nutrition"],"_links":{"self":[{"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/article\/17838","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/article"}],"about":[{"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/types\/article"}],"author":[{"embeddable":true,"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/users\/135"}],"replies":[{"embeddable":true,"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/comments?post=17838"}],"version-history":[{"count":0,"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/article\/17838\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/media\/17839"}],"wp:attachment":[{"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/media?parent=17838"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/categories?post=17838"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/tags?post=17838"},{"taxonomy":"section","embeddable":true,"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/section?post=17838"},{"taxonomy":"interest","embeddable":true,"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/interest?post=17838"},{"taxonomy":"_magazine","embeddable":true,"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/_magazine?post=17838"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}<!-- This website is optimized by Airlift. Learn more: https://airlift.net. Template:. Learn more: https://airlift.net. Template: 6a3c9e6bc6af5a91495580da. Config Timestamp: 2026-06-25 03:19:51 UTC, Cached Timestamp: 2026-09-02 04:55:22 UTC -->