{"id":12190,"date":"2022-05-01T06:05:55","date_gmt":"2022-04-30T22:05:55","guid":{"rendered":"https:\/\/instantkarmamag.com\/?post_type=article&#038;p=12190"},"modified":"2024-07-03T16:24:04","modified_gmt":"2024-07-03T08:24:04","slug":"e-um-ajuste-perfeito","status":"publish","type":"article","link":"https:\/\/instantkarmamag.com\/pt\/artigo\/e-um-ajuste-perfeito\/","title":{"rendered":"\u00c9 um ajuste perfeito"},"content":{"rendered":"<div id=\"bsf_rt_marker\"><\/div><h2 style=\"text-align: center;\">A educa\u00e7\u00e3o oferece uma solu\u00e7\u00e3o<b><br \/>\n<\/b><\/h2>\n<blockquote>\n<h5 style=\"text-align: center;\">As raparigas de muitas regi\u00f5es do globo acreditam que a menstrua\u00e7\u00e3o \u00e9 uma doen\u00e7a e uma barreira devido \u00e0 falta de informa\u00e7\u00e3o.<\/h5>\n<h5 style=\"text-align: center;\">Eles n\u00e3o est\u00e3o preparados para isso e n\u00e3o t\u00eam ideia do que est\u00e1 acontecendo com eles quando come\u00e7a o primeiro sangramento.<\/h5>\n<h5 style=\"text-align: center;\">Al\u00e9m disso, a menstrua\u00e7\u00e3o ainda \u00e9 evitada, alienada e estigmatizada como suja.<\/h5>\n<\/blockquote>\n<p>Quando voc\u00ea sabe que a menstrua\u00e7\u00e3o \u00e9 a coisa mais normal e natural que acontece no aparelho reprodutor feminino, voc\u00ea come\u00e7a a entender que n\u00e3o devemos ter vergonha de falar sobre isso. Portanto, este projeto \u00e9 um ajuste perfeito.<\/p>\n<p>&nbsp;<\/p>\n<h3>A menstrua\u00e7\u00e3o deve se assemelhar ao poder de uma mulher.<\/h3>\n<p>Sem menstrua\u00e7\u00e3o e um sistema reprodutivo saud\u00e1vel, voc\u00ea e eu n\u00e3o ter\u00edamos nascido neste mundo.<\/p>\n<p>Felizmente, existem ativistas da menstrua\u00e7\u00e3o, como Tungga e Icha, os fundadores da Perfect Fit Indonesia.<\/p>\n<p><a href=\"https:\/\/instantkarmamag.com\/pt\" target=\"_blank\" rel=\"noopener\">Carma instant\u00e2neo<\/a> teve uma breve entrevista com os dois cofundadores da Perfect Fit Tungga e Icha.<\/p>\n<figure id=\"attachment_12198\" aria-describedby=\"caption-attachment-12198\" style=\"width: 325px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-12198\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/05\/Co-Founders-IchaTungga-scaled-1-683x1024.jpg\" alt=\"a educa\u00e7\u00e3o de ajuste perfeito fornece uma solu\u00e7\u00e3o artigo bandita revista karma instant\u00e2nea viajante atento\" width=\"325\" height=\"487\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/05\/Co-Founders-IchaTungga-scaled-1-683x1024.jpg 683w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/05\/Co-Founders-IchaTungga-scaled-1-200x300.jpg 200w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/05\/Co-Founders-IchaTungga-scaled-1-768x1152.jpg 768w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/05\/Co-Founders-IchaTungga-scaled-1-1024x1536.jpg 1024w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/05\/Co-Founders-IchaTungga-scaled-1-1366x2048.jpg 1366w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/05\/Co-Founders-IchaTungga-scaled-1-624x936.jpg 624w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/05\/Co-Founders-IchaTungga-scaled-1.jpg 1707w\" sizes=\"auto, (max-width: 325px) 100vw, 325px\" \/><figcaption id=\"caption-attachment-12198\" class=\"wp-caption-text\"><em>Cofundadores da Perfect Fit<\/em><\/figcaption><\/figure>\n<h5>Voc\u00eas est\u00e3o se esfor\u00e7ando ativamente para desestigmatizar a menstrua\u00e7\u00e3o e aumentar a conscientiza\u00e7\u00e3o menstrual. Voc\u00eas agora s\u00e3o ativistas menstruais?<\/h5>\n<p>Sim, n\u00f3s somos.<\/p>\n<p>Crescendo como mulher, Icha e eu nunca percebemos que t\u00ednhamos falta de consci\u00eancia em rela\u00e7\u00e3o ao nosso pr\u00f3prio corpo, ao nosso ciclo menstrual e aos nossos direitos como mulher. Come\u00e7amos a perceber que a menstrua\u00e7\u00e3o \u00e9 uma parte realmente cr\u00edtica para empoderar mulheres e meninas. Fizemos uma viagem \u00e0s Flores em 2018, quando ainda trabalh\u00e1vamos na Kopernik, uma ONG sediada em Ubud que se concentra na resolu\u00e7\u00e3o de desafios sociais e ambientais na Indon\u00e9sia.<\/p>\n<p>Iniciamos um projeto chamado \u201cPerfect Fit\u201d para melhorar a conscientiza\u00e7\u00e3o sobre menstrua\u00e7\u00e3o e sa\u00fade reprodutiva entre mulheres e meninas em Flores, prov\u00edncia de NTT.<\/p>\n<h3 style=\"text-align: center;\">Durante o projeto, entrevist\u00e1mos 150 mulheres e raparigas e fic\u00e1mos chocados ao saber que 58% de raparigas n\u00e3o sabiam de onde vinha o seu sangue menstrual.<\/h3>\n<p>Esse desafio da falta de educa\u00e7\u00e3o nos lembrou da nossa pr\u00f3pria experi\u00eancia quando tivemos a primeira menstrua\u00e7\u00e3o.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-12191\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/05\/DA1_3257-scaled-1-1024x684.jpg\" alt=\"a educa\u00e7\u00e3o de ajuste perfeito fornece uma solu\u00e7\u00e3o artigo bandita revista karma instant\u00e2nea viajante atento\" width=\"668\" height=\"446\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/05\/DA1_3257-scaled-1-1024x684.jpg 1024w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/05\/DA1_3257-scaled-1-300x200.jpg 300w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/05\/DA1_3257-scaled-1-768x513.jpg 768w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/05\/DA1_3257-scaled-1-1536x1025.jpg 1536w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/05\/DA1_3257-scaled-1-2048x1367.jpg 2048w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/05\/DA1_3257-scaled-1-624x417.jpg 624w\" sizes=\"auto, (max-width: 668px) 100vw, 668px\" \/><\/p>\n<h5>A menstrua\u00e7\u00e3o ainda \u00e9 um tema tabu na Indon\u00e9sia em 2022?<strong><br \/>\n<\/strong><\/h5>\n<p>Sim, falar profundamente sobre menstrua\u00e7\u00e3o e sobre nosso pr\u00f3prio corpo ainda \u00e9 um grande tabu. As meninas v\u00e3o rir quando ouvem a palavra menstrua\u00e7\u00e3o e as mulheres tamb\u00e9m n\u00e3o se sentem confort\u00e1veis em compartilhar.<\/p>\n<p>Como resultado, 88% das mulheres indon\u00e9sias n\u00e3o sabiam sobre o seu pr\u00f3prio ciclo menstrual. 25% das meninas que v\u00e3o ter a primeira menstrua\u00e7\u00e3o nunca falaram sobre menstrua\u00e7\u00e3o com ningu\u00e9m antes.<\/p>\n<h5>Por que a educa\u00e7\u00e3o \u00e9 sua prioridade?<\/h5>\n<p>A nossa miss\u00e3o \u00e9 capacitar mulheres e meninas atrav\u00e9s de produtos inovadores e mudan\u00e7as sociais na menstrua\u00e7\u00e3o e na sa\u00fade e direitos reprodutivos das mulheres. Vemos a educa\u00e7\u00e3o como a principal prioridade para criar mudan\u00e7as sociais.<\/p>\n<figure id=\"attachment_12194\" aria-describedby=\"caption-attachment-12194\" style=\"width: 564px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-12194\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/05\/Our-tailors-for-Buy-One-Give-Model-NTT-scaled-1-1024x684.jpeg\" alt=\"a educa\u00e7\u00e3o de ajuste perfeito fornece uma solu\u00e7\u00e3o artigo bandita revista karma instant\u00e2nea viajante atento\" width=\"564\" height=\"377\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/05\/Our-tailors-for-Buy-One-Give-Model-NTT-scaled-1-1024x684.jpeg 1024w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/05\/Our-tailors-for-Buy-One-Give-Model-NTT-scaled-1-300x200.jpeg 300w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/05\/Our-tailors-for-Buy-One-Give-Model-NTT-scaled-1-768x513.jpeg 768w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/05\/Our-tailors-for-Buy-One-Give-Model-NTT-scaled-1-1536x1026.jpeg 1536w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/05\/Our-tailors-for-Buy-One-Give-Model-NTT-scaled-1-2048x1368.jpeg 2048w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/05\/Our-tailors-for-Buy-One-Give-Model-NTT-scaled-1-624x417.jpeg 624w\" sizes=\"auto, (max-width: 564px) 100vw, 564px\" \/><figcaption id=\"caption-attachment-12194\" class=\"wp-caption-text\"><em>Seus Alfaiates em Flores \u2013 Compre um, d\u00ea outro<\/em><\/figcaption><\/figure>\n<h5>Muitas mulheres aparecem e elas ficam interessadas quando voc\u00ea aborda esse assunto?<\/h5>\n<p>Sim! Como esse tema \u00e9 um tabu, sempre que temos atividades educativas muitas mulheres v\u00eam participar. Vemos que as mulheres est\u00e3o agora mais abertas a falar sobre o seu per\u00edodo e o estigma que o rodeia. No entanto, a mudan\u00e7a comportamental precisa de tempo. Portanto, precisamos do seu apoio para divulgar esse tema.<\/p>\n<h5>Como surgiu a ideia dessa calcinha feminina, a Perfect Fit?<\/h5>\n<p>As mulheres t\u00eam sido confrontadas com op\u00e7\u00f5es limitadas no que diz respeito \u00e0 sa\u00fade reprodutiva, incluindo a menstrua\u00e7\u00e3o. 95% de mulheres indon\u00e9sias ainda usam absorventes descart\u00e1veis para controlar a menstrua\u00e7\u00e3o. No entanto, os absorventes descart\u00e1veis s\u00e3o muito desconfort\u00e1veis, cont\u00eam muitos produtos qu\u00edmicos e geram toneladas de res\u00edduos. Estamos tentando melhorar a sa\u00fade das mulheres trazendo produtos inovadores que sejam confort\u00e1veis, seguros e ecologicamente corretos. Portanto, criamos esta solu\u00e7\u00e3o. Nossos produtos s\u00e3o projetados e fabricados na Indon\u00e9sia usando materiais certificados OEKO Tex, livres de produtos qu\u00edmicos nocivos.<\/p>\n<figure id=\"attachment_12195\" aria-describedby=\"caption-attachment-12195\" style=\"width: 579px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-12195\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/05\/With-producers-in-Java-scaled-e1651384736826-1024x603.jpg\" alt=\"a educa\u00e7\u00e3o de ajuste perfeito fornece uma solu\u00e7\u00e3o artigo bandita revista karma instant\u00e2nea viajante atento\" width=\"579\" height=\"341\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/05\/With-producers-in-Java-scaled-e1651384736826-1024x603.jpg 1024w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/05\/With-producers-in-Java-scaled-e1651384736826-300x177.jpg 300w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/05\/With-producers-in-Java-scaled-e1651384736826-1536x904.jpg 1536w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/05\/With-producers-in-Java-scaled-e1651384736826-600x353.jpg 600w\" sizes=\"auto, (max-width: 579px) 100vw, 579px\" \/><figcaption id=\"caption-attachment-12195\" class=\"wp-caption-text\">Produ\u00e7\u00e3o de roupas \u00edntimas Perfect Fit em Java<\/figcaption><\/figure>\n<h5><strong>Qual \u00e9 a sua abordagem e como voc\u00ea faz isso?<\/strong><\/h5>\n<p>Nossa abordagem \u00e9 atrav\u00e9s de:<\/p>\n<ol>\n<li>\n<h5>Trazendo os melhores produtos, inovadores e sustent\u00e1veis.<\/h5>\n<\/li>\n<li>\n<h5>Quebrando tabus sobre menstrua\u00e7\u00e3o e sa\u00fade da mulher por meio da educa\u00e7\u00e3o.<\/h5>\n<\/li>\n<li>\n<h5>Criar uma comunidade de mulheres que ajudam mulheres atrav\u00e9s do nosso modelo de neg\u00f3cios Buy One Give One.<\/h5>\n<\/li>\n<\/ol>\n<p>Somos inspirados por empresas como The Body Shop e Patagonia que se dedicam n\u00e3o apenas a fabricar produtos de alta qualidade, mas tamb\u00e9m a resolver quest\u00f5es sociais sobre as mulheres e o meio ambiente. A Perfect Fit existe para resolver a quest\u00e3o do estigma sobre a menstrua\u00e7\u00e3o e para dar acesso igualit\u00e1rio a produtos menstruais sustent\u00e1veis.<\/p>\n<h5>Como voc\u00ea faz isto?<\/h5>\n<p>Com nosso modelo Compre Um, D\u00ea Um = A cada compra de nosso produto, doaremos um absorvente reutiliz\u00e1vel para mulheres carentes que n\u00e3o t\u00eam recursos para ter produtos e educa\u00e7\u00e3o sustent\u00e1veis para o per\u00edodo menstrual.<\/p>\n<h5>Qual \u00e9 a miss\u00e3o do Perfect Fit?<\/h5>\n<p>Um mundo onde as mulheres e as raparigas possam atingir o seu pleno potencial, livres de desigualdade e discrimina\u00e7\u00e3o devido ao seu g\u00e9nero e sexualidade.<\/p>\n<p>Nossa miss\u00e3o \u00e9 capacitar as mulheres para que tenham melhor menstrua\u00e7\u00e3o e sa\u00fade reprodutiva por meio de produtos inovadores e mudan\u00e7as sociais na menstrua\u00e7\u00e3o e nos direitos das mulheres.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-12192 size-large\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/05\/Penjahit-Labuan-Bajo-1024x683.jpeg\" alt=\"a educa\u00e7\u00e3o de ajuste perfeito fornece uma solu\u00e7\u00e3o artigo bandita revista karma instant\u00e2nea viajante atento\" width=\"1024\" height=\"683\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/05\/Penjahit-Labuan-Bajo-1024x683.jpeg 1024w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/05\/Penjahit-Labuan-Bajo-300x200.jpeg 300w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/05\/Penjahit-Labuan-Bajo-768x512.jpeg 768w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/05\/Penjahit-Labuan-Bajo-1536x1024.jpeg 1536w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/05\/Penjahit-Labuan-Bajo-2048x1365.jpeg 2048w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/05\/Penjahit-Labuan-Bajo-624x416.jpeg 624w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<h5>O que voc\u00ea j\u00e1 fez nesse sentido?<\/h5>\n<p>Temos trabalhado na quest\u00e3o da menstrua\u00e7\u00e3o desde o final de 2017. De 2017 a 2020, o nosso foco foi principalmente na Prov\u00edncia NTT, atrav\u00e9s de parcerias com comunidades de baixa renda para produzir absorventes reutiliz\u00e1veis. Produzimos 50 mil absorventes e alcan\u00e7amos 12.500 meninas e mulheres.<\/p>\n<p>Em setembro de 2020, regist\u00e1mo-nos como uma start-up para nos concentrarmos na expans\u00e3o desta vis\u00e3o e miss\u00e3o a todas as mulheres e raparigas na Indon\u00e9sia.<\/p>\n<p>&nbsp;<\/p>\n<h3>\u00c9 um ajuste perfeito<\/h3>\n<p><em>Quando voc\u00ea sabe que a menstrua\u00e7\u00e3o \u00e9 a coisa mais normal e natural que acontece no aparelho reprodutor feminino, voc\u00ea come\u00e7a a entender que n\u00e3o devemos ter vergonha de falar sobre isso.<\/em><\/p>\n<p><em>A abertura para come\u00e7ar a falar sobre isso em casa, na escola e nas institui\u00e7\u00f5es sociais ajudar\u00e1 a reduzir o estigma e ajudar\u00e1 as pessoas a aceitarem a menstrua\u00e7\u00e3o pelo que ela \u00e9: \u201cUm processo natural e necess\u00e1rio no corpo feminino que permite que uma nova vida cres\u00e7a\u201d.<\/em><\/p>\n<p>&nbsp;<\/p>\n<h5>Siga o Ajuste Perfeito no Instagram <a href=\"https:\/\/www.instagram.com\/perfectfit_id\/\" target=\"_blank\" rel=\"noopener\"><strong>@perfectfit_id<\/strong><\/a><\/h5>\n<h5>Leia mais sobre este incr\u00edvel projeto em<strong> <a href=\"https:\/\/perfectfit.start.page\/\" target=\"_blank\" rel=\"noopener\">www.perfectfit.start.page<\/a><\/strong><\/h5>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/perfectfit.start.page\/\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-12199 size-full aligncenter\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/05\/1650264831823.perfect-fit-logo-secondary-color-variation-02.jpg\" alt=\"\" width=\"160\" height=\"200\" title=\"\"><\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Quando voc\u00ea sabe que a menstrua\u00e7\u00e3o \u00e9 a coisa mais normal e natural que acontece no aparelho reprodutor feminino, voc\u00ea come\u00e7a a entender que n\u00e3o devemos ter vergonha de falar sobre isso.<\/p>","protected":false},"author":214,"featured_media":12198,"comment_status":"open","ping_status":"closed","template":"","meta":{"footnotes":""},"categories":[275],"tags":[351],"section":[387,388],"interest":[381,378],"_magazine":[352],"class_list":["post-12190","article","type-article","status-publish","has-post-thumbnail","hentry","category-impact","tag-351","section-impact","section-people","interest-empowerment","interest-social","_magazine-352"],"_links":{"self":[{"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/article\/12190","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/article"}],"about":[{"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/types\/article"}],"author":[{"embeddable":true,"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/users\/214"}],"replies":[{"embeddable":true,"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/comments?post=12190"}],"version-history":[{"count":0,"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/article\/12190\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/media\/12198"}],"wp:attachment":[{"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/media?parent=12190"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/categories?post=12190"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/tags?post=12190"},{"taxonomy":"section","embeddable":true,"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/section?post=12190"},{"taxonomy":"interest","embeddable":true,"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/interest?post=12190"},{"taxonomy":"_magazine","embeddable":true,"href":"https:\/\/instantkarmamag.com\/pt\/wp-json\/wp\/v2\/_magazine?post=12190"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}<!-- This website is optimized by Airlift. Learn more: https://airlift.net. Template:. Learn more: https://airlift.net. Template: 6a3c9e6bc6af5a91495580da. Config Timestamp: 2026-06-25 03:19:51 UTC, Cached Timestamp: 2026-09-02 02:51:04 UTC -->