{"id":9710,"date":"2022-01-01T00:00:00","date_gmt":"2021-12-31T16:00:00","guid":{"rendered":"https:\/\/instantkarmamag.com\/article\/the-island-that-time-forgot\/"},"modified":"2024-06-22T04:20:55","modified_gmt":"2024-06-21T20:20:55","slug":"lisola-di-buru-quella-volta-lho-dimenticata","status":"publish","type":"article","link":"https:\/\/instantkarmamag.com\/it\/articolo\/lisola-di-buru-quella-volta-lho-dimenticata\/","title":{"rendered":"Buru, l&#039;isola dimenticata dal tempo"},"content":{"rendered":"<div id=\"bsf_rt_marker\"><\/div><h2><strong>Isola di Bur\u00f9<br \/>\n<\/strong><\/h2>\n<p>Mentre il mio volo scende verso la citt\u00e0 di Ambon, le isole delle Molucche cominciano ad apparire attraverso le acque azzurre del Mare di Banda come Pleiadi sparse complete di spiagge di sabbia bianca accecante fiancheggiate da palme ondeggianti.<\/p>\n<figure id=\"attachment_7763\" aria-describedby=\"caption-attachment-7763\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-7763 size-medium\" src=\"https:\/\/mlucpnxbn6mg.i.optimole.com\/w:300\/h:245\/q:mauto\/process:7763\/id:e2b8e7a3c9591f9a09d1b6bb682a9b6a\/https:\/\/instantkarmamag.com\/better-map.png\" alt=\"Posizione sulla mappa dell&#039;isola di Buru, Maluku\" width=\"300\" height=\"245\" title=\"\"><figcaption id=\"caption-attachment-7763\" class=\"wp-caption-text\"><em>La posizione delle Molucche (Isole delle Spezie)<\/em><\/figcaption><\/figure>\n<p>Sto per realizzare il sogno di una vita: scoprire le Isole delle Spezie!<\/p>\n<p>La provincia indonesiana di Maluku, anglicizzata nel tempo come Molucche, comprende centinaia di minuscole isole che sono tra le pi\u00f9 remote e meno popolate dell&#039;Indonesia e del mondo e, nonostante la loro squisita bellezza, non sono certamente sulla mappa turistica.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-7759 aligncenter\" src=\"https:\/\/mlucpnxbn6mg.i.optimole.com\/w:1024\/h:683\/q:mauto\/process:7759\/id:51be606ee2f0912eb7ce9e34c65b5f28\/https:\/\/instantkarmamag.com\/IMG_66991.jpg\" alt=\"Buru Island Beach Water Indonesia Esplora\" width=\"285\" height=\"190\" title=\"\"><\/p>\n<p>Per secoli, questo idilliaco arcipelago \u00e8 stato chiamato Le Isole delle Spezie e copre un&#039;area di 75.000 chilometri quadrati e ospita solo 2,1 milioni di persone, la maggior parte risiede nella capitale della provincia, Ambon.<\/p>\n<p>Le Molucche, circondate dal Mare di Banda, si collegano con il Mare di Seram a nord e con i mari di Arafura e Timor a sud, circondando questo paradiso idilliaco.<\/p>\n<p>&nbsp;<\/p>\n<p>La zona ha avuto una storia turbolenta, soprattutto durante il XVII secolo, quando sia gli olandesi che gli inglesi entrarono nella corsa alle spezie gareggiando per saccheggiare e monopolizzare l&#039;abbondanza di noce moscata, pepe e chiodi di garofano per soddisfare l&#039;enorme domanda in Europa.<\/p>\n<p>Questa brama di territorio e di profitto si \u00e8 rivelata un periodo brutale per queste isole assediate, lasciando oggi una macchia indelebile evidente. Nel corso dei secoli successivi, questo angolo quasi dimenticato dell\u2019Indonesia ha subito numerosi sconvolgimenti, ma la realt\u00e0 \u00e8 che questa provincia \u00e8 stata in gran parte dimenticata.<\/p>\n<p>Il mio soggiorno sull&#039;isola di Ambon \u00e8 stato relativamente breve, ed \u00e8 stato un peccato perch\u00e9 ho trovato questa &quot;citt\u00e0 della musica&quot; un&#039;affascinante mini-metropoli piena di vita. Ho trascorso la maggior parte del mio tempo a cercare uno sbocco per ottenere un test rapido Covid e, cosa pi\u00f9 importante, avevo un traghetto da prendere!<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-7762 size-medium aligncenter\" src=\"https:\/\/mlucpnxbn6mg.i.optimole.com\/w:225\/h:300\/q:mauto\/process:7762\/id:48ef67249b942ae1e14279a1c4375bfb\/https:\/\/instantkarmamag.com\/IMG_07951.jpg\" alt=\"Buru Island Boat Water Indonesia Esplora\" width=\"225\" height=\"300\" title=\"\"><\/p>\n<p>Ambon ha un&#039;intrigante forma a punta, perch\u00e9 \u00e8 come se il paesaggio si fosse distorto e girato su se stesso, creando la baia di Ambon che taglia l&#039;isola per 20 km, fornendo un ingresso sicuro per la flotta di piccole barche da pesca ormeggiate lungo le sue sponde.<\/p>\n<p>Il porto di Amboina brulica di attivit\u00e0 in cui il traghetto notturno per l&#039;isola di Buru stava caricando gli ultimi camion, automobili e centinaia di passeggeri per la traversata notturna di dodici ore.<\/p>\n<p>Puntuali alle 20:00, salpiamo e entriamo lentamente nella baia prima di virare a ovest, diretti verso la nostra destinazione.<\/p>\n<p>Sul ponte superiore, i passeggeri si siedono immediatamente per consumare la cena mentre gli altoparlanti gemelli accanto alla mensa diffondono una serie di rauca musica da discoteca che continuer\u00e0 a tutto volume per tutta la notte.<\/p>\n<p>Al termine del pasto serale, la maggior parte dei passeggeri comincia a ritirarsi sul ponte centrale dove centinaia di letti a castello, impilati tre in alto, forniranno un riposo notturno, anche se piuttosto soffocante, sulle note di &quot;I Love The Night Life&quot;. a tutto volume dagli altoparlanti di dimensioni industriali in alto.<\/p>\n<h3>Buru Island \u00e8 una delle isole pi\u00f9 grandi dell&#039;arcipelago, 13 volte pi\u00f9 grande di Singapore, ma con meno di 200.000 abitanti, \u00e8 piena di storie di tragedie e ispirazione ed \u00e8 satura di politica.<\/h3>\n<h2 style=\"text-align: left;\">Dovrebbe essere il sogno di uno scrittore.<\/h2>\n<p>L&#039;isola vive con una sfortunata reputazione poich\u00e9 \u00e8 un luogo dove i prigionieri politici furono esiliati durante l&#039;era del Nuovo Ordine degli anni &#039;60 sotto il regime di Suharto. Di conseguenza, era vista come un&#039;isola-prigione, il che probabilmente era vero vent&#039;anni fa, ma col tempo l&#039;isola \u00e8 riuscita a scrollarsi di dosso quello sfortunato soprannome e sta cercando disperatamente di reinventarsi.<\/p>\n<p>Nelle prime luci dell&#039;alba, l&#039;isola emerge dalla bassa nebbia e, man mano che ci avviciniamo, la sua geografia appare in netto rilievo. Le colline sono ricoperte da fitte foreste sempreverdi di pini, casuarina ed eucalipti selvatici, mentre le fertili pianure sono inondate di rigogliose mangrovie.<\/p>\n<p>Con poca confusione, il traghetto attracca al porto di Namlea, la capitale, e i passeggeri, freschi di sonno, si uniscono alla miriade di camion e macchine che scendono dalla rampa mentre il diligente DJ sul ponte superiore cambia il suo repertorio in un pi\u00f9 soft amore indonesiano. canzoni suonate agli stessi livelli di decibel che ha mantenuto per tutta la notte.<\/p>\n<p>L&#039;isola di Buru, menzionata per la prima volta in occidente intorno al 1365, e si ha la sensazione che gli abitanti avrebbero preferito restare anonimi. Tuttavia, dal 1658 al 1942, regnava la Compagnia olandese delle Indie Orientali, seguita dalla Corona dei Paesi Bassi e, per aggiungere la beffa al danno, fu occupata dai giapponesi durante la Seconda Guerra Mondiale.<\/p>\n<p>Namlea \u00e8 una cittadina nel complesso piacevole con mercati vivaci, circondata da dolci colline e abbondanti praterie fertili. In una delle strade principali, il mio anonimo hotel si trovava di fronte a un grande accampamento militare dipinto di un verde chiaro e vivido. Nei prossimi giorni vedr\u00f2 molte di queste tentacolari installazioni militari.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-7760\" src=\"https:\/\/mlucpnxbn6mg.i.optimole.com\/w:auto\/h:auto\/q:mauto\/process:7760\/id:6cf1efa6eebe3a90bfbb1835d8564f5b\/https:\/\/instantkarmamag.com\/IMG_08301.jpg\" alt=\"Buru Island Jungle Trekking River Indonesia Esplora\" width=\"552\" height=\"414\" title=\"\"><\/p>\n<h3>La mia prima tappa di questo viaggio \u00e8 stata visitare lo spiacevole segreto dell&#039;isola di Buru.<\/h3>\n<p>Nel profondo dell&#039;interno dell&#039;isola si trova uno dei campi di prigionia pi\u00f9 remoti e famigerati dell&#039;Indonesia. Durante la repressione della sinistra politica del 1965, circa 12.000 uomini furono deportati a Buru senza accusa formale o processo. Durante la detenzione, i prigionieri hanno subito torture, lavoro forzato e malnutrizione, nonch\u00e9 isolamento sociale. Il loro esilio dur\u00f2 pi\u00f9 di tredici anni.<\/p>\n<p>Il sito del campo originale adiacente al villaggio di Savanajaya \u00e8 relativamente anonimo. Non c&#039;\u00e8 praticamente alcuna prova visiva che questo fosse il punto di smistamento centrale per i prigionieri in arrivo, con solo un piccolo monumento coperto di erbacce nel mezzo di un grande campo.<\/p>\n<p>Ho fatto visita al capo del villaggio locale dove lui, alcuni membri del suo staff e l&#039;insegnante di inglese della scuola locale sono stati pi\u00f9 che disposti a rispondere alle mie domande su ci\u00f2 che \u00e8 accaduto durante quei tempi bui. Nel gruppo c&#039;erano tre ottuagenari piuttosto vivaci, ex prigionieri dell&#039;epoca.<\/p>\n<p>Questi anziani signori, separati dalle loro famiglie cinquant&#039;anni fa, furono spediti dal governo per migliaia di miglia in questo paesaggio sconosciuto.<\/p>\n<p>Tutti e tre avevano scelto, una volta rilasciati, di restare, sposare donne del posto, mettere su famiglia ed entrare a far parte della loro nuova comunit\u00e0. Sembravano piuttosto contenti, ma nonostante ci\u00f2, questo periodo oscuro della storia dell&#039;isola di Buru \u00e8 dimenticato tanto quanto il triste monumento che si erge in quel campo desolato.<\/p>\n<p>Dirigendosi verso il villaggio di Sanlekoon, il nostro percorso ci ha portato oltre vaste risaie coltivate da agricoltori con i loro cappelli conici, che li proteggevano dal feroce sole tropicale. Questi stessi campi creati dalle povere anime che furono strappate alle loro vite a Giava e trasportate qui, a miglia di distanza da qualsiasi luogo.<\/p>\n<p>Arrivando al villaggio di Sanlekoon a bordo di una piccola barca, i miei compagni che ho incontrato ad Ambon sono accolti da un grande comitato di benvenuto che ci ha inondato di ghirlande e poi ha eseguito una danza cerimoniale. L&#039;intero villaggio si \u00e8 riunito per salutare il nostro arrivo!<\/p>\n<p>Questo rituale sarebbe stato eseguito altre due volte nei successivi villaggi che avremmo visitato nei due giorni successivi. La cerimonia era la stessa, ci venivano donate ghirlande, bambini in abiti cerimoniali eseguivano coreografie con abbondanti quantit\u00e0 di cibo e bevande offerte.<\/p>\n<p>Chiedo con discrezione se il nostro arrivo \u00e8 avvenuto da quando \u00e8 iniziata la pandemia. No, siamo i primi visitatori in assoluto a visitare il loro villaggio!!<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-10580 aligncenter\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/03\/IMG_09281-scaled-1.webp\" alt=\"l&#039;isola dimenticata dal tempo Buru esplora le Molucche Indonesia\" width=\"312\" height=\"416\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/03\/IMG_09281-scaled-1.webp 768w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/03\/IMG_09281-scaled-1-225x300.webp 225w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/03\/IMG_09281-scaled-1-624x832.webp 624w\" sizes=\"auto, (max-width: 312px) 100vw, 312px\" \/><\/p>\n<p>Questi abitanti sono ora incoraggiati a impegnarsi in attivit\u00e0 turistiche, creare alloggi in famiglia e promuovere escursioni e safari con uccelli. Questo programma, finanziato da una ONG tedesca, sta cercando di svezzare la popolazione dall\u2019estrazione illegale e dal disboscamento come modo pi\u00f9 sostenibile per guadagnarsi da vivere.<\/p>\n<p>Spero che funzioni per persone come queste, che meritano una vita migliore, ma si pensa che sar\u00e0 una battaglia ardua poich\u00e9, data la lontananza e la difficolt\u00e0 di raggiungere questi villaggi, \u00e8 necessaria una grande dose di intrepidezza.<\/p>\n<p>L&#039;isola di Buru \u00e8 una bellissima isola brulicante di avifauna, tra cui mangiatori di miele, martin pescatori, cacatua e buceri giganti. I ritmi sono tranquilli, le spiagge sono da cartolina, la gente calda e accogliente\u2026 mi piace pensare che un giorno torner\u00f2.<\/p>\n<p>&nbsp;<\/p>\n<p><b><br \/>\nContinua \u2026.<\/b><\/p>\n<p>&nbsp;<\/p>\n<p>_____________<\/p>\n<p><em>Testo di Paul v Walters<\/em><\/p>\n<p><em>Foto di Paul contro Walters e Elisabeth Lenahan<\/em><\/p>\n<h3 style=\"text-align: center;\"><b>Isola di Buru Isola delle Molucche Indonesia. Novembre 2021<\/b><\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-7757 aligncenter\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/01\/headshot-author-Paul-v-Walters1.jpg\" alt=\"\" width=\"160\" height=\"160\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/01\/headshot-author-Paul-v-Walters1.jpg 200w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/01\/headshot-author-Paul-v-Walters1-150x150.jpg 150w\" sizes=\"auto, (max-width: 160px) 100vw, 160px\" \/><\/p>\n<p><i>\u201cIl mio viaggio a Buru e in altre isole \u00e8 stato reso possibile dalle spedizioni Go Wild, un\u2019organizzazione no-profit con sede a Giakarta.\u201d<br \/>\n<\/i><\/p>\n<p><i>Paul v Walters \u00e8 l&#039;autore di numerosi romanzi e racconti pi\u00f9 venduti. Inoltre, occasionalmente rilancia per scarabocchiare per diversi <strong><a href=\"https:\/\/instantkarmamag.com\/it\">diari di viaggio e vox pop<\/a><\/strong> quando non avvolto nell&#039;indolenza e nella procrastinazione.<\/i><\/p>\n<p>&nbsp;<\/p>\n<p><em>Sito web: <a href=\"https:\/\/www.paulvwalters.net\/\" target=\"_blank\" rel=\"noopener\"><strong>paulvwalters.net<\/strong><\/a><\/em><\/p>\n<p><em>E-mail: <a href=\"mailto:walterspaul7@gmail.com\" target=\"_blank\" rel=\"noopener\"><strong>walterspaul7@gmail.com<\/strong><\/a><\/em><\/p>","protected":false},"excerpt":{"rendered":"<p>L&#039;isola di Buru \u00e8 una bellissima isola brulicante di avifauna, tra cui mangiatori di miele, martin pescatori, cacatua e buceri giganti. Il ritmo \u00e8 tranquillo, le spiagge sono da cartolina e la gente \u00e8 calda e accogliente<\/p>","protected":false},"author":121,"featured_media":10582,"comment_status":"open","ping_status":"closed","template":"","meta":{"footnotes":""},"categories":[270],"tags":[348],"section":[385],"interest":[199,401,377,400],"_magazine":[329],"class_list":["post-9710","article","type-article","status-publish","has-post-thumbnail","hentry","category-explore","tag-348","section-explore","interest-expeditions","interest-nature","interest-sightseeing","interest-things-to-do","_magazine-329"],"_links":{"self":[{"href":"https:\/\/instantkarmamag.com\/it\/wp-json\/wp\/v2\/article\/9710","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/instantkarmamag.com\/it\/wp-json\/wp\/v2\/article"}],"about":[{"href":"https:\/\/instantkarmamag.com\/it\/wp-json\/wp\/v2\/types\/article"}],"author":[{"embeddable":true,"href":"https:\/\/instantkarmamag.com\/it\/wp-json\/wp\/v2\/users\/121"}],"replies":[{"embeddable":true,"href":"https:\/\/instantkarmamag.com\/it\/wp-json\/wp\/v2\/comments?post=9710"}],"version-history":[{"count":0,"href":"https:\/\/instantkarmamag.com\/it\/wp-json\/wp\/v2\/article\/9710\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/instantkarmamag.com\/it\/wp-json\/wp\/v2\/media\/10582"}],"wp:attachment":[{"href":"https:\/\/instantkarmamag.com\/it\/wp-json\/wp\/v2\/media?parent=9710"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/instantkarmamag.com\/it\/wp-json\/wp\/v2\/categories?post=9710"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/instantkarmamag.com\/it\/wp-json\/wp\/v2\/tags?post=9710"},{"taxonomy":"section","embeddable":true,"href":"https:\/\/instantkarmamag.com\/it\/wp-json\/wp\/v2\/section?post=9710"},{"taxonomy":"interest","embeddable":true,"href":"https:\/\/instantkarmamag.com\/it\/wp-json\/wp\/v2\/interest?post=9710"},{"taxonomy":"_magazine","embeddable":true,"href":"https:\/\/instantkarmamag.com\/it\/wp-json\/wp\/v2\/_magazine?post=9710"}],"curies":[{"name":"scrivere","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}<!-- This website is optimized by Airlift. Learn more: https://airlift.net. Template:. Learn more: https://airlift.net. Template: 6a3c9e6bc6af5a91495580da. Config Timestamp: 2026-06-25 03:19:51 UTC, Cached Timestamp: 2026-09-02 07:44:56 UTC -->