{"id":32326,"date":"2024-04-11T12:05:54","date_gmt":"2024-04-11T04:05:54","guid":{"rendered":"https:\/\/instantkarmamag.com\/?post_type=article&#038;p=32326"},"modified":"2024-06-24T05:00:41","modified_gmt":"2024-06-23T21:00:41","slug":"comunita-in-cerca","status":"publish","type":"article","link":"https:\/\/instantkarmamag.com\/it\/articolo\/comunita-in-cerca\/","title":{"rendered":"Alla ricerca di comunit\u00e0"},"content":{"rendered":"<div id=\"bsf_rt_marker\"><\/div><p><span data-contrast=\"none\">La pandemia attuale sembra essere la ragione pi\u00f9 ovvia dell\u2019epidemia di solitudine.<\/span><span data-contrast=\"auto\"> Tuttavia, anche prima di allora, le persone rischiavano la vita solo per riunirsi con gli amici, nonostante tutti gli avvertimenti e le punizioni. Quando le restrizioni furono rimosse, tutti furono felici di ritrovarsi tra le persone della propria comunit\u00e0. <\/span><\/p>\n<p><span data-contrast=\"auto\">Ma ci sentiamo ancora soli anche senza il distanziamento sociale forzato. Ci stiamo allontanando volontariamente?<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;134245417&quot;:true,&quot;335551550&quot;:1,&quot;335551620&quot;:1}\">\u00a0<\/span><\/p>\n<h2>Il problema dell&#039;isolamento sociale<\/h2>\n<p><strong>Recenti ricerche sullo stato di solitudine e isolamento sociale hanno rilevato:\u00a0<\/strong><\/p>\n<p><span data-contrast=\"auto\">34% degli adulti in Australia erano soli, con 21% che sperimentavano solitudine episodica e 13% che sperimentavano solitudine cronica. <\/span><\/p>\n<p><span data-contrast=\"auto\">Negli Stati Uniti, 43% degli adulti sentivano di non avere compagnia, 43% sentiva che le loro relazioni non erano significative, 43% si sentiva isolato dagli altri e 39% non si sentiva pi\u00f9 vicino a nessuno. <\/span><\/p>\n<p><span data-contrast=\"auto\">In Australia, 17% della popolazione generale sono stati classificati come socialmente isolati, con 13% che hanno subito un isolamento episodico e 4% che hanno subito un isolamento cronico.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;134245417&quot;:true,&quot;335551550&quot;:1,&quot;335551620&quot;:1}\">\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><strong>Mezzi sociali<\/strong><\/h3>\n<p><span data-contrast=\"none\">Anche se i social media ci danno la sensazione cos\u00ec ricercata di stare con le persone, comunicare, restare in contatto, in realt\u00e0 ci isolano gli uni dagli altri. Internet pu\u00f2 essere un ottimo strumento di connessione se usato bene, ma in questo caso richiede impegno e consapevolezza.\u00a0<\/span><span data-ccp-props=\"{&quot;134245417&quot;:false,&quot;335551550&quot;:6,&quot;335551620&quot;:6}\">\u00a0<\/span><\/p>\n<p><\/p>\n<p><span data-contrast=\"none\">Potresti facilmente essere risucchiato in una comunit\u00e0 da un algoritmo. Bastano solo un paio di clic ed eccoti qui, consumato da una nuova idea <\/span><span data-contrast=\"auto\">sembra <\/span><span data-contrast=\"none\">risolve tanti tuoi problemi. <\/span><\/p>\n<p><span data-contrast=\"none\">Molto probabilmente si basa sull&#039;odio e sull&#039;abbattimento delle persone. Trovare una comunit\u00e0 in linea con i tuoi valori e punti di vista, basata su idee positive, richiede impegno.\u00a0<\/span><span data-ccp-props=\"{&quot;134245417&quot;:false,&quot;335551550&quot;:6,&quot;335551620&quot;:6}\">\u00a0<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-32649 size-large\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2024\/04\/seeking-community-2-1024x683.jpg\" alt=\"comunit\u00e0 in cerca\" width=\"1024\" height=\"683\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2024\/04\/seeking-community-2-1024x683.jpg 1024w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2024\/04\/seeking-community-2-300x200.jpg 300w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2024\/04\/seeking-community-2-768x512.jpg 768w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2024\/04\/seeking-community-2.jpg 1500w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<h3><strong>Creazione di comunit\u00e0<\/strong><\/h3>\n<p><span data-contrast=\"none\">Recentemente ho scoperto una cosa nuova per me: creare comunit\u00e0. <\/span><\/p>\n<p><span data-contrast=\"none\">Una volta caduto nella tana del coniglio di brevi video depressivi, potresti sembrare che tu sia l&#039;unica persona sana di mente al mondo. Soprattutto se ti capita di non avere familiari e amici che sono sulla tua stessa lunghezza d&#039;onda. <\/span><\/p>\n<p><span data-contrast=\"none\">Ma se ti fai avanti e parli online, o riunisci persone offline, o magari semplicemente raggiungi qualcuno che ha le tue stesse opinioni (o hai letteralmente pubblicato qualcosa in cui puoi identificarti, facile!), vedrai che \u00e8 molto pi\u00f9 semplice per trovare quel senso di connessione di quanto pensavi.<\/span><\/p>\n<p><strong>Vieni e unisciti a noi a <a href=\"https:\/\/karmakommunity.org\/\" target=\"_blank\" rel=\"noopener\">Comunit\u00e0 Karma<\/a><\/strong><\/p>\n<p><span data-ccp-props=\"{&quot;134245417&quot;:false,&quot;335551550&quot;:6,&quot;335551620&quot;:6}\"><strong>teniamo riunioni regolari sull&#039;isola di Bali.<\/strong><br \/>\n<\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>Man mano che diventiamo pi\u00f9 isolati, il bisogno di una comunit\u00e0 e di un sentimento di unione diventa pi\u00f9 importante.\u00a0<\/p>","protected":false},"author":40,"featured_media":32650,"comment_status":"open","ping_status":"closed","template":"","meta":{"footnotes":""},"categories":[274],"tags":[411],"section":[317],"interest":[378],"_magazine":[407],"class_list":["post-32326","article","type-article","status-publish","has-post-thumbnail","hentry","category-mindful","tag-readmore","section-mindful","interest-social","_magazine-407"],"_links":{"self":[{"href":"https:\/\/instantkarmamag.com\/it\/wp-json\/wp\/v2\/article\/32326","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/instantkarmamag.com\/it\/wp-json\/wp\/v2\/article"}],"about":[{"href":"https:\/\/instantkarmamag.com\/it\/wp-json\/wp\/v2\/types\/article"}],"author":[{"embeddable":true,"href":"https:\/\/instantkarmamag.com\/it\/wp-json\/wp\/v2\/users\/40"}],"replies":[{"embeddable":true,"href":"https:\/\/instantkarmamag.com\/it\/wp-json\/wp\/v2\/comments?post=32326"}],"version-history":[{"count":0,"href":"https:\/\/instantkarmamag.com\/it\/wp-json\/wp\/v2\/article\/32326\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/instantkarmamag.com\/it\/wp-json\/wp\/v2\/media\/32650"}],"wp:attachment":[{"href":"https:\/\/instantkarmamag.com\/it\/wp-json\/wp\/v2\/media?parent=32326"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/instantkarmamag.com\/it\/wp-json\/wp\/v2\/categories?post=32326"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/instantkarmamag.com\/it\/wp-json\/wp\/v2\/tags?post=32326"},{"taxonomy":"section","embeddable":true,"href":"https:\/\/instantkarmamag.com\/it\/wp-json\/wp\/v2\/section?post=32326"},{"taxonomy":"interest","embeddable":true,"href":"https:\/\/instantkarmamag.com\/it\/wp-json\/wp\/v2\/interest?post=32326"},{"taxonomy":"_magazine","embeddable":true,"href":"https:\/\/instantkarmamag.com\/it\/wp-json\/wp\/v2\/_magazine?post=32326"}],"curies":[{"name":"scrivere","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}<!-- This website is optimized by Airlift. Learn more: https://airlift.net. Template:. Learn more: https://airlift.net. Template: 6a3c9e6bc6af5a91495580da. Config Timestamp: 2026-06-25 03:19:51 UTC, Cached Timestamp: 2026-09-02 08:58:31 UTC -->