{"id":26531,"date":"2023-07-04T12:06:08","date_gmt":"2023-07-04T04:06:08","guid":{"rendered":"https:\/\/instantkarmamag.com\/?post_type=article&#038;p=26531"},"modified":"2024-10-21T17:04:49","modified_gmt":"2024-10-21T09:04:49","slug":"rumah-berdaya-2","status":"publish","type":"article","link":"https:\/\/instantkarmamag.com\/it\/articolo\/rumah-berdaya-2\/","title":{"rendered":"Casa Berdaya"},"content":{"rendered":"<div id=\"bsf_rt_marker\"><\/div><p><span data-contrast=\"auto\">L&#039;incarnazione di tale amore disinteressato pu\u00f2 essere vividamente osservata presso RUMAH BERDAYA, una struttura dedicata alla riabilitazione psicosociale delle persone affette da schizofrenia (PWS), RUMAH BERDAYA ora opera sotto gli auspici del Servizio Sociale della<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Abbiamo avuto l&#039;opportunit\u00e0 di incontrare la signora Agung Diah, responsabile degli sforzi di riabilitazione presso Rumah Berdaya nell&#039;ambito del dipartimento dei servizi sociali, e di parlare direttamente con lei di Rumah Berdaya.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<h3><b><i><span data-contrast=\"auto\">Come sta signora Agung Diah, pu\u00f2 raccontarci come \u00e8 entrata a far parte del team RUMAH BERDAYA?<\/span><\/i><\/b><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/h3>\n<p><span data-contrast=\"auto\">Inizialmente, RUMAH BERDAYA era guidata dall\u2019Ufficio sanitario perch\u00e9 i nostri amici con problemi di salute mentale facevano parte del programma dell\u2019Ufficio sanitario provinciale di Bali. Tuttavia, nel 2019, data la sua attenzione alla riabilitazione e al sostegno, la responsabilit\u00e0 di RUMAH BERDAYA \u00e8 stata trasferita al servizio sociale provinciale di Bali. Il 10 gennaio 2019, il servizio sociale provinciale di Bali ha ufficialmente assunto la gestione di RUMAH BERDAYA e ha istituito una casa di riabilitazione dedicata per persone affette da schizofrenia (PWS) situata a Jalan Raya Sesetan, Denpasar.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<h3><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/h3>\n<h3><b><i><span data-contrast=\"auto\">Puoi raccontarci come \u00e8 iniziata la fondazione di RUMAH BERDAYA?<\/span><\/i><\/b><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/h3>\n<p><span data-contrast=\"auto\">RUMAH BERDAYA \u00e8 stata fondata nel settembre 2016 da uno psichiatra di nome Dr I Gusti Rai Putra Wiguna e dalla signora Komang Ayu dell&#039;ufficio sanitario provinciale di Bali. La struttura di riabilitazione si trova a Jalan Hayam Wuruk a Denpasar.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-26572 size-large aligncenter\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/07\/DSC05106.jpg\" alt=\"\" width=\"683\" height=\"1024\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/07\/DSC05106.jpg 1365w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/07\/DSC05106-200x300.jpg 200w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/07\/DSC05106-768x1152.jpg 768w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/07\/DSC05106-683x1024.jpg 683w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/07\/DSC05106-1024x1536.jpg 1024w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/07\/DSC05106-624x936.jpg 624w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/><\/p>\n<h5><\/h5>\n<h3><b><i><span data-contrast=\"auto\">Esiste uno stigma nei confronti delle persone con schizofrenia (PWS) qui a Bali? Quali sono gli esempi di stigmatizzazione da parte della comunit\u00e0?<\/span><\/i><\/b><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/h3>\n<p><span data-contrast=\"auto\">Sfortunatamente, uno degli stigmi vissuti dalle PWS \u00e8 che possono dover affrontare il rifiuto da parte delle loro famiglie e comunit\u00e0 o dell\u2019ambiente circostante. Ci\u00f2 pu\u00f2 portare a situazioni estreme in cui alcune famiglie ricorrono ad incatenarli. L&#039;incatenamento comporta il vincolo fisico degli individui con catene e l&#039;attaccamento delle mani a pesi di legno, limitando gravemente la loro mobilit\u00e0 e autonomia. \u00c8 una pratica angosciante.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Si dice che le PWS portino disgrazia alla famiglia e all&#039;ambiente circostante, quindi secondo la comunit\u00e0, queste PWS dovrebbero essere bandite, ostracizzate o incatenate. Questi approcci ignorano i diritti e la dignit\u00e0 delle persone con problemi di salute mentale e non riescono nemmeno a fornire loro il sostegno e le cure di cui hanno bisogno per il loro recupero.\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Per questo motivo, abbiamo creato RUMAH BERDAYA per facilitare le persone con disabilit\u00e0 a allontanarsi dagli stigmi che ricevono nella comunit\u00e0 e per educare la comunit\u00e0 sul fatto che la schizofrenia non \u00e8 una vergogna. Sono stigmi come questi che vogliamo rimuovere dai pensieri delle persone riguardo alla PWS.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-26574 size-large aligncenter\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/07\/DSC05109.jpg\" alt=\"\" width=\"1024\" height=\"683\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/07\/DSC05109.jpg 2048w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/07\/DSC05109-300x200.jpg 300w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/07\/DSC05109-768x512.jpg 768w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/07\/DSC05109-1024x683.jpg 1024w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/07\/DSC05109-1536x1024.jpg 1536w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/07\/DSC05109-624x416.jpg 624w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<h5><\/h5>\n<h3><b><i><span data-contrast=\"auto\">Quali sono i passaggi che un paziente dell&#039;ospedale psichiatrico di Bangli deve seguire per ricevere servizi di riabilitazione presso questo RUMAH BERDAYA?<\/span><\/i><\/b><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/h3>\n<p><span data-contrast=\"auto\">Abbiamo ottenuto alcune informazioni dalla comunit\u00e0 se vi fosse \u201cincatenamento\u201d o altro stigma vissuto da PWS, partendo dal rapporto della signora Selly, l\u2019ex sindaco di Denpasar che visitava spesso i villaggi nell\u2019area di Bali, e ha riscontrato il trattamento \u201cincatenato\u201d in uno dei villaggi che ha visitato. Ha discusso con il dottor Rai in qualit\u00e0 di psichiatra affinch\u00e9 questo episodio di \u201cincatenamento\u201d non si ripetesse.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Anche il dottor Rai \u00e8 intervenuto per curare la PWS e dalle cure e dalle osservazioni fatte possiamo decidere se la PWS \u00e8 deferita al manicomio o ad altri luoghi di terapia.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Pertanto, prima di intraprendere ulteriori azioni, eseguiamo una &quot;valutazione&quot;.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<h3><b><i><span data-contrast=\"auto\">Dopo essere entrati qui, quali sono i primi passi compiuti dal team BERDAYA per queste PWS?<\/span><\/i><\/b><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/h3>\n<p><span data-contrast=\"auto\">Il primo passo \u00e8 dare il benvenuto a PWS affinch\u00e9 si unisca a RUMAH BERDAYA gratuitamente (senza alcun costo) portando una carta d&#039;identit\u00e0 e una carta di famiglia. Successivamente, ci avviciniamo nuovamente alla famiglia e incoraggiamo le PWS a interagire e familiarizzare tra loro in un ambiente di supporto facilitato dal coordinatore RUMAH BERDAYA.\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Anche il nostro coordinatore \u00e8 un ex PWS. Dopo essersi ripresi, diamo loro la possibilit\u00e0 di lavorare qui con noi per aiutare e fornire cose positive alle altre PWS che si sono appena unite a RUMAH BERDAYA.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-31729 size-large\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/07\/rumah-berdaya-3-1024x683.jpg\" alt=\"Rumah Berdaya Bali\" width=\"1024\" height=\"683\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/07\/rumah-berdaya-3-1024x683.jpg 1024w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/07\/rumah-berdaya-3-300x200.jpg 300w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/07\/rumah-berdaya-3-768x512.jpg 768w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/07\/rumah-berdaya-3.jpg 1500w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<h5><\/h5>\n<h3><b><i><span data-contrast=\"auto\">Quali sono le attivit\u00e0 di routine tenute a RUMAH BERDAYA per gli amici PWS qui?<\/span><\/i><\/b><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/h3>\n<p><span data-contrast=\"auto\">Avevamo un programma regolare di attivit\u00e0 prima della pandemia, c&#039;era la cucina, lo yoga e la preparazione dell&#039;incenso, e siamo stati molto aiutati dalle comunit\u00e0 che avevano a cuore RUMAH BERDAYA, come gli studenti che si specializzano in salute e molti studenti provenienti da fuori dall&#039;Indonesia che spesso visitavano Qui. Queste comunit\u00e0 spesso organizzano attivit\u00e0 come l&#039;attivit\u00e0 terapeutica di gruppo che pu\u00f2 stimolare i movimenti motori e sensoriali della PWS.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<h3><b><i><span data-contrast=\"auto\">Quante persone sono state ufficialmente riabilitate finora al RUMAH BERDAYA?<\/span><\/i><\/b><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/h3>\n<p><span data-contrast=\"auto\">Nei nostri registri dall&#039;inizio della nostra fondazione, 80 persone sono state ufficialmente riabilitate a RUMAH BERDAYA. E per fortuna, alcuni di loro si sentono stabili, quindi abbiamo deciso di sottoporli a cure ambulatoriali, sempre sotto il monitoraggio del team di RUMAH BERDAYA che visita regolarmente le loro case per scoprire le loro condizioni. Alcuni sono diventati dipendenti pubblici, giornalisti e hanno persino riaperto le attivit\u00e0. E ci sono 20 PWS attivi adesso.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<h3><b><i><span data-contrast=\"auto\">La loro famiglia e i loro amici possono visitarli qui liberamente? Oppure ci sono delle regole?<\/span><\/i><\/b><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/h3>\n<p><span data-contrast=\"auto\">Siamo molto aperti alle visite dei loro familiari e amici. In effetti, \u00e8 proprio il sostegno di cui hanno bisogno, dove sentono che la loro famiglia e i loro amici li apprezzano, si prendono cura e li amano ancora. E non ci sono regole per la visita. Siamo molto aperti finch\u00e9 la famiglia e gli amici che vengono in visita portano cose positive alla PWS qui.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<h3><b><i><span data-contrast=\"auto\">Quali sono le speranze del team RUMAH BERDAYA per gli amici PWS dopo aver completato il programma di riabilitazione qui?<\/span><\/i><\/b><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/h3>\n<p><span data-contrast=\"auto\">Secondo me non li consideriamo finiti con il programma di riabilitazione mentre rimangono sotto la supervisione del team RUMAH BERDAYA perch\u00e9 in qualsiasi momento possono avere delle ricadute.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">E, naturalmente, niente pi\u00f9 Stigma per PWS l\u00e0 fuori<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">E ricorda... la schizofrenia non \u00e8 una vergogna!\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-31728 size-large\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/07\/rumah-berdaya-2-1024x683.jpg\" alt=\"rumah berdaya\" width=\"1024\" height=\"683\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/07\/rumah-berdaya-2-1024x683.jpg 1024w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/07\/rumah-berdaya-2-300x200.jpg 300w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/07\/rumah-berdaya-2-768x512.jpg 768w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/07\/rumah-berdaya-2.jpg 1500w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span data-contrast=\"auto\">Segui il loro Instagram:<\/span> <a href=\"https:\/\/www.instagram.com\/rumahberdaya.kpsibali\" target=\"_blank\" rel=\"noopener\"><span data-contrast=\"auto\">rumahberdaya.kpsibali<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/a><\/p>\n<p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:2,&quot;335551620&quot;:2,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>\u00a0Abbiamo avuto l&#039;opportunit\u00e0 di incontrare la signora Agung Diah, responsabile degli sforzi di riabilitazione presso RUMAH BERDAYA come parte del dipartimento dei servizi sociali, e di parlare direttamente con lei di RUMAH BERDAYA.\u00a0<\/p>","protected":false},"author":61,"featured_media":31726,"comment_status":"open","ping_status":"closed","template":"","meta":{"footnotes":""},"categories":[275],"tags":[365],"section":[387],"interest":[381,378],"_magazine":[366],"class_list":["post-26531","article","type-article","status-publish","has-post-thumbnail","hentry","category-impact","tag-365","section-impact","interest-empowerment","interest-social","_magazine-366"],"_links":{"self":[{"href":"https:\/\/instantkarmamag.com\/it\/wp-json\/wp\/v2\/article\/26531","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/instantkarmamag.com\/it\/wp-json\/wp\/v2\/article"}],"about":[{"href":"https:\/\/instantkarmamag.com\/it\/wp-json\/wp\/v2\/types\/article"}],"author":[{"embeddable":true,"href":"https:\/\/instantkarmamag.com\/it\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/instantkarmamag.com\/it\/wp-json\/wp\/v2\/comments?post=26531"}],"version-history":[{"count":0,"href":"https:\/\/instantkarmamag.com\/it\/wp-json\/wp\/v2\/article\/26531\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/instantkarmamag.com\/it\/wp-json\/wp\/v2\/media\/31726"}],"wp:attachment":[{"href":"https:\/\/instantkarmamag.com\/it\/wp-json\/wp\/v2\/media?parent=26531"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/instantkarmamag.com\/it\/wp-json\/wp\/v2\/categories?post=26531"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/instantkarmamag.com\/it\/wp-json\/wp\/v2\/tags?post=26531"},{"taxonomy":"section","embeddable":true,"href":"https:\/\/instantkarmamag.com\/it\/wp-json\/wp\/v2\/section?post=26531"},{"taxonomy":"interest","embeddable":true,"href":"https:\/\/instantkarmamag.com\/it\/wp-json\/wp\/v2\/interest?post=26531"},{"taxonomy":"_magazine","embeddable":true,"href":"https:\/\/instantkarmamag.com\/it\/wp-json\/wp\/v2\/_magazine?post=26531"}],"curies":[{"name":"scrivere","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}<!-- This website is optimized by Airlift. Learn more: https://airlift.net. Template:. Learn more: https://airlift.net. Template: 6a3c9e6bc6af5a91495580da. Config Timestamp: 2026-06-25 03:19:51 UTC, Cached Timestamp: 2026-09-02 00:47:02 UTC -->