{"id":26293,"date":"2023-07-03T13:31:27","date_gmt":"2023-07-03T05:31:27","guid":{"rendered":"https:\/\/instantkarmamag.com\/?post_type=article&#038;p=26293"},"modified":"2024-06-22T04:49:26","modified_gmt":"2024-06-21T20:49:26","slug":"fine-settimana-culinario-del-festival-gastronomico-di-ubud","status":"publish","type":"article","link":"https:\/\/instantkarmamag.com\/it\/articolo\/fine-settimana-culinario-del-festival-gastronomico-di-ubud\/","title":{"rendered":"Festival gastronomico di Ubud: concediti un delizioso fine settimana culinario"},"content":{"rendered":"<div id=\"bsf_rt_marker\"><\/div><h3>Festival gastronomico di Ubud<\/h3>\n<p><span data-contrast=\"auto\">, l&#039;evento culinario pi\u00f9 importante del Sud-Est asiatico, torna anche quest&#039;anno. Dal 30 giugno al 2 luglio, il festival presenter\u00e0 circa 40 chef locali e internazionali che delizieranno i vostri palati con una vasta gamma di cibi sullo sfondo dello splendido paesaggio di Ubud: sar\u00e0 un tour de force culinario indimenticabile.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Il tema del festival quest&#039;anno \u00e8 il suolo (Tanah). Circa il 95% del nostro cibo proviene dal nostro suolo, che fa parte di un ecosistema molto complesso. Il festival sar\u00e0 un\u2019esplorazione di come le nostre risorse naturali sostengono le nostre vite attraverso il cibo che ci danno, e di cosa possiamo fare per consumare queste risorse in modo responsabile.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p>\n<h2 style=\"text-align: center;\"><span data-contrast=\"auto\">\u201cIn quanto fonte di vita, la terra ci d\u00e0 sempre tutto ci\u00f2 che le chiediamo. Miracolosamente, i semi che piantiamo crescono e danno sempre frutti. L&#039;acqua scorre lungo il suolo, proteggendo tutti gli esseri viventi sopra e sotto la sua superficie. La terra \u00e8 come una saggia madre spirituale. Ci aiuta a diventare consapevoli di mantenere l\u2019equilibrio e i cicli vitali nella natura umana\u201d.\u00a0<\/span><\/h2>\n<p style=\"text-align: center;\"><span data-contrast=\"auto\">\u2013 Fondatrice e direttrice dell&#039;UFF, Janet DeNeefe-<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\"><br \/>\n<\/span><\/p>\n<p><span data-contrast=\"auto\">\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p>\n<h3><span data-contrast=\"auto\"><strong>Allo stesso tempo, il festival \u00e8 anche una celebrazione della diversit\u00e0 delle tradizioni culinarie che abbiamo noi esseri umani.<\/strong> <\/span><\/h3>\n<p><span data-contrast=\"auto\">Coerentemente con questo spirito, il festival di quest&#039;anno riunir\u00e0 chef provenienti da tutto il mondo per mostrare il loro stile culinario. Presenteranno il loro stile culinario unico in una serie di eventi speciali tra cui dimostrazioni di cucina, masterclass e conferenze sul cibo, tra gli altri.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Uno di questi chef \u00e8 la chef indonesiana e autrice di libri di cucina, Petty Elliott, nota soprattutto per le sue fusioni innovative e appetitose: un incrocio tra la cucina manadonese del Nord Sulawesi e cibi occidentali, che si traduce in piatti come il risotto manadonese. Tra i suoi numerosi risultati eccezionali figurano le valutazioni dei 50 migliori ristoranti dell&#039;Asia e dei 50 migliori ristoranti del mondo rispettivamente nel 2016 e nel 2017.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Abbiamo anche lo chef indonesiano Hans Christian, il cui ristorante August di Giakarta \u00e8 stato appena nominato &quot;The One to Watch&quot; dalla classifica Asia&#039;s 50 Best Restaurants. Il ristorante serve piatti indonesiani provenienti da diverse regioni, come il polpo con spezie andalimane del nord di Sumatra, utilizzando tecniche di cucina francesi.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Sul versante internazionale, sar\u00e0 presente Gabriele Castagnetti, che condivider\u00e0 gli spunti dei suoi 20 anni di esperienza come scienziato alimentare in Europa e Asia. I suoi progetti esplorano modi per creare alimenti sani, mitigando al tempo stesso i problemi ambientali come la deforestazione. Ha interpretato ruoli da protagonista nelle aziende Fortune 500.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p>\n<p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Poi avremo anche la chef filippina Johanne Siy, che attualmente lavora come capo chef del Lolla Singapore, ristorante specializzato in cucina mediterranea. Ha lavorato anche negli Stati Uniti e in diversi paesi scandinavi. \u00c8 stata nominata dalla classifica Asia&#039;s 50 Best la migliore chef donna dell&#039;Asia. Scopri di pi\u00f9 sulla sua cucina basata sui prodotti durante la sua apparizione all&#039;UFF.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p>\n<p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Il tema di quest&#039;anno \u00e8 accompagnato anche da un&#039;opera visiva dell&#039;artista balinese quindicenne Ni Wayan Tiksna Gangga, originario di Gianyar, la reggenza dove si svolge il festival. Le sue opere sono state esposte al prestigioso Agung Rai Museum of Arts (ARMA). La sua opera d&#039;arte visualizza gli elementi del suolo, che crescono sopra di esso come piante e ci\u00f2 che si trova sotto di esso come radici.\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p>\n<p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Abbiamo scelto di lavorare con lei per le opere d&#039;arte di quest&#039;anno per via del suo uso di elementi organici nelle sue arti visive, che sono in linea con il nostro tema. <\/span><span data-contrast=\"none\">&quot;Il materiale che ho utilizzato per creare quest&#039;opera d&#039;arte proviene dalla natura, come i fiori, la buccia dei frutti e l&#039;arack [balinese]&quot;, ha detto Gangga. Ha aggiunto che l&#039;uso di materiali organici per le sue opere d&#039;arte \u00e8 stato ispirato dal principio balinese di armonia tra uomo e natura<\/span><span data-contrast=\"auto\">.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>Buongustai affamati l\u00e0 fuori, questo \u00e8 per te. Fai un viaggio culinario con noi all&#039;Ubud Food Festival di quest&#039;anno! <\/p>","protected":false},"author":1,"featured_media":26295,"comment_status":"open","ping_status":"closed","template":"","meta":{"footnotes":""},"categories":[271],"tags":[363],"section":[386,394],"interest":[195,399],"_magazine":[364],"class_list":["post-26293","article","type-article","status-publish","has-post-thumbnail","hentry","category-culture","tag-363","section-culture","section-review","interest-families","interest-nutrition","_magazine-364"],"_links":{"self":[{"href":"https:\/\/instantkarmamag.com\/it\/wp-json\/wp\/v2\/article\/26293","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/instantkarmamag.com\/it\/wp-json\/wp\/v2\/article"}],"about":[{"href":"https:\/\/instantkarmamag.com\/it\/wp-json\/wp\/v2\/types\/article"}],"author":[{"embeddable":true,"href":"https:\/\/instantkarmamag.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/instantkarmamag.com\/it\/wp-json\/wp\/v2\/comments?post=26293"}],"version-history":[{"count":0,"href":"https:\/\/instantkarmamag.com\/it\/wp-json\/wp\/v2\/article\/26293\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/instantkarmamag.com\/it\/wp-json\/wp\/v2\/media\/26295"}],"wp:attachment":[{"href":"https:\/\/instantkarmamag.com\/it\/wp-json\/wp\/v2\/media?parent=26293"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/instantkarmamag.com\/it\/wp-json\/wp\/v2\/categories?post=26293"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/instantkarmamag.com\/it\/wp-json\/wp\/v2\/tags?post=26293"},{"taxonomy":"section","embeddable":true,"href":"https:\/\/instantkarmamag.com\/it\/wp-json\/wp\/v2\/section?post=26293"},{"taxonomy":"interest","embeddable":true,"href":"https:\/\/instantkarmamag.com\/it\/wp-json\/wp\/v2\/interest?post=26293"},{"taxonomy":"_magazine","embeddable":true,"href":"https:\/\/instantkarmamag.com\/it\/wp-json\/wp\/v2\/_magazine?post=26293"}],"curies":[{"name":"scrivere","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}<!-- This website is optimized by Airlift. Learn more: https://airlift.net. Template:. Learn more: https://airlift.net. Template: 6a3c9e6bc6af5a91495580da. Config Timestamp: 2026-06-25 03:19:51 UTC, Cached Timestamp: 2026-09-02 13:47:59 UTC -->