{"id":23138,"date":"2023-03-05T22:54:33","date_gmt":"2023-03-05T14:54:33","guid":{"rendered":"https:\/\/instantkarmamag.com\/?post_type=article&#038;p=23138"},"modified":"2024-06-06T19:52:57","modified_gmt":"2024-06-06T11:52:57","slug":"oh-oh-oh","status":"publish","type":"article","link":"https:\/\/instantkarmamag.com\/it\/articolo\/oh-oh-oh\/","title":{"rendered":"Kedux: Progettare Ghoul con uno scopo \u2013 Ogoh Ogoh"},"content":{"rendered":"<div id=\"bsf_rt_marker\"><\/div>\r\n<p class=\"wp-block-paragraph\">&nbsp;<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Ci sono molti artigiani ogoh-ogoh in ogni <em>Banjar<\/em> a Bali. Tuttavia, spicca il nome Kedux, che rappresenta banjar Tainsiat a Denpasar. \u00c8 un multi-trattino: possiede un negozio di motociclette personalizzate di successo, un&#039;azienda di sculture e un negozio di abbigliamento, ma crea un <em>ogoh-ogoh<\/em> da zero far\u00e0 sempre parte della sua vita da balinese.\u00a0<\/p>\r\n\r\n\r\n\r\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" class=\"wp-image-23142\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/03\/CgeL_Kss-1024x683.jpeg\" alt=\"Ogoh Ogoh-Ogoh di Tainsiat Denpasar foto di Cari Manik sculture premiate scultura Bali\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/03\/CgeL_Kss-1024x683.jpeg 1024w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/03\/CgeL_Kss-300x200.jpeg 300w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/03\/CgeL_Kss-768x512.jpeg 768w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/03\/CgeL_Kss-624x416.jpeg 624w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/03\/CgeL_Kss.jpeg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\r\n<figcaption class=\"wp-element-caption\"><em>Foto di Cari Manik <a href=\"https:\/\/www.instagram.com\/stysbtainsiat\/\" target=\"_blank\" rel=\"noreferrer noopener\" data-type=\"URL\" data-id=\"https:\/\/www.instagram.com\/stysbtainsiat\/\">@stysbtainsiat<\/a><\/em><\/figcaption>\r\n<\/figure>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Le sue creazioni hanno vinto numerosi premi, ma lui \u00e8 umile e fatica anche a ricordare i giorni in cui vinceva (ha &quot;vinto il terzo posto, il secondo posto e il primo posto&quot;).<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">In questi giorni Kedux agisce pi\u00f9 come un mentore per i giovani nel suo <em>Banjar <\/em>con grandi speranze che le competenze e le conoscenze acquisite dalla progettazione di un <em>ogoh-ogoh<\/em> pu\u00f2 portarli a cose pi\u00f9 grandi.\u00a0<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Incontriamo Komang Gede Sentana Putra, alias Kedux, nel suo negozio di automobili chiamato Kedux Garage per parlare di <em>ogoh-ogoh<\/em>.\u00a0<\/p>\r\n\r\n\r\n\r\n<h3 class=\"wp-block-heading\">Ci\u00f2 che inizialmente ti ha portato all&#039;arte di creare il <em>ogoh-ogoh<\/em>?\u00a0<\/h3>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">All&#039;inizio non ci avevo mai pensato perch\u00e9 \u00e8 una parte della cultura balinese che seguo da quando ero piccola. E&#039; un po&#039; come pregare. La gente chiederebbe: perch\u00e9 ti piace pregare? E ho risposto perch\u00e9 mi hanno insegnato a farlo fin da quando ero ragazzino. Quindi \u00e8 stato pi\u00f9 un processo culturale.\u00a0\u00a0<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Un&#039;altra cosa che mi piace della creazione <em>ogoh-ogoh<\/em> \u00e8 il lavoro di squadra.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Ci sono differenze di competenze e conoscenze all&#039;interno del team, ma l&#039;obiettivo \u00e8 lo stesso: creare <em>ogoh-ogoh<\/em>. C&#039;\u00e8 sempre quel senso di euforia ad esso associato perch\u00e9<em> Hari Raya Nyepi <\/em>\u00e8 il capodanno ind\u00f9 di Bali e il giorno prima... il <em>pengerupukan<\/em>- ci riuniamo tutti per mostrare la nostra creativit\u00e0.\u00a0\u00a0<\/p>\r\n\r\n\r\n\r\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"853\" height=\"568\" class=\"wp-image-23155\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/03\/CwTz5Vk0.jpeg\" alt=\"Ogoh Ogoh-Ogoh di Tainsiat Denpasar foto di Cari Manik sculture premiate scultura Bali\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/03\/CwTz5Vk0.jpeg 853w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/03\/CwTz5Vk0-300x200.jpeg 300w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/03\/CwTz5Vk0-768x511.jpeg 768w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/03\/CwTz5Vk0-624x416.jpeg 624w\" sizes=\"auto, (max-width: 853px) 100vw, 853px\" \/>\r\n<figcaption class=\"wp-element-caption\"><em>Foto di Cari Manik <a href=\"https:\/\/www.instagram.com\/stysbtainsiat\/\" target=\"_blank\" rel=\"noreferrer noopener\" data-type=\"URL\" data-id=\"https:\/\/www.instagram.com\/stysbtainsiat\/\">@stysbtainsiat<\/a><\/em><\/figcaption>\r\n<\/figure>\r\n\r\n\r\n\r\n<h3 class=\"wp-block-heading\">Raccontaci il processo di pensiero nella creazione del <em>ogoh-ogoh<\/em>? Inizi con una storia o una filosofia particolare?\u00a0<\/h3>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Beh, non sempre. A volte non iniziavo con niente in mente finch\u00e9 avevamo un <em>ogoh-ogoh<\/em> alla fine. Tuttavia, a volte ci sono storie dietro. L\u2019esempio pi\u00f9 recente \u00e8 stato durante la pandemia.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">C\u2019era silenzio a casa mia durante i due anni di pandemia. I miei parenti che lavoravano negli alberghi ora si erano dedicati alla vendita di cibo oppure erano disoccupati, e c&#039;era un senso di disperazione.\u00a0\u00a0<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Ho trovato il coraggio di offrire l&#039;idea di creare un <em>ogoh-ogoh <\/em>ai giovani della mia <em>Banjar,<\/em> anche se potrebbe non essere sfilato per strada.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Lo prenderemo in considerazione <em>mebanten <\/em>(un atto di servizio) nel <em>Banjar<\/em>.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Poi inaspettatamente \u00e8 cresciuto e i giovani sono diventati altri <em>Banjar<\/em>, e anche altre regioni come Negara e Gianyar hanno voluto partecipare. Abbiamo chiesto l\u2019attenzione del governatore e avevamo tutti la stessa visione: rilanciare l\u2019economia.\u00a0\u00a0<\/p>\r\n\r\n\r\n\r\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"511\" height=\"556\" class=\"wp-image-23161\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/03\/Screenshot-2023-03-05-at-21-44-59-15-w-o-bleed.pdf.png\" alt=\"\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/03\/Screenshot-2023-03-05-at-21-44-59-15-w-o-bleed.pdf.png 511w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/03\/Screenshot-2023-03-05-at-21-44-59-15-w-o-bleed.pdf-276x300.png 276w\" sizes=\"auto, (max-width: 511px) 100vw, 511px\" \/><\/figure>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Il tema di quell&#039;anno era <em>kipas <\/em>O <em>mantenere <\/em>in balinese (ventaglio) perch\u00e9 d\u00e0 conforto, e ne avevamo bisogno in quel momento.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">C\u2019erano tutte queste informazioni contrastanti [durante la pandemia] con il blocco, che hanno spaventato le persone. Avevamo bisogno di certezze, e avevamo bisogno di qualcosa che potesse darci conforto. Ecco perch\u00e9 ho scelto il <em>kipas <\/em>come tema.\u00a0\u00a0<\/p>\r\n\r\n\r\n\r\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"678\" class=\"wp-image-23159\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/03\/6ooV3cK0-1-1024x678.jpeg\" alt=\"Ogoh Ogoh-Ogoh di Tainsiat Denpasar foto di Cari Manik sculture premiate scultura Bali\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/03\/6ooV3cK0-1-1024x678.jpeg 1024w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/03\/6ooV3cK0-1-300x199.jpeg 300w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/03\/6ooV3cK0-1-768x509.jpeg 768w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/03\/6ooV3cK0-1-1536x1018.jpeg 1536w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/03\/6ooV3cK0-1-2048x1357.jpeg 2048w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/03\/6ooV3cK0-1-624x413.jpeg 624w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\r\n<figcaption class=\"wp-element-caption\"><em>Foto di Cari Manik <a href=\"https:\/\/www.instagram.com\/stysbtainsiat\/\" target=\"_blank\" rel=\"noreferrer noopener\" data-type=\"URL\" data-id=\"https:\/\/www.instagram.com\/stysbtainsiat\/\">@stysbtainsiat<\/a><\/em><\/figcaption>\r\n<\/figure>\r\n\r\n\r\n\r\n<h3 class=\"wp-block-heading\"><strong>Ce ne sono altri che si distinguono?<\/strong>\u00a0<\/h3>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">L\u2019anno prima, nel 2019, il tema era <em>pagamento <\/em>O <em>tedung <\/em>(ombrello). A quel tempo, l\u2019economia era buona e il lavoro cominciava ad arrivare, ma il clima era insolitamente caldo. Dovevo realizzare questo progetto motociclistico che sarebbe stato esposto in Giappone, e il caldo mi stava attaccando.\u00a0\u00a0<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Poi sono volato a Kyoto e quando sono arrivato l\u00ec, sei ore dopo da Bali, sono rimasto stupito da quanto fosse diverso il tempo. Pioveva e faceva freddo, e la gente indossava kimono e ombrelli anche se c&#039;era solo una pioggia leggera. Questo contrasto mi ha fatto pensare al tema dell\u2019ombrello come a un oggetto che fornisce riparo.\u00a0\u00a0<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Abbiamo fatto il solito <em>ogoh-ogoh<\/em> e la corona era un ombrello, con la speranza che potesse proteggere il mio villaggio perch\u00e9 avevo paura che il caldo estremo potesse causare qualche tipo di peste o siccit\u00e0. A quanto pare, l\u2019anno successivo accadde il covid.\u00a0\u00a0<\/p>\r\n\r\n\r\n\r\n<h3 class=\"wp-block-heading\"><strong>Hai mai avuto un commento sociale di fondo nel tuo <\/strong><strong><em>ogoh-ogoh<\/em><\/strong><strong>?<\/strong>\u00a0<\/h3>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">\u00c8 un dato di fatto, abbiamo progettato il <em>kipas<\/em>-a tema <em>ogoh-ogoh a <\/em>potersi sdraiare, e quella era una critica alla citt\u00e0 di <a href=\"https:\/\/instantkarmamag.com\/it\/all-about-bali\/\" data-type=\"post\" data-id=\"19906\">Denpasar<\/a>. La citt\u00e0 viene pubblicizzata come una destinazione turistica culturale, ma in realt\u00e0 \u00e8 un po&#039; disordinata con cavi elettrici bassi che rendono difficile qualcosa come <em>ogoh-ogoh<\/em> o altri oggetti cerimoniali da passare.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Tendiamo a mostrare solo il lato positivo di Bali nei libri o su Internet, ma temo che le persone rimarranno deluse quando lo vedranno nella vita reale.\u00a0\u00a0<\/p>\r\n\r\n\r\n\r\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"678\" height=\"1024\" class=\"wp-image-23139\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/03\/AETy0uQ4-1-678x1024.jpeg\" alt=\"Ogoh Ogoh-Ogoh di Tainsiat Denpasar foto di Cari Manik sculture premiate scultura Bali\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/03\/AETy0uQ4-1-678x1024.jpeg 678w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/03\/AETy0uQ4-1-199x300.jpeg 199w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/03\/AETy0uQ4-1-768x1159.jpeg 768w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/03\/AETy0uQ4-1-1018x1536.jpeg 1018w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/03\/AETy0uQ4-1-1357x2048.jpeg 1357w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/03\/AETy0uQ4-1-624x942.jpeg 624w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/03\/AETy0uQ4-1.jpeg 1696w\" sizes=\"auto, (max-width: 678px) 100vw, 678px\" \/>\r\n<figcaption class=\"wp-element-caption\"><em>Foto di Cari Manik <a href=\"https:\/\/www.instagram.com\/stysbtainsiat\/\" target=\"_blank\" rel=\"noreferrer noopener\" data-type=\"URL\" data-id=\"https:\/\/www.instagram.com\/stysbtainsiat\/\">@stysbtainsiat<\/a><\/em><\/figcaption>\r\n<\/figure>\r\n\r\n\r\n\r\n<h3 class=\"wp-block-heading\"><strong>Quanto tempo ci vuole per creare un ogoh-ogoh e puoi dirci i costi per realizzarli?<\/strong>\u00a0<\/h3>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Ci vuole circa un mese o un mese e mezzo al massimo con 10-20 persone a bordo. E il costo varia da 50 a 100 milioni di rupie e di solito riceviamo questa cifra dagli sponsor.\u00a0\u00a0<\/p>\r\n\r\n\r\n\r\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" class=\"wp-image-23162\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/03\/1234-1-1-685x1024.jpeg\" alt=\"\" title=\"\">\r\n<figcaption class=\"wp-element-caption\"><em>Foto di Cari Manik <a href=\"https:\/\/www.instagram.com\/stysbtainsiat\/\" target=\"_blank\" rel=\"noreferrer noopener\" data-type=\"URL\" data-id=\"https:\/\/www.instagram.com\/stysbtainsiat\/\">@stysbtainsiat<\/a><\/em><\/figcaption>\r\n<\/figure>\r\n\r\n\r\n\r\n<h3 class=\"wp-block-heading\"><strong>La creazione di <\/strong><strong><em>ogoh-ogoh<\/em><\/strong><strong> \u00e8 una confluenza di diversi tipi di forme d&#039;arte. Quali sono i tuoi pensieri a riguardo?<\/strong>\u00a0<\/h3>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Sono convinto che un artista ogoh-ogoh non dovrebbe essere relegato a quel giorno particolare. La mia visione \u00e8 che dovremmo essere in grado di affinare pi\u00f9 a fondo le nostre competenze e scoprire cosa pu\u00f2 essere sviluppato in modo che possa diventare una risorsa in futuro.\u00a0\u00a0<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Dopo una discussione con il team, ho fondato un&#039;altra impresa commerciale chiamata Wahana Karya Semesta (WKS), specializzata nella creazione di sculture. Con questa compagnia ho voluto riunire tutti i miei amici artisti in tutta Bali, dove un&#039;attivit\u00e0 di routine \u00e8 diventata parte della cultura.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Una volta che avranno imparato l\u2019arte di creare un personaggio o una filosofia, ho fiducia che i paesi tecnologicamente avanzati vorranno utilizzare le nostre risorse umane.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Spero che in futuro, a Bali, le risorse umane non si limitino solo a lavorare sulle navi da crociera o a fare il bucato, ma possano anche diventare, ad esempio, un progettista di robot in Giappone o uno scultore nel progetto di un palazzo da qualche parte .\u00a0\u00a0<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Potrebbe non esserci una scuola (per creare <em>ogoh-ogoh<\/em>), ma almeno pu\u00f2 esserci un futuro.\u00a0\u00a0<\/p>\r\n\r\n\r\n\r\n<h3 class=\"wp-block-heading\">Di cosa sei pi\u00f9 orgoglioso dopo aver completato un ogoh-ogoh?\u00a0<\/h3>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Vincere il primo posto non \u00e8 ci\u00f2 di cui sono pi\u00f9 orgoglioso, personalmente. Si tratta pi\u00f9 di creare un personaggio e una filosofia [dietro ad esso], specialmente quando sembra rilevante per i nostri tempi. Per me conquistare il cuore delle persone \u00e8 molto pi\u00f9 importante.\u00a0\u00a0<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Inoltre, quando posso infondere un design tradizionale.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">A volte vedi un moderno <em>ogoh-ogoh<\/em> sotto forma di un essere umano che indossa un bikini o di un personaggio dei cartoni animati con musica da club a tutto volume dall&#039;impianto audio. Non c&#039;\u00e8 niente di sbagliato in questo, ma non \u00e8 appropriato per scopi cerimoniali. Mi piace vedere rappresentata la cultura tradizionale.\u00a0<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\"><strong>Segui su Instagram <a href=\"https:\/\/www.instagram.com\/stysbtainsiat\/\" target=\"_blank\" rel=\"noreferrer noopener\" data-type=\"URL\" data-id=\"https:\/\/www.instagram.com\/stysbtainsiat\/\">@STYSBTAINSIAT<\/a><\/strong><\/p>","protected":false},"excerpt":{"rendered":"<p>Incontriamo Komang Gede Sentana Putra, alias Kedux, nel suo negozio di automobili chiamato Kedux Garage per parlare di ogoh-ogoh. Le sue creazioni hanno vinto numerosi premi, ma lui \u00e8 umile e fatica anche a ricordare i suoi giorni vincenti.<\/p>","protected":false},"author":46,"featured_media":23144,"comment_status":"open","ping_status":"closed","template":"","meta":{"footnotes":""},"categories":[271],"tags":[361,78],"section":[386],"interest":[380,378],"_magazine":[362],"class_list":["post-23138","article","type-article","status-publish","has-post-thumbnail","hentry","category-culture","tag-361","tag-bali","section-culture","interest-creative","interest-social","_magazine-362"],"_links":{"self":[{"href":"https:\/\/instantkarmamag.com\/it\/wp-json\/wp\/v2\/article\/23138","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/instantkarmamag.com\/it\/wp-json\/wp\/v2\/article"}],"about":[{"href":"https:\/\/instantkarmamag.com\/it\/wp-json\/wp\/v2\/types\/article"}],"author":[{"embeddable":true,"href":"https:\/\/instantkarmamag.com\/it\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/instantkarmamag.com\/it\/wp-json\/wp\/v2\/comments?post=23138"}],"version-history":[{"count":0,"href":"https:\/\/instantkarmamag.com\/it\/wp-json\/wp\/v2\/article\/23138\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/instantkarmamag.com\/it\/wp-json\/wp\/v2\/media\/23144"}],"wp:attachment":[{"href":"https:\/\/instantkarmamag.com\/it\/wp-json\/wp\/v2\/media?parent=23138"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/instantkarmamag.com\/it\/wp-json\/wp\/v2\/categories?post=23138"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/instantkarmamag.com\/it\/wp-json\/wp\/v2\/tags?post=23138"},{"taxonomy":"section","embeddable":true,"href":"https:\/\/instantkarmamag.com\/it\/wp-json\/wp\/v2\/section?post=23138"},{"taxonomy":"interest","embeddable":true,"href":"https:\/\/instantkarmamag.com\/it\/wp-json\/wp\/v2\/interest?post=23138"},{"taxonomy":"_magazine","embeddable":true,"href":"https:\/\/instantkarmamag.com\/it\/wp-json\/wp\/v2\/_magazine?post=23138"}],"curies":[{"name":"scrivere","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}<!-- This website is optimized by Airlift. Learn more: https://airlift.net. Template:. Learn more: https://airlift.net. Template: 6a3c9e6bc6af5a91495580da. Config Timestamp: 2026-06-25 03:19:51 UTC, Cached Timestamp: 2026-09-02 08:36:42 UTC -->