{"id":14901,"date":"2022-09-01T11:04:48","date_gmt":"2022-09-01T03:04:48","guid":{"rendered":"https:\/\/instantkarmamag.com\/?post_type=article&#038;p=14901"},"modified":"2024-07-03T16:20:11","modified_gmt":"2024-07-03T08:20:11","slug":"gente-dellisola-di-flores","status":"publish","type":"article","link":"https:\/\/instantkarmamag.com\/it\/articolo\/gente-dellisola-di-flores\/","title":{"rendered":"Gente dell&#039;isola di Flores \u2013 Incredibile diversit\u00e0"},"content":{"rendered":"<div id=\"bsf_rt_marker\"><\/div><p>L&#039;isola di Flores ospita una tale diversit\u00e0, ma perch\u00e9 le persone dell&#039;isola di Flores sono cos\u00ec diverse? Come convivono sulla stessa isola?<\/p>\n<h2>Ecco 6 punti salienti della vita e della cultura degli abitanti dell&#039;isola di Flores<\/h2>\n<p>Gli abitanti di Flores ci hanno raccontato le loro esperienze personali riguardo ciascuno di questi punti salienti.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-14902 size-large\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/09\/3E816ADC-3896-4C5D-84E0-0E6888A2C1C3-scaled-1.jpg\" alt=\"gente dell&#039;isola di flores nel villaggio\" width=\"683\" height=\"1024\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/09\/3E816ADC-3896-4C5D-84E0-0E6888A2C1C3-scaled-1.jpg 1707w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/09\/3E816ADC-3896-4C5D-84E0-0E6888A2C1C3-scaled-1-200x300.jpg 200w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/09\/3E816ADC-3896-4C5D-84E0-0E6888A2C1C3-scaled-1-768x1152.jpg 768w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/09\/3E816ADC-3896-4C5D-84E0-0E6888A2C1C3-scaled-1-683x1024.jpg 683w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/09\/3E816ADC-3896-4C5D-84E0-0E6888A2C1C3-scaled-1-1024x1536.jpg 1024w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/09\/3E816ADC-3896-4C5D-84E0-0E6888A2C1C3-scaled-1-1366x2048.jpg 1366w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/09\/3E816ADC-3896-4C5D-84E0-0E6888A2C1C3-scaled-1-624x936.jpg 624w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/><\/p>\n<h3>Gente di Flores<\/h3>\n<p>Flores \u00e8 composta da pi\u00f9 etnie. I principali gruppi etnici sono i Manggarai, i Ngada, gli Ende e i Lio, i Sikka e i Lamaholot. Ognuno di loro ha le proprie tradizioni e credenze. Alcuni di loro hanno ancora un sistema di caste.<\/p>\n<p>Esistono diversi tipi di matrimonio come il matrimonio tra cugini, il matrimonio levirato (un tipo di matrimonio in cui il fratello di un uomo deceduto \u00e8 obbligato a sposare la vedova di suo fratello).<\/p>\n<p>Matrimonio sororate (un tipo di matrimonio in cui un marito ha rapporti matrimoniali o sessuali con la sorella di sua moglie) di solito dopo la morte di sua moglie o se sua moglie si \u00e8 rivelata sterile.<\/p>\n<p style=\"text-align: center;\"><em><strong>La gente di Flores ha ancora a cuore la propria terra.\u00a0<\/strong><\/em><\/p>\n<p>Cinque anni fa, due abitanti del posto furono uccisi durante una disputa sul disboscamento. Le persone qui sembrano ancora preoccuparsi pi\u00f9 delle loro tradizioni che degli affari e del turismo.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-14905 size-large\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/09\/A4F4B80A-A6D1-4AD1-BCF6-6AB0F159E5FC-scaled-1.jpg\" alt=\"gente dell&#039;isola di Flores\" width=\"683\" height=\"1024\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/09\/A4F4B80A-A6D1-4AD1-BCF6-6AB0F159E5FC-scaled-1.jpg 1707w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/09\/A4F4B80A-A6D1-4AD1-BCF6-6AB0F159E5FC-scaled-1-200x300.jpg 200w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/09\/A4F4B80A-A6D1-4AD1-BCF6-6AB0F159E5FC-scaled-1-768x1152.jpg 768w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/09\/A4F4B80A-A6D1-4AD1-BCF6-6AB0F159E5FC-scaled-1-683x1024.jpg 683w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/09\/A4F4B80A-A6D1-4AD1-BCF6-6AB0F159E5FC-scaled-1-1024x1536.jpg 1024w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/09\/A4F4B80A-A6D1-4AD1-BCF6-6AB0F159E5FC-scaled-1-1366x2048.jpg 1366w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/09\/A4F4B80A-A6D1-4AD1-BCF6-6AB0F159E5FC-scaled-1-624x936.jpg 624w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/><\/p>\n<p>Ogni regione ha le proprie tradizioni e usanze, una lingua diversa e un diverso tipo di tessitura. Tutto \u00e8 diverso. Tuttavia, consideriamo queste differenze come la diversit\u00e0 che arricchisce il<\/p>\n<h2>Tutti i gruppi etnici qui convivono fianco a fianco in pace e rispetto.<\/h2>\n<p>&nbsp;<\/p>\n<h3>Lingue e dialetti degli abitanti dell&#039;isola di Flores<\/h3>\n<p>Un&#039;altra caratteristica insolita dell&#039;isola di Flores \u00e8 il gran numero di dialetti che possiede. A causa dei rilievi montuosi le comunit\u00e0 furono separate le une dalle altre e dovettero formare la propria lingua.<\/p>\n<p>Persone provenienti da diversi villaggi comunicano usando Bahasa Indonesia. Viene utilizzato anche per l&#039;istruzione e gli affari formali. Ma amici e familiari continuano a chiacchierare usando il dialetto della loro comunit\u00e0.<\/p>\n<p style=\"text-align: center;\"><strong><i>\u201c Poich\u00e9 parliamo lingue diverse, ci sono alcune parole che suonano uguali ma hanno significati assolutamente diversi e ci\u00f2 potrebbe portare a conflitti.<\/i><\/strong><\/p>\n<p style=\"text-align: center;\"><strong><i>Ad esempio, c&#039;\u00e8 una parola &quot;mena&quot;. Significa &quot;l\u00e0&quot; per le persone della comunit\u00e0 Nageko. Lo dicono quando danno indicazioni. Ma in Lamaholot questa parola esatta \u00e8 usata come parolaccia per le donne. Quindi puoi immaginare che tipo di malinteso potrebbe accadere.<\/i><\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-14904 size-large\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/09\/10-Clear-blue-sky-outside-a-church-in-Larantuka-East-Flores-scaled-1.jpg\" alt=\"flores isola cultura chiesa cielo blu\" width=\"683\" height=\"1024\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/09\/10-Clear-blue-sky-outside-a-church-in-Larantuka-East-Flores-scaled-1.jpg 1707w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/09\/10-Clear-blue-sky-outside-a-church-in-Larantuka-East-Flores-scaled-1-200x300.jpg 200w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/09\/10-Clear-blue-sky-outside-a-church-in-Larantuka-East-Flores-scaled-1-768x1152.jpg 768w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/09\/10-Clear-blue-sky-outside-a-church-in-Larantuka-East-Flores-scaled-1-683x1024.jpg 683w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/09\/10-Clear-blue-sky-outside-a-church-in-Larantuka-East-Flores-scaled-1-1024x1536.jpg 1024w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/09\/10-Clear-blue-sky-outside-a-church-in-Larantuka-East-Flores-scaled-1-1366x2048.jpg 1366w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/09\/10-Clear-blue-sky-outside-a-church-in-Larantuka-East-Flores-scaled-1-624x936.jpg 624w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/><\/p>\n<h3>Religioni degli abitanti dell&#039;isola di Flores<\/h3>\n<p>Quando si tratta di religione Flores \u00e8 abbastanza diversa dal resto dell&#039;Indonesia. 85% delle persone qui sono cattoliche. Nel XVI secolo coloni e missionari portoghesi iniziarono ad arrivare sull&#039;isola. Hanno fortemente influenzato la cultura e la religione di Flores. Ma sull\u2019isola ci sono ancora musulmani e animisti.<\/p>\n<p>Le persone a Flores sono molto tolleranti verso le diverse religioni.<\/p>\n<p style=\"text-align: center;\"><em><strong>\u201cCi aiutiamo a vicenda durante le festivit\u00e0 religiose. Ad esempio, se i cattolici celebrano il Natale o la Pasqua, i musulmani si offrono volontari per aiutare a preparare il cibo. Non solo, i musulmani aiutano anche a mantenere l\u2019ordine mentre i cattolici si riuniscono in chiesa per le celebrazioni. E viceversa quando i musulmani celebrano l\u2019Eid-al-Adha o l\u2019Eid al-Fitr\u201d.<\/strong><\/em><\/p>\n<p>&nbsp;<\/p>\n<h3>Tradizioni degli abitanti dell&#039;isola di Flores<\/h3>\n<p>Questo \u00e8 ci\u00f2 che varia di pi\u00f9 da trib\u00f9 a trib\u00f9 all&#039;interno della popolazione dell&#039;isola di Flores.<\/p>\n<p>Una delle tradizioni pi\u00f9 insolite proviene dalla trib\u00f9 dei Lio. Si chiama Pati ka ata mata ot Dhera, che significa nutrire gli antenati. Questa tradizione viene solitamente portata avanti durante cerimonie o festivit\u00e0 (Natale e Pasqua), e in occasione dei festeggiamenti di Capodanno. Il cibo viene servito su piccoli piatti con un bicchierino di moke (tradizionale bevanda alcolica) e acqua.<\/p>\n<p>Questo rituale inizia con il servire il cibo su una grande pietra a forma di tavolo o in una casa speciale dove le persone credono che vivessero i loro antenati. Quindi qualcuno che si crede sia un anziano dir\u00e0 una preghiera per invitare gli antenati a venire e godersi il cibo. Successivamente, il piatto verr\u00e0 lasciato in pace per trenta minuti o un&#039;ora.<\/p>\n<p style=\"text-align: center;\"><strong><i>\u201cDa bambino mia madre mi affidava spesso il compito di controllare la temperatura dei cibi. Quando fa molto freddo significa che gli antenati hanno finito di mangiare e i piatti possono essere portati via oppure si pu\u00f2 mangiare. Tradizioni come questa si possono trovare in quasi tutte le zone della terraferma di Flores. A Manggarai, dove vivo adesso, la gente lo chiama: teing hang\u201d.<\/i><\/strong><\/p>\n<p>&nbsp;<\/p>\n<h3>Caff\u00e8 sull&#039;isola di Flores<\/h3>\n<p>C&#039;\u00e8 un tipo speciale di caff\u00e8 Arabica coltivato a Bajawa a Flores. Ha un sapore diverso dal caff\u00e8 Arabica di altri luoghi perch\u00e9 l&#039;Arabica a Bajawa cresce su un&#039;alta collina a pi\u00f9 di 1200 metri sul livello del mare, quindi ha un basso livello di acidit\u00e0. Ogni villaggio di Bajawa ha la propria piantagione di caff\u00e8 perch\u00e9 qui il caff\u00e8 \u00e8 una delle principali fonti di reddito.<\/p>\n<p><strong><i>\u201cSono nato e cresciuto <a href=\"https:\/\/en.wikipedia.org\/wiki\/Ende,_East_Nusa_Tenggara\" target=\"_blank\" rel=\"noopener\">a Ende, Centro di Flores<\/a>. Noi di Ende abbiamo l&#039;abitudine di bere il caff\u00e8 con una grande quantit\u00e0 di zucchero in modo che la sensazione amara del caff\u00e8 non si avverta pi\u00f9. Quando mi sono trasferito a Ruteng, Manggarai, sono rimasto sorpreso: i Maggarai bevono caff\u00e8 amaro. <\/i><\/strong><\/p>\n<p><strong><i>Credono che bere il caff\u00e8 con lo zucchero sia come tradire il processo di coltivazione e lavorazione del caff\u00e8. Il caff\u00e8 Manggarai ha il suo gusto grazie alle condizioni uniche del terreno, cos\u00ec come alle altre piante che crescono insieme al caff\u00e8\u201d.<\/i><\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-14907 size-large\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/09\/Rice-fields-Moni-by-Fabian-gruber-037-kasuma-photo-travel-blog-flores-indonesia-2017.jpg\" alt=\"risaie della cultura dell&#039;isola di flores\" width=\"682\" height=\"1024\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/09\/Rice-fields-Moni-by-Fabian-gruber-037-kasuma-photo-travel-blog-flores-indonesia-2017.jpg 1333w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/09\/Rice-fields-Moni-by-Fabian-gruber-037-kasuma-photo-travel-blog-flores-indonesia-2017-200x300.jpg 200w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/09\/Rice-fields-Moni-by-Fabian-gruber-037-kasuma-photo-travel-blog-flores-indonesia-2017-768x1152.jpg 768w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/09\/Rice-fields-Moni-by-Fabian-gruber-037-kasuma-photo-travel-blog-flores-indonesia-2017-682x1024.jpg 682w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/09\/Rice-fields-Moni-by-Fabian-gruber-037-kasuma-photo-travel-blog-flores-indonesia-2017-1024x1536.jpg 1024w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/09\/Rice-fields-Moni-by-Fabian-gruber-037-kasuma-photo-travel-blog-flores-indonesia-2017-624x936.jpg 624w\" sizes=\"auto, (max-width: 682px) 100vw, 682px\" \/><\/p>\n<h3>Il cibo degli abitanti dell&#039;isola di Flores<\/h3>\n<p>Uno dei piatti tradizionali pi\u00f9 popolari dell&#039;isola di Flores \u00e8 il Lekun \u2013 torta di riso. Viene cucinato principalmente nella parte orientale dell&#039;isola, nella reggenza Sikka. I Sikka Kowe celebrano cerimonie per ogni fase della vita: quando le donne sono incinte, quando nascono i bambini e cos\u00ec via fino alla morte.<\/p>\n<p>Ad ogni cerimonia preparano questa torta speciale. La ricetta \u00e8 semplice: mescola farina di riso, farina di riso nero, farina di riso glutinoso, latte di cocco, zucchero, sale, zucchero di canna e banana, mettilo nel bamb\u00f9 e metti sopra una foglia di banana. Quindi cuocerlo sul fuoco finch\u00e9 la pelle del bamb\u00f9 non si carbonizza. Ecco come sai che \u00e8 pronto.<\/p>\n<p><i>\u201cChiamiamo Lekun una \u201ctorta della pace\u201d. Perch\u00e9 lo mangiamo anche durante le trattative sulla cerimonia nuziale e in attesa dei risultati delle trattative. Crediamo che porter\u00e0 la pace in una nuova famiglia e in una nuova vita\u201d.<\/i><\/p>\n<p>&nbsp;<\/p>\n<h4>Molte grazie a: Alfridus, Martinus e Maria Pankratia per aver condiviso le vostre storie sulla bellissima cultura di <a href=\"https:\/\/instantkarmamag.com\/it\/articolo\/isola-di-flores\/\" target=\"_blank\" rel=\"noopener\">Isola di Flores<\/a>.<\/h4>","protected":false},"excerpt":{"rendered":"<p>L&#039;isola di Flores vanta una tale diversit\u00e0, ma perch\u00e9 gli abitanti sono cos\u00ec diversi? Come convivono sulla stessa isola? Ecco 6 momenti salienti della vita e della cultura di Flores. Gli abitanti di Flores ci hanno raccontato le loro esperienze personali riguardo a ciascuno di questi momenti salienti. Gli abitanti di Flores [\u2026]<\/p>","protected":false},"author":135,"featured_media":14903,"comment_status":"open","ping_status":"closed","template":"","meta":{"footnotes":""},"categories":[271,270],"tags":[355,294],"section":[386,385],"interest":[378],"_magazine":[356],"class_list":["post-14901","article","type-article","status-publish","has-post-thumbnail","hentry","category-culture","category-explore","tag-355","tag-flores","section-culture","section-explore","interest-social","_magazine-356"],"_links":{"self":[{"href":"https:\/\/instantkarmamag.com\/it\/wp-json\/wp\/v2\/article\/14901","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/instantkarmamag.com\/it\/wp-json\/wp\/v2\/article"}],"about":[{"href":"https:\/\/instantkarmamag.com\/it\/wp-json\/wp\/v2\/types\/article"}],"author":[{"embeddable":true,"href":"https:\/\/instantkarmamag.com\/it\/wp-json\/wp\/v2\/users\/135"}],"replies":[{"embeddable":true,"href":"https:\/\/instantkarmamag.com\/it\/wp-json\/wp\/v2\/comments?post=14901"}],"version-history":[{"count":0,"href":"https:\/\/instantkarmamag.com\/it\/wp-json\/wp\/v2\/article\/14901\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/instantkarmamag.com\/it\/wp-json\/wp\/v2\/media\/14903"}],"wp:attachment":[{"href":"https:\/\/instantkarmamag.com\/it\/wp-json\/wp\/v2\/media?parent=14901"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/instantkarmamag.com\/it\/wp-json\/wp\/v2\/categories?post=14901"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/instantkarmamag.com\/it\/wp-json\/wp\/v2\/tags?post=14901"},{"taxonomy":"section","embeddable":true,"href":"https:\/\/instantkarmamag.com\/it\/wp-json\/wp\/v2\/section?post=14901"},{"taxonomy":"interest","embeddable":true,"href":"https:\/\/instantkarmamag.com\/it\/wp-json\/wp\/v2\/interest?post=14901"},{"taxonomy":"_magazine","embeddable":true,"href":"https:\/\/instantkarmamag.com\/it\/wp-json\/wp\/v2\/_magazine?post=14901"}],"curies":[{"name":"scrivere","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}<!-- This website is optimized by Airlift. Learn more: https://airlift.net. Template:. Learn more: https://airlift.net. Template: 6a3c9e6bc6af5a91495580da. Config Timestamp: 2026-06-25 03:19:51 UTC, Cached Timestamp: 2026-09-02 09:22:51 UTC -->