{"id":12042,"date":"2022-05-01T01:34:48","date_gmt":"2022-04-30T17:34:48","guid":{"rendered":"https:\/\/instantkarmamag.com\/?post_type=article&#038;p=12042"},"modified":"2024-02-15T16:14:09","modified_gmt":"2024-02-15T08:14:09","slug":"fate-larte-non-la-guerra","status":"publish","type":"article","link":"https:\/\/instantkarmamag.com\/it\/articolo\/fate-larte-non-la-guerra\/","title":{"rendered":"Fate l&#039;arte non la guerra"},"content":{"rendered":"<div id=\"bsf_rt_marker\"><\/div><h3><strong>Fate l&#039;arte non la guerra<\/strong><\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-12046 size-full\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/05\/Screenshot_ik10_answerissimple4-e1651367588516.png\" alt=\"la risposta \u00e8 semplice: fai arte, non guerra, impatto karmico istantaneo, arte, liina klauss, rivista consapevole di viaggio, bali, indonesia\" width=\"924\" height=\"494\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/05\/Screenshot_ik10_answerissimple4-e1651367588516.png 924w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/05\/Screenshot_ik10_answerissimple4-e1651367588516-300x160.png 300w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/05\/Screenshot_ik10_answerissimple4-e1651367588516-768x411.png 768w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/05\/Screenshot_ik10_answerissimple4-e1651367588516-600x321.png 600w\" sizes=\"auto, (max-width: 924px) 100vw, 924px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Liina Klauss ha invitato Bali a immaginare la pace con una nuova installazione d&#039;arte pubblica chiamata \u201cMake Art Not War\u201d. Aveva bisogno di 20.000 infradito, che sono state portate sul luogo dell&#039;installazione vicino a Pantai Kendungu a Tabanan, su diversi piccoli camioncini. L\u00e0, <a href=\"https:\/\/www.instagram.com\/liinaklauss\/\" target=\"_blank\" rel=\"noopener\"><strong>Liina<\/strong><\/a> ha collaborato con oltre 100 volontari di diversa estrazione, adulti e bambini e il locale Banjar per creare il progetto artistico alto 5 metri e lungo 50 metri: \u201cMake Art, Not War\u201d.<\/p>\n<p>Liina Klauss, con la sua innovativa installazione di arte pubblica intitolata \u201cMake Art Not War\u201d, ha esteso un invito alla comunit\u00e0 di Bali a immaginare un mondo di pace e creativit\u00e0. Questo ambizioso progetto ha richiesto l&#039;incredibile cifra di 20.000 infradito, che sono state trasportate al sito di installazione vicino a Pantai Kendungu a Tabanan utilizzando diversi piccoli camioncini. Qui, Liina ha orchestrato uno sforzo di collaborazione che ha coinvolto oltre 100 volontari, di diverse fasce di et\u00e0 e background, in collaborazione con il locale Banjar. Insieme, hanno realizzato un\u2019impressionante installazione artistica alta 5 metri e lunga 50 metri, che porta il nome \u201cMake Art, Not War\u201d. Questo sforzo non solo ha riproposto migliaia di infradito, ma ha anche presentato una soluzione ecologica ed economica per l\u2019abbellimento delle strade.<\/p>\n<p>Al di l\u00e0 del suo significato artistico, \u201cMake Art, Not War\u201d porta un profondo messaggio sociale. Serve come testimonianza delle scoperte di SungaiWatch, evidenziando che le politiche governative radicate nella sostenibilit\u00e0 e nel coinvolgimento della comunit\u00e0 si rivelano il mezzo pi\u00f9 efficiente per rivitalizzare rapidamente ed economicamente gli spazi urbani. Allo stesso tempo, tali iniziative promuovono un ambiente pi\u00f9 sano e vivace per la comunit\u00e0 locale.<\/p>\n<h3><a href=\"https:\/\/instantkarmamag.com\/it\/about\/\" target=\"_blank\" rel=\"noopener\">Noi<\/a> ha incontrato Liina, l&#039;ha conosciuta e ha avuto un discorso illuminante sulla sua recente installazione intitolata Make Art Not War<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-12044 size-full\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/05\/Screenshot_ik10_answerissimple2.png\" alt=\"la risposta \u00e8 semplice, impatto karma istantaneo, arte, liina klauss, rivista consapevole di viaggio, bali, indonesia\" width=\"795\" height=\"422\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/05\/Screenshot_ik10_answerissimple2.png 795w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/05\/Screenshot_ik10_answerissimple2-300x159.png 300w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/05\/Screenshot_ik10_answerissimple2-768x408.png 768w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/05\/Screenshot_ik10_answerissimple2-624x331.png 624w\" sizes=\"auto, (max-width: 795px) 100vw, 795px\" \/><\/p>\n<p><i>\u00a0<\/i><\/p>\n<h5><strong><i>Con la guerra in Ucraina, ora i cuori di molte persone sanguinano. Anche se siamo cos\u00ec lontani qui a Bali, le persone vogliono ancora manifestare le loro preoccupazioni. \u201c<\/i><i>Non possiamo davvero fare nulla\u201d, \u00e8 la risposta della maggior parte delle persone. Oppure possiamo? L&#039;arte, almeno per me come artista, \u00e8 un ottimo strumento, non solo per esprimere ma anche per elaborare.<\/i><\/strong><\/h5>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-31314 size-large\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/05\/make-art-not-war-1024x683.jpg\" alt=\"fate l&#039;arte non la guerra\" width=\"1024\" height=\"683\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/05\/make-art-not-war-1024x683.jpg 1024w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/05\/make-art-not-war-300x200.jpg 300w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/05\/make-art-not-war-768x512.jpg 768w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/05\/make-art-not-war.jpg 1500w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<h5><strong><i>Volevo fare un&#039;installazione davvero grande per la quale avevo bisogno di molti scarti. <a href=\"https:\/\/www.instagram.com\/sungaiwatch\/\" target=\"_blank\" rel=\"noopener\">SungaiWatch<\/a> raccolto migliaia di infradito durante la scorsa stagione delle piogge e quando ne ho parlato <\/i><i>Gary, era molto entusiasta. Abbiamo unito le forze e<\/i><i> T<\/i><i>Grazie alla nostra vasta e diversificata comunit\u00e0 di sensibilizzazione, hanno partecipato oltre 100 persone. L&#039;atmosfera era fantastica e sudare, sporcarsi e scottarsi faceva parte di tutto questo.<\/i><\/strong><\/h5>\n<p dir=\"auto\" data-pm-slice=\"1 1 []\">Questi volontari hanno raccolto migliaia di infradito per ideare un trattamento di strada ecologico e a basso costo.<\/p>\n<p dir=\"auto\">E ha un messaggio sociale. SungaiWatch ha dimostrato che la politica del governo non \u00e8 solo sostenibile e guidata dalle persone, ma \u00e8 anche il modo pi\u00f9 efficiente per ripulire le strade in brevi periodi di tempo ed economicamente vantaggioso, creando allo stesso tempo un ambiente migliore per la comunit\u00e0.<\/p>\n<p>&nbsp;<\/p>\n<h3>\u00c8 l&#039;atto e la sensazione di fare e cambiare fisicamente qualcosa.<\/h3>\n<h5><strong><i>C&#039;\u00e8 questo entusiasmo e un&#039;enorme energia, tutto con l&#039;unico scopo di inviare un messaggio semplice e positivo al mondo. Emana ed \u00e8 semplicemente indescrivibile. Devi sperimentarlo per capire cosa intendo.<\/i><\/strong><\/h5>\n<h5><strong><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-12045 size-full\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/05\/Screenshot_ik10_answerissimple3.png\" alt=\"la risposta \u00e8 semplice, impatto karma istantaneo, arte, liina klauss, rivista consapevole di viaggio, bali, indonesia\" width=\"739\" height=\"146\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/05\/Screenshot_ik10_answerissimple3.png 739w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/05\/Screenshot_ik10_answerissimple3-300x59.png 300w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/05\/Screenshot_ik10_answerissimple3-624x123.png 624w\" sizes=\"auto, (max-width: 739px) 100vw, 739px\" \/><\/strong><\/h5>\n<h5><strong><i>Anche se non puoi vederlo, sento che \u00e8 molto potente. Funziona in entrambe le direzioni: se metti energia positiva, l\u2019energia positiva arriver\u00e0.\u201d<\/i><\/strong><\/h5>\n<p>L\u2019arte pu\u00f2 connetterti ai tuoi sensi, al tuo corpo e alla tua mente. Pu\u00f2 creare il mondo <i>Tatto<\/i>.<\/p>\n<p>Grazie, Liina per il discorso e i tuoi movimenti attivi per rendere il mondo un luogo colorato e ricordarci di fare arte e non guerra, perch\u00e9 l&#039;arte \u00e8 un&#039;espressione e l&#039;amore \u00e8 la risposta, e sappiamo che \u00e8 vero!<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-31316 size-large\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/05\/make-art-not-war-2-1024x576.jpg\" alt=\"la risposta \u00e8 semplice: fai arte, non guerra, impatto karmico istantaneo, arte, liina klauss, rivista consapevole di viaggio, bali, indonesia\" width=\"1024\" height=\"576\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/05\/make-art-not-war-2-1024x576.jpg 1024w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/05\/make-art-not-war-2-300x169.jpg 300w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/05\/make-art-not-war-2-768x432.jpg 768w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/05\/make-art-not-war-2.jpg 1500w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>&nbsp;<\/p>\n<h3>Brevi fatti su Liina:<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-12052 size-medium\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/05\/LIINA_2021_2896-scaled-e1651368778461-203x300.jpg\" alt=\"la risposta \u00e8 semplice: fai arte, non guerra, impatto karmico istantaneo, arte, liina klauss, rivista consapevole di viaggio, bali, indonesia\" width=\"203\" height=\"300\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/05\/LIINA_2021_2896-scaled-e1651368778461-203x300.jpg 203w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/05\/LIINA_2021_2896-scaled-e1651368778461-694x1024.jpg 694w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/05\/LIINA_2021_2896-scaled-e1651368778461-600x885.jpg 600w\" sizes=\"auto, (max-width: 203px) 100vw, 203px\" \/>Ex stilista, spirito libero e artista berlinese.<\/p>\n<p>10 anni come stilista a Berlino, Tokyo, Hong Kong \u2013 ora a Bali come artista, attivista e guerriero dell&#039;oceano.<\/p>\n<p>Dal 2011 Liina realizza opere d&#039;arte colorate con i \u201crifiuti di plastica dell&#039;oceano\u201d.<\/p>\n<p>Quando Liina si concentra sul colore piuttosto che sui rifiuti di plastica, il valore negativo \u201cspazzatura\u201d viene eliminato.<\/p>\n<p>&nbsp;<\/p>\n<p><i>\u201cNon giudichi pi\u00f9 ci\u00f2 che trovi; lavori esclusivamente con il colore. Di conseguenza diventi notevolmente pi\u00f9 aperto e creativo.<\/i><\/p>\n<p><strong>Segui Liina Klauss su Instagram <a href=\"https:\/\/www.instagram.com\/liinaklauss\/\" target=\"_blank\" rel=\"noopener\">@liinaklauss<\/a><\/strong><\/p>\n<p><strong>Visita la sua mostra pi\u00f9 recente a Canggu <a href=\"https:\/\/www.instagram.com\/soundvisionlibrary\/\" target=\"_blank\" rel=\"noopener\">@soundvisionlibrary<\/a><\/strong><\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>L\u2019arte ha un messaggio sociale. Questi volontari hanno raccolto migliaia di infradito per questa installazione di Liina Klauss.<\/p>","protected":false},"author":1,"featured_media":31314,"comment_status":"open","ping_status":"closed","template":"","meta":{"footnotes":""},"categories":[272,273],"tags":[351],"section":[390,388],"interest":[380,372,378],"_magazine":[352],"class_list":["post-12042","article","type-article","status-publish","has-post-thumbnail","hentry","category-artsy","category-people","tag-351","section-artsy","section-people","interest-creative","interest-eco","interest-social","_magazine-352"],"_links":{"self":[{"href":"https:\/\/instantkarmamag.com\/it\/wp-json\/wp\/v2\/article\/12042","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/instantkarmamag.com\/it\/wp-json\/wp\/v2\/article"}],"about":[{"href":"https:\/\/instantkarmamag.com\/it\/wp-json\/wp\/v2\/types\/article"}],"author":[{"embeddable":true,"href":"https:\/\/instantkarmamag.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/instantkarmamag.com\/it\/wp-json\/wp\/v2\/comments?post=12042"}],"version-history":[{"count":0,"href":"https:\/\/instantkarmamag.com\/it\/wp-json\/wp\/v2\/article\/12042\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/instantkarmamag.com\/it\/wp-json\/wp\/v2\/media\/31314"}],"wp:attachment":[{"href":"https:\/\/instantkarmamag.com\/it\/wp-json\/wp\/v2\/media?parent=12042"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/instantkarmamag.com\/it\/wp-json\/wp\/v2\/categories?post=12042"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/instantkarmamag.com\/it\/wp-json\/wp\/v2\/tags?post=12042"},{"taxonomy":"section","embeddable":true,"href":"https:\/\/instantkarmamag.com\/it\/wp-json\/wp\/v2\/section?post=12042"},{"taxonomy":"interest","embeddable":true,"href":"https:\/\/instantkarmamag.com\/it\/wp-json\/wp\/v2\/interest?post=12042"},{"taxonomy":"_magazine","embeddable":true,"href":"https:\/\/instantkarmamag.com\/it\/wp-json\/wp\/v2\/_magazine?post=12042"}],"curies":[{"name":"scrivere","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}<!-- This website is optimized by Airlift. Learn more: https://airlift.net. Template:. Learn more: https://airlift.net. Template: 6a3c9e6bc6af5a91495580da. Config Timestamp: 2026-06-25 03:19:51 UTC, Cached Timestamp: 2026-09-02 04:29:01 UTC -->