{"id":9693,"date":"2021-08-31T00:00:00","date_gmt":"2021-08-30T16:00:00","guid":{"rendered":"https:\/\/instantkarmamag.com\/article\/create-your-own-bubble-of-happiness\/"},"modified":"2024-06-12T15:42:05","modified_gmt":"2024-06-12T07:42:05","slug":"comment-creer-du-bonheur","status":"publish","type":"article","link":"https:\/\/instantkarmamag.com\/fr\/article\/comment-creer-du-bonheur\/","title":{"rendered":"Comment cr\u00e9er du bonheur"},"content":{"rendered":"<div id=\"bsf_rt_marker\"><\/div><h3><strong>Et si vous d\u00e9cidiez de cr\u00e9er votre propre Bulle de bonheur ?<\/strong><\/h3>\n<p>Quand tout va mal, ou de fa\u00e7on chaotique dehors, \u00e7a fait du bien de rentrer \u00e0 la maison.<\/p>\n<p>Et si vous d\u00e9cidiez de faire de votre maison un lieu de bonheur o\u00f9 vous vous sentez bien ?<\/p>\n<p>Votre abri pour restaurer et entretenir les fondations pour accepter le changement et m\u00eame s&#039;agrandir.<\/p>\n<p>Par maison, j&#039;entends votre Univers personnel, votre maison mat\u00e9rielle bien s\u00fbr, mais principalement votre esprit, votre \u00c2me et votre champ \u00e9nerg\u00e9tique.<\/p>\n<p>Vous savez que tout est question d\u2019\u00e9nergie sur cette plan\u00e8te.<\/p>\n<p>Nos pens\u00e9es, sentiments et \u00e9motions g\u00e9n\u00e8rent des \u00e9nergies qui cr\u00e9ent notre prochaine r\u00e9alit\u00e9 car notre monde fonctionne par r\u00e9p\u00e9tition (Physique Quantique).<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-6635 size-full aligncenter\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2021\/09\/Screenshot-2021-09-01-at-04-34-21-Instant-Karma-FLIPBOOK-pdf.png\" alt=\"karma instantan\u00e9 Cr\u00e9er du bonheur\" width=\"715\" height=\"290\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2021\/09\/Screenshot-2021-09-01-at-04-34-21-Instant-Karma-FLIPBOOK-pdf.png 715w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2021\/09\/Screenshot-2021-09-01-at-04-34-21-Instant-Karma-FLIPBOOK-pdf-300x122.png 300w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2021\/09\/Screenshot-2021-09-01-at-04-34-21-Instant-Karma-FLIPBOOK-pdf-624x253.png 624w\" sizes=\"auto, (max-width: 715px) 100vw, 715px\" \/><\/p>\n<p>L\u2019autor\u00e9gulation est essentielle pour maintenir une bonne vibration, vivre sur un flux de haute fr\u00e9quence et cr\u00e9er du bonheur.<\/p>\n<h3><strong>Trucs et astuces pour cr\u00e9er du bonheur<\/strong><\/h3>\n<p><strong>1. Assumer la responsabilit\u00e9 de votre \u00e9nergie<\/strong><\/p>\n<p>L\u00e2cher le contr\u00f4le sur les \u00e9v\u00e9nements ext\u00e9rieurs, mais d\u00e9cider d\u00e9finitivement de garder la main ferme sur votre fa\u00e7on de r\u00e9agir en choisissant de rester dans un endroit o\u00f9 l&#039;on se sent bien, quoi qu&#039;il arrive.<\/p>\n<p><strong><br \/>\n2-Int\u00e9grer que le bonheur est un choix<\/strong><\/p>\n<p>Concentrez-vous sur le c\u00f4t\u00e9 brillant et positif de tout au lieu de vous plaindre et d\u2019entretenir la n\u00e9gativit\u00e9.<\/p>\n<p>C&#039;est comme un muscle ; nous pouvons tous pratiquer avec volont\u00e9 et nous entra\u00eener.<\/p>\n<p><strong><br \/>\n3-Mettre en place une routine pour construire et entretenir une bonne \u00e9nergie<\/strong><\/p>\n<p>-M\u00e9ditation au r\u00e9veil lorsque votre cerveau est encore naturellement dans un \u00e9tat th\u00eata, cette onde acc\u00e9dant \u00e0 votre subconscient et vous permettant de t\u00e9l\u00e9charger le message que vous souhaitez faire passer sans effort.<\/p>\n<p>-Exercice physique pour produire la bonne chimie pour vous sentir bien et pour garder un corps sain avec un syst\u00e8me immunitaire solide, la pratique en plein air est la meilleure pour la connexion avec la nature.<\/p>\n<p>-Aliments nourrissants naturels, le bio est le meilleur.<\/p>\n<p>Oubliez tous les aliments transform\u00e9s, vous prendrez soin de l\u2019environnement en r\u00e9duisant les emballages, et votre corps vous en sera reconnaissant.<\/p>\n<p>La nourriture a des vibrations et des fr\u00e9quences\u00a0; vous devenez ce que vous mangez, alors mieux vaut \u00eatre tr\u00e8s attentif \u00e0 ce que vous ing\u00e9rez.<\/p>\n<p><strong><br \/>\n4-G\u00e9rer votre relation avec l&#039;environnement num\u00e9rique<\/strong><\/p>\n<p>-Coupez votre wifi la nuit, \u00e9teignez votre t\u00e9l\u00e9phone<\/p>\n<p>-d\u00e9sabonnez-vous des notifications et d\u00e9cidez quand vous souhaitez ouvrir vos applications<\/p>\n<p>-Nous savons que les r\u00e9seaux sociaux cr\u00e9ent une d\u00e9pendance, observez votre comportement et choisissez de ne pas \u00eatre sous le contr\u00f4le de votre t\u00e9l\u00e9phone<\/p>\n<p><strong><br \/>\n5-Choisissez votre environnement<\/strong><\/p>\n<p>-Nous devenons comme les cinq personnes que nous voyons le plus, soyez s\u00e9lectifs concernant les personnes qui vous entourent.<\/p>\n<p>Si vous sentez que votre \u00e9quilibre est fragile, n&#039;h\u00e9sitez pas \u00e0 reporter, limiter ou supprimer le temps que vous accordez \u00e0 des personnes dont vous savez qu&#039;elles vous entra\u00eeneront vers le bas ou susciteront la peur en vous.<\/p>\n<p>Ce n\u2019est pas \u00e9go\u00efste ; c&#039;est prendre soin de votre propre sant\u00e9 et de votre sant\u00e9 mentale.<\/p>\n<p>Vous devez \u00eatre vital pour aider les autres, et si ce n\u2019est pas le cas, il est temps de commencer \u00e0 vous renseigner sur<\/p>\n<p>l&#039;amour-propre et avoir soi-m\u00eame en premier.<\/p>\n<p>-G\u00e9rez votre relation avec les m\u00e9dias et o\u00f9 vous obtenez vos informations. Analysez toujours avec discernement et objectivit\u00e9 afin de ne pas vous laisser manipuler par la peur.<\/p>\n<p><strong><br \/>\n6-Faites de votre maison votre sanctuaire<\/strong><\/p>\n<p>Cr\u00e9ez ce cocon physique o\u00f9 vous aimez vous d\u00e9tendre et vous ressourcer.<\/p>\n<p>-Feng Shui le lieu en supprimant le d\u00e9sordre, en faisant circuler l&#039;\u00e9nergie partout<\/p>\n<p>-Investir dans des plantes d&#039;int\u00e9rieur comme l&#039;aloe vera ou des plantes serpent qui absorbent les \u00e9nergies n\u00e9gatives<\/p>\n<p>-Cr\u00e9ez votre lieu sacr\u00e9 avec des cristaux, des bougies, de l&#039;encens, des plumes, des cartes oracle et toutes divinit\u00e9s en r\u00e9sonance avec votre spiritualit\u00e9<\/p>\n<p>-\u00c9coutez des fr\u00e9quences de solf\u00e8ge, des mantras ou toute musique \u00e0 hautes fr\u00e9quences<\/p>\n<p>-\u00c9vitez les \u00e9quipements num\u00e9riques, la t\u00e9l\u00e9vision, les miroirs, les livres dans votre chambre (bases du Feng Shui)<\/p>\n<p><strong><br \/>\n7-VIVRE LE MAINTENANT<\/strong><\/p>\n<p>Le conseil le plus important, revenez au pr\u00e9sent, au seul moment qui existe.<\/p>\n<p><strong><br \/>\n8-Faites confiance \u00e0 la vie et \u00e0 l&#039;Univers\u00a0<\/strong><\/p>\n<p>Comme si tout \u00e9tait toujours dispos\u00e9 dans un endroit parfait.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-6634 size-medium\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2021\/09\/Screenshot-2021-09-01-at-04-34-53-Instant-Karma-FLIPBOOK-pdf-e1630442249326.png\" alt=\"cr\u00e9er du bonheur karma instantan\u00e9 \" width=\"300\" height=\"111\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2021\/09\/Screenshot-2021-09-01-at-04-34-53-Instant-Karma-FLIPBOOK-pdf-e1630442249326.png 383w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2021\/09\/Screenshot-2021-09-01-at-04-34-53-Instant-Karma-FLIPBOOK-pdf-e1630442249326-300x111.png 300w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>\u2013 par Freeyourmindbali<\/p>\n<p><a href=\"https:\/\/freeyourmindbali.com\" target=\"_blank\" rel=\"noopener\"><strong>https:\/\/freeyourmindbali.com<\/strong><\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Et si vous d\u00e9cidiez de cr\u00e9er votre propre Bulle de bonheur ? Quand tout va mal, ou de fa\u00e7on chaotique dehors, \u00e7a fait du bien de rentrer \u00e0 la maison.<\/p>","protected":false},"author":122,"featured_media":29460,"comment_status":"open","ping_status":"closed","template":"","meta":{"footnotes":""},"categories":[274],"tags":[344],"section":[317],"interest":[381,393,398,383],"_magazine":[345],"class_list":["post-9693","article","type-article","status-publish","has-post-thumbnail","hentry","category-mindful","tag-344","section-mindful","interest-empowerment","interest-philosphy","interest-self-help","interest-wisdom","_magazine-345"],"_links":{"self":[{"href":"https:\/\/instantkarmamag.com\/fr\/wp-json\/wp\/v2\/article\/9693","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/instantkarmamag.com\/fr\/wp-json\/wp\/v2\/article"}],"about":[{"href":"https:\/\/instantkarmamag.com\/fr\/wp-json\/wp\/v2\/types\/article"}],"author":[{"embeddable":true,"href":"https:\/\/instantkarmamag.com\/fr\/wp-json\/wp\/v2\/users\/122"}],"replies":[{"embeddable":true,"href":"https:\/\/instantkarmamag.com\/fr\/wp-json\/wp\/v2\/comments?post=9693"}],"version-history":[{"count":0,"href":"https:\/\/instantkarmamag.com\/fr\/wp-json\/wp\/v2\/article\/9693\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/instantkarmamag.com\/fr\/wp-json\/wp\/v2\/media\/29460"}],"wp:attachment":[{"href":"https:\/\/instantkarmamag.com\/fr\/wp-json\/wp\/v2\/media?parent=9693"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/instantkarmamag.com\/fr\/wp-json\/wp\/v2\/categories?post=9693"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/instantkarmamag.com\/fr\/wp-json\/wp\/v2\/tags?post=9693"},{"taxonomy":"section","embeddable":true,"href":"https:\/\/instantkarmamag.com\/fr\/wp-json\/wp\/v2\/section?post=9693"},{"taxonomy":"interest","embeddable":true,"href":"https:\/\/instantkarmamag.com\/fr\/wp-json\/wp\/v2\/interest?post=9693"},{"taxonomy":"_magazine","embeddable":true,"href":"https:\/\/instantkarmamag.com\/fr\/wp-json\/wp\/v2\/_magazine?post=9693"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}<!-- This website is optimized by Airlift. Learn more: https://airlift.net. Template:. Learn more: https://airlift.net. Template: 6a3c9e6bc6af5a91495580da. Config Timestamp: 2026-06-25 03:19:51 UTC, Cached Timestamp: 2026-09-02 10:06:26 UTC -->