{"id":9683,"date":"2021-07-01T00:00:00","date_gmt":"2021-06-30T16:00:00","guid":{"rendered":"https:\/\/instantkarmamag.com\/article\/serayu-pot-terracotta-ubud\/"},"modified":"2024-07-03T16:46:29","modified_gmt":"2024-07-03T08:46:29","slug":"pot-serayu-en-terre-cuite-ubud-2","status":"publish","type":"article","link":"https:\/\/instantkarmamag.com\/fr\/article\/pot-serayu-en-terre-cuite-ubud-2\/","title":{"rendered":"Pot Serayu et Terre Cuite Ubud"},"content":{"rendered":"<div id=\"bsf_rt_marker\"><\/div><p>Si vous recherchez une journ\u00e9e cr\u00e9ative et amusante \u00e0 Ubud, Serayu Pot est la destination id\u00e9ale. <span class=\"markedContent\"><span dir=\"ltr\">nous recommandons fortement d&#039;y aller, m\u00eame si ce n&#039;est que pour prendre un caf\u00e9. <\/span><\/span>Cette charmante boutique en terre cuite pr\u00e9sente non seulement de magnifiques pots peints \u00e0 la main, mais propose \u00e9galement des cours de poterie o\u00f9 vous pourrez lib\u00e9rer votre c\u00f4t\u00e9 artistique. Que vous soyez un artiste chevronn\u00e9 ou simplement \u00e0 la recherche d&#039;un nouveau passe-temps, Serayu Pot vous promet une exp\u00e9rience m\u00e9morable.<\/p>\n<p style=\"text-align: left;\"><span class=\"markedContent\">\u00a0<\/span><\/p>\n<h2>Le voyage au pot Serayu<\/h2>\n<p>Mon aventure a commenc\u00e9 de mani\u00e8re inattendue lorsque je me suis rendu au bureau de mon agent des visas pour renouveler mon visa. <span class=\"markedContent\"><span dir=\"ltr\">J&#039;ai vu un fascinant <\/span><span dir=\"ltr\">photo d&#039;un homme avec une barbe distinctive accroch\u00e9e \u00e0 <\/span><span dir=\"ltr\">le bureau de mon agent des visas, un passionn\u00e9 <\/span><span dir=\"ltr\">photographe.\u00a0<\/span><\/span>J&#039;ai interrog\u00e9 mon agent sur la personne sur la photo.<\/p>\n<p>Il a expliqu\u00e9 qu&#039;il s&#039;agissait de \u00ab\u00a0I Wayan Cameng\u00a0\u00bb, un c\u00e9l\u00e8bre <a href=\"https:\/\/instantkarmamag.com\/fr\/section\/artistique\/\">artiste<\/a> d&#039;Ubud. Intrigu\u00e9 par l&#039;histoire derri\u00e8re l&#039;image, j&#039;ai d\u00e9cid\u00e9 de rencontrer cet individu fascinant. Une adresse en main, je pars pour Peliatan Ubud. <span class=\"markedContent\"><span dir=\"ltr\">J&#039;ai imm\u00e9diatement dit : \u00ab Cette photo est g\u00e9niale ; qui est cette personne?&quot; <\/span><\/span><\/p>\n<p><span class=\"markedContent\"><span dir=\"ltr\">Il a dit : \u00ab Oh, c&#039;est \u00ab I Wayan Cameng \u00bb, un artiste d&#039;Ubud. <\/span><span dir=\"ltr\">Mon agent m&#039;a donn\u00e9 son adresse parce que je voulais vraiment rencontrer \u00e7a <\/span><span dir=\"ltr\">homme derri\u00e8re ce visage impressionnant. J&#039;ai eu l&#039;adresse, et bient\u00f4t j&#039;\u00e9tais <\/span><span dir=\"ltr\">route vers Peliatan Ubud.<\/span><\/span><\/p>\n<h2>Boutique en terre cuite color\u00e9e<\/h2>\n<h3 style=\"text-align: left;\"><span class=\"markedContent\"><span dir=\"ltr\">La boutique color\u00e9e en terre cuite avec des d\u00e9corations faites \u00e0 la main<\/span><span dir=\"ltr\">des pots suspendus peints, il \u00e9tait difficile de les manquer. <\/span><\/span><span class=\"markedContent\"><span dir=\"ltr\">Il semble <\/span><span dir=\"ltr\">vraiment cool.<\/span><\/span><\/h3>\n<p style=\"text-align: left;\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-10762 aligncenter\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/03\/I-Wayan-Cameng-Closeup-by-Eko-Hardiyanto-scaled-e1625559137589.webp\" alt=\"pot serayu je wayan cameng\" width=\"375\" height=\"563\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/03\/I-Wayan-Cameng-Closeup-by-Eko-Hardiyanto-scaled-e1625559137589.webp 394w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/03\/I-Wayan-Cameng-Closeup-by-Eko-Hardiyanto-scaled-e1625559137589-200x300.webp 200w\" sizes=\"auto, (max-width: 375px) 100vw, 375px\" \/><\/p>\n<h3><strong>Premi\u00e8res impressions du pot Serayu<\/strong><\/h3>\n<p>D\u00e8s mon arriv\u00e9e, la boutique color\u00e9e en terre cuite a imm\u00e9diatement attir\u00e9 mon attention. Des pots suspendus peints \u00e0 la main ornaient l&#039;ext\u00e9rieur, cr\u00e9ant une atmosph\u00e8re vibrante et accueillante. Je me suis dirig\u00e9 vers le magasin et j&#039;ai \u00e9t\u00e9 accueilli par la vue du \u00ab plus gros chien de Bali \u00bb allong\u00e9 sur le sol, accompagn\u00e9 d&#039;une femme souriante et de l&#039;homme au visage le plus fascinant du monde.<\/p>\n<h3><strong>Rencontre avec la famille derri\u00e8re Serayu Pot<\/strong><\/h3>\n<p><span class=\"markedContent\"><span dir=\"ltr\">Mon Bahasa Indonesia \u00e9tait trop mauvais, tout comme le sien. <\/span><span dir=\"ltr\">Anglais. <\/span><\/span><\/p>\n<p><span class=\"markedContent\"><span dir=\"ltr\">Alors ils m&#039;ont dit : <em>&quot;Allez au premier <\/em><\/span><em><span dir=\"ltr\">\u00e9tage, voici notre fille Jay, si vous en avez <\/span><span dir=\"ltr\">questions, elle peut tout vous dire sur notre <\/span><span dir=\"ltr\">magasin et nous.<\/span><\/em><\/span><\/p>\n<p>En raison de la barri\u00e8re de la langue, la femme m&#039;a dirig\u00e9 vers leur fille, Jay, qui se trouvait au premier \u00e9tage.<\/p>\n<p><span class=\"markedContent\"><span dir=\"ltr\">Des escaliers raides montaient; Je me demandais comment ce chien <\/span><span dir=\"ltr\">\u00e7a arrive ici tous les jours\u2026<\/span><\/span><\/p>\n<p>Au sommet, j&#039;ai trouv\u00e9 un espace de travail ouvert avec un espace caf\u00e9 et bar. Jay nous a accueillis chaleureusement et apr\u00e8s avoir expliqu\u00e9 pourquoi nous \u00e9tions l\u00e0, elle a partag\u00e9 que de nombreuses personnes lui rendaient visite en raison de la pr\u00e9sence intrigante de son p\u00e8re.<\/p>\n<h2><strong>L&#039;\u00e9volution artistique du pot Serayu<\/strong><\/h2>\n<p>Jay a expliqu\u00e9 que Serayu Pot s&#039;\u00e9tait initialement sp\u00e9cialis\u00e9 dans les pots faits \u00e0 la main pour les c\u00e9r\u00e9monies balinaises. Cependant, \u00e0 mesure que la demande diminuait, son p\u00e8re commen\u00e7a \u00e0 peindre les pots de mani\u00e8re artistique et \u00e0 les exposer \u00e0 l&#039;ext\u00e9rieur du magasin. Ces vitrines vibrantes ont attir\u00e9 l\u2019attention, faisant du magasin un point de rep\u00e8re local.<\/p>\n<p style=\"text-align: left;\"><span class=\"markedContent\"><strong><span dir=\"ltr\">Nous sommes entr\u00e9s dans un espace de travail ouvert id\u00e9al, avec <\/span><span dir=\"ltr\">un caf\u00e9 et un bar.<\/span><\/strong><\/span><span class=\"markedContent\"> <span dir=\"ltr\">Jay \u00e9tait l\u00e0 ; nous avons pr\u00e9sent\u00e9 <\/span><span dir=\"ltr\">nous-m\u00eames et avons dit pourquoi nous \u00e9tions ici.<\/span><\/span><\/p>\n<p style=\"text-align: left;\"><span class=\"markedContent\"><span dir=\"ltr\">Jay a d\u00fb rire et nous a dit que nous n&#039;\u00e9tions pas les <\/span><span dir=\"ltr\">les seuls qui viennent ici \u00e0 cause de son p\u00e8re, <\/span><span dir=\"ltr\">mais les seuls jusqu&#039;\u00e0 pr\u00e9sent qui demandent si nous pouvons prendre <\/span><span dir=\"ltr\">Une image. Habituellement, les gens prennent des photos sans <\/span><span dir=\"ltr\">demander; \u00e9galement une marque de renomm\u00e9e mondiale, ils ont pris un <\/span><span dir=\"ltr\">photo de mon p\u00e8re et je l&#039;ai utilis\u00e9 pour leur nouveau <\/span><span dir=\"ltr\">campagne.<\/span><\/span><\/p>\n<h3 style=\"text-align: left;\"><span class=\"markedContent\"><span dir=\"ltr\">Pot Serayu utilis\u00e9 pour fabriquer et importer des produits faits \u00e0 la main <\/span><span dir=\"ltr\">pots pour les c\u00e9r\u00e9monies balinaises.<\/span><\/span><\/h3>\n<p style=\"text-align: left;\"><span class=\"markedContent\"><span dir=\"ltr\">Soudain, la demande est devenue trop faible et le <\/span><span dir=\"ltr\">entrep\u00f4t trop rempli de pots en terre cuite. Alors, mon <\/span><span dir=\"ltr\">mon p\u00e8re a commenc\u00e9 \u00e0 peindre ces pots de mani\u00e8re artistique et <\/span><span dir=\"ltr\">les accrocher devant le magasin ou les placer <\/span><span dir=\"ltr\">l&#039;un apr\u00e8s l&#039;autre. Un bel accroche-regard qui <\/span><span dir=\"ltr\">a attir\u00e9 de nombreuses personnes au magasin pour en acheter.<\/span><\/span><\/p>\n<h2>Salissez-vous les mains \u2013 c&#039;est amusant\u00a0!<\/h2>\n<p>En r\u00e9ponse \u00e0 l&#039;\u00e9volution du march\u00e9, Jay a transform\u00e9 l&#039;espace en un centre cr\u00e9atif. D\u00e9sormais, les visiteurs peuvent prendre un caf\u00e9 tout en travaillant dans le bureau et s&#039;essayer \u00e0 la fabrication et \u00e0 la peinture de leurs propres casseroles, assiettes et tasses. Ce qui \u00e9tait cens\u00e9 \u00eatre une courte visite s&#039;est transform\u00e9 en un d\u00e9licieux apr\u00e8s-midi lorsque je me suis inscrit \u00e0 un cours de poterie. M\u00eame si c\u2019\u00e9tait un d\u00e9fi, c\u2019\u00e9tait tr\u00e8s amusant pour ma fille et moi.<\/p>\n<p style=\"text-align: left;\"><span class=\"markedContent\"><span dir=\"ltr\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-3364 size-medium aligncenter\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2021\/07\/IMG_20210531_152618-scaled-e1625102168277.jpg\" alt=\"pot serayu et terre cuite ubud i wayan cameng bali activit\u00e9 amusante voyage en famille expatri\u00e9 artisanat original asli travellust jay\" width=\"300\" height=\"259\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2021\/07\/IMG_20210531_152618-scaled-e1625102168277.jpg 1227w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2021\/07\/IMG_20210531_152618-scaled-e1625102168277-300x259.jpg 300w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2021\/07\/IMG_20210531_152618-scaled-e1625102168277-768x664.jpg 768w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2021\/07\/IMG_20210531_152618-scaled-e1625102168277-1024x885.jpg 1024w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2021\/07\/IMG_20210531_152618-scaled-e1625102168277-624x540.jpg 624w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/span><\/span><\/p>\n<blockquote><p>\u00ab Mon p\u00e8re a commenc\u00e9 \u00e0 peindre ces pots de mani\u00e8re artistique et les accrochait devant le magasin ou les pla\u00e7ait les uns apr\u00e8s les autres. Un bel accroche-regard qui a attir\u00e9 de nombreuses personnes au magasin pour en acheter. La situation actuelle rend beaucoup de gens plus cr\u00e9atifs, comme Jay, elle a ouvert un caf\u00e9, un bureau et un atelier de poterie, nous y sommes all\u00e9s pour l&#039;essayer.<\/p><\/blockquote>\n<p>&nbsp;<\/p>\n<p style=\"text-align: left;\"><span class=\"markedContent\"><span dir=\"ltr\">La situation actuelle rend beaucoup plus de gens <\/span><span dir=\"ltr\">cr\u00e9ative, comme Jay, elle a ouvert un caf\u00e9, un bureau et <\/span><span dir=\"ltr\">lieu de travail et \u00e0 c\u00f4t\u00e9, vous pouvez essayer de faire <\/span><span dir=\"ltr\">et peignez vos propres pots, assiettes et tasses. <\/span><\/span><span class=\"markedContent\"><span dir=\"ltr\">Notre visite, qui devait \u00eatre courte, <\/span><span dir=\"ltr\">\u00e7a a dur\u00e9 un peu plus longtemps, et \u00e7a s&#039;est termin\u00e9 par moi <\/span><span dir=\"ltr\">s&#039;inscrire \u00e0 un cours de poterie. <\/span><span dir=\"ltr\">Cela a l&#039;air beaucoup plus facile qu&#039;il ne l&#039;est, mais c&#039;\u00e9tait tr\u00e8s amusant <\/span><span dir=\"ltr\">pour ma fille et moi. <\/span><\/span><\/p>\n<h3><strong>Une exp\u00e9rience m\u00e9morable<\/strong><\/h3>\n<p>Gr\u00e2ce \u00e0 Jay et \u00e0 sa famille, notre visite \u00e0 Serayu Pot a \u00e9t\u00e9 une exp\u00e9rience inoubliable. Nous sommes repartis avec non seulement de beaux pots mais aussi de merveilleux souvenirs d&#039;une journ\u00e9e cr\u00e9ative et amusante. Si vous \u00eates \u00e0 Ubud et recherchez une activit\u00e9 unique, nous vous recommandons vivement de visiter le Serayu Pot.<\/p>\n<h3 style=\"text-align: left;\"><span class=\"markedContent\"><span dir=\"ltr\">Merci Jay! <\/span><\/span><\/h3>\n<h3 style=\"text-align: left;\"><span class=\"markedContent\"><span dir=\"ltr\">Nous reviendrons au Serayu Pot<\/span><\/span><\/h3>\n<blockquote>\n<p style=\"text-align: left;\"><span class=\"markedContent\"><em><span dir=\"ltr\">Si vous souhaitez passer une journ\u00e9e cr\u00e9ative et amusante \u00e0 Ubud, <\/span><\/em><span dir=\"ltr\"><em>nous recommandons fortement Serayu Pot.<\/em> <\/span><\/span><\/p>\n<\/blockquote>\n<h3 style=\"text-align: left;\"><a href=\"https:\/\/www.instagram.com\/serayupot\/\" target=\"_blank\" rel=\"noopener\">@serayupot<\/a><\/h3>\n<h3 style=\"text-align: left;\"><em><span class=\"markedContent\"><span dir=\"ltr\">Amusant et <\/span><span dir=\"ltr\">cr\u00e9ativit\u00e9 garantie !<\/span><\/span><\/em><\/h3>\n<figure id=\"attachment_3363\" aria-describedby=\"caption-attachment-3363\" style=\"width: 1011px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-3363 size-large\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2021\/07\/IMG_20210531_151038-scaled-e1625102236217-1011x1024.jpg\" alt=\"serayu pot et terre cuite ubud i wayan cameng bali activit\u00e9 amusante voyage en famille expatri\u00e9 artisanat original asli\" width=\"1011\" height=\"1024\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2021\/07\/IMG_20210531_151038-scaled-e1625102236217-1011x1024.jpg 1011w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2021\/07\/IMG_20210531_151038-scaled-e1625102236217-296x300.jpg 296w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2021\/07\/IMG_20210531_151038-scaled-e1625102236217-768x778.jpg 768w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2021\/07\/IMG_20210531_151038-scaled-e1625102236217-1516x1536.jpg 1516w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2021\/07\/IMG_20210531_151038-scaled-e1625102236217-624x632.jpg 624w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2021\/07\/IMG_20210531_151038-scaled-e1625102236217.jpg 1920w\" sizes=\"auto, (max-width: 1011px) 100vw, 1011px\" \/><figcaption id=\"caption-attachment-3363\" class=\"wp-caption-text\">Pot Serayu et ubud en terre cuite<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>Une visite \u00e0 la poterie Serayu \u00e0 Ubud est un voyage dans la cr\u00e9ativit\u00e9 et l&#039;art. De l&#039;histoire captivante d&#039;I Wayan Cameng aux cours pratiques de poterie, Serayu Pot offre une exp\u00e9rience unique et enrichissante. Que vous soyez passionn\u00e9 d&#039;art ou simplement \u00e0 la recherche d&#039;une activit\u00e9 amusante, Serayu Pot est l&#039;endroit id\u00e9al. Ne manquez pas ce joyau d&#039;Ubud : plaisir et cr\u00e9ativit\u00e9 sont garantis !<\/p>\n<p>&nbsp;<\/p>\n<h2>FAQ<\/h2>\n<h3>Qu\u2019est-ce que le pot Serayu\u00a0?<\/h3>\n<p>Serayu Pot est un magasin de terre cuite anim\u00e9 \u00e0 Ubud, Bali, proposant des pots peints \u00e0 la main et des cours de poterie.<\/p>\n<h3>Qui suis-je Wayan Cameng ?<\/h3>\n<p>I Wayan Cameng est un artiste renomm\u00e9 d&#039;Ubud et la force cr\u00e9atrice derri\u00e8re Serayu Pot.<\/p>\n<h3>Les visiteurs peuvent-ils suivre des cours de poterie au Serayu Pot\u00a0?<\/h3>\n<p>Oui, vous pouvez participer \u00e0 des cours de poterie o\u00f9 ils pourront fabriquer et peindre leurs propres pots, assiettes et tasses. Id\u00e9alement, r\u00e9servez au pr\u00e9alable via leur compte Instagram.<\/p>\n<h3>Y a-t-il un caf\u00e9 au Serayu Pot ?<\/h3>\n<p>Oui, Jay a am\u00e9nag\u00e9 un espace caf\u00e9 et bar au sein de l&#039;espace de travail, ce qui en fait un endroit id\u00e9al pour se d\u00e9tendre et cr\u00e9er.<\/p>\n<h3>Qu&#039;est-ce qui rend le pot Serayu unique ?<\/h3>\n<p>Les pots en terre cuite color\u00e9s et peints \u00e0 la main du magasin et la possibilit\u00e9 de participer \u00e0 des activit\u00e9s pratiques de poterie font de Serayu Pot une destination hors du commun.<\/p>\n<h3>Comment puis-je trouver le Pot Serayu ?<\/h3>\n<p>Serayu Pot est situ\u00e9 \u00e0 Peliatan, Ubud. Difficile de le manquer avec son exposition color\u00e9e de pots en terre cuite.<\/p>\n<h3><strong>Combien co\u00fbte le pot Serayu ?<\/strong><\/h3>\n<p>Chaque adulte sera factur\u00e9 13 USD, soit environ 183 000 Rp, et les enfants seront factur\u00e9s 9 USD, soit environ 127 000 Rp. Le cours dure environ 1h30 et comprend des pots sp\u00e9ciaux pour la peinture et des collations. La condition pour rejoindre ce cours est d&#039;un minimum de 8 participants par session.<\/p>\n<h3>Qu&#039;est-ce qu&#039;un cours de poterie ?<\/h3>\n<p>Un cours de poterie est un cours qui fournit des instructions sur le processus de fabrication de la poterie. La poterie est un produit fabriqu\u00e9 \u00e0 partir d&#039;argile, g\u00e9n\u00e9ralement recouvert d&#039;autres mat\u00e9riaux color\u00e9s ou peint.<\/p>\n<h3><strong>Quelles sont les \u00e9tapes de fabrication de la poterie ?<\/strong><\/h3>\n<ul>\n<li><strong>Processus de s\u00e9lection et d\u2019extraction de l\u2019argile<\/strong><\/li>\n<li><strong>Traitement de l&#039;argile<\/strong><\/li>\n<li><strong>Processus de mise en forme de l&#039;argile<\/strong><\/li>\n<li><strong>Processus de s\u00e9chage de la poterie<\/strong><\/li>\n<li><strong>Processus de cuisson de la poterie<\/strong><\/li>\n<li><strong>Processus de finition<\/strong><\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>Explore Serayu Pot \u00e0 Ubud, un magasin de terre cuite anim\u00e9 proposant des cours de poterie et une exp\u00e9rience artistique unique. Id\u00e9al pour une journ\u00e9e cr\u00e9ative et ludique !<\/p>","protected":false},"author":214,"featured_media":10762,"comment_status":"open","ping_status":"closed","template":"","meta":{"footnotes":""},"categories":[272,270],"tags":[342],"section":[390,395],"interest":[195,198,400],"_magazine":[343],"class_list":["post-9683","article","type-article","status-publish","has-post-thumbnail","hentry","category-artsy","category-explore","tag-342","section-artsy","section-places","interest-families","interest-honeymoon","interest-things-to-do","_magazine-343"],"_links":{"self":[{"href":"https:\/\/instantkarmamag.com\/fr\/wp-json\/wp\/v2\/article\/9683","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/instantkarmamag.com\/fr\/wp-json\/wp\/v2\/article"}],"about":[{"href":"https:\/\/instantkarmamag.com\/fr\/wp-json\/wp\/v2\/types\/article"}],"author":[{"embeddable":true,"href":"https:\/\/instantkarmamag.com\/fr\/wp-json\/wp\/v2\/users\/214"}],"replies":[{"embeddable":true,"href":"https:\/\/instantkarmamag.com\/fr\/wp-json\/wp\/v2\/comments?post=9683"}],"version-history":[{"count":0,"href":"https:\/\/instantkarmamag.com\/fr\/wp-json\/wp\/v2\/article\/9683\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/instantkarmamag.com\/fr\/wp-json\/wp\/v2\/media\/10762"}],"wp:attachment":[{"href":"https:\/\/instantkarmamag.com\/fr\/wp-json\/wp\/v2\/media?parent=9683"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/instantkarmamag.com\/fr\/wp-json\/wp\/v2\/categories?post=9683"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/instantkarmamag.com\/fr\/wp-json\/wp\/v2\/tags?post=9683"},{"taxonomy":"section","embeddable":true,"href":"https:\/\/instantkarmamag.com\/fr\/wp-json\/wp\/v2\/section?post=9683"},{"taxonomy":"interest","embeddable":true,"href":"https:\/\/instantkarmamag.com\/fr\/wp-json\/wp\/v2\/interest?post=9683"},{"taxonomy":"_magazine","embeddable":true,"href":"https:\/\/instantkarmamag.com\/fr\/wp-json\/wp\/v2\/_magazine?post=9683"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}<!-- This website is optimized by Airlift. Learn more: https://airlift.net. Template:. Learn more: https://airlift.net. Template: 6a3c9e6bc6af5a91495580da. Config Timestamp: 2026-06-25 03:19:51 UTC, Cached Timestamp: 2026-09-02 04:55:20 UTC -->