{"id":9681,"date":"2021-06-30T00:00:00","date_gmt":"2021-06-29T16:00:00","guid":{"rendered":"https:\/\/instantkarmamag.com\/article\/origin-of-ubud\/"},"modified":"2024-07-03T16:46:42","modified_gmt":"2024-07-03T08:46:42","slug":"origine-dubud","status":"publish","type":"article","link":"https:\/\/instantkarmamag.com\/fr\/article\/origine-dubud\/","title":{"rendered":"L&#039;origine magique d&#039;Ubud"},"content":{"rendered":"<div id=\"bsf_rt_marker\"><\/div><p><span class=\"markedContent\"><span dir=\"ltr\">L&#039;origine d&#039;Ubud est importante et complexe ; chez Instant Karma, nous avons eu la chance de nous rencontrer <strong>Ratu Cokorda Agung Darmayasa et Jro Dasaran Istri Ayu Mas Gading<\/strong>, deux personnes hautement spirituelles qui s&#039;engagent sinc\u00e8rement \u00e0 ce que l&#039;histoire et l&#039;origine d&#039;Ubud soient racont\u00e9es de mani\u00e8re holistique et correcte. <\/span><\/span><\/p>\n<p><span class=\"markedContent\"><span dir=\"ltr\">T<\/span><span dir=\"ltr\">Il existe de nombreux endroits \u00e0 Bali avec des histoires impressionnantes sur l&#039;art, la culture et la religion. <\/span><span dir=\"ltr\">Ubud en fait partie. <\/span><span dir=\"ltr\">Ubud est le centre culturel de Bali. Tous les artistes et pr\u00eatres avant notre \u00e9poque <\/span><span dir=\"ltr\">\u00e0 cet endroit car il d\u00e9gage une certaine magie. <\/span><\/span><\/p>\n<figure id=\"attachment_3327\" aria-describedby=\"caption-attachment-3327\" style=\"width: 387px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-3327 size-full\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2021\/07\/DSC7587-e1625094604286.jpg\" alt=\"origine ubud culture histoire hindouisme bali voyage voyages\" width=\"387\" height=\"356\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2021\/07\/DSC7587-e1625094604286.jpg 387w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2021\/07\/DSC7587-e1625094604286-300x276.jpg 300w\" sizes=\"auto, (max-width: 387px) 100vw, 387px\" \/><figcaption id=\"caption-attachment-3327\" class=\"wp-caption-text\">Ratu Cokorda Agung Darmayasa, malheureusement d\u00e9c\u00e9d\u00e9 en 2023, et Jro Dasaran Istri Ayu Mas Gading<\/figcaption><\/figure>\n<p><span class=\"markedContent\"><span dir=\"ltr\">Avec des artistes comme Walter Spies, Rudolf Bonnet, Don Antonio Maria Blanco et le <\/span><span dir=\"ltr\">p\u00e8re du marketing Philip Kottler \u2013 le roi d&#039;Ubud voulait montrer au monde que Bali a <\/span><span dir=\"ltr\">bien plus \u00e0 offrir que les plages du sud.<\/span><\/span><\/p>\n<h3 style=\"text-align: center\"><em><span class=\"markedContent\"><span dir=\"ltr\">Un aper\u00e7u de l&#039;hindouisme en <\/span><span dir=\"ltr\">Bali <\/span><\/span><\/em><\/h3>\n<p>&nbsp;<\/p>\n<p><span class=\"markedContent\"><span dir=\"ltr\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-3333 size-full\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2021\/07\/Screenshot-2021-07-01-at-07-01-43-IK-magz-5-print-final-pdf.png\" alt=\"origine ubud culture histoire hindouisme bali voyage voyages\" width=\"317\" height=\"425\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2021\/07\/Screenshot-2021-07-01-at-07-01-43-IK-magz-5-print-final-pdf.png 317w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2021\/07\/Screenshot-2021-07-01-at-07-01-43-IK-magz-5-print-final-pdf-224x300.png 224w\" sizes=\"auto, (max-width: 317px) 100vw, 317px\" \/><\/span><\/span><\/p>\n<h2>L&#039;origine d&#039;Ubud<\/h2>\n<p><span class=\"markedContent\"><span dir=\"ltr\">Maha Rsi Markandhya a commenc\u00e9 son voyage \u00e0 Bali <\/span><span dir=\"ltr\">du mont Raung dans la r\u00e9gion de Banuyuwangi. <\/span><span dir=\"ltr\">Apr\u00e8s avoir plac\u00e9 son Panca Datu (brassard) \u00e0 Besakih <\/span><span dir=\"ltr\">Temple, il poursuit sa route vers Campuhan <\/span><span dir=\"ltr\">Colline. En arrivant l\u00e0-bas, Maha Rsi Markandhya \u00e9tait <\/span><span dir=\"ltr\">\u00e9merveill\u00e9 par la beaut\u00e9 de la colline, et elle fut nomm\u00e9e <\/span><span dir=\"ltr\">Gunung Lebah. <\/span><\/span><\/p>\n<p><span class=\"markedContent\"><span dir=\"ltr\">Du c\u00f4t\u00e9 ouest, il y a une rivi\u00e8re appel\u00e9e Tukad Yeh. <\/span><span dir=\"ltr\">Wos Kiwa, et \u00e0 l&#039;est, on l&#039;appelle Tukad Yeh Wos <\/span><span dir=\"ltr\">Tengen. Les rivi\u00e8res se confondent dans la zone sud du <\/span><span dir=\"ltr\">colline connue sous le nom de Campuhan (Pecampuhan \u2013 signifiant <\/span><span dir=\"ltr\">m\u00e9lange des rivi\u00e8res) du d\u00e9bit de la rivi\u00e8re. C&#039;\u00e9tait en <\/span><span dir=\"ltr\">cette zone que Maha Rsi Markandhya a construit un lieu saint <\/span><span dir=\"ltr\">appel\u00e9 Pura Gunung Lebah.<\/span><\/span><\/p>\n<p><span class=\"markedContent\"><span dir=\"ltr\">Apr\u00e8s cela, il commen\u00e7a \u00e0 explorer la for\u00eat pour cr\u00e9er un lieu d&#039;ermitage, puis \u00e0 construire <\/span><span dir=\"ltr\">colonies et cr\u00e9er des terres pour l\u2019agriculture. <\/span><span dir=\"ltr\">Bas\u00e9 sur les manuscrits Lontar (feuille de palmier), Markandhya Purana, le nom Uos ou Wos pour le <\/span><span dir=\"ltr\">rivi\u00e8res, suit le nom des colonies de la r\u00e9gion depuis l&#039;Antiquit\u00e9. <\/span><\/span><\/p>\n<h4><strong><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-3331 size-full\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2021\/07\/Screenshot-2021-07-01-at-07-02-10-IK-magz-5-print-final-pdf.png\" alt=\"origine ubud culture histoire hindouisme bali voyage voyage karma instantan\u00e9 magazine\" width=\"670\" height=\"413\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2021\/07\/Screenshot-2021-07-01-at-07-02-10-IK-magz-5-print-final-pdf.png 670w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2021\/07\/Screenshot-2021-07-01-at-07-02-10-IK-magz-5-print-final-pdf-300x185.png 300w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2021\/07\/Screenshot-2021-07-01-at-07-02-10-IK-magz-5-print-final-pdf-624x385.png 624w\" sizes=\"auto, (max-width: 670px) 100vw, 670px\" \/><\/strong><\/h4>\n<h3><\/h3>\n<h3 style=\"text-align: left\"><span class=\"markedContent\"><span dir=\"ltr\">Premi\u00e8rement, il y avait les noms \u00ab Wos \u00bb ou \u00ab Uos \u00bb pour la rivi\u00e8re, <\/span><span dir=\"ltr\">qui a chang\u00e9 au fil du temps pour \u00ab Usadi \u00bb et \u00ab Usada \u00bb. <\/span><\/span><\/h3>\n<h3 style=\"text-align: left\"><span class=\"markedContent\"><span dir=\"ltr\">&quot;Usada&quot; <\/span><span dir=\"ltr\">d\u00e9velopp\u00e9 plus en d\u00e9tail dans la narration \u00ab Ubad \u00bb, et le <\/span><span dir=\"ltr\">nom encore d\u00e9form\u00e9 en \u00ab Ubud \u00bb.<\/span><\/span><\/h3>\n<p>&nbsp;<\/p>\n<p><span class=\"markedContent\"><span dir=\"ltr\">Des h\u00e9ros culturels tels que Maha Rsi Markandhya sont <\/span><span dir=\"ltr\">important pour l&#039;\u00e9tablissement de temples \u00e0 Bali. <\/span><span dir=\"ltr\">Le <\/span><span dir=\"ltr\">les concepts et l&#039;id\u00e9ologie qu&#039;il enseignait sont toujours ancr\u00e9s <\/span><span dir=\"ltr\">dans l&#039;histoire et le folklore qui circulent dans la communaut\u00e9.<\/span><\/span><\/p>\n<p><span class=\"markedContent\"><span dir=\"ltr\">Apr\u00e8s avoir jou\u00e9 un r\u00f4le d\u00e9terminant dans la gestion du Gunung Lebah <\/span><span dir=\"ltr\">Temple, Maha Rsi Markandhya, puis s&#039;est d\u00e9plac\u00e9 plus loin <\/span><span dir=\"ltr\">nord. On l&#039;appelait autrefois \u00ab\u00a0Sarwa\u00a0\u00bb, o\u00f9 on l&#039;appelle maintenant <\/span><span dir=\"ltr\">comme Village de Taro.<\/span><\/span><\/p>\n<h3><\/h3>\n<h2>Il existe un mythe inh\u00e9rent au temple Gunung Lebah \u00e0 Ubud :<\/h2>\n<p>On raconte qu&#039;autrefois autour du temple Gunung Lebah \u00e0 Ubud, il y avait deux g\u00e9ants, Luh (femelle) et Muani (m\u00e2le), qui vivaient dans une grotte dans la rivi\u00e8re Yeh Wos Kiwa. Cet incident a commenc\u00e9 lorsque le public a finalement su que les danseurs Rejang qui avaient myst\u00e9rieusement disparu pendant Ngayah au temple Gunung Lebah avaient disparu parce qu&#039;ils avaient \u00e9t\u00e9 mang\u00e9s par un monstre.<\/p>\n<p>Finalement, les deux g\u00e9ants sont morts aux mains des habitants. Le g\u00e9ant \u00ab\u00a0Muani\u00a0\u00bb est mort parce qu&#039;il a \u00e9t\u00e9 poignard\u00e9 avec une houe par un agriculteur dans un village appel\u00e9 Penestanan. En revanche, le g\u00e9ant \u00ab Luh \u00bb, d\u00e9c\u00e9d\u00e9 parce que la communaut\u00e9 locale a incendi\u00e9 la grotte o\u00f9 il vivait.<\/p>\n<p>N\u00e9anmoins, des artefacts de ces monstres se trouvent toujours dans la zone du temple de Gunung Lebah, comme la grotte g\u00e9ante de mortier, un march\u00e9 g\u00e9ant et une tombe g\u00e9ante.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<h3>Respectez la Terre M\u00e8re et la Terre M\u00e8re vous b\u00e9nira.<\/h3>\n<p>Les rivi\u00e8res \u00ab Yeh Wos Kiwa \u00bb (\u00e0 droite) et \u00ab Yeh Wos Tengen \u00bb (\u00e0 gauche) repr\u00e9sentent les enseignements de Rwa Bhineda, l&#039;un des aspects les plus myst\u00e9rieux et intrigants de la philosophie balinaise. Cela se traduit vaguement par dualisme car il s\u2019agit de la croyance que toute vie d\u00e9pend d\u2019un \u00e9quilibre entre des forces oppos\u00e9es.<\/p>\n<p>Ces oppos\u00e9s-en-<a href=\"https:\/\/instantkarmamag.com\/fr\/article\/equilibre\/\" target=\"_blank\" rel=\"noopener\">\u00e9quilibre<\/a> ne sont pas strictement consid\u00e9r\u00e9s comme bons ou mauvais, et l\u2019un n\u2019est pas cens\u00e9 vaincre l\u2019autre. On ne croit pas que la vie \u00e9volue vers une \u00e9ventuelle perfection cosmique et personnelle. Le but ultime de la vie est l\u2019\u00e9quilibre et l\u2019adaptation de tous les aspects de la vie, tant constructifs que destructeurs.<\/p>\n<h3 style=\"text-align: center\"><em>Le concept de Rwa Bhineda consid\u00e8re la vie telle qu&#039;elle est, et non telle qu&#039;elle est cens\u00e9e \u00eatre.<\/em><\/h3>\n<p>&nbsp;<\/p>\n<div class=\"flex flex-grow flex-col gap-3 max-w-full\">\n<div class=\"min-h-[20px] flex flex-col items-start gap-3 whitespace-pre-wrap break-words overflow-x-auto\">\n<div class=\"markdown prose w-full break-words dark:prose-invert light\">\n<h2>En fin de compte, l\u2019histoire d\u2019Ubud ressemble \u00e0 un voyage magique.<\/h2>\n<p>Des personnes comme feu Ratu Cokorda Agung Darmayasa et Jro Dasaran Istri Ayu Mas Gading nous aident \u00e0 mieux le comprendre.<\/p>\n<p><a href=\"https:\/\/maps.app.goo.gl\/dw2UtZuq1DCZr4zi7\" target=\"_blank\" rel=\"noopener\">Ubud est un endroit sp\u00e9cial \u00e0 Bali<\/a> o\u00f9 artistes et pr\u00eatres trouvaient un enchantement unique.<\/p>\n<p>Ils ont apport\u00e9 un art et une culture extraordinaires \u00e0 cette terre, et m\u00eame des artistes c\u00e9l\u00e8bres comme Walter Spies et Don Antonio Maria Blanco ont ressenti sa magie particuli\u00e8re. Tout a commenc\u00e9 avec Maha Rsi Markandhya, qui a d\u00e9couvert la beaut\u00e9 de <a href=\"https:\/\/maps.app.goo.gl\/f4DFY1hKbNPx2drDA\" target=\"_blank\" rel=\"noopener\">Colline de Campuhan<\/a> et commen\u00e7a \u00e0 construire des temples importants.<\/p>\n<p>Le nom \u00ab Ubud \u00bb lui-m\u00eame a une longue histoire, passant au fil du temps de \u00ab Wos \u00bb \u00e0 \u00ab Usada \u00bb et enfin \u00ab Ubud \u00bb. Cet endroit est riche en l\u00e9gendes et en histoires, comme celle des g\u00e9ants Luh et Muani.<\/p>\n<p>Ubud nous enseigne \u00e9galement l&#039;\u00e9quilibre et l&#039;harmonie dans la vie, tout comme nous le montrent les rivi\u00e8res Yeh Wos Kiwa et Yeh Wos Tengen. Il s\u2019agit de garder tout en \u00e9quilibre, bon et moins bon, tout comme la vie elle-m\u00eame.<\/p>\n<p>Alors souviens-toi:<\/p>\n<h3>Profitez de la vie telle qu&#039;elle est et appr\u00e9ciez sa magie !<\/h3>\n<\/div>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>L&#039;origine d&#039;Ubud est importante et complexe ; Chez Instant Karma, nous avons eu la chance de rencontrer Ratu Cokorda et Jro Dasaran pour nous raconter l&#039;histoire authentique.<\/p>","protected":false},"author":214,"featured_media":10766,"comment_status":"open","ping_status":"closed","template":"","meta":{"footnotes":""},"categories":[271],"tags":[342],"section":[386,385],"interest":[397,377,400],"_magazine":[343],"class_list":["post-9681","article","type-article","status-publish","has-post-thumbnail","hentry","category-culture","tag-342","section-culture","section-explore","interest-history","interest-sightseeing","interest-things-to-do","_magazine-343"],"_links":{"self":[{"href":"https:\/\/instantkarmamag.com\/fr\/wp-json\/wp\/v2\/article\/9681","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/instantkarmamag.com\/fr\/wp-json\/wp\/v2\/article"}],"about":[{"href":"https:\/\/instantkarmamag.com\/fr\/wp-json\/wp\/v2\/types\/article"}],"author":[{"embeddable":true,"href":"https:\/\/instantkarmamag.com\/fr\/wp-json\/wp\/v2\/users\/214"}],"replies":[{"embeddable":true,"href":"https:\/\/instantkarmamag.com\/fr\/wp-json\/wp\/v2\/comments?post=9681"}],"version-history":[{"count":0,"href":"https:\/\/instantkarmamag.com\/fr\/wp-json\/wp\/v2\/article\/9681\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/instantkarmamag.com\/fr\/wp-json\/wp\/v2\/media\/10766"}],"wp:attachment":[{"href":"https:\/\/instantkarmamag.com\/fr\/wp-json\/wp\/v2\/media?parent=9681"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/instantkarmamag.com\/fr\/wp-json\/wp\/v2\/categories?post=9681"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/instantkarmamag.com\/fr\/wp-json\/wp\/v2\/tags?post=9681"},{"taxonomy":"section","embeddable":true,"href":"https:\/\/instantkarmamag.com\/fr\/wp-json\/wp\/v2\/section?post=9681"},{"taxonomy":"interest","embeddable":true,"href":"https:\/\/instantkarmamag.com\/fr\/wp-json\/wp\/v2\/interest?post=9681"},{"taxonomy":"_magazine","embeddable":true,"href":"https:\/\/instantkarmamag.com\/fr\/wp-json\/wp\/v2\/_magazine?post=9681"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}<!-- This website is optimized by Airlift. Learn more: https://airlift.net. Template:. Learn more: https://airlift.net. Template: 6a3c9e6bc6af5a91495580da. Config Timestamp: 2026-06-25 03:19:51 UTC, Cached Timestamp: 2026-09-02 18:04:56 UTC -->