{"id":28500,"date":"2023-11-10T15:26:09","date_gmt":"2023-11-10T07:26:09","guid":{"rendered":"https:\/\/instantkarmamag.com\/?post_type=online&#038;p=28500"},"modified":"2024-10-27T23:56:14","modified_gmt":"2024-10-27T15:56:14","slug":"lorigine-du-sauvetage-des-reptiles-a-bali","status":"publish","type":"article","link":"https:\/\/instantkarmamag.com\/fr\/article\/lorigine-du-sauvetage-des-reptiles-a-bali\/","title":{"rendered":"L&#039;origine du sauvetage des reptiles \u00e0 Bali"},"content":{"rendered":"<div id=\"bsf_rt_marker\"><\/div><p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-28510 aligncenter\" src=\"https:\/\/mlucpnxbn6mg.i.optimole.com\/w:auto\/h:auto\/q:mauto\/process:28510\/id:be89bacdaa54aafe450c170d8be4e2f5\/https:\/\/instantkarmamag.com\/Picture5.jpg\" alt=\"\" width=\"602\" height=\"338\" title=\"\"><\/p>\n<p>Je vous promets que l&#039;histoire que je m&#039;appr\u00eate \u00e0 partager avec vous sera l&#039;histoire de conservation la plus remarquable que vous ayez jamais entendue ou que vous entendrez jamais. Je vous garantis que c&#039;est le 100% r\u00e9el.<\/p>\n<p>Naturellement, nous souhaitons vous raconter une histoire si captivante que vous ne pouvez pas attendre notre prochain article. Alors d\u00e9tendez-vous, d\u00e9tendez-vous et participez \u00e0 ce voyage.<\/p>\n<p>Faisons connaissance, et je peux aussi partager un peu notre incroyable r\u00f4le au sein de la communaut\u00e9. Avez-vous pris votre caf\u00e9\u00a0? es-tu assis et confortable ?<\/p>\n<p>C&#039;est une histoire vraiment incroyable. En fait, je vais m\u00eame vous fournir des documents pour prouver son authenticit\u00e9.<\/p>\n<p>C&#039;est l&#039;histoire originale de la naissance de Bali Reptile Rescue et, \u00e9tonnamment, cela n&#039;a absolument rien \u00e0 voir avec les serpents ou les reptiles.<\/p>\n<p>Pr\u00e9parez-vous \u00e0 une histoire sur le sauvetage des orangs-outans, la corruption, les pots-de-vin, les menaces de mort et les \u00ab seins \u00bb (oui, les seins, les melons, les chiots \u00e0 la poitrine !). C&#039;est l&#039;histoire des chasseurs de t\u00eates Dayak de Kalimantan (Born\u00e9o), d&#039;une aventure d&#039;escalade passionnante et de l&#039;entra\u00eenement rigoureux des forces sp\u00e9ciales indon\u00e9siennes. Mais surtout, c&#039;est l&#039;incroyable parcours de Shinta Sukmawati, fondateur et propri\u00e9taire de Bali Reptile Rescue.<\/p>\n<p>Alerte spoiler\u00a0: un terrain de 43\u00a0km sur 43\u00a0km dans le sud du Kalimantan est d\u00e9sormais d\u00e9di\u00e9 \u00e0 la conservation des orangs-outans, tout cela gr\u00e2ce aux \u00ab\u00a0gros fous\u00a0\u00bb de Shinta Sukmawati. Histoire vraie, pas de mensonges. Mais quel est le rapport avec Bali Reptile Rescue, vous demandez-vous peut-\u00eatre\u00a0? Continuez \u00e0 lire et tout se mettra en place.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-28511 aligncenter\" src=\"https:\/\/mlucpnxbn6mg.i.optimole.com\/w:auto\/h:auto\/q:mauto\/process:28511\/id:239cd9e82d5148f0ee3e8cb73dfe2351\/https:\/\/instantkarmamag.com\/Picture4.jpg\" alt=\"\" width=\"344\" height=\"396\" title=\"\"><\/p>\n<p>Pour vraiment comprendre cette histoire, nous devons comprendre Shinta. N\u00e9e en 1970, elle \u00e9tait la cinqui\u00e8me d&#039;une famille de huit fr\u00e8res et s\u0153urs. Son p\u00e8re, originaire de Java oriental, \u00e9tait issu d&#039;une lign\u00e9e royale et avait le grade de capitaine dans l&#039;arm\u00e9e indon\u00e9sienne. Il \u00e9tait musulman. En raison de la lign\u00e9e de son p\u00e8re, Shinta et ses fr\u00e8res et s\u0153urs avaient des titres royaux et \u00e9taient appel\u00e9s prince ou princesse. Ce n&#039;\u00e9tait qu&#039;un titre honorifique ; aucune richesse n&#039;y \u00e9tait associ\u00e9e.<\/p>\n<p>La m\u00e8re de Shinta, quant \u00e0 elle, appartenait \u00e0 la communaut\u00e9 chr\u00e9tienne Dayak, indig\u00e8ne du Kalimantan. L&#039;histoire d&#039;amour entre les parents de Shinta a commenc\u00e9 lorsque son p\u00e8re \u00e9tait en poste \u00e0 Palang Karaya. Ils tomb\u00e8rent profond\u00e9ment amoureux et voulurent se marier. Leur mariage se heurtait n\u00e9anmoins \u00e0 un obstacle de taille : le gouvernement indon\u00e9sien ne reconna\u00eet pas les mariages mixtes, une politique qui est toujours en vigueur aujourd&#039;hui.<\/p>\n<p>Pour r\u00e9it\u00e9rer, le mariage des parents de Shinta a donn\u00e9 naissance \u00e0 huit enfants. Les quatre premiers enfants \u00e9taient tous des filles. Le p\u00e8re de Shintas voulait vraiment un gar\u00e7on, alors il pr\u00e9voyait de continuer \u00e0 avoir des enfants jusqu&#039;\u00e0 la naissance d&#039;un h\u00e9ritier m\u00e2le. Il a pris une d\u00e9cision ferme en d\u00e9clarant que le prochain enfant, quel que soit son sexe \u00e0 la naissance, serait \u00e9lev\u00e9 comme un gar\u00e7on.<\/p>\n<p>L&#039;enfant suivant \u00e9tait une fille : Shinta.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-28503 aligncenter\" src=\"https:\/\/mlucpnxbn6mg.i.optimole.com\/w:auto\/h:auto\/q:mauto\/process:28503\/id:d7936d2f05d4b13668297ba0c5b0add3\/https:\/\/instantkarmamag.com\/1699088087125blob.png\" alt=\"\" width=\"720\" height=\"960\" title=\"\"><\/p>\n<p>Shinta a \u00e9t\u00e9 \u00e9lev\u00e9 comme un gar\u00e7on.<\/p>\n<p>Cet aspect de son \u00e9ducation fournit un aper\u00e7u pr\u00e9cieux du caract\u00e8re de Shinta. \u00c9tant dans l&#039;arm\u00e9e, son p\u00e8re a engag\u00e9 Shinta dans des activit\u00e9s comme le camping, la chasse et la p\u00eache, g\u00e9n\u00e9ralement r\u00e9serv\u00e9es aux gar\u00e7ons, tandis que ses s\u0153urs restaient \u00e0 la maison. Trois autres enfants sont n\u00e9s : une fille et deux gar\u00e7ons. Shinta \u00e9tait l&#039;a\u00een\u00e9e de ses fr\u00e8res et s\u0153urs et a \u00e9t\u00e9 \u00e9lev\u00e9e comme un gar\u00e7on aux c\u00f4t\u00e9s de ses fr\u00e8res. Avec la lign\u00e9e guerri\u00e8re Dayak de sa m\u00e8re et les conseils militaires de son p\u00e8re, elle a naturellement assum\u00e9 un r\u00f4le de leadership parmi ses fr\u00e8res et s\u0153urs.<\/p>\n<p>Shinta est all\u00e9 \u00e0 l&#039;universit\u00e9 pour obtenir un dipl\u00f4me en finance et en \u00e9conomie. Pendant ses \u00e9tudes \u00e0 l&#039;universit\u00e9, elle est devenue membre du club d&#039;aventure en plein air, sp\u00e9cialis\u00e9 dans l&#039;art de l&#039;escalade. Son \u00e9quipe universitaire a particip\u00e9 activement \u00e0 des comp\u00e9titions d&#039;escalade et a obtenu des succ\u00e8s remarquables. Cela a attir\u00e9 l&#039;attention de l&#039;arm\u00e9e indon\u00e9sienne, qui a fait appel \u00e0 son expertise pour former ses forces militaires et sp\u00e9ciales en raison d&#039;une p\u00e9nurie d&#039;instructeurs d&#039;escalade qualifi\u00e9s.<\/p>\n<p>Cependant, les int\u00e9r\u00eats de Shinta ne r\u00e9sidaient pas particuli\u00e8rement dans les serpents ou les reptiles ; ce sont ses aventures d&#039;escalade en plein air qui ont amen\u00e9 ces cr\u00e9atures fascinantes dans sa vie. Apr\u00e8s avoir obtenu son dipl\u00f4me universitaire, elle a d\u00e9croch\u00e9 un emploi dans le service comptable d\u2019une soci\u00e9t\u00e9 mini\u00e8re de charbon. Malgr\u00e9 sa vie professionnelle bien remplie, elle a continu\u00e9 \u00e0 entretenir son r\u00e9seau d&#039;amis aventureux qui exploraient toujours Kalimantan.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-28514 aligncenter\" src=\"https:\/\/mlucpnxbn6mg.i.optimole.com\/w:auto\/h:auto\/q:mauto\/process:28514\/id:e91e77cb287ffdc090c3c82d55f0f07b\/https:\/\/instantkarmamag.com\/Picture1.jpg\" alt=\"\" width=\"602\" height=\"343\" title=\"\"><\/p>\n<p>Shinta et ses amis ont fond\u00e9 Borneo Wildlife Rescue, qui, je crois, est toujours actif aujourd&#039;hui.<\/p>\n<p>Au cours de l\u2019une de leurs nombreuses aventures, ils sont tomb\u00e9s sur quelque chose de vraiment extraordinaire : une colonie d\u2019orangs-outans sauvages dans le sud du Kalimantan.<\/p>\n<p>Voici ce qui rend cette d\u00e9couverte si remarquable : il n&#039;y avait jamais eu de signalement d&#039;orangs-outans dans cette r\u00e9gion auparavant.<\/p>\n<p>Shinta et ses amis ont fait tout leur possible pour alerter les autorit\u00e9s et les m\u00e9dias de leur remarquable d\u00e9couverte.<\/p>\n<p>Malheureusement, personne ne les a cru. Les enjeux financiers importants impliqu\u00e9s et le manque de preuves document\u00e9es (lire : photos) pour \u00e9tayer leur d\u00e9couverte ont conduit \u00e0 ce que leurs affirmations soient accueillies avec scepticisme.<\/p>\n<p>Les projets destructeurs se poursuivraient et les maisons et les vies des orangs-outans seraient d\u00e9truites.<\/p>\n<p>Malgr\u00e9 ces d\u00e9fis, un journaliste intr\u00e9pide a \u00e9cout\u00e9.<\/p>\n<p>Frustr\u00e9s par le manque de confiance dans leur d\u00e9couverte, Shinta et son \u00e9quipe ont contact\u00e9 la communaut\u00e9 scientifique internationale. Quatre scientifiques venus des quatre coins du monde ont r\u00e9pondu \u00e0 l&#039;appel. Ils sont chacun mont\u00e9s \u00e0 bord d&#039;un avion et sont partis \u00e0 la rencontre de Shinta et de son \u00e9quipage. Leur mission \u00e9tait claire : confirmer ou infirmer les affirmations de Shinta concernant les orangs-outans dans le Kalimantan du Sud.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-28508 aligncenter\" src=\"https:\/\/mlucpnxbn6mg.i.optimole.com\/w:auto\/h:auto\/q:mauto\/process:28508\/id:b864218ddb81f5429319e8849fc6bb54\/https:\/\/instantkarmamag.com\/Picture7.jpg\" alt=\"\" width=\"602\" height=\"338\" title=\"\"><\/p>\n<p>Pour approfondir l\u2019authenticit\u00e9 et le caract\u00e8re unique de ce conte, je vous encourage \u00e0 explorer les articles et publications propos\u00e9s.<\/p>\n<h2>Corruption et menaces<\/h2>\n<p>Pendant que l\u2019\u00e9quipe attendait l\u2019arriv\u00e9e des scientifiques, Shinta se retrouvait au centre de toutes les attentions. Des journalistes et des partis ayant des enjeux financiers importants dans la r\u00e9gion l\u2019ont contact\u00e9e. Ils lui ont fait des offres substantielles, souvent des sommes \u00e0 six chiffres, pour la dissuader de rendre compte ou de publier ses d\u00e9couvertes. L&#039;offre d&#039;argent s&#039;accompagnait \u00e9galement de menaces si elle n&#039;acceptait pas.<\/p>\n<h3>Le sacrifice<\/h3>\n<p>Avant de continuer, vous devez comprendre l\u2019immense sacrifice personnel impliqu\u00e9.<\/p>\n<p>Shinta \u00e9tait titulaire d&#039;un dipl\u00f4me en finance et en \u00e9conomie et occupait un emploi bien r\u00e9mun\u00e9r\u00e9 dans une soci\u00e9t\u00e9 multinationale d&#039;extraction de charbon. Elle \u00e9tait enti\u00e8rement propri\u00e9taire de sa maison \u00e0 Kalimantan, sans aucune dette malgr\u00e9 son jeune \u00e2ge. Elle aurait un bel avenir financier si elle respectait les r\u00e8gles et oubliait les orangs-outans. Mais ce n&#039;est pas Shinta.<\/p>\n<h3>Histoire vraie<\/h3>\n<p>D\u00e8s l\u2019arriv\u00e9e des scientifiques, l\u2019exp\u00e9dition n\u2019a pas perdu de temps pour partir \u00e0 la recherche des orangs-outans. Men\u00e9s par Shinta, ils s&#039;enfoncent au plus profond de la jungle. Les scientifiques avaient des contraintes financi\u00e8res et temporelles et ne pouvaient pas poursuivre sans fin ces cr\u00e9atures insaisissables. Le temps pressait donc.<\/p>\n<p>Il est difficile d\u2019exprimer \u00e0 quel point ces jungles peuvent \u00eatre formidables. Ce n&#039;\u00e9tait pas une randonn\u00e9e tranquille ; ce fut une exp\u00e9dition \u00e9puisante au c\u0153ur d\u2019une nature sauvage et sauvage, une v\u00e9ritable mission impossible.<\/p>\n<p>Pendant un jour ou deux, l&#039;\u00e9quipe de Shinta a pu entendre les orangs-outans, mais ils n&#039;ont pas pu s&#039;approcher suffisamment pour une confirmation visuelle. Les orangs-outans gardaient leurs distances et, m\u00eame si l&#039;\u00e9quipe scientifique \u00e9tait enthousiasm\u00e9e par les bruits des singes dans les arbres, cela ne suffirait pas \u00e0 stopper la destruction de leur habitat.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-28513 aligncenter\" src=\"https:\/\/mlucpnxbn6mg.i.optimole.com\/w:auto\/h:auto\/q:mauto\/process:28513\/id:5017c29f4fb56297a8458af901a4af53\/https:\/\/instantkarmamag.com\/Picture2.jpg\" alt=\"\" width=\"602\" height=\"338\" title=\"\"><\/p>\n<p>&nbsp;<\/p>\n<h3>Il leur fallait des preuves et le temps presse.<\/h3>\n<p>L&#039;\u00e9quipe \u00e9tait toujours \u00e0 port\u00e9e de voix mais jamais assez pr\u00e8s pour une confirmation visuelle. Ils discutaient constamment des solutions \u00e0 ce probl\u00e8me, heure par heure, sachant que l&#039;\u00e9quipe scientifique devrait bient\u00f4t rentrer chez elle.<\/p>\n<p>La frustration \u00e9tait le mot du jour. L&#039;exp\u00e9dition pouvait dire \u00e0 quel point ils \u00e9taient proches gr\u00e2ce aux bruits. Si proche, mais pourtant si loin.<\/p>\n<p>Le lendemain matin, l\u2019\u00e9quipe est partie t\u00f4t, sachant qu\u2019elle aurait la meilleure chance de capturer les orangs-outans avant qu\u2019ils ne deviennent mobiles.<\/p>\n<h3>\u00ab Fous \u00bb sauvent la journ\u00e9e<\/h3>\n<p>\u00c0 la t\u00eate de l&#039;exp\u00e9dition, Shinta a entendu la colonie d&#039;orangs-outans. Elle savait qu&#039;ils \u00e9taient proches.<\/p>\n<p>Ce que je m\u2019appr\u00eate \u00e0 dire sera attest\u00e9 par Dieu, et puis-je dire seulement la v\u00e9rit\u00e9.<\/p>\n<p>Shinta a fait signe \u00e0 son \u00e9quipe et aux scientifiques de s&#039;arr\u00eater et de tenir bon. Elle s&#039;est d\u00e9plac\u00e9e environ 100 m\u00e8tres devant l&#039;\u00e9quipe en direction du bruit. Lorsqu\u2019elle a su que les orangs-outans l\u2019observaient, elle a su qu\u2019elle avait l\u2019attention des m\u00e2les Alpha.<\/p>\n<p>Dans un geste audacieux, elle a enlev\u00e9 ses v\u00eatements et, faute d&#039;une meilleure expression, &quot;a montr\u00e9 ses seins&quot;. La r\u00e9ponse fut imm\u00e9diate ; il y avait du chahut dans les arbres alors que les m\u00e2les devenaient fous. Les m\u00e2les et peut-\u00eatre m\u00eame les femelles sont devenus curieux et ont commenc\u00e9 \u00e0 venir enqu\u00eater.<\/p>\n<p>Shinta avait toute leur attention ; les orangs-outans \u00e9taient captiv\u00e9s et ont mis la peur de c\u00f4t\u00e9. Elle a communiqu\u00e9 avec l&#039;exp\u00e9dition et ils ont r\u00e9ussi \u00e0 prendre des photographies d&#039;orangs-outans du Kalimantan du Sud qui n&#039;avaient jamais \u00e9t\u00e9 enregistr\u00e9es auparavant.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-28509 aligncenter\" src=\"https:\/\/mlucpnxbn6mg.i.optimole.com\/w:auto\/h:auto\/q:mauto\/process:28509\/id:b3c548a53e9735d1ebcc1a1fb7c3966f\/https:\/\/instantkarmamag.com\/Picture6.jpg\" alt=\"\" width=\"493\" height=\"493\" title=\"\"><\/p>\n<h3>Le prix \u00e0 payer<\/h3>\n<p>L\u2019\u00e9quipe est rentr\u00e9e chez elle ravie. Tout le monde \u00e9tait au top. Mission accomplie.<\/p>\n<p>Tout le monde sauf Shinta. La confirmation de la pr\u00e9sence d&#039;orangs-outans signifiait que la vie de Shinta \u00e9tait en danger.<\/p>\n<p>Elle a d\u00fb rapidement mettre en \u0153uvre son plan de secours.<\/p>\n<p>&nbsp;<\/p>\n<h2>La naissance du sauvetage des reptiles \u00e0 Bali<\/h2>\n<p>Shinta s&#039;\u00e9tait vu offrir des sommes d&#039;argent substantielles pour se taire. Elle a contact\u00e9 le journaliste qui souhaitait publier l&#039;article et a organis\u00e9 des vols vers Bali. Shinta a demand\u00e9 \u00e0 la journaliste de ne pas publier l&#039;article jusqu&#039;\u00e0 ce qu&#039;elle ait confirm\u00e9 son arriv\u00e9e \u00e0 Bali, et un accord similaire a \u00e9t\u00e9 conclu avec les scientifiques. Tout le monde a d\u00fb attendre que Shinta quitte Born\u00e9o.<\/p>\n<p>Une fois que Shinta a atteint Bali en toute s\u00e9curit\u00e9, tout le monde a \u00e9t\u00e9 inform\u00e9 et les articles ont \u00e9t\u00e9 publi\u00e9s, ce qui n&#039;a pas plu aux grandes entreprises. Shinta a d\u00e9m\u00e9nag\u00e9 \u00e0 Bali et a cr\u00e9\u00e9 Bali Reptile Rescue.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-28507 aligncenter\" src=\"https:\/\/mlucpnxbn6mg.i.optimole.com\/w:auto\/h:auto\/q:mauto\/process:28507\/id:6c63379928af79f65051cd9be27222e0\/https:\/\/instantkarmamag.com\/Picture8.png\" alt=\"\" width=\"250\" height=\"327\" title=\"\"><\/p>\n<p>&nbsp;<\/p>\n<p>Les terres de Born\u00e9o sont d\u00e9sormais devenues un sanctuaire pour les orangs-outans.<\/p>\n<p>Shinta s&#039;est abstenue de retourner l\u00e0 o\u00f9 elle a grandi pendant dix ans. M\u00eame \u00e0 ce moment-l\u00e0, elle avait toujours peur que son nom soit connu en raison des menaces de mort port\u00e9es contre elle.<\/p>\n<p>L&#039;auteur de cet article est son mari. Je suis tellement fier de ma femme.<\/p>\n<p>J\u2019esp\u00e8re que vous attendez avec impatience notre prochain article.<\/p>\n<p>Nous avons tellement d\u2019informations \u00e0 partager avec la communaut\u00e9.<\/p>\n<p>&nbsp;<\/p>\n<h2>Qu&#039;avez-vous besoin de savoir:<\/h2>\n<p>Bali Reptile Rescue est au service de la communaut\u00e9. De la peur au respect.<\/p>\n<p>Nous sommes une organisation \u00e0 but non lucratif qui ne re\u00e7oit aucun financement externe.<\/p>\n<p>Nous collaborons \u00e9troitement avec le gouvernement indon\u00e9sien et nos efforts ont re\u00e7u un soutien officiel.<\/p>\n<p>Nous sommes une famille de b\u00e9n\u00e9voles.<\/p>\n<p>Nous ne vendons pas, ne gardons pas, ne tuons pas et ne profitons pas des reptiles captur\u00e9s. Tous les animaux sont rel\u00e2ch\u00e9s dans la nature. Nous ne faisons ni commerce ni \u00e9levage d&#039;animaux. Notre \u00e9quipe est compos\u00e9e d&#039;experts, notamment des scientifiques, des v\u00e9t\u00e9rinaires et des manutentionnaires qualifi\u00e9s. Nous b\u00e9n\u00e9ficions d\u2019une reconnaissance et d\u2019un respect internationaux gr\u00e2ce \u00e0 un r\u00e9seau d\u2019amis et d\u2019associ\u00e9s \u00e0 travers le monde.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Vous aimez les histoires d\u2019aventures ? J\u2019en ai une pour vous, une vraie. <\/p>","protected":false},"author":1,"featured_media":28506,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"categories":[275],"tags":[],"section":[387,388],"interest":[372,401],"_magazine":[],"class_list":["post-28500","article","type-article","status-publish","has-post-thumbnail","hentry","category-impact","section-impact","section-people","interest-eco","interest-nature"],"_links":{"self":[{"href":"https:\/\/instantkarmamag.com\/fr\/wp-json\/wp\/v2\/article\/28500","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/instantkarmamag.com\/fr\/wp-json\/wp\/v2\/article"}],"about":[{"href":"https:\/\/instantkarmamag.com\/fr\/wp-json\/wp\/v2\/types\/article"}],"author":[{"embeddable":true,"href":"https:\/\/instantkarmamag.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/instantkarmamag.com\/fr\/wp-json\/wp\/v2\/comments?post=28500"}],"version-history":[{"count":0,"href":"https:\/\/instantkarmamag.com\/fr\/wp-json\/wp\/v2\/article\/28500\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/instantkarmamag.com\/fr\/wp-json\/wp\/v2\/media\/28506"}],"wp:attachment":[{"href":"https:\/\/instantkarmamag.com\/fr\/wp-json\/wp\/v2\/media?parent=28500"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/instantkarmamag.com\/fr\/wp-json\/wp\/v2\/categories?post=28500"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/instantkarmamag.com\/fr\/wp-json\/wp\/v2\/tags?post=28500"},{"taxonomy":"section","embeddable":true,"href":"https:\/\/instantkarmamag.com\/fr\/wp-json\/wp\/v2\/section?post=28500"},{"taxonomy":"interest","embeddable":true,"href":"https:\/\/instantkarmamag.com\/fr\/wp-json\/wp\/v2\/interest?post=28500"},{"taxonomy":"_magazine","embeddable":true,"href":"https:\/\/instantkarmamag.com\/fr\/wp-json\/wp\/v2\/_magazine?post=28500"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}<!-- This website is optimized by Airlift. Learn more: https://airlift.net. Template:. Learn more: https://airlift.net. Template: 6a3c9e6bc6af5a91495580da. Config Timestamp: 2026-06-25 03:19:51 UTC, Cached Timestamp: 2026-09-02 03:40:09 UTC -->