{"id":28269,"date":"2023-11-06T13:20:34","date_gmt":"2023-11-06T05:20:34","guid":{"rendered":"https:\/\/instantkarmamag.com\/?post_type=article&#038;p=28269"},"modified":"2024-02-13T15:48:09","modified_gmt":"2024-02-13T07:48:09","slug":"activer-la-communaute-pour-le-tourisme-durable","status":"publish","type":"article","link":"https:\/\/instantkarmamag.com\/fr\/article\/activer-la-communaute-pour-le-tourisme-durable\/","title":{"rendered":"Activer la communaut\u00e9 pour le tourisme durable"},"content":{"rendered":"<div id=\"bsf_rt_marker\"><\/div><h3 style=\"text-align: center;\"><span data-contrast=\"auto\">Une renomm\u00e9e<\/span><span data-contrast=\"none\">\u00e9d<\/span><span data-contrast=\"auto\"> Un professeur balinais a dit un jour\u00a0: <\/span><\/h3>\n<h3 style=\"text-align: center;\"><span data-contrast=\"auto\">\u00ab Bali devrait appliquer le concept d&#039;\u00e9cotourisme : ce que nous avons en <\/span><span data-contrast=\"none\">la nature est <\/span><span data-contrast=\"auto\">l&#039;attraction&quot;.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/h3>\n<p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">C&#039;est un peu <\/span><span data-contrast=\"none\">c&#039;est d\u00e9courageant<\/span><span data-contrast=\"auto\">t le tourisme de masse actuel impose que les terres et les rizi\u00e8res soient converties en caf\u00e9s, clubs de plage, h\u00f4tels et bien d\u2019autres p\u00f4les d\u2019attraction touristique.\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Mais l\u2019\u00e9cotourisme \u2013 ou tourisme durable \u2013 reste <\/span><span data-contrast=\"none\">a<\/span><span data-contrast=\"auto\"> ses champions, et l&#039;un d&#039;eux est Jaringan Ekowisata Desa (Village Ecotourism Network), une \u00e9manation de l&#039;ONG locale Wisnu Foundation, qui vise \u00e0 construire un tourisme communautaire, o\u00f9 les <\/span><span data-contrast=\"none\">la communaut\u00e9 est l\u2019acteur cl\u00e9 qui dirige le spectacle, et non les entreprises.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\"> <img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-28276 aligncenter\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/11\/why-jed-intro-images3@2x.jpg\" alt=\"tourisme durable bali jaringan ekowisata desa jed.or.id\" width=\"660\" height=\"750\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/11\/why-jed-intro-images3@2x.jpg 660w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/11\/why-jed-intro-images3@2x-264x300.jpg 264w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/11\/why-jed-intro-images3@2x-624x709.jpg 624w\" sizes=\"auto, (max-width: 660px) 100vw, 660px\" \/><\/span><\/p>\n<h3><span data-contrast=\"none\">Quoi<\/span><span data-contrast=\"auto\"> qu&#039;est-ce que l&#039;\u00e9cotourisme ?<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/h3>\n<p><span data-contrast=\"auto\">\u00ab Tout a commenc\u00e9 avec le th\u00e8me du tourisme durable, mais c&#039;est un terme g\u00e9n\u00e9rique. Nous pr\u00e9f\u00e9rons <\/span><span data-contrast=\"none\">approche <\/span><span data-contrast=\"auto\">le sujet d&#039;un point de vue environnemental \u00bb, d\u00e9clare Bapak Gede Sugiartha, responsable des donn\u00e9es et de la communication de la Fondation Wisnu.\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">\u00ab Le tourisme de masse existe depuis longtemps \u00e0 Bali et a drain\u00e9 nos ressources naturelles, de la nourriture \u00e0 l&#039;eau en passant par l&#039;\u00e9nergie, sans parler de la cr\u00e9ation de davantage de d\u00e9chets. Ainsi, alors que les agences gouvernementales ont opt\u00e9 pour des ateliers et des formations sur le tourisme durable, nous choisissons une solution plus naturelle qui ne change pas le \u00ab visage \u00bb du village. Nous n\u2019avons pas besoin de construire des h\u00f4tels et des villas. Il ne s&#039;agit pas d&#039;essayer de mettre les clients \u00e0 l&#039;aise mais plut\u00f4t de leur montrer le vrai visage de <a href=\"https:\/\/instantkarmamag.com\/fr\/destination\/bali\/\">Bali.<\/a>\u00bb<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">L&#039;authenticit\u00e9 est <\/span><span data-contrast=\"none\">cl\u00e9 - un<\/span><span data-contrast=\"auto\">Cela inclut la pr\u00e9servation de la nature environnante, de la fa\u00e7ade du village et du mode de vie des habitants. <\/span><\/p>\n<p><span data-contrast=\"none\">\u00ab Votre guide touristique est le village.<\/span><span data-contrast=\"auto\"> De quoi parlent-ils? <\/span><span data-contrast=\"auto\">Ils parlent de leur gagne-pain ; si <\/span><span data-contrast=\"none\">ils sont<\/span><span data-contrast=\"auto\"> de la plantation de caf\u00e9, alors ils parleront de caf\u00e9. Ainsi, ce qui est naturellement disponible renforce l\u2019attrait.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\"> <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-31276\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/11\/sustainable-tourism.jpg\" alt=\"tourisme durable\" width=\"801\" height=\"660\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/11\/sustainable-tourism.jpg 801w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/11\/sustainable-tourism-300x247.jpg 300w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/11\/sustainable-tourism-768x633.jpg 768w\" sizes=\"auto, (max-width: 801px) 100vw, 801px\" \/><br \/>\n<\/span><\/p>\n<h2>Le d\u00e9fi du territoire<\/h2>\n<p><span data-contrast=\"none\">Jaringan Ekowisata Desa (JED) <\/span><span data-contrast=\"auto\">a \u00e9t\u00e9 cr\u00e9\u00e9 depuis 2002 et leur projet pilote a d\u00e9but\u00e9 dans quatre villages (ou <\/span><i><span data-contrast=\"auto\">banjar<\/span><\/i><span data-contrast=\"auto\">, la plus petite unit\u00e9 de gouvernance du village, comme l&#039;a corrig\u00e9 pak Gede) : le village de Kiadan \u00e0 Pelaga (connu pour son caf\u00e9), le village de Dukuh \u00e0 Karangasem (pour son<\/span><i><span data-contrast=\"auto\"> salak<\/span><\/i><span data-contrast=\"auto\"> ou fruit en peau de serpent), l&#039;\u00eele de Ceningan \u00e0 Klungkung (pour sa culture d&#039;algues) et le village de Tenganan Pegrinsingan \u00e0 Karangasem (une communaut\u00e9 autochtone qui g\u00e8re ses territoires et ses traditions de mani\u00e8re ind\u00e9pendante).\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\"> <img loading=\"lazy\" decoding=\"async\" class=\"wp-image-28274 size-large aligncenter\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/11\/DSC00037-1-683x1024.jpg\" alt=\"tourisme durable bali jaringan ekowisata desa jed.or.id\" width=\"683\" height=\"1024\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/11\/DSC00037-1-683x1024.jpg 683w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/11\/DSC00037-1-1365x2048.jpg 1365w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/11\/DSC00037-1-200x300.jpg 200w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/11\/DSC00037-1-768x1152.jpg 768w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/11\/DSC00037-1-1024x1536.jpg 1024w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/11\/DSC00037-1-624x936.jpg 624w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/11\/DSC00037-1-scaled.jpg 1707w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/><\/span><\/p>\n<p><span data-contrast=\"auto\">Chaque projet n\u00e9cessite en moyenne trois ann\u00e9es de planification ardue, de cartographie des ressources naturelles, de transfert de connaissances, de renforcement des capacit\u00e9s, de formation, d&#039;encadrement, etc. Le processus est naturellement complexe, et m\u00eame lorsque le r\u00e9sultat est satisfaisant, l\u2019ombre des investisseurs plane parfois.\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Une fois que leur projet dans le village de Dukuh a commenc\u00e9 \u00e0 porter ses fruits, un investisseur \u00e9tranger est arriv\u00e9 avec son permis (d\u00e9livr\u00e9 par le gouvernement) pour cr\u00e9er une marque de vin \u00e0 base de salak ; une opportunit\u00e9 qui aurait pu \u00eatre donn\u00e9e \u00e0 la communaut\u00e9 elle-m\u00eame. Ou comme le d\u00e9plore Pak Gede : \u00ab La communaut\u00e9 devrait \u00eatre les investisseurs \u00bb.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Un autre revers survient lorsque l&#039;attrait du tourisme moderne s&#039;installe. Comme ce qui s&#039;est pass\u00e9 sur l&#039;\u00eele de Ceningan lorsque les habitants ont commenc\u00e9 \u00e0 construire des caf\u00e9s\/restos destin\u00e9s aux touristes \u00e9trangers. Ainsi commen\u00e7a le changement de visage de Ceningan.\u00a0\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\"> <img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-28278 aligncenter\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/11\/why-jed-images-collaboration2@2x.jpg\" alt=\"tourisme durable bali jaringan ekowisata desa jed.or.id\" width=\"754\" height=\"718\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/11\/why-jed-images-collaboration2@2x.jpg 754w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/11\/why-jed-images-collaboration2@2x-300x286.jpg 300w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/11\/why-jed-images-collaboration2@2x-624x594.jpg 624w\" sizes=\"auto, (max-width: 754px) 100vw, 754px\" \/><\/span><\/p>\n<h2>Potentiel en mati\u00e8re sociale<\/h2>\n<p><span data-contrast=\"auto\">Ce mod\u00e8le de tourisme s\u2019est toutefois r\u00e9v\u00e9l\u00e9 non durable face \u00e0 la pand\u00e9mie. Lorsque le Covid a frapp\u00e9, les habitants des villages qui emploient le programme d&#039;\u00e9cotourisme de JED n&#039;ont pratiquement pas \u00e9t\u00e9 touch\u00e9s. Pourquoi? Parce qu\u2019ils ne d\u00e9pendent pas uniquement du tourisme pour gagner leur vie.\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">\u00ab Ils travaillent comme agriculteurs, p\u00eacheurs, couturi\u00e8res et artisans \u2013 et nombre d&#039;entre eux ont pu survivre pendant la pand\u00e9mie \u00bb, explique Fransiska Natalia, responsable des programmes et du marketing de JED. \u00ab Une application id\u00e9ale de l\u2019\u00e9cotourisme est qu\u2019il ne repose pas uniquement sur le tourisme. Le tourisme n\u2019est qu\u2019un bonus.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Siska explique en outre qu&#039;au c\u0153ur du d\u00e9veloppement durable<\/span><span data-contrast=\"none\"> le tourisme, r\u00e9side dans <\/span><span data-contrast=\"auto\">la communaut\u00e9. \u00ab [Dans l&#039;\u00e9cotourisme] la communaut\u00e9 n&#039;est plus \u00ab l&#039;objet \u00bb, mais <\/span><span data-contrast=\"none\">le sujet que<\/span><span data-contrast=\"auto\"> est activement impliqu\u00e9. La participation ne concerne pas seulement le lieu, mais aussi le fait qu\u2019ils g\u00e8rent ensemble la gestion.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\"> <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-31278 size-full\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/11\/sustainable-tourism-2.jpg\" alt=\"\" width=\"676\" height=\"805\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/11\/sustainable-tourism-2.jpg 676w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/11\/sustainable-tourism-2-252x300.jpg 252w\" sizes=\"auto, (max-width: 676px) 100vw, 676px\" \/><\/span><\/p>\n<h3 style=\"text-align: center;\"><span data-contrast=\"auto\">L&#039;aspect environnemental devrait en effet \u00eatre un aspect crucial du tourisme durable. <\/span><\/h3>\n<p>&nbsp;<\/p>\n<h2 style=\"text-align: center;\"><span data-contrast=\"auto\">JED nous rappelle de ne pas oublier les gens. <\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/h2>\n<p><span data-contrast=\"auto\">\u00abLorsque nous parlons d&#039;\u00e9cotourisme durable, trois \u00e9l\u00e9ments sont g\u00e9n\u00e9ralement impliqu\u00e9s\u00a0: le social, l&#039;environnement et l&#039;\u00e9conomie&quot;, explique Siska. \u00ab On parle souvent davantage de quel impact financier apportez-vous \u00e0 la communaut\u00e9 ? Mais nous voyons plus de potentiel dans le social. En responsabilisant la communaut\u00e9.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<h2 style=\"text-align: center;\"><span data-contrast=\"none\">Il faut un village pour donner le pouvoir au peuple. C&#039;est plus durable de cette fa\u00e7on.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/h2>\n<p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"none\">Vivez une vie authentique \u00e0 Bali pendant vos vacances ici, rendez-vous sur <\/span><a href=\"http:\/\/www.jed.com\" target=\"_blank\" rel=\"noopener\"><span data-contrast=\"none\">www.jed.or.id<\/span><\/a><span data-contrast=\"none\"> pour d\u00e9couvrir les 10 villages avec lesquels ils collaborent.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p>Site web <a href=\"http:\/\/www.jed.or.id\" target=\"_blank\" rel=\"noopener\"><i><span data-contrast=\"none\">www.jed.or.id<\/span><\/i><\/a><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><i><span data-contrast=\"auto\">Instagram <a href=\"https:\/\/www.instagram.com\/jed.bali\/\" target=\"_blank\" rel=\"noopener\">@jed.bali<\/a><\/span><\/i><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>Le tourisme de masse a caus\u00e9 plus de mal que de bien. Selon Jaringan Ekowisata Desa, la solution r\u00e9side dans la communaut\u00e9.   <\/p>","protected":false},"author":46,"featured_media":31276,"comment_status":"open","ping_status":"closed","template":"","meta":{"footnotes":""},"categories":[275],"tags":[368],"section":[387],"interest":[381,377],"_magazine":[328],"class_list":["post-28269","article","type-article","status-publish","has-post-thumbnail","hentry","category-impact","tag-368","section-impact","interest-empowerment","interest-sightseeing","_magazine-328"],"_links":{"self":[{"href":"https:\/\/instantkarmamag.com\/fr\/wp-json\/wp\/v2\/article\/28269","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/instantkarmamag.com\/fr\/wp-json\/wp\/v2\/article"}],"about":[{"href":"https:\/\/instantkarmamag.com\/fr\/wp-json\/wp\/v2\/types\/article"}],"author":[{"embeddable":true,"href":"https:\/\/instantkarmamag.com\/fr\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/instantkarmamag.com\/fr\/wp-json\/wp\/v2\/comments?post=28269"}],"version-history":[{"count":0,"href":"https:\/\/instantkarmamag.com\/fr\/wp-json\/wp\/v2\/article\/28269\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/instantkarmamag.com\/fr\/wp-json\/wp\/v2\/media\/31276"}],"wp:attachment":[{"href":"https:\/\/instantkarmamag.com\/fr\/wp-json\/wp\/v2\/media?parent=28269"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/instantkarmamag.com\/fr\/wp-json\/wp\/v2\/categories?post=28269"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/instantkarmamag.com\/fr\/wp-json\/wp\/v2\/tags?post=28269"},{"taxonomy":"section","embeddable":true,"href":"https:\/\/instantkarmamag.com\/fr\/wp-json\/wp\/v2\/section?post=28269"},{"taxonomy":"interest","embeddable":true,"href":"https:\/\/instantkarmamag.com\/fr\/wp-json\/wp\/v2\/interest?post=28269"},{"taxonomy":"_magazine","embeddable":true,"href":"https:\/\/instantkarmamag.com\/fr\/wp-json\/wp\/v2\/_magazine?post=28269"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}<!-- This website is optimized by Airlift. Learn more: https://airlift.net. Template:. Learn more: https://airlift.net. Template: 6a3c9e6bc6af5a91495580da. Config Timestamp: 2026-06-25 03:19:51 UTC, Cached Timestamp: 2026-09-02 03:02:34 UTC -->