{"id":19697,"date":"2022-11-04T15:35:11","date_gmt":"2022-11-04T07:35:11","guid":{"rendered":"https:\/\/instantkarmamag.com\/?post_type=article&#038;p=19697"},"modified":"2024-10-27T22:20:00","modified_gmt":"2024-10-27T14:20:00","slug":"festival-sumbas-pasola","status":"publish","type":"article","link":"https:\/\/instantkarmamag.com\/fr\/article\/festival-sumbas-pasola\/","title":{"rendered":"Festival Pasola de Sumba"},"content":{"rendered":"<div id=\"bsf_rt_marker\"><\/div><p>Ici, il n&#039;y a pas de rizi\u00e8res en terrasses abruptes, pas de volcans imposants, de temples orn\u00e9s ou de monuments embl\u00e9matiques si r\u00e9pandus sur d&#039;autres \u00eeles de ce pays tentaculaire et diversifi\u00e9 appel\u00e9 l&#039;\u00eele de Sumba. [\u2026]<\/p>\n<h2>&quot;<span lang=\"en-US\">Il y aura du sang.&quot; <\/span><\/h2>\n<h3><span lang=\"en-US\">Le festival Pasola de Sumba <\/span><\/h3>\n<p><span lang=\"en-US\">\u00c0 la fin des ann\u00e9es 1800, Sumba \u00e9tait une escale commerciale privil\u00e9gi\u00e9e pour les marins hollandais qui, pendant environ cent ans, ont syst\u00e9matiquement d\u00e9pouill\u00e9 et abattu pratiquement tous les arbres de bois de santal qui couvraient la majeure partie de ce paradis idyllique et ont ramen\u00e9 cette ressource naturelle tr\u00e8s pris\u00e9e en Europe. \u00e0 vendre. <\/span><\/p>\n<p><span lang=\"en-US\">Le r\u00e9sultat du pillage a transform\u00e9 l\u2019est de l\u2019\u00eele en une prairie vallonn\u00e9e grill\u00e9e par le soleil impitoyable du sud pendant la longue et chaude saison s\u00e8che. L&#039;ouest de l&#039;\u00eele semble recevoir la part du lion des pluies avec des collines basses au vert verdoyant et des rizi\u00e8res s&#039;\u00e9tendant presque jusqu&#039;\u00e0 l&#039;horizon.<\/span><\/p>\n<p><span lang=\"en-US\">D&#039;une position \u00e9lev\u00e9e, le terrain vallonn\u00e9 rappelle la Meseta Central en Espagne et, comme son homologue espagnol, il s&#039;est d\u00e9velopp\u00e9 en un pays de bons chevaux et la joute est devenue un sport favori. <\/span><\/p>\n<p><span lang=\"en-US\">En quittant le seul a\u00e9roport de l&#039;\u00eele, la pauvret\u00e9 est palpable si l&#039;on en croit les routes, car beaucoup se sont d\u00e9t\u00e9rior\u00e9es au point que sur certains tron\u00e7ons, elles se transforment en une s\u00e9rie de nids-de-poule reli\u00e9s par de fines couches de bitume. <\/span><\/p>\n<p><span lang=\"en-US\">Dans les villes h\u00e9t\u00e9roclites, les minibus qui passent, les motos, les voitures et les chevaux cannibalis\u00e9s rejettent des nuages de poussi\u00e8re qui d\u00e9rivent dans les magasins \u00e0 devanture ouverte pour se d\u00e9poser sur la vaste gamme de marchandises qui s&#039;y trouvent. Ces magasins faiblement \u00e9clair\u00e9s sont de v\u00e9ritables grottes d&#039;Aladdin, chacune remplie jusqu&#039;aux chevrons de sacs de riz, de chaises en plastique vert sinistre, de ballons de plage, de tongs, de mat\u00e9riaux de construction, de bo\u00eetes de thon et de lait concentr\u00e9, de bouteilles g\u00e9antes de sauce soja, de pneus de moto, de carton ondul\u00e9. des tuiles, en fait, tout ce dont un villageois isol\u00e9 pourrait avoir besoin lors d&#039;un voyage peu fr\u00e9quent en \u00ab ville \u00bb. <\/span><\/p>\n<p>En savoir plus sur <a href=\"https:\/\/instantkarmamag.com\/fr\/article\/the-enchantment-of-sumba-island\/\">L&#039;enchantement de l&#039;\u00eele de Sumba<\/a><\/p>\n<p><span lang=\"en-US\">Comme la plupart des r\u00e9gions pauvres de ce vaste comt\u00e9, ce sont les gens qui font briller chaque r\u00e9gion et Sumba n\u2019est pas diff\u00e9rente. Les sourires sont une \u00e9vidence et les enfants qui se rendent dans des \u00e9coles \u00e9loign\u00e9es, portant des chaussures mal ajust\u00e9es, n&#039;h\u00e9sitent pas \u00e0 crier un joyeux \u00ab\u00a0Bonjour Monsieur\u00a0\u00bb du haut de leur voix collective.<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-19791 size-large\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/11\/Toda-Village-3.jpeg\" alt=\"festival pasola pour enfants de sumba\" width=\"1024\" height=\"1024\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/11\/Toda-Village-3.jpeg 1080w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/11\/Toda-Village-3-250x250.jpeg 250w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/11\/Toda-Village-3-300x300.jpeg 300w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/11\/Toda-Village-3-768x768.jpeg 768w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/11\/Toda-Village-3-1024x1024.jpeg 1024w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/11\/Toda-Village-3-150x150.jpeg 150w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/11\/Toda-Village-3-624x624.jpeg 624w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p lang=\"de-CH\"><span lang=\"en-US\">Je suis venu \u00e0 Sumba pour exp\u00e9rimenter le <\/span><span lang=\"en-US\"><i>Festival Pasola<\/i><\/span><span lang=\"en-US\"> tournois qui ont lieu dans toute l&#039;\u00eele pendant les mois pluvieux de f\u00e9vrier et mars. L&#039;origine du pourquoi et du moment de cette f\u00eate semble \u00eatre sujette \u00e0 interpr\u00e9tation selon le quartier ou le village visit\u00e9. <\/span><\/p>\n<p lang=\"de-CH\"><span lang=\"en-US\">Une description d\u00e9taill\u00e9e m&#039;a \u00e9t\u00e9 racont\u00e9e alors que j&#039;\u00e9tais assis sur la terrasse en bambou d&#039;une maison de village avec son toit de chaume embl\u00e9matique de forme conique s&#039;\u00e9levant \u00e0 cinquante ou soixante pieds au-dessus de nous. Certaines th\u00e9ories sugg\u00e8rent que l&#039;arriv\u00e9e des vers marins qui d\u00e9barquent \u00e0 une certaine heure chaque ann\u00e9e est le signe qu&#039;il est temps de r\u00e9colter et qu&#039;il faut donc verser du sang sur les champs. <\/span><\/p>\n<h2 lang=\"de-CH\" style=\"text-align: center;\">\u00ab Pendant la f\u00eate de Pasola, le sang doit couler dans les champs \u00bb<\/h2>\n<p lang=\"de-CH\"><span lang=\"en-US\">Une autre l\u00e9gende raconte qu&#039;un certain chef de village partit un jour pour des \u00ab affaires de clan \u00bb et ne revint pas. Sa femme, le croyant mort, prit un autre amant dans un village rival. Apr\u00e8s plusieurs ann\u00e9es, le mari revint inopin\u00e9ment et se rendit compte que son \u00e9pouse l&#039;avait quitt\u00e9. UN<\/span><span lang=\"en-US\"><i> Festival Pasola<\/i><\/span><span lang=\"en-US\"> a \u00e9t\u00e9 arrang\u00e9 pour tenter d&#039;apaiser sa solitude. <\/span><\/p>\n<h3 lang=\"de-CH\"><span lang=\"en-US\">Alors, qui sait ? <\/span><\/h3>\n<p>&nbsp;<\/p>\n<h2 lang=\"de-CH\" style=\"text-align: center;\"><span lang=\"en-US\">Le mot <\/span><span lang=\"en-US\"><i>Pasola<\/i><\/span><span lang=\"en-US\"> dans le dialecte local, cela signifie lance et c&#039;est l&#039;arme de choix des cavaliers capables de lancer ces javelots potentiellement mortels jusqu&#039;\u00e0 soixante-dix m\u00e8tres alors qu&#039;ils sont assis sur un cheval au grand galop. <\/span><\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-19698 size-full\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/11\/0c3b93b9-8e8e-4fa1-8b38-b15659f6a0a0.jpg\" alt=\"festival sumbas pasola\" width=\"960\" height=\"544\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/11\/0c3b93b9-8e8e-4fa1-8b38-b15659f6a0a0.jpg 960w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/11\/0c3b93b9-8e8e-4fa1-8b38-b15659f6a0a0-300x170.jpg 300w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/11\/0c3b93b9-8e8e-4fa1-8b38-b15659f6a0a0-768x435.jpg 768w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/11\/0c3b93b9-8e8e-4fa1-8b38-b15659f6a0a0-624x354.jpg 624w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/p>\n<p>Le \u00ab champ de bataille \u00bb est une vaste \u00e9tendue de terrain plat et ouvert adjacente \u00e0 l&#039;oc\u00e9an. Autour du terrain, le terrain est en pente ascendante sur trois c\u00f4t\u00e9s, offrant une excellente plate-forme d&#039;observation aux milliers de spectateurs rassembl\u00e9s pour les festivit\u00e9s de la journ\u00e9e. Ce spectacle du Festival Pasola ressemble vraiment \u00e0 celui des citoyens de Rome assistant \u00e0 une journ\u00e9e au Colis\u00e9e o\u00f9 hommes, femmes et enfants turbulents attendent en pleine voix l&#039;arriv\u00e9e des gladiateurs pour se battre.<\/p>\n<p lang=\"de-CH\"><span lang=\"en-US\">Au bon moment, des groupes de jeunes hommes f\u00e9roces \u00e0 cheval se frayent un chemin depuis la plage et \u00e0 travers la foule, portant une gamme de coiffures plut\u00f4t splendides : des fascinations de plumes aux couleurs vives ou des c\u00f4nes \u00e9trangement pointus attach\u00e9s par de longs rubans et foulards fluides. <\/span><\/p>\n<p lang=\"de-CH\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-19702 size-large\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/11\/b4b6940d-8cab-4034-bd26-1e281d9ff197.jpg\" alt=\"festival sumbas pasola\" width=\"1024\" height=\"563\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/11\/b4b6940d-8cab-4034-bd26-1e281d9ff197.jpg 1280w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/11\/b4b6940d-8cab-4034-bd26-1e281d9ff197-300x165.jpg 300w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/11\/b4b6940d-8cab-4034-bd26-1e281d9ff197-768x422.jpg 768w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/11\/b4b6940d-8cab-4034-bd26-1e281d9ff197-1024x563.jpg 1024w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/11\/b4b6940d-8cab-4034-bd26-1e281d9ff197-624x343.jpg 624w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p lang=\"de-CH\"><span lang=\"en-US\">Ils sont assis \u00e0 califourchon sur des poneys qui ont \u00e9t\u00e9 d\u00e9cor\u00e9s de la m\u00eame mani\u00e8re avec des pompons sur les oreilles et des rubans multicolores qui tombent de leur cou dans une explosion de couleurs. Leurs pattes sont \u00e9galement orn\u00e9es de petites clochettes et de pi\u00e8ces de monnaie tintantes. C&#039;est un joli spectacle mais il n&#039;y a rien de joli dans les combats ! <\/span><\/p>\n<p lang=\"de-CH\"><span lang=\"en-US\">Les clans rivaux mont\u00e9s se rassemblent et s&#039;affrontent \u00e0 travers le terrain, puis se rapprochent et se frottent les uns contre les autres en groupes serr\u00e9s. <\/span><\/p>\n<h3 lang=\"de-CH\"><span lang=\"en-US\">Ensuite, c&#039;est parti\u00a0! <\/span><\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-19703 size-large\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/11\/bc72ecaf-2009-45ee-8625-170115dfe130.jpg\" alt=\"festival sumbas pasola\" width=\"1024\" height=\"528\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/11\/bc72ecaf-2009-45ee-8625-170115dfe130.jpg 1280w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/11\/bc72ecaf-2009-45ee-8625-170115dfe130-300x155.jpg 300w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/11\/bc72ecaf-2009-45ee-8625-170115dfe130-768x396.jpg 768w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/11\/bc72ecaf-2009-45ee-8625-170115dfe130-1024x528.jpg 1024w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/11\/bc72ecaf-2009-45ee-8625-170115dfe130-624x322.jpg 624w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>Les cavaliers d&#039;un clan galopent dans le sens des aiguilles d&#039;une montre, tandis que leurs rivaux courent \u00e0 fond dans le sens inverse des aiguilles d&#039;une montre. Un cavalier al\u00e9atoire se lib\u00e9rera soudainement du cercle et chargera vers son ennemi. Avec une main agrippant les r\u00eanes, il se penchera vers l&#039;ext\u00e9rieur, au-dessus du cou du cheval pour tenter d&#039;utiliser sa monture comme bouclier, puis s&#039;allongera sur les flancs du cheval et lancera son javelot dans la m\u00eal\u00e9e des cavaliers essayant de marquer un coup direct sur un cheval. l&#039;un des adversaires avant d&#039;effectuer un virage serr\u00e9 en une fraction de seconde pour rejoindre le cercle.<\/p>\n<p lang=\"de-CH\"><span lang=\"en-US\">Tous les cavaliers doivent se tordre, virevolter, esquiver et se prot\u00e9ger du barrage de lances se dirigeant vers eux \u00e0 grande vitesse dans les airs.<\/span><\/p>\n<p lang=\"de-CH\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-19708 size-large\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/11\/IMG_4720-1.jpg\" alt=\"festival sumbas pasola\" width=\"1024\" height=\"725\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/11\/IMG_4720-1.jpg 2560w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/11\/IMG_4720-1-300x213.jpg 300w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/11\/IMG_4720-1-768x544.jpg 768w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/11\/IMG_4720-1-1024x726.jpg 1024w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/11\/IMG_4720-1-1536x1088.jpg 1536w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/11\/IMG_4720-1-2048x1451.jpg 2048w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/11\/IMG_4720-1-624x442.jpg 624w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<h3 lang=\"de-CH\"><span lang=\"en-US\"><strong>C&#039;est \u00e0 couper le souffle.<\/strong> <\/span><\/h3>\n<p lang=\"de-CH\"><span lang=\"en-US\">\u00c0 un moment donn\u00e9, un cavalier particuli\u00e8rement ambitieux s&#039;est \u00e9gar\u00e9 trop pr\u00e8s de \u00ab l&#039;ennemi \u00bb et un d\u00e9luge de lances a \u00e9t\u00e9 lanc\u00e9 \u00e0 son approche. Plusieurs trouv\u00e8rent leur cible avec une lance bien cibl\u00e9e le frappant directement sur le c\u00f4t\u00e9 de la t\u00eate.<\/span><\/p>\n<p lang=\"de-CH\"><span lang=\"en-US\">Lui et son cheval tomb\u00e8rent dans un tourbillon de jambes et de bras volants, le cavalier gisait \u00e0 plat ventre, clairement inconscient. Ce fut l&#039;occasion de c\u00e9l\u00e9brations endiabl\u00e9es, la foule ex\u00e9cutant une danse impromptue sur une jambe en criant des insultes aux clans adverses sur la terrasse d&#039;en face. <\/span><\/p>\n<h3 lang=\"de-CH\"><span lang=\"en-US\">Les tensions commen\u00e7aient \u00e0 monter. <\/span><\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-19704 size-large\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/11\/ccd45d22-f010-47ff-b56b-bdd142b0f457.jpg\" alt=\"festival sumbas pasola\" width=\"1024\" height=\"682\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/11\/ccd45d22-f010-47ff-b56b-bdd142b0f457.jpg 1280w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/11\/ccd45d22-f010-47ff-b56b-bdd142b0f457-300x200.jpg 300w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/11\/ccd45d22-f010-47ff-b56b-bdd142b0f457-768x512.jpg 768w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/11\/ccd45d22-f010-47ff-b56b-bdd142b0f457-1024x682.jpg 1024w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/11\/ccd45d22-f010-47ff-b56b-bdd142b0f457-624x416.jpg 624w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p lang=\"de-CH\"><span lang=\"en-US\">Quelques secondes plus tard, des centaines de spectateurs se sont pr\u00e9cipit\u00e9s sur le terrain et tout le spectacle a soudainement \u00e9clat\u00e9 en \u00e9meute ! Des pierres et des lances \u00e9taient lanc\u00e9es et des machettes vicieuses \u00e9taient brandies par des jeunes hommes en col\u00e8re. \u00c0 ce moment-l\u00e0, la police est arriv\u00e9e, v\u00eatue d&#039;un \u00e9quipement anti-\u00e9meute complet, accompagn\u00e9e d&#039;un v\u00e9hicule blind\u00e9 qui a commenc\u00e9 \u00e0 tirer sur les \u00e9meutiers avec un grand canon \u00e0 eau. Une phalange de policiers, munis de grands boucliers, a avanc\u00e9 en tirant des gaz lacrymog\u00e8nes dans la m\u00eal\u00e9e.<\/span><\/p>\n<p lang=\"de-CH\"><span lang=\"en-US\">En quelques minutes, tout fut termin\u00e9 \u00e0 plus d&#039;un titre lorsqu&#039;une voix autoritaire r\u00e9sonna dans le syst\u00e8me de sonorisation pour informer les 15 000 personnes que le <\/span><span lang=\"en-US\"><i>Pasola<\/i><\/span><span lang=\"en-US\"> Le festival \u00e9tait termin\u00e9 et tout le monde devait rentrer chez soi. <\/span><\/p>\n<p lang=\"de-CH\"><span lang=\"en-US\">En quittant l&#039;\u00e9v\u00e9nement, je savais que j&#039;avais \u00e9t\u00e9 t\u00e9moin de quelque chose d&#039;assez remarquable alors que je rejoignais la foule qui sortait de l&#039;\u00e9v\u00e9nement et qui semblait toujours de bonne humeur. <\/span><\/p>\n<h3>Le monde est vraiment un endroit incroyable.<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-19700 size-large\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/11\/4efd858d-e181-42bf-a9d8-b499cff48aab.jpg\" alt=\"festival sumbas pasola\" width=\"1024\" height=\"768\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/11\/4efd858d-e181-42bf-a9d8-b499cff48aab.jpg 1280w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/11\/4efd858d-e181-42bf-a9d8-b499cff48aab-300x225.jpg 300w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/11\/4efd858d-e181-42bf-a9d8-b499cff48aab-768x576.jpg 768w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/11\/4efd858d-e181-42bf-a9d8-b499cff48aab-1024x768.jpg 1024w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/11\/4efd858d-e181-42bf-a9d8-b499cff48aab-624x468.jpg 624w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p><a href=\"https:\/\/instantkarmamag.com\/fr\/destination\/sumba\/\">Si vous voulez<strong> en savoir plus sur Sumba<\/strong>, Cliquez ici.<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Cet article a \u00e9t\u00e9 \u00e9crit, v\u00e9cu et photographi\u00e9 par <a href=\"https:\/\/www.paulvwalters.net\" target=\"_blank\" rel=\"noopener\">Paul contre Walters<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Ici, il n&#039;y a pas de rizi\u00e8res en terrasses abruptes, pas de volcans imposants, de temples orn\u00e9s ou de monuments embl\u00e9matiques si r\u00e9pandus sur d&#039;autres \u00eeles de ce pays tentaculaire et diversifi\u00e9 appel\u00e9 l&#039;\u00eele de Sumba. [\u2026]<\/p>","protected":false},"author":121,"featured_media":19701,"comment_status":"open","ping_status":"closed","template":"","meta":{"footnotes":""},"categories":[270],"tags":[359,289],"section":[385],"interest":[199,377,400],"_magazine":[357],"class_list":["post-19697","article","type-article","status-publish","has-post-thumbnail","hentry","category-explore","tag-359","tag-sumba","section-explore","interest-expeditions","interest-sightseeing","interest-things-to-do","_magazine-357"],"_links":{"self":[{"href":"https:\/\/instantkarmamag.com\/fr\/wp-json\/wp\/v2\/article\/19697","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/instantkarmamag.com\/fr\/wp-json\/wp\/v2\/article"}],"about":[{"href":"https:\/\/instantkarmamag.com\/fr\/wp-json\/wp\/v2\/types\/article"}],"author":[{"embeddable":true,"href":"https:\/\/instantkarmamag.com\/fr\/wp-json\/wp\/v2\/users\/121"}],"replies":[{"embeddable":true,"href":"https:\/\/instantkarmamag.com\/fr\/wp-json\/wp\/v2\/comments?post=19697"}],"version-history":[{"count":0,"href":"https:\/\/instantkarmamag.com\/fr\/wp-json\/wp\/v2\/article\/19697\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/instantkarmamag.com\/fr\/wp-json\/wp\/v2\/media\/19701"}],"wp:attachment":[{"href":"https:\/\/instantkarmamag.com\/fr\/wp-json\/wp\/v2\/media?parent=19697"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/instantkarmamag.com\/fr\/wp-json\/wp\/v2\/categories?post=19697"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/instantkarmamag.com\/fr\/wp-json\/wp\/v2\/tags?post=19697"},{"taxonomy":"section","embeddable":true,"href":"https:\/\/instantkarmamag.com\/fr\/wp-json\/wp\/v2\/section?post=19697"},{"taxonomy":"interest","embeddable":true,"href":"https:\/\/instantkarmamag.com\/fr\/wp-json\/wp\/v2\/interest?post=19697"},{"taxonomy":"_magazine","embeddable":true,"href":"https:\/\/instantkarmamag.com\/fr\/wp-json\/wp\/v2\/_magazine?post=19697"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}<!-- This website is optimized by Airlift. Learn more: https://airlift.net. Template:. Learn more: https://airlift.net. Template: 6a3c9e6bc6af5a91495580da. Config Timestamp: 2026-06-25 03:19:51 UTC, Cached Timestamp: 2026-09-02 03:03:47 UTC -->