{"id":14837,"date":"2022-09-01T08:02:26","date_gmt":"2022-09-01T00:02:26","guid":{"rendered":"https:\/\/instantkarmamag.com\/?post_type=article&#038;p=14837"},"modified":"2024-07-03T16:20:53","modified_gmt":"2024-07-03T08:20:53","slug":"joseph-nettoie","status":"publish","type":"article","link":"https:\/\/instantkarmamag.com\/fr\/article\/joseph-nettoie\/","title":{"rendered":"Joseph nettoie!"},"content":{"rendered":"<div id=\"bsf_rt_marker\"><\/div><p>Joseph nettoie. Il d\u00e9montre que d&#039;autres choses sont plus importantes pour lui que l&#039;\u00e9cole. Joseph est socialement engag\u00e9 et soucieux de l\u2019environnement. Il a choisi la meilleure voie pour lui-m\u00eame parce que c&#039;est sa voie. Les parents de Joseph le prennent au s\u00e9rieux et le soutiennent sur le chemin d&#039;une vie consciente et responsable qu&#039;il a choisie pour lui-m\u00eame.<\/p>\n<p>&nbsp;<\/p>\n<h3>Ses parents le soutiennent pour d\u00e9finir sa propre vie.<\/h3>\n<p>Joseph est une personne qui r\u00e9fl\u00e9chit tr\u00e8s profond\u00e9ment et qui veut savoir comment tout fonctionne dans la vraie vie. Il a du cran et trouve ainsi sa voie avec le soutien de ses parents.<\/p>\n<p>&nbsp;<\/p>\n<h3 style=\"text-align: center\"><em>Pour Joseph, l\u2019\u00e9ducation \u00e0 la vie est plus importante que l\u2019\u00e9ducation \u00e0 la carri\u00e8re.<\/em><\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-14843 size-large\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/09\/IMG_2613-scaled-1.jpg\" alt=\"Joseph recyclant deux amis embrassant des enfants\" width=\"1024\" height=\"683\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/09\/IMG_2613-scaled-1.jpg 2560w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/09\/IMG_2613-scaled-1-300x200.jpg 300w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/09\/IMG_2613-scaled-1-768x512.jpg 768w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/09\/IMG_2613-scaled-1-1024x683.jpg 1024w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/09\/IMG_2613-scaled-1-1536x1024.jpg 1536w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/09\/IMG_2613-scaled-1-2048x1366.jpg 2048w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/09\/IMG_2613-scaled-1-624x416.jpg 624w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>Pour Joseph, l\u2019\u00e9cole est un moyen incroyablement inefficace de transmettre des connaissances. Ses parents le soutiennent dans son chemin et lui apprennent les math\u00e9matiques et l&#039;anglais ; c&#039;est tout ce dont il a besoin car il apprend de la nature, par choix, et s&#039;impr\u00e8gne du savoir !<\/p>\n<p>L\u2019\u00e9ducation a besoin de libert\u00e9, la libert\u00e9 signifie l\u2019incertitude, et les parents doivent la supporter pour garder l\u2019espace de cette incertitude ouvert pour l\u2019enfant \u2013 alors seulement l\u2019\u00e9ducation peut \u00e9merger comme un processus actif qui part de l\u2019enfant.<\/p>\n<p>Sa m\u00e8re a dit : <i>\u00ab Nous sommes fiers de Joseph ; il fait son chemin. Nous avons d\u00e9sormais confiance en son parcours \u00bb. \u00ab Un poisson sait bien nager ; pourquoi essayons-nous de le grimper dans un arbre ?<\/i><\/p>\n<p>&nbsp;<\/p>\n<h2>Nous avons rencontr\u00e9 ce gar\u00e7on intrigant dans son centre de recyclage et de recyclage \u00e0 la maison. Voyons ce qu&#039;il a \u00e0 dire sur les raisons pour lesquelles Joseph nettoie\u00a0:<\/h2>\n<p>&nbsp;<\/p>\n<h3>Comment vivez-vous votre monde ? Qu&#039;est-ce qui est important pour toi?<\/h3>\n<p>C&#039;est ma famille, Dieu et Karma. Je crois au Karma, et ce qui se passe revient. Le karma, c&#039;est lorsque vous faites quelque chose de bien, cela vous arrivera dans le futur.<\/p>\n<p>&nbsp;<\/p>\n<h3 style=\"text-align: center\">Joseph nettoie et fait sa part pour am\u00e9liorer le monde en recyclant et en r\u00e9cup\u00e9rant les d\u00e9chets.<\/h3>\n<p>&nbsp;<\/p>\n<h3>Qu\u2019est-ce qui vous a inspir\u00e9 \u00e0 faire cela ? Quand avez-vous d\u00e9cid\u00e9 de rendre le monde meilleur ?<\/h3>\n<p>J&#039;avais l&#039;habitude de collectionner des c\u00e2bles avec mes amis. Puis j&#039;ai vu les gens rouler \u00e0 v\u00e9lo et ramasser les d\u00e9tritus. L&#039;un de ces gars conna\u00eet mon p\u00e8re, et il a dit \u00e0 mon p\u00e8re qu&#039;il m&#039;avait vu collectionner des c\u00e2bles. Il a donn\u00e9 \u00e0 mon p\u00e8re l\u2019id\u00e9e que je devrais collecter les d\u00e9chets plastiques, car cela me rapporterait de l\u2019argent.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-14839 size-large\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/09\/DSC08282_1-scaled-1.jpg\" alt=\"\" width=\"1024\" height=\"683\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/09\/DSC08282_1-scaled-1.jpg 2560w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/09\/DSC08282_1-scaled-1-300x200.jpg 300w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/09\/DSC08282_1-scaled-1-768x512.jpg 768w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/09\/DSC08282_1-scaled-1-1024x683.jpg 1024w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/09\/DSC08282_1-scaled-1-1536x1024.jpg 1536w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/09\/DSC08282_1-scaled-1-2048x1366.jpg 2048w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/09\/DSC08282_1-scaled-1-624x416.jpg 624w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<h3>Que fais-tu avec cet argent ?<\/h3>\n<p>Avec l&#039;argent que j&#039;en tire, je paie les frais de scolarit\u00e9 pendant une ann\u00e9e enti\u00e8re pour les enfants de mon \u00e2ge en<\/p>\n<p>&nbsp;<\/p>\n<h3>Connaissiez-vous les enfants avant ?<\/h3>\n<p>Non, j\u2019ai d\u2019abord jou\u00e9 avec eux pour mieux nous conna\u00eetre, et maintenant nous sommes aussi amis.<\/p>\n<p>Je leur rends visite aussi souvent que possible. Nous avons \u00e0 peu pr\u00e8s le m\u00eame \u00e2ge. Chaque ann\u00e9e, c&#039;est un d\u00e9fi pour les familles d&#039;\u00e9conomiser pour les frais de scolarit\u00e9 afin que leurs enfants puissent aller \u00e0 l&#039;\u00e9cole.<b>\u00a0<\/b><\/p>\n<p>&nbsp;<\/p>\n<h3>Que comprenez-vous \u00e0 propos de la durabilit\u00e9\u00a0?<\/h3>\n<p>La durabilit\u00e9 signifie que si vous avez une rivi\u00e8re pleine de poissons et que vous n\u2019en prenez que ce dont vous avez besoin, il y aura suffisamment de poisson pour tout le monde. Si vous prenez plus de poisson que ce dont vous avez besoin, il n\u2019y aura plus de poisson dans la rivi\u00e8re et il y en aura pour tout le monde.<\/p>\n<p>&nbsp;<\/p>\n<h3>Pourquoi la durabilit\u00e9 est-elle si importante ?<\/h3>\n<p>Il peut y avoir un \u00e9quilibre dans le monde.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-14842\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/09\/IMG_2576-scaled-e1661990467708-879x1024.jpg\" alt=\"\" width=\"479\" height=\"558\" title=\"\"><\/p>\n<h3>Vous prenez des d\u00e9cisions et assumez vos responsabilit\u00e9s. Comment voyez-vous votre r\u00f4le dans la soci\u00e9t\u00e9 d\u2019aujourd\u2019hui ?<\/h3>\n<p>Mon r\u00f4le dans la soci\u00e9t\u00e9 d&#039;aujourd&#039;hui est d&#039;aider les gens et de leur donner du travail, d&#039;aider les enfants \u00e0 aller \u00e0 l&#039;\u00e9cole. Je nettoie Bali et je veux dire aux enfants que peu importe si vous \u00eates petit, vous pouvez <a href=\"https:\/\/instantkarmamag.com\/fr\/article\/sois-le-changement-2\/\">faire une diff\u00e9rence sur la plan\u00e8te<\/a>.<\/p>\n<h3><\/h3>\n<h3>Comment imaginez-vous le monde\/votre monde dans les 20 prochaines ann\u00e9es ?<\/h3>\n<p>Tout le monde recycle et il n\u2019y aura plus de plastique. Et si le contraire se produisait, et que les gens continuent \u00e0 jeter des d\u00e9chets, le monde entier serait rempli de d\u00e9chets. En 2050, il y aura plus de plastique que de poissons dans la mer. Nous devons agir maintenant ; si les poissons meurent, les gens mourront aussi.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-14838\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/10\/DSC08278_1-scaled-1-150x150.jpg\" alt=\"\" width=\"549\" height=\"366\" title=\"\"><\/p>\n<h3>Que faites-vous d\u2019autre pendant votre temps libre ?<\/h3>\n<p>Pendant mon temps libre, j&#039;aime aller \u00e0 la p\u00eache, grimper aux manguiers ou aux cocotiers, ou encore confectionner des petites feuilles de plastique, et je les r\u00e9alise avec une presse \u00e0 panini.<\/p>\n<p>&nbsp;<\/p>\n<p><em>Merci, Joseph, pour l&#039;interview.<\/em><\/p>\n<p>&nbsp;<\/p>\n<h4><i>Faits sur Joseph :<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-14841 size-large\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/09\/IMG_2567-scaled-1.jpg\" alt=\"\" width=\"1024\" height=\"683\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/09\/IMG_2567-scaled-1.jpg 2560w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/09\/IMG_2567-scaled-1-300x200.jpg 300w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/09\/IMG_2567-scaled-1-768x512.jpg 768w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/09\/IMG_2567-scaled-1-1024x683.jpg 1024w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/09\/IMG_2567-scaled-1-1536x1024.jpg 1536w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/09\/IMG_2567-scaled-1-2048x1366.jpg 2048w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/09\/IMG_2567-scaled-1-624x416.jpg 624w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/i><\/h4>\n<h3>10 ans et vit la vie qu&#039;il s&#039;est choisie. Il est inspir\u00e9 par le recyclage et par la cr\u00e9ation d&#039;un monde meilleur avec le soutien de ses parents. C&#039;est pourquoi Joseph nettoie.<\/h3>\n<p>Ils lui apprennent l&#039;entrepreneuriat, l&#039;anglais et les math\u00e9matiques. Joseph r\u00e9cup\u00e8re les produits de recyclage tous les mardis avec son p\u00e8re dans le camion. Les gens connaissent d\u00e9j\u00e0 Joseph, ils pr\u00e9parent le plastique et il faut tout laver.<\/p>\n<p>Il r\u00e9alise ses \u0153uvres \u00e0 partir du plastique et les vend tous les dimanches \u00e0 LaBrisa \u00e0 Canggu.<\/p>\n<h3>Suivez Joseph Cleans sur Instagram <a href=\"https:\/\/www.instagram.com\/joseph_recycling\/\" target=\"_blank\" rel=\"noopener\">@joseph_recyclage<\/a><\/h3>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Joseph fait le m\u00e9nage. Il d\u00e9montre que d&#039;autres choses sont plus importantes pour lui que l&#039;\u00e9cole. Joseph est engag\u00e9 socialement et soucieux de l&#039;environnement. Il a choisi la meilleure voie pour lui-m\u00eame, car c&#039;est sa voie. Ses parents le prennent au s\u00e9rieux et le soutiennent dans son cheminement vers la vie consciente et responsable qu&#039;il a choisie [\u2026]<\/p>","protected":false},"author":214,"featured_media":14838,"comment_status":"open","ping_status":"closed","template":"","meta":{"footnotes":""},"categories":[275,273],"tags":[355,290],"section":[388],"interest":[380,372,378],"_magazine":[356],"class_list":["post-14837","article","type-article","status-publish","has-post-thumbnail","hentry","category-impact","category-people","tag-355","tag-kids","section-people","interest-creative","interest-eco","interest-social","_magazine-356"],"_links":{"self":[{"href":"https:\/\/instantkarmamag.com\/fr\/wp-json\/wp\/v2\/article\/14837","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/instantkarmamag.com\/fr\/wp-json\/wp\/v2\/article"}],"about":[{"href":"https:\/\/instantkarmamag.com\/fr\/wp-json\/wp\/v2\/types\/article"}],"author":[{"embeddable":true,"href":"https:\/\/instantkarmamag.com\/fr\/wp-json\/wp\/v2\/users\/214"}],"replies":[{"embeddable":true,"href":"https:\/\/instantkarmamag.com\/fr\/wp-json\/wp\/v2\/comments?post=14837"}],"version-history":[{"count":0,"href":"https:\/\/instantkarmamag.com\/fr\/wp-json\/wp\/v2\/article\/14837\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/instantkarmamag.com\/fr\/wp-json\/wp\/v2\/media\/14838"}],"wp:attachment":[{"href":"https:\/\/instantkarmamag.com\/fr\/wp-json\/wp\/v2\/media?parent=14837"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/instantkarmamag.com\/fr\/wp-json\/wp\/v2\/categories?post=14837"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/instantkarmamag.com\/fr\/wp-json\/wp\/v2\/tags?post=14837"},{"taxonomy":"section","embeddable":true,"href":"https:\/\/instantkarmamag.com\/fr\/wp-json\/wp\/v2\/section?post=14837"},{"taxonomy":"interest","embeddable":true,"href":"https:\/\/instantkarmamag.com\/fr\/wp-json\/wp\/v2\/interest?post=14837"},{"taxonomy":"_magazine","embeddable":true,"href":"https:\/\/instantkarmamag.com\/fr\/wp-json\/wp\/v2\/_magazine?post=14837"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}<!-- This website is optimized by Airlift. Learn more: https://airlift.net. Template:. Learn more: https://airlift.net. Template: 6a3c9e6bc6af5a91495580da. Config Timestamp: 2026-06-25 03:19:51 UTC, Cached Timestamp: 2026-09-02 02:28:56 UTC -->