{"id":9684,"date":"2021-07-01T00:00:00","date_gmt":"2021-06-30T16:00:00","guid":{"rendered":"https:\/\/instantkarmamag.com\/article\/a-culinary-journey-ubud\/"},"modified":"2024-07-03T16:46:22","modified_gmt":"2024-07-03T08:46:22","slug":"viaje-culinario-a-ubud","status":"publish","type":"article","link":"https:\/\/instantkarmamag.com\/es\/articulo\/viaje-culinario-a-ubud\/","title":{"rendered":"Viaje culinario a Ubud"},"content":{"rendered":"<div id=\"bsf_rt_marker\"><\/div><p><span class=\"markedContent\"><span dir=\"ltr\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-3377 size-full\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2021\/07\/Screenshot-2021-07-01-at-09-27-34-IK-magz-5-print-final-pdf.png\" alt=\"Viaje culinario a Ubud Pruebe las delicias de la comida deliciosa y gourmet\" width=\"605\" height=\"145\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2021\/07\/Screenshot-2021-07-01-at-09-27-34-IK-magz-5-print-final-pdf.png 605w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2021\/07\/Screenshot-2021-07-01-at-09-27-34-IK-magz-5-print-final-pdf-300x72.png 300w\" sizes=\"auto, (max-width: 605px) 100vw, 605px\" \/><\/span><\/span><\/p>\n<p><span class=\"markedContent\"><span dir=\"ltr\">\u00a1Hoy te llevamos a un peque\u00f1o viaje culinario por Ubud! <\/span><span dir=\"ltr\">\u00bfSab\u00edas que Ubud no es s\u00f3lo un centro art\u00edstico y espiritual, sino tambi\u00e9n culinario?<\/span><\/span><\/p>\n<p><span class=\"markedContent\"><span dir=\"ltr\">Nosotros, desde <a href=\"https:\/\/instantkarma.10web.me\/\" target=\"_blank\" rel=\"noopener\">Instant Karma<\/a> Hemos elegido las siguientes ubicaciones porque creemos que su gastronom\u00eda <\/span><span dir=\"ltr\">La elecci\u00f3n, calidad y variedad son excepcionales. <\/span><span dir=\"ltr\">Especialmente ahora en esta situaci\u00f3n, en comparaci\u00f3n con otros lugares gourmet conocidos, son <\/span><span dir=\"ltr\">Emprendedores con cierto \u201cGusto\u201d y que aman lo que hacen.<\/span><\/span><\/p>\n<p><span class=\"markedContent\"><span dir=\"ltr\">Conducimos nuestras motos por las animadas calles de Singakerta hasta Peliatan. <\/span><span dir=\"ltr\">Me encanta cuando ya est\u00e1 oscuro, hay una atm\u00f3sfera completamente diferente que durante el d\u00eda, y <\/span><span dir=\"ltr\">Por todas partes a lo largo de la calle, hay olor a comida como Sate, Babi Guling, Gorengan, Lalapan. <\/span><span dir=\"ltr\">y mucho m\u00e1s de lo que el coraz\u00f3n local desea.<\/span><\/span><\/p>\n<h3><span class=\"markedContent\"><span dir=\"ltr\">ASCENSO BALI<\/span><\/span><\/h3>\n<p><span class=\"markedContent\"><span dir=\"ltr\">Hambrientos, llegamos a nuestro destino final, <\/span><span dir=\"ltr\">El restaurante \u201cRise\u201d en Peliatan. <\/span><span dir=\"ltr\">Rise ofrece delicias mediterr\u00e1neas de <\/span><span dir=\"ltr\">Pavo. Todo est\u00e1 reci\u00e9n cocinado y <\/span><span dir=\"ltr\">preparado con amor por Asli, la due\u00f1a de <\/span><span dir=\"ltr\">Rise. Rise Bali solo utiliza sus propios productos, <\/span><span dir=\"ltr\">yogur, tahini, encurtidos, pan pita, turco <\/span><span dir=\"ltr\">deleite y mucho m\u00e1s. <\/span><\/span><\/p>\n<p><span class=\"markedContent\"><span dir=\"ltr\">Su cocina tradicional y recetas secretas <\/span><span dir=\"ltr\">viene de sus abuelos y padres, <\/span><span dir=\"ltr\">que dirige un restaurante en su ciudad natal <\/span><span dir=\"ltr\">Ciudad de Bodrum.<\/span><\/span><\/p>\n<p><span class=\"markedContent\"><span dir=\"ltr\">Asli se mud\u00f3 a Bali hace dos a\u00f1os con su <\/span><span dir=\"ltr\">Hija de 5 a\u00f1os y esposo y <\/span><span dir=\"ltr\">Rise abri\u00f3 en Ubud en septiembre de 2020. <\/span><span dir=\"ltr\">Con las diferentes delicias mediterr\u00e1neas <\/span><span dir=\"ltr\">Ella ofrece, la elecci\u00f3n no fue f\u00e1cil, pero la <\/span><span dir=\"ltr\">La expectaci\u00f3n era a\u00fan mayor.<\/span><\/span><\/p>\n<ul>\n<li><span class=\"markedContent\"><span dir=\"ltr\">Babagannus (berenjenas y pimientos a la parrilla, <\/span><span dir=\"ltr\">ajo, perejil en aceite de oliva)<\/span><\/span><\/li>\n<li><span class=\"markedContent\"><span dir=\"ltr\">Humus <\/span><\/span><\/li>\n<li><span class=\"markedContent\"><span dir=\"ltr\">Zanahoria-<\/span><span dir=\"ltr\">tarator: (yogur con zanahorias, ajo y aceitunas) <\/span><span dir=\"ltr\">aceite) <\/span><\/span><\/li>\n<li><span class=\"markedContent\"><span dir=\"ltr\">Tzatziki<\/span><\/span><\/li>\n<li><span class=\"markedContent\"><span dir=\"ltr\"><strong>Kibbeh<\/strong>, son bolas de burghul fritas con carne de res <\/span><\/span><span class=\"markedContent\"><span dir=\"ltr\">y el <\/span><strong><span dir=\"ltr\">Wrap de pollo tantuni<\/span><\/strong><\/span><\/li>\n<\/ul>\n<p><span class=\"markedContent\"><span dir=\"ltr\">Todo estaba reci\u00e9n preparado y servido. <\/span><span dir=\"ltr\">con pan pita casero: un fest\u00edn para tus <\/span><span dir=\"ltr\">papilas gustativas.<\/span><\/span><\/p>\n<p><span class=\"markedContent\"><span dir=\"ltr\">Felices y completos, decidimos tomar el postre. <\/span><span dir=\"ltr\">Como no pod\u00eda ser de otra manera, baklava, oh s\u00ed, <\/span><span dir=\"ltr\">Y oh dios m\u00edo, nunca he comido tan bien <\/span><span dir=\"ltr\">baklava. Por supuesto, el caf\u00e9 turco original, <\/span><span dir=\"ltr\">que se sirvi\u00f3 con el turco original <\/span><span dir=\"ltr\">La taza de cobre, no pod\u00eda faltar.<\/span><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span class=\"markedContent\"><strong><span dir=\"ltr\">Conclusi\u00f3n: <\/span><\/strong><\/span><\/p>\n<p><strong><span class=\"markedContent\"><span dir=\"ltr\">Chicos, \u00bfqu\u00e9 puedo decir? Fue simplemente... <\/span><span dir=\"ltr\">\u00a1MEGA DELICIOSO! Una variedad de platos peque\u00f1os y <\/span><span dir=\"ltr\">delicias con aut\u00e9nticos platos turcos que <\/span><span dir=\"ltr\">\u00a1Definitivamente tienes que probarlo! <\/span><\/span><\/strong><\/p>\n<p><strong><span class=\"markedContent\"><span dir=\"ltr\">Baklkavaaaaaaaaaaaa, y la suerte es perfecta.<\/span><\/span><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong><span class=\"markedContent\"><span dir=\"ltr\">RISE BALI, cocina mediterr\u00e1nea y del mar Egeo<\/span><\/span><\/strong><\/p>\n<p><span class=\"markedContent\"><span dir=\"ltr\">JL. Sukma Kesuma No. 21, Peliatan Ubud<\/span><\/span><\/p>\n<p><span class=\"markedContent\"><span dir=\"ltr\">Abierto de 9 a 21 horas, cerrado los domingos.<\/span><\/span><\/p>\n<p><span class=\"markedContent\"><span dir=\"ltr\">Realiza tu pedido por WhatsApp: (+62) 0821 4561 0532<\/span><\/span><\/p>\n<p><span class=\"markedContent\"><span dir=\"ltr\">Yo: <a href=\"https:\/\/www.instagram.com\/rise_bali\/\" target=\"_blank\" rel=\"noopener\"><strong>@rise_bali<\/strong><\/a><\/span><\/span><\/p>\n<p>________________________________________________________________________________<\/p>\n<p><strong><span class=\"markedContent\"><span dir=\"ltr\">Otro d\u00eda, salimos con Cynthia, una joven, alegre y hermosa cantante de jazz. Ella <\/span><span dir=\"ltr\">Vive en Ubud desde hace 6 a\u00f1os. Nos conocimos hace poco en la playa Sindhu en Sanur. <\/span><span dir=\"ltr\">Tuve la oportunidad de llamarla y preguntarle si le gustar\u00eda mostrarnos un poco de Ubud.<\/span><\/span><\/strong><\/p>\n<p><span class=\"markedContent\"><span dir=\"ltr\">Lo primero que nos pregunt\u00f3 Cynthia en el punto de encuentro:<\/span><\/span><\/p>\n<figure id=\"attachment_3382\" aria-describedby=\"caption-attachment-3382\" style=\"width: 576px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-3382 size-large\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2021\/07\/hcmp204971_1041730.jpeg\" alt=\"viaje culinario ubud degustaci\u00f3n de deliciosas delicias gastron\u00f3micas\" width=\"576\" height=\"1024\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2021\/07\/hcmp204971_1041730.jpeg 1024w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2021\/07\/hcmp204971_1041730-169x300.jpeg 169w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2021\/07\/hcmp204971_1041730-768x1366.jpeg 768w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2021\/07\/hcmp204971_1041730-576x1024.jpeg 576w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2021\/07\/hcmp204971_1041730-864x1536.jpeg 864w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2021\/07\/hcmp204971_1041730-624x1110.jpeg 624w\" sizes=\"auto, (max-width: 576px) 100vw, 576px\" \/><figcaption id=\"caption-attachment-3382\" class=\"wp-caption-text\">Sopa Pho \u2013 Loto Verde<\/figcaption><\/figure>\n<p><em><span class=\"markedContent\"><span dir=\"ltr\">\u00bfTienen hambre, chicos? \u00bfYa han comido algo? Tengo mucha hambre y quiero mostrarles <\/span><span dir=\"ltr\">Eres mi nuevo lugar favorito, donde recientemente com\u00ed la mejor sopa Pho. Ya sabes, no es solo la <\/span><span dir=\"ltr\">\u201cLa comida, la filosof\u00eda del hombre que crea los deliciosos platos, merece absolutamente una visita\u201d.<\/span><\/span><\/em><\/p>\n<p><span class=\"markedContent\"><span dir=\"ltr\">Despu\u00e9s de un corto viaje llegamos a Penestanan. Le\u00ed que los primeros hippies fueron vistos aqu\u00ed. <\/span><span dir=\"ltr\">en 1969 y que el pintor holand\u00e9s Arie Smit vivi\u00f3 aqu\u00ed a finales de los a\u00f1os 50. Fund\u00f3 <\/span><span dir=\"ltr\">la Escuela de J\u00f3venes Artistas, por eso el lugar se llama El Pueblo de los J\u00f3venes Artistas. <\/span><span dir=\"ltr\">que la zona prosper\u00f3; m\u00e1s balineses vinieron aqu\u00ed para aprender pintura, curaci\u00f3n y magia.<\/span><\/span><\/p>\n<figure id=\"attachment_3387\" aria-describedby=\"caption-attachment-3387\" style=\"width: 469px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-3387 size-full\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2021\/07\/Screenshot_2021-06-06-green-lotus-ubud-Google-Search4.png\" alt=\"viaje culinario ubud degustaci\u00f3n de deliciosas delicias gastron\u00f3micas\" width=\"469\" height=\"636\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2021\/07\/Screenshot_2021-06-06-green-lotus-ubud-Google-Search4.png 469w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2021\/07\/Screenshot_2021-06-06-green-lotus-ubud-Google-Search4-221x300.png 221w\" sizes=\"auto, (max-width: 469px) 100vw, 469px\" \/><figcaption id=\"caption-attachment-3387\" class=\"wp-caption-text\">Almuerzo de loto verde<\/figcaption><\/figure>\n<h3><span class=\"markedContent\"><span dir=\"ltr\">LOTO VERDE BALI<\/span><\/span><\/h3>\n<p><span class=\"markedContent\"><span dir=\"ltr\">Hay innumerables peque\u00f1os restaurantes y entramos en el \u201cLoto Verde\u201d.<\/span><\/span><\/p>\n<p><span class=\"markedContent\"><span dir=\"ltr\">Un warung contempor\u00e1neo vegano simple pero s\u00faper delicioso. No <\/span><span dir=\"ltr\">leche, sin miel y sin huevo. El due\u00f1o del Loto Verde, un <\/span><span dir=\"ltr\">filos\u00f3fico, de esp\u00edritu brillante, nos recibi\u00f3 de manera amistosa y en <\/span><span dir=\"ltr\">Al mismo tiempo, estaba encantado de volver a ver a Cynthia. <\/span><\/span><\/p>\n<p><span class=\"markedContent\"><span dir=\"ltr\">Despu\u00e9s de que nosotros <\/span><span dir=\"ltr\">Disfrutamos de la comida deliciosa y saludable, tuvimos una charla muy agradable. <\/span><span dir=\"ltr\">con el propietario. Si quieres saber m\u00e1s, lee su art\u00edculo &#039;Un <\/span><span dir=\"ltr\">pensamiento del Loto Verde&#039;.<\/span><\/span><\/p>\n<h5 style=\"text-align: center;\"><em><span class=\"markedContent\"><strong><span dir=\"ltr\">Nos dijo que cuando est\u00e1s comiendo, no hay voz. <\/span><\/strong><span dir=\"ltr\"><strong>Comunicaci\u00f3n entre el ser humano y la Madre Naturaleza.<\/strong> <\/span><\/span><\/em><\/h5>\n<p><span class=\"markedContent\"><span dir=\"ltr\"> Cuando <\/span><span dir=\"ltr\">Cuando comes, la energ\u00eda de los alimentos va directamente a tu cuerpo. <\/span><span dir=\"ltr\">cuerpo, en tu mente, en tu esp\u00edritu y en tu alma. <\/span><\/span><\/p>\n<p><span class=\"markedContent\"><span dir=\"ltr\">Su mensaje es la comida de aqu\u00ed. Traen felicidad, <\/span><span dir=\"ltr\">salud, y as\u00ed es como traen m\u00e1s alegr\u00eda. Cuando la gente <\/span><span dir=\"ltr\">Coma m\u00e1s vegano, seguramente habr\u00e1 menos matanzas. <\/span><span dir=\"ltr\">Animales.<\/span><\/span><\/p>\n<h5 style=\"text-align: center;\"><em><strong><span class=\"markedContent\"><span dir=\"ltr\">El Loto Verde trae el mensaje: Conoce qui\u00e9n eres.<\/span><\/span><\/strong><\/em><\/h5>\n<p>&nbsp;<\/p>\n<p style=\"text-align: right;\"><a href=\"https:\/\/www.google.com\/maps\/place\/Green+Lotus+Fusion+Vegan+Cuisine\/@-8.5036853,115.2471406,15z\/data=!4m2!3m1!1s0x0:0x90de55f537fe2084?sa=X&amp;ved=2ahUKEwj60enR4sDxAhXCXSsKHQYPAF0Q_BIwFHoECD8QBQ\" target=\"_blank\" rel=\"noopener\"><strong>VISITA GREEN LOTUS -&gt; ENLACE DE MAPAS AQU\u00cd<\/strong><\/a><\/p>\n<p><strong><span class=\"markedContent\"><span dir=\"ltr\">COCINA VEGANA FUSI\u00d3N LOTO VERDE <\/span><\/span><\/strong><\/p>\n<p><span class=\"markedContent\"><span dir=\"ltr\">Sayan, Kecamatan Ubud, Kabupaten Gianyar, Bali<\/span><\/span><\/p>\n<p><span class=\"markedContent\"><span dir=\"ltr\">Abierto de 10 a 19 horas, martes cerrado.<\/span><\/span><\/p>\n<p>________________________________________________________________________________<\/p>\n<p>&nbsp;<\/p>\n<p><span class=\"markedContent\"><span dir=\"ltr\">Despu\u00e9s, conducimos un poco m\u00e1s a trav\u00e9s de la sinuosa carretera. <\/span><span dir=\"ltr\">caminos, jungla a izquierda y derecha, hasta Nyuh Kuning.<\/span><\/span><\/p>\n<p><span class=\"markedContent\"><span dir=\"ltr\">Nyuh Kuning es un pueblo al lado del bosque de monos con <\/span><span dir=\"ltr\">Tiene car\u00e1cter propio, ah\u00ed nos detuvimos en el Viejo <\/span><span dir=\"ltr\">Caf\u00e9 de los amigos. <\/span><span dir=\"ltr\">Una vez m\u00e1s, los ojos de Cynthia brillaron y con su encanto... <\/span><span dir=\"ltr\">Sonr\u00ede, dijo: <\/span><\/span><\/p>\n<p><span class=\"markedContent\"><span dir=\"ltr\">\u201cCuidado muchachos, aqu\u00ed ten\u00e9is lo mejor <\/span><span dir=\"ltr\">Caf\u00e9 y el mejor batido de espresso de pl\u00e1tano puro <\/span><span dir=\"ltr\">\u201cAz\u00facar de ca\u00f1a.\u201d<\/span><\/span><\/p>\n<p><strong><span class=\"markedContent\"><span dir=\"ltr\">Y ella ten\u00eda simplemente raz\u00f3n.<\/span><\/span><\/strong><\/p>\n<p>&nbsp;<\/p>\n<h3><span class=\"markedContent\"><span dir=\"ltr\">CAF\u00c9 DE VIEJOS AMIGOS<\/span><\/span><\/h3>\n<p><span class=\"markedContent\"><span dir=\"ltr\">Nos sentamos un rato y disfrutamos de nuestras bebidas en este lugar tranquilo. De repente, Made, el propietario <\/span><span dir=\"ltr\">del Caf\u00e9 de los Viejos Amigos, lleg\u00f3 a la vuelta de la esquina.<\/span><\/span><\/p>\n<p style=\"text-align: center;\"><em><strong><span class=\"markedContent\"><span dir=\"ltr\">Solo ten\u00eda que hacer una peque\u00f1a entrevista.<\/span><\/span><\/strong><\/em><\/p>\n<p><strong><span class=\"markedContent\"><span dir=\"ltr\">Made naci\u00f3 y creci\u00f3 en Belantih, que se encuentra cerca <\/span><span dir=\"ltr\">El monte Batur en la regi\u00f3n monta\u00f1osa de Kintamani, no lejos de <\/span><span dir=\"ltr\">Templo de Ubud.<\/span><\/span><\/strong><\/p>\n<p><em><span class=\"markedContent\"><span dir=\"ltr\">\u201cCrec\u00ed trabajando en la granja de mi familia. Cuando era ni\u00f1a, <\/span><span dir=\"ltr\">Encend\u00edamos l\u00e1mparas de queroseno por la noche porque no hab\u00eda electricidad disponible. <\/span><span dir=\"ltr\">Viv\u00edamos una vida sencilla rodeados de hermosas monta\u00f1as.<\/span><\/span><\/em><\/p>\n<p><em><span class=\"markedContent\"><span dir=\"ltr\">Con mi caf\u00e9 quiero apoyar a los caficultores de Kintamani. <\/span><span dir=\"ltr\">No hago mucho marketing. Solo intento mostrar lo que hago y el trabajo y la gente que hay detr\u00e1s de ello. <\/span><\/span><\/em><\/p>\n<p><em><span class=\"markedContent\"><span dir=\"ltr\">El <\/span><span dir=\"ltr\">Para m\u00ed, el marketing m\u00e1s probado es la Madre Naturaleza: ella atrae a las personas adecuadas. <\/span><span dir=\"ltr\">A mi caf\u00e9, bellamente elegido por el universo.<\/span><\/span><\/em><\/p>\n<p><em><span class=\"markedContent\"><span dir=\"ltr\">No quer\u00eda ser agricultor, as\u00ed que trabaj\u00e9 en turismo y aprend\u00ed ingl\u00e9s. <\/span><span dir=\"ltr\">Al mismo tiempo. Entonces, un d\u00eda not\u00e9 un desequilibrio y de repente... <\/span><span dir=\"ltr\">comprendi\u00f3 la dedicaci\u00f3n y la alegr\u00eda de cultivar y labrar la tierra.<\/span><\/span><\/em><\/p>\n<p><em><span class=\"markedContent\"><span dir=\"ltr\">Estoy orgulloso de ser un agricultor de Kintamani, donde crec\u00ed, y soy <\/span><span dir=\"ltr\">Orgulloso de compartir los frutos de la tierra. <\/span><span dir=\"ltr\">Este tiempo de coronavirus me da m\u00e1s confianza y conf\u00edo en lo que soy. <\/span><span dir=\"ltr\">haciendo.<\/span><span dir=\"ltr\">Simplemente trabajo, de manera aut\u00e9ntica y directa, y me dejo llevar por la corriente. <\/span><span dir=\"ltr\">\u201cnaturaleza de la vida.\u201d<\/span><\/span><\/em><\/p>\n<p>&nbsp;<\/p>\n<p><span class=\"markedContent\"><span dir=\"ltr\">Su familia cultiva varias cepas de Coffea arabica a mano y sin ning\u00fan producto qu\u00edmico. <\/span><span dir=\"ltr\">fertilizantes o pesticidas. Cada grano de caf\u00e9 se recolecta a mano solo cuando est\u00e1 realmente rojo y maduro, <\/span><span dir=\"ltr\">Luego secan los granos sobre madera, a aproximadamente un metro en el aire. <\/span><\/span><\/p>\n<p style=\"text-align: center;\"><em><strong><span class=\"markedContent\"><span dir=\"ltr\">Esto hace que los frijoles se mantengan <\/span><span dir=\"ltr\">Todo su aroma.<\/span><\/span><\/strong><\/em><\/p>\n<h5 style=\"text-align: center;\"><span class=\"markedContent\"><span dir=\"ltr\"><em><strong>Old Friends Cafe es un maravilloso oasis de tranquilidad con excelente caf\u00e9 directamente de la familia. <\/strong><\/em><\/span><em><span dir=\"ltr\"><strong>finca, tostado en el lugar y seleccionado cuidadosamente a mano grano por grano.<\/strong> <\/span><\/em><\/span><\/h5>\n<p><span class=\"markedContent\"><span dir=\"ltr\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-3396 aligncenter\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2021\/07\/coffee-300x300.png\" alt=\"Caf\u00e9 instant\u00e1neo Karma Viaje culinario de viejos amigos Ubud Sabor Comida deliciosa Delicias Gourmet deliciosa\" width=\"168\" height=\"168\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2021\/07\/coffee-300x300.png 300w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2021\/07\/coffee-250x250.png 250w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2021\/07\/coffee-150x150.png 150w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2021\/07\/coffee.png 500w\" sizes=\"auto, (max-width: 168px) 100vw, 168px\" \/>Este caf\u00e9 est\u00e1 dirigido por verdaderos artesanos <\/span><span dir=\"ltr\">y puedes ver el cuidado y la atenci\u00f3n al detalle en todo lo que hacen, as\u00ed como la <\/span><span dir=\"ltr\">Elegante equipamiento. <\/span><\/span><\/p>\n<p><span class=\"markedContent\"><span dir=\"ltr\">Nos encanta la filosof\u00eda genuinamente solidaria del propietario. El peque\u00f1o pueblo de <\/span><span dir=\"ltr\">Nyuh Kuning tiene la enorme suerte de contar con una cafeter\u00eda de primer nivel como Old Friends\u2026<\/span><\/span><\/p>\n<h6><span class=\"markedContent\"><span dir=\"ltr\"><a href=\"https:\/\/www.google.com\/maps\/place\/Old+Friends+Coffee+--Bali+Coffee+Farmer+%26+Roaster\/@-8.5220418,115.2544397,17z\/data=!3m1!4b1!4m5!3m4!1s0x2dd23d0b98c1aeb9:0xa8e59522e0341b97!8m2!3d-8.5220338!4d115.2565892\" target=\"_blank\" rel=\"noopener\"><strong>Visita OLD FRIENDS COFFE<\/strong><\/a><\/span><\/span><\/h6>\n<h6 style=\"text-align: left;\"><span class=\"markedContent\"><span dir=\"ltr\"><a href=\"https:\/\/www.google.com\/maps\/place\/Old+Friends+Coffee+--Bali+Coffee+Farmer+%26+Roaster\/@-8.5220418,115.2544397,17z\/data=!3m1!4b1!4m5!3m4!1s0x2dd23d0b98c1aeb9:0xa8e59522e0341b97!8m2!3d-8.5220338!4d115.2565892\" target=\"_blank\" rel=\"noopener\"><strong>-&gt; ENLACE DEL MAPA AQU\u00cd<\/strong><\/a><br \/>\n<\/span><\/span><\/h6>\n<p><strong><span class=\"markedContent\"><span dir=\"ltr\">Jalan Nyuh Bojog No 5, Nyuh Kuning, Ubud, Bali<\/span><\/span><\/strong><\/p>\n<p><strong><span class=\"markedContent\"><span dir=\"ltr\">Abierto de 8:00 a 16:00 horas, <\/span><\/span><\/strong><span class=\"markedContent\"><span dir=\"ltr\">Martes cerrado<\/span><\/span><\/p>\n<p><span class=\"markedContent\"><span dir=\"ltr\"><strong>Sitio web:\u00a0<\/strong> caf\u00e9viejosamigos.com<\/span><\/span><\/p>\n<h5 style=\"text-align: center;\"><em><strong><span class=\"markedContent\"><span dir=\"ltr\">Si est\u00e1s en Ubud y te encanta el buen caf\u00e9, debes ir all\u00ed. <\/span><\/span><\/strong><\/em><\/h5>\n<h5 style=\"text-align: center;\"><em><strong><span class=\"markedContent\"><span dir=\"ltr\">Es una delicia. <\/span><\/span><\/strong><\/em><\/h5>\n<h5 style=\"text-align: center;\"><em><strong><span class=\"markedContent\"><span dir=\"ltr\">Gracias por <\/span><span dir=\"ltr\">Tu incre\u00edble experiencia de caf\u00e9.<\/span><\/span><\/strong><\/em><\/h5>","protected":false},"excerpt":{"rendered":"<p>Conducimos nuestras motos por las animadas calles de Singakerta y Peliatan para encontrar nuestras peque\u00f1as delicias culinarias para usted.<\/p>","protected":false},"author":1,"featured_media":3382,"comment_status":"open","ping_status":"closed","template":"","meta":{"footnotes":""},"categories":[270,313],"tags":[342],"section":[385,395],"interest":[195,399],"_magazine":[343],"class_list":["post-9684","article","type-article","status-publish","has-post-thumbnail","hentry","category-explore","category-review","tag-342","section-explore","section-places","interest-families","interest-nutrition","_magazine-343"],"_links":{"self":[{"href":"https:\/\/instantkarmamag.com\/es\/wp-json\/wp\/v2\/article\/9684","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/instantkarmamag.com\/es\/wp-json\/wp\/v2\/article"}],"about":[{"href":"https:\/\/instantkarmamag.com\/es\/wp-json\/wp\/v2\/types\/article"}],"author":[{"embeddable":true,"href":"https:\/\/instantkarmamag.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/instantkarmamag.com\/es\/wp-json\/wp\/v2\/comments?post=9684"}],"version-history":[{"count":0,"href":"https:\/\/instantkarmamag.com\/es\/wp-json\/wp\/v2\/article\/9684\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/instantkarmamag.com\/es\/wp-json\/wp\/v2\/media\/3382"}],"wp:attachment":[{"href":"https:\/\/instantkarmamag.com\/es\/wp-json\/wp\/v2\/media?parent=9684"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/instantkarmamag.com\/es\/wp-json\/wp\/v2\/categories?post=9684"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/instantkarmamag.com\/es\/wp-json\/wp\/v2\/tags?post=9684"},{"taxonomy":"section","embeddable":true,"href":"https:\/\/instantkarmamag.com\/es\/wp-json\/wp\/v2\/section?post=9684"},{"taxonomy":"interest","embeddable":true,"href":"https:\/\/instantkarmamag.com\/es\/wp-json\/wp\/v2\/interest?post=9684"},{"taxonomy":"_magazine","embeddable":true,"href":"https:\/\/instantkarmamag.com\/es\/wp-json\/wp\/v2\/_magazine?post=9684"}],"curies":[{"name":"Gracias","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}<!-- This website is optimized by Airlift. Learn more: https://airlift.net. Template:. Learn more: https://airlift.net. Template: 6a3c9e6bc6af5a91495580da. Config Timestamp: 2026-06-25 03:19:51 UTC, Cached Timestamp: 2026-09-02 10:31:53 UTC -->