{"id":38400,"date":"2025-09-15T11:59:32","date_gmt":"2025-09-15T03:59:32","guid":{"rendered":"https:\/\/instantkarmamag.com\/?post_type=article&#038;p=38400"},"modified":"2025-09-22T11:56:46","modified_gmt":"2025-09-22T03:56:46","slug":"grand-blue-project","status":"publish","type":"article","link":"https:\/\/instantkarmamag.com\/es\/articulo\/grand-blue-project\/","title":{"rendered":"El guardi\u00e1n del oc\u00e9ano \u2013 Grand Blue Project"},"content":{"rendered":"<div id=\"bsf_rt_marker\"><\/div>\n<figure class=\"wp-block-embed aligncenter is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Bienvenido a Grand Blue Project\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/PEiUc2uT_8c?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Mientras la mayor\u00eda de nosotros est\u00e1bamos aprendiendo sobre esta nueva cosa llamada Internet, Edi Frommenwiler estaba construyendo a mano un barco en un astillero indonesio.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Era el a\u00f1o 1992. La World Wide Web acababa de nacer, pero Edi estaba creando algo completamente distinto: un laboratorio flotante que se convertir\u00eda en el primer barco de vida a bordo de est\u00e1ndar internacional de Indonesia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lo que ocurri\u00f3 despu\u00e9s parece un cuento de hadas sobre conservaci\u00f3n, excepto que es real.<br><br><em>\u201cSabemos m\u00e1s sobre la superficie de Marte que sobre nuestro propio fondo oce\u00e1nico\u201d<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante m\u00e1s de 33 a\u00f1os, este explorador marino nacido en Suiza ha estado compilando silenciosamente lo que puede ser el registro visual m\u00e1s completo del mundo submarino de Indonesia: m\u00e1s de 80.000 clips de material sin editar que capturan la vida en algunas de las aguas con mayor biodiversidad de la Tierra.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ahora, esa vida de trabajo ha emergido como la <strong>Grand Blue Project<\/strong>, una plataforma digital que podr\u00eda cambiar la forma en que la humanidad entiende y protege nuestros oc\u00e9anos.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"439\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2025\/09\/pindito-3-1024x439.jpg\" alt=\"\" class=\"wp-image-38403\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2025\/09\/pindito-3-1024x439.jpg 1024w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2025\/09\/pindito-3-300x129.jpg 300w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2025\/09\/pindito-3-768x329.jpg 768w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2025\/09\/pindito-3-18x8.jpg 18w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2025\/09\/pindito-3.jpg 1400w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>El hombre que vio venir el ma\u00f1ana<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La historia de Edi comienza con una simple observaci\u00f3n: sabemos m\u00e1s sobre la superficie de Marte que sobre nuestro propio lecho oce\u00e1nico. Pero a diferencia de la mayor\u00eda de la gente que simplemente lamenta este hecho, \u00e9l decidi\u00f3 hacer algo al respecto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A principios de la d\u00e9cada de 1990, cuando Raja Ampat todav\u00eda era un susurro entre los c\u00edrculos de buceo, Edi ya estaba all\u00ed con su c\u00e1mara.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cuando los cient\u00edficos necesitaron pruebas de que estas aguas albergaban la mayor biodiversidad marina del planeta, las im\u00e1genes de Edi proporcionaron la evidencia.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Su documentaci\u00f3n ayud\u00f3 a proteger lo que ahora es el \u00c1rea Marina Protegida Bird&#039;s Head Seascape, que protege el \u00e1rea de h\u00e1bitat marino m\u00e1s grande de Indonesia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero Edi vio venir algo m\u00e1s: la carrera contra el tiempo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>\u201cCada d\u00eda que demoramos en comprender lo que vive bajo las olas, corremos el riesgo de perderlo para siempre\u201d.<\/em>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2013 Edi Frommenwiler<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El cambio clim\u00e1tico, la contaminaci\u00f3n y la sobrepesca se est\u00e1n acelerando m\u00e1s r\u00e1pido que nuestra capacidad de documentar lo que estamos destruyendo.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En sus tres d\u00e9cadas de buceo en aguas indonesias, ha visto c\u00f3mo se blanqueaban los arrecifes, c\u00f3mo desaparec\u00edan especies y c\u00f3mo cambiaban ecosistemas enteros.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><em><strong>\u201cNo podemos proteger lo que no entendemos\u201d.<\/strong><\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"427\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2025\/09\/Copy-of-edi-diving-1.jpeg\" alt=\"\" class=\"wp-image-38410\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2025\/09\/Copy-of-edi-diving-1.jpeg 640w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2025\/09\/Copy-of-edi-diving-1-300x200.jpeg 300w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2025\/09\/Copy-of-edi-diving-1-18x12.jpeg 18w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>De archivo personal a recurso global<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Lo que comenz\u00f3 como el proyecto apasionante de un hombre se ha convertido en algo m\u00e1s grande.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Grand Blue Project ahora alberga <strong>5.500 v\u00eddeos 4K verificados<\/strong> cubierta <strong>m\u00e1s de 1.500 especies marinas<\/strong> \u2013 cada uno vinculado a m\u00e1s de 50 puntos de datos que incluyen h\u00e1bitat, dieta, comportamiento y estado de conservaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este es un sistema de aprendizaje interactivo dise\u00f1ado para nuestra era conectada:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Para buceadores<\/strong>:<br>Sesiones informativas previas y posteriores a la inmersi\u00f3n que transforman los encuentros submarinos en oportunidades de aprendizaje.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Para educadores<\/strong>:<br>Planes de lecciones alineados al curr\u00edculo para programas de biolog\u00eda marina.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Para los cient\u00edficos<\/strong>:<br>Pr\u00f3ximamente se agregar\u00e1 mapeo de especies en tiempo real impulsado por avistamientos de la comunidad.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Para todos<\/strong>:<br>Una plataforma multiling\u00fce que hace que el conocimiento marino sea accesible en todas las culturas.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"499\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2025\/09\/Tree-of-Life-Screenshot-1-1024x499.png\" alt=\"\" class=\"wp-image-38411\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2025\/09\/Tree-of-Life-Screenshot-1-1024x499.png 1024w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2025\/09\/Tree-of-Life-Screenshot-1-300x146.png 300w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2025\/09\/Tree-of-Life-Screenshot-1-768x375.png 768w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2025\/09\/Tree-of-Life-Screenshot-1-1536x749.png 1536w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2025\/09\/Tree-of-Life-Screenshot-1-18x9.png 18w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2025\/09\/Tree-of-Life-Screenshot-1.png 1739w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">La herramienta &quot;\u00c1rbol de la Vida&quot; de la plataforma revela conexiones entre especies, convirtiendo la taxonom\u00eda abstracta en narrativa visual. Es educaci\u00f3n marina reinventada para la generaci\u00f3n de smartphones.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Detr\u00e1s de la belleza<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Esto es lo que hace que Grand Blue Project sea m\u00e1s que una simple base de datos impresionante: es una respuesta a una crisis en desarrollo. El oc\u00e9ano produce m\u00e1s de la mitad del ox\u00edgeno que respiramos y absorbe una cuarta parte de todas las emisiones de di\u00f3xido de carbono.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, la mayor\u00eda de la gente nunca ha visto las criaturas que hacen esto posible.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"900\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2025\/09\/pindito-4.jpg\" alt=\"\" class=\"wp-image-38406\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2025\/09\/pindito-4.jpg 400w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2025\/09\/pindito-4-133x300.jpg 133w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2025\/09\/pindito-4-5x12.jpg 5w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><em>No podemos proteger lo que no entendemos. No podemos valorar lo que nunca hemos visto.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las aguas de Indonesia, el coraz\u00f3n del Tri\u00e1ngulo de Coral, albergan la mayor biodiversidad marina del mundo. Pero tambi\u00e9n son la zona cero de las presiones ambientales. El blanqueamiento de los corales, la contaminaci\u00f3n por pl\u00e1sticos, la sobrepesca y el desarrollo costero est\u00e1n creando lo que los cient\u00edficos denominan una &quot;tormenta perfecta&quot; de amenazas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las im\u00e1genes de Edi capturan esta realidad en tiempo real. Su archivo no solo muestra el aspecto actual de las aguas indonesias, sino que tambi\u00e9n ofrece una visi\u00f3n de lo que podemos perder.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Construyendo un movimiento<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">El aspecto m\u00e1s innovador es la impresionante videoteca y c\u00f3mo transforma a los espectadores pasivos en participantes activos. Las tripulaciones de los cruceros de vida a bordo acceden a la plataforma para mejorar las sesiones informativas con los hu\u00e9spedes.&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Las escuelas lo integran en los programas de biolog\u00eda marina.&nbsp;<\/li>\n\n\n\n<li>Cada interacci\u00f3n fortalece la imagen global de la biodiversidad marina.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Y pronto, los operadores de buceo recibir\u00e1n c\u00f3digos QR para ayudar a los hu\u00e9spedes a contribuir con sus observaciones.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cada persona que registra un avistamiento, comparte im\u00e1genes o etiqueta una especie ayuda a ampliar la base de conocimientos de la plataforma.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los socios ganan comisiones por las suscripciones vendidas a trav\u00e9s de sus referencias, creando incentivos sostenibles para la educaci\u00f3n en conservaci\u00f3n.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es una prueba de que la protecci\u00f3n del medio ambiente y la viabilidad econ\u00f3mica pueden ir de la mano.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>\u201cLos desaf\u00edos globales requieren colaboraci\u00f3n global\u201d<\/em><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"800\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2025\/09\/pindito-2.jpg\" alt=\"\" class=\"wp-image-38412\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2025\/09\/pindito-2.jpg 600w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2025\/09\/pindito-2-225x300.jpg 225w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2025\/09\/pindito-2-9x12.jpg 9w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>La carrera contra el tiempo<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Al igual que las b\u00f3vedas de semillas que preservan la gen\u00e9tica de las plantas, esta plataforma preserva nuestra comprensi\u00f3n visual y cient\u00edfica de los ecosistemas marinos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero a diferencia de un archivo pasivo, est\u00e1 dise\u00f1ado para inspirar la acci\u00f3n.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cada video, cada perfil de especie, cada contribuci\u00f3n de la comunidad muestra a la gente lo que vive debajo de las olas para que tengan m\u00e1s probabilidades de protegerlo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta es la narrativa de conservaci\u00f3n evolucionada, cuando los desaf\u00edos globales requieren colaboraci\u00f3n global, cuando la educaci\u00f3n tradicional lucha por competir con el entretenimiento digital y cuando la protecci\u00f3n del medio ambiente necesita tanto rigor cient\u00edfico como conexi\u00f3n emocional.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2025\/09\/GBP-In-Action_4-1024x576.jpg\" alt=\"\" class=\"wp-image-38413\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2025\/09\/GBP-In-Action_4-1024x576.jpg 1024w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2025\/09\/GBP-In-Action_4-300x169.jpg 300w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2025\/09\/GBP-In-Action_4-768x432.jpg 768w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2025\/09\/GBP-In-Action_4-1536x864.jpg 1536w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2025\/09\/GBP-In-Action_4-18x10.jpg 18w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2025\/09\/GBP-In-Action_4.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\"><strong><em>Contribuir, aprender, compartir, proteger.<\/em><\/strong><br><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Esta plataforma est\u00e1 dise\u00f1ada para su participaci\u00f3n. Es la herramienta ideal para que escuelas y pasajeros de cruceros aprendan m\u00e1s sobre la interconexi\u00f3n del mar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El mensaje de Edi es claro:&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>\u201cSi la gente puede ver la vida marina en detalle, es m\u00e1s probable que la respeten y la protejan\u201d.<\/em>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Grand Blue Project toma esa filosof\u00eda y la escala globalmente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En una \u00e9poca en la que las noticias sobre medio ambiente suelen resultar abrumadoras, esta es una historia sobre soluciones.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El compromiso de una persona ha creado una herramienta que democratiza el conocimiento marino, conecta comunidades globales y transforma nuestra forma de pensar sobre la conservaci\u00f3n de los oc\u00e9anos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sum\u00e9rgete en la plataforma educativa marina interactiva m\u00e1s grande del mundo. Porque el futuro del oc\u00e9ano depende de nuestra comprensi\u00f3n actual.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br><br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00bfQuieres esto para tu aula o crucero?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Visita<a href=\"https:\/\/grandblueproject.com\/\" target=\"_blank\" rel=\"noopener\"> grandblueproject.com<\/a>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Siguenos en Instagram:<br><a href=\"https:\/\/www.instagram.com\/grandblueproject\/\" target=\"_blank\" rel=\"noopener\">proyecto grandblue<\/a><br><br><\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"499\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2025\/09\/Copy-of-edi.jpeg\" alt=\"\" class=\"wp-image-38414\" style=\"width:230px;height:auto\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2025\/09\/Copy-of-edi.jpeg 750w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2025\/09\/Copy-of-edi-300x200.jpeg 300w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2025\/09\/Copy-of-edi-18x12.jpeg 18w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><br><em>\u00a1P\u00f3ngase en contacto con Edi y su equipo hoy mismo!&nbsp;<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Correo electr\u00f3nico:<br><a href=\"mailto:hello@grandblueproject.com\">hola@grandblueproject.com<\/a> <br><br>WhatsApp<br><a href=\"https:\/\/wa.me\/628123815771\" target=\"_blank\" rel=\"noopener\">+62 812-3815-771<\/a><em> <\/em><br><em>Edi Frommenwiler<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em><strong><br><\/strong>Este art\u00edculo fue posible gracias a la colaboraci\u00f3n con <a href=\"https:\/\/pindito.com\/\" target=\"_blank\" rel=\"noopener\">Pindito vive a bordo.<\/a><\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>","protected":false},"excerpt":{"rendered":"<p>Un hombre film\u00f3 bajo el agua durante 30 a\u00f1os. Su archivo podr\u00eda salvar el mar.<br \/>\nLa b\u00fasqueda de tres d\u00e9cadas de un pionero para documentar la vida marina de Indonesia ha creado una plataforma digital que convierte a los espectadores en protectores del oc\u00e9ano.<\/p>","protected":false},"author":135,"featured_media":38405,"comment_status":"open","ping_status":"closed","template":"","meta":{"footnotes":""},"categories":[270,275],"tags":[427],"section":[385,387],"interest":[372,199,401,400],"_magazine":[426],"class_list":["post-38400","article","type-article","status-publish","has-post-thumbnail","hentry","category-explore","category-impact","tag-427","section-explore","section-impact","interest-eco","interest-expeditions","interest-nature","interest-things-to-do","_magazine-426"],"_links":{"self":[{"href":"https:\/\/instantkarmamag.com\/es\/wp-json\/wp\/v2\/article\/38400","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/instantkarmamag.com\/es\/wp-json\/wp\/v2\/article"}],"about":[{"href":"https:\/\/instantkarmamag.com\/es\/wp-json\/wp\/v2\/types\/article"}],"author":[{"embeddable":true,"href":"https:\/\/instantkarmamag.com\/es\/wp-json\/wp\/v2\/users\/135"}],"replies":[{"embeddable":true,"href":"https:\/\/instantkarmamag.com\/es\/wp-json\/wp\/v2\/comments?post=38400"}],"version-history":[{"count":6,"href":"https:\/\/instantkarmamag.com\/es\/wp-json\/wp\/v2\/article\/38400\/revisions"}],"predecessor-version":[{"id":38472,"href":"https:\/\/instantkarmamag.com\/es\/wp-json\/wp\/v2\/article\/38400\/revisions\/38472"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/instantkarmamag.com\/es\/wp-json\/wp\/v2\/media\/38405"}],"wp:attachment":[{"href":"https:\/\/instantkarmamag.com\/es\/wp-json\/wp\/v2\/media?parent=38400"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/instantkarmamag.com\/es\/wp-json\/wp\/v2\/categories?post=38400"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/instantkarmamag.com\/es\/wp-json\/wp\/v2\/tags?post=38400"},{"taxonomy":"section","embeddable":true,"href":"https:\/\/instantkarmamag.com\/es\/wp-json\/wp\/v2\/section?post=38400"},{"taxonomy":"interest","embeddable":true,"href":"https:\/\/instantkarmamag.com\/es\/wp-json\/wp\/v2\/interest?post=38400"},{"taxonomy":"_magazine","embeddable":true,"href":"https:\/\/instantkarmamag.com\/es\/wp-json\/wp\/v2\/_magazine?post=38400"}],"curies":[{"name":"Gracias","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}<!-- This website is optimized by Airlift. Learn more: https://airlift.net. Template:. Learn more: https://airlift.net. Template: 6a3c9e6bc6af5a91495580da. Config Timestamp: 2026-06-25 03:19:51 UTC, Cached Timestamp: 2026-09-02 02:28:42 UTC -->