{"id":32326,"date":"2024-04-11T12:05:54","date_gmt":"2024-04-11T04:05:54","guid":{"rendered":"https:\/\/instantkarmamag.com\/?post_type=article&#038;p=32326"},"modified":"2024-06-24T05:00:41","modified_gmt":"2024-06-23T21:00:41","slug":"buscando-comunidad","status":"publish","type":"article","link":"https:\/\/instantkarmamag.com\/es\/articulo\/buscando-comunidad\/","title":{"rendered":"Buscando comunidad"},"content":{"rendered":"<div id=\"bsf_rt_marker\"><\/div><p><span data-contrast=\"none\">La pandemia actual parece ser la raz\u00f3n m\u00e1s obvia de la epidemia de soledad.<\/span><span data-contrast=\"auto\"> Sin embargo, incluso antes de eso, la gente sol\u00eda arriesgar sus vidas solo para reunirse con amigos a pesar de todas las advertencias y castigos. Cuando se levantaron las restricciones, todos estaban felices de estar entre las personas de su comunidad. <\/span><\/p>\n<p><span data-contrast=\"auto\">Pero a\u00fan nos sentimos solos incluso sin el distanciamiento social obligatorio. \u00bfNos estamos distanciando voluntariamente?<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;134245417&quot;:true,&quot;335551550&quot;:1,&quot;335551620&quot;:1}\">\u00a0<\/span><\/p>\n<h2>El problema del aislamiento social<\/h2>\n<p><strong>Investigaciones recientes sobre el estado de soledad y aislamiento social encontraron que:\u00a0<\/strong><\/p>\n<p><span data-contrast=\"auto\">En Australia, el 34% de los adultos se sent\u00edan solos, de los cuales el 21% experimentaba soledad epis\u00f3dica y el 13% experimentaba soledad cr\u00f3nica. <\/span><\/p>\n<p><span data-contrast=\"auto\">En Estados Unidos, el 43% de los adultos sent\u00edan que carec\u00edan de compa\u00f1\u00eda, el 43% sent\u00edan que sus relaciones no eran significativas, el 43% se sent\u00edan aislados de los dem\u00e1s y el 39% ya no se sent\u00edan cercanos a nadie. <\/span><\/p>\n<p><span data-contrast=\"auto\">En Australia, 17% de la poblaci\u00f3n general fueron clasificados como socialmente aislados, de los cuales 13% experimentaron aislamiento epis\u00f3dico y 4% experimentaron aislamiento cr\u00f3nico.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;134245417&quot;:true,&quot;335551550&quot;:1,&quot;335551620&quot;:1}\">\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><strong>Redes sociales<\/strong><\/h3>\n<p><span data-contrast=\"none\">Si bien las redes sociales nos brindan la sensaci\u00f3n tan deseada de estar con otras personas, de comunicarnos y de estar en contacto, en realidad nos a\u00edslan unos de otros. Internet puede ser una gran herramienta de conexi\u00f3n si se utiliza correctamente, pero en este caso, requiere esfuerzo y conciencia.\u00a0<\/span><span data-ccp-props=\"{&quot;134245417&quot;:false,&quot;335551550&quot;:6,&quot;335551620&quot;:6}\">\u00a0<\/span><\/p>\n<p><\/p>\n<p><span data-contrast=\"none\">Es muy f\u00e1cil que un algoritmo te absorba en una comunidad. Solo hace falta un par de clics y ya est\u00e1s, absorbido por una nueva idea que... <\/span><span data-contrast=\"auto\">parece <\/span><span data-contrast=\"none\">Resuelve muchos de tus problemas. <\/span><\/p>\n<p><span data-contrast=\"none\">Lo m\u00e1s probable es que se base en el odio y en menospreciar a las personas. Encontrar una comunidad que est\u00e9 alineada con tus valores y opiniones, que se base en ideas positivas, requiere esfuerzo.\u00a0<\/span><span data-ccp-props=\"{&quot;134245417&quot;:false,&quot;335551550&quot;:6,&quot;335551620&quot;:6}\">\u00a0<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-32649 size-large\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2024\/04\/seeking-community-2-1024x683.jpg\" alt=\"Buscando comunidad\" width=\"1024\" height=\"683\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2024\/04\/seeking-community-2-1024x683.jpg 1024w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2024\/04\/seeking-community-2-300x200.jpg 300w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2024\/04\/seeking-community-2-768x512.jpg 768w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2024\/04\/seeking-community-2.jpg 1500w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<h3><strong>Creando comunidad<\/strong><\/h3>\n<p><span data-contrast=\"none\">Recientemente descubr\u00ed algo nuevo para m\u00ed: crear comunidades. <\/span><\/p>\n<p><span data-contrast=\"none\">Una vez que caes en la madriguera de los videos cortos depresivos, puedes parecer que eres la \u00fanica persona cuerda en este mundo. Especialmente si no tienes familiares y amigos que piensen lo mismo que t\u00fa. <\/span><\/p>\n<p><span data-contrast=\"none\">Pero si das un paso adelante y hablas en l\u00ednea, o re\u00fanes a personas fuera de l\u00ednea, o tal vez simplemente te comunicas con alguien que tiene las mismas opiniones que t\u00fa (o literalmente simplemente publica algo identificable, \u00a1as\u00ed de f\u00e1cil!), ver\u00e1s que es mucho m\u00e1s f\u00e1cil encontrar ese sentido de conexi\u00f3n de lo que pensabas.<\/span><\/p>\n<p><strong>Ven y \u00fanete a nosotros en <a href=\"https:\/\/karmakommunity.org\/\" target=\"_blank\" rel=\"noopener\">Comunidad Karma<\/a><\/strong><\/p>\n<p><span data-ccp-props=\"{&quot;134245417&quot;:false,&quot;335551550&quot;:6,&quot;335551620&quot;:6}\"><strong>Celebramos reuniones peri\u00f3dicas en la isla de Bali.<\/strong><br \/>\n<\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>A medida que nos volvemos m\u00e1s aislados, la necesidad de una comunidad y un sentimiento de uni\u00f3n se vuelve m\u00e1s importante.\u00a0<\/p>","protected":false},"author":40,"featured_media":32650,"comment_status":"open","ping_status":"closed","template":"","meta":{"footnotes":""},"categories":[274],"tags":[411],"section":[317],"interest":[378],"_magazine":[407],"class_list":["post-32326","article","type-article","status-publish","has-post-thumbnail","hentry","category-mindful","tag-readmore","section-mindful","interest-social","_magazine-407"],"_links":{"self":[{"href":"https:\/\/instantkarmamag.com\/es\/wp-json\/wp\/v2\/article\/32326","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/instantkarmamag.com\/es\/wp-json\/wp\/v2\/article"}],"about":[{"href":"https:\/\/instantkarmamag.com\/es\/wp-json\/wp\/v2\/types\/article"}],"author":[{"embeddable":true,"href":"https:\/\/instantkarmamag.com\/es\/wp-json\/wp\/v2\/users\/40"}],"replies":[{"embeddable":true,"href":"https:\/\/instantkarmamag.com\/es\/wp-json\/wp\/v2\/comments?post=32326"}],"version-history":[{"count":0,"href":"https:\/\/instantkarmamag.com\/es\/wp-json\/wp\/v2\/article\/32326\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/instantkarmamag.com\/es\/wp-json\/wp\/v2\/media\/32650"}],"wp:attachment":[{"href":"https:\/\/instantkarmamag.com\/es\/wp-json\/wp\/v2\/media?parent=32326"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/instantkarmamag.com\/es\/wp-json\/wp\/v2\/categories?post=32326"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/instantkarmamag.com\/es\/wp-json\/wp\/v2\/tags?post=32326"},{"taxonomy":"section","embeddable":true,"href":"https:\/\/instantkarmamag.com\/es\/wp-json\/wp\/v2\/section?post=32326"},{"taxonomy":"interest","embeddable":true,"href":"https:\/\/instantkarmamag.com\/es\/wp-json\/wp\/v2\/interest?post=32326"},{"taxonomy":"_magazine","embeddable":true,"href":"https:\/\/instantkarmamag.com\/es\/wp-json\/wp\/v2\/_magazine?post=32326"}],"curies":[{"name":"Gracias","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}<!-- This website is optimized by Airlift. Learn more: https://airlift.net. Template:. Learn more: https://airlift.net. Template: 6a3c9e6bc6af5a91495580da. Config Timestamp: 2026-06-25 03:19:51 UTC, Cached Timestamp: 2026-09-02 19:06:54 UTC -->