{"id":26962,"date":"2023-09-20T17:33:59","date_gmt":"2023-09-20T09:33:59","guid":{"rendered":"https:\/\/instantkarmamag.com\/?post_type=article&#038;p=26962"},"modified":"2024-02-05T01:51:54","modified_gmt":"2024-02-04T17:51:54","slug":"festival-de-escritores-de-ubud-2023","status":"publish","type":"article","link":"https:\/\/instantkarmamag.com\/es\/articulo\/festival-de-escritores-de-ubud-2023\/","title":{"rendered":"Festival de Escritores de Ubud 2023: creatividad inspiradora"},"content":{"rendered":"<div id=\"bsf_rt_marker\"><\/div><h3>Celebraci\u00f3n del 20\u00ba aniversario: el Festival de Escritores de Ubud regresa con un tema profundo en 2023<\/h3>\n<p><span data-contrast=\"auto\">El Festival de Escritores de Ubud 2023 (UWRF), uno de los festivales literarios m\u00e1s prestigiosos del sudeste asi\u00e1tico, acaba de anunciar su regreso para su edici\u00f3n n\u00famero 20, programada del 18 al 22 de octubre de 2023.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Para conmemorar este importante hito y al mismo tiempo abordar el estado global actual, el festival de este a\u00f1o adopta un tema apropiadamente contemplativo: <\/span><\/p>\n<h3><i><span data-contrast=\"auto\">Atita, Wartamana, Anagata: el pasado, el presente y el futuro<\/span><\/i><\/h3>\n<p><span data-contrast=\"auto\">Inspirada en el concepto balin\u00e9s del tiempo, Tri Semaya. Con crisis multifac\u00e9ticas como los conflictos globales y el cambio clim\u00e1tico, la humanidad se encuentra en una encrucijada crucial.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p>\n<p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\"> <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-26967 size-large\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/09\/Copyright-\u00a9-Ubud-Writers-_-Readers-Festival_General_4-1-1.jpg\" alt=\"\" width=\"1024\" height=\"684\" title=\"\"> <\/span><\/p>\n<h3>Oradores destacados: aspectos destacados del Festival de escritores de Ubud 2023<\/h3>\n<p><span data-contrast=\"auto\">Para involucrar a la audiencia en debates reflexivos a trav\u00e9s de la literatura y las artes, el festival contar\u00e1 con oradores visionarios y destacados como la intr\u00e9pida defensora del medio ambiente Vandana Shiva, la autora ganadora del premio Pulitzer y periodista de investigaci\u00f3n Geraldine Brooks, la autora ganadora del premio Booker <\/span><i><span data-contrast=\"auto\">Chica, Mujer, Otro<\/span><\/i><span data-contrast=\"auto\">, Bernadine Evaristo, Geetanjali Shree, el ganador del Premio Booker 2022 Shehan Karunatilaka, y el periodista, defensor de los derechos humanos, escritor y productor de cine Behrouz Boochani.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">La obra de arte del Festival, creada por la leyenda viviente de Indonesia, periodista, poeta, ensayista, novelista, artista visual y activista prodemocracia Goenawan Mohamad, tambi\u00e9n ser\u00e1 un punto destacado del festival.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p>\n<h2><strong>Celebrando la excelencia literaria de Indonesia<\/strong><\/h2>\n<p><span data-contrast=\"auto\">Adem\u00e1s, el festival exhibir\u00e1 autores indonesios de renombre internacional como Leila S. Chudori, cuyas novelas han sido traducidas al ingl\u00e9s, siendo la \u00faltima <\/span><i><span data-contrast=\"auto\">El mar dice su nombre<\/span><\/i><span data-contrast=\"auto\">, publicado por Penguin Random House Southeast Asia en 2020. Otra figura destacada es la autora y acad\u00e9mica Intan Paramaditha, cuyos libros han sido traducidos al ingl\u00e9s bajo los t\u00edtulos <\/span><i><span data-contrast=\"auto\">Manzana y cuchillo <\/span><\/i><span data-contrast=\"auto\">y <\/span><i><span data-contrast=\"auto\">El vagabundo<\/span><\/i><span data-contrast=\"auto\">, ambos publicados por Harvill Secker.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><strong>\u00a1Te esperan un retiro de escritura inmersiva y un festival m\u00e1gico!<\/strong><\/h2>\n<p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\"> <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-26966 size-large\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/09\/Copyright-\u00a9-Ubud-Writers-_-Readers-Festival_General_1-1.jpg\" alt=\"Festival de escritores y lectores de Ubud 2023 \" width=\"1024\" height=\"683\" title=\"\"><\/span><\/p>\n<p><span data-contrast=\"auto\">El Festival de Escritores de Ubud 2023 tambi\u00e9n inaugura su retiro de escritura del 15 al 22 de octubre. Esta aventura de escritura inmersiva de tres d\u00edas, que se celebrar\u00e1 en los exuberantes terrenos del Plataran Resort &amp; Spa de 5 estrellas, estar\u00e1 dirigida por las reconocidas novelistas Louise Doughty, Jill Dawson, Kathryn Heyman y Kate Pullinger. <\/span><\/p>\n<p><span data-contrast=\"auto\">Despu\u00e9s de este retiro, los participantes experimentar\u00e1n cuatro d\u00edas de magia del festival, incluida la exclusiva Gala de apertura, una cena en Casa Luna organizada por Janet De Neefe y mucho m\u00e1s.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">El Festival de Escritores de Ubud 2023 se celebra en medio del fascinante y m\u00edstico paisaje de Ubud, la capital cultural de Bali. El Festival pretende ser un oasis intelectual y creativo, que proporcione un espacio seguro para que tanto los oradores como el p\u00fablico puedan expresarse a trav\u00e9s de la literatura y las artes.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p>\n<div class=\"flex flex-grow flex-col gap-3 max-w-full\">\n<div class=\"min-h-[20px] flex flex-col items-start gap-3 overflow-x-auto whitespace-pre-wrap break-words\">\n<div class=\"markdown prose w-full break-words dark:prose-invert light\">\n<h2>Un oasis literario en el coraz\u00f3n de Bali<\/h2>\n<p>El Festival de Escritores y Lectores de Ubud (UWRF) siempre ha sido m\u00e1s que un encuentro de escritores y amantes de los libros. Es una celebraci\u00f3n del esp\u00edritu humano, un vibrante tapiz de culturas y una plataforma para el di\u00e1logo sobre los problemas m\u00e1s urgentes de nuestros tiempos.<\/p>\n<p>La UWRF celebra su 20.\u00ba aniversario con un tema profundo que resume la esencia de su trayectoria: \u201cAtita, Wartamana, Anagata: el pasado, el presente y el futuro\u201d. Este tema, inspirado en el concepto balin\u00e9s del tiempo, Tri Semaya, no podr\u00eda ser m\u00e1s apropiado para un mundo que se encuentra en una encrucijada crucial.<\/p>\n<h3 style=\"text-align: center;\">El regreso del Festival de Escritores de Ubud promete ser memorable en 2023, con un grupo de distinguidos oradores que est\u00e1n listos para iniciar conversaciones interesantes.<\/h3>\n<h2>Autores nacionales e internacionales se unen<\/h2>\n<p>Desde la defensora del medio ambiente Vandana Shiva hasta la autora ganadora del premio Pulitzer Geraldine Brooks y la novelista ganadora del premio Booker Bernadine Evaristo, el escenario est\u00e1 preparado para la exploraci\u00f3n intelectual y la inspiraci\u00f3n art\u00edstica.<\/p>\n<p>El festival se ve reforzado por las obras de Goenawan Mohamad, una leyenda viva cuyo trabajo abarca el periodismo, la poes\u00eda, los ensayos, las novelas y las artes visuales. Sus creaciones prometen ser un fest\u00edn visual y una fuente de contemplaci\u00f3n.<\/p>\n<h2>Escritores indonesios<\/h2>\n<p>Pero el Festival de Escritores de Ubud 2023 no se limita a las luminarias internacionales; tambi\u00e9n celebra la excelencia literaria indonesia.<\/p>\n<p>Leila S. Chudori e Intan Paramaditha, dos reconocidas autoras indonesias, compartir\u00e1n su trabajo, tendiendo puentes entre culturas a trav\u00e9s del poder de la narraci\u00f3n.<\/p>\n<h2>Retiro de escritura ofrecido por el Festival de Escritores de Ubud 2023<\/h2>\n<p>Para aquellos que buscan una inmersi\u00f3n m\u00e1s profunda, su retiro de escritura ofrece una oportunidad \u00fanica para perfeccionar su arte bajo la gu\u00eda de novelistas consumados.<\/p>\n<p>Ubicado en medio de los exuberantes jardines del hotel de 5 estrellas Plataran Resort &amp; Spa, este refugio es un preludio a la magia del festival. Desde la exclusiva gala de apertura hasta una cena en Casa Luna organizada por <a href=\"https:\/\/instantkarmamag.com\/es\/articulo\/janet-deneefe-fostering-creativity-and-embracing-cultural-diversity\/\" target=\"_blank\" rel=\"noopener\">Janet De Neefe<\/a>Los participantes del retiro vivir\u00e1n una experiencia inolvidable.<\/p>\n<p>M\u00e1s detalles aqu\u00ed <i><span data-contrast=\"auto\"><a href=\"http:\/\/www.ubudwritersfestival.com\/retreat\/\" target=\"_blank\" rel=\"noopener\">ubudwritersfestival.com\/retreat<\/a><\/span><\/i><\/p>\n<h2>Conclusi\u00f3n<\/h2>\n<p>El Festival de Escritores de Ubud 2023 no es solo un evento; es un oasis intelectual y creativo enclavado en el fascinante y m\u00edstico paisaje de Ubud, la capital cultural de Bali. Es un espacio donde convergen voces de diversos or\u00edgenes, donde se nutren las mentes y donde florece el arte. \u00danase a nosotros en esta celebraci\u00f3n de la literatura, las artes y el esp\u00edritu humano.<\/p>\n<h3>\u00danase a nosotros en el Festival de Escritores de Ubud 2023 y conozca a autores importantes. \u00a1Nos vemos all\u00ed!<\/h3>\n<\/div>\n<\/div>\n<\/div>\n<p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">&#8211;<br \/>\n<\/span><\/p>\n<p><i><span data-contrast=\"auto\">Para m\u00e1s detalles sobre el programa, visite <a href=\"http:\/\/www.ubudwritersfestival.com\/program\/\" target=\"_blank\" rel=\"noopener\">ubudwritersfestival.com\/program\/<\/a><\/span><\/i><\/p>\n<p><i><span data-contrast=\"auto\">Para explorar las opciones de entradas, vaya a <a href=\"http:\/\/www.ubudwritersfestival.com\/tickets\/\" target=\"_blank\" rel=\"noopener\">ubudwritersfestival.com\/tickets<\/a> .<\/span><\/i><\/p>\n<p><i><span data-contrast=\"auto\">Para obtener m\u00e1s informaci\u00f3n sobre el retiro de escritura, visite <a href=\"http:\/\/www.ubudwritersfestival.com\/retreat\/\" target=\"_blank\" rel=\"noopener\">ubudwritersfestival.com\/retreat.<\/a><\/span><\/i><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p>\n<p>&#8211;<\/p>\n<h3><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559740&quot;:276}\">Sigue a UWRF<br \/>\n<\/span><\/h3>\n<h3><a href=\"https:\/\/www.instagram.com\/ubudwritersfest\/\" target=\"_blank\" rel=\"noopener sponsored\" data-schema-attribute=\"mentions\">Instagram @ubudwritersfest<\/a><\/h3>","protected":false},"excerpt":{"rendered":"<p>Celebraci\u00f3n del 20.\u00ba aniversario: El Festival de Escritores de Ubud regresa con una tem\u00e1tica profunda en 2023. El Festival de Escritores de Ubud 2023 (UWRF), uno de los festivales literarios m\u00e1s prestigiosos del Sudeste Asi\u00e1tico, acaba de anunciar su regreso para su edici\u00f3n del 20.\u00ba aniversario, programada del 18 al 22 de octubre de 2023. Para conmemorar este importante hito y abordar la situaci\u00f3n mundial actual, [\u2026]<\/p>","protected":false},"author":1,"featured_media":26963,"comment_status":"open","ping_status":"closed","template":"","meta":{"footnotes":""},"categories":[271,313],"tags":[367],"section":[394],"interest":[380,383],"_magazine":[316],"class_list":["post-26962","article","type-article","status-publish","has-post-thumbnail","hentry","category-culture","category-review","tag-367","section-review","interest-creative","interest-wisdom","_magazine-316"],"_links":{"self":[{"href":"https:\/\/instantkarmamag.com\/es\/wp-json\/wp\/v2\/article\/26962","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/instantkarmamag.com\/es\/wp-json\/wp\/v2\/article"}],"about":[{"href":"https:\/\/instantkarmamag.com\/es\/wp-json\/wp\/v2\/types\/article"}],"author":[{"embeddable":true,"href":"https:\/\/instantkarmamag.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/instantkarmamag.com\/es\/wp-json\/wp\/v2\/comments?post=26962"}],"version-history":[{"count":0,"href":"https:\/\/instantkarmamag.com\/es\/wp-json\/wp\/v2\/article\/26962\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/instantkarmamag.com\/es\/wp-json\/wp\/v2\/media\/26963"}],"wp:attachment":[{"href":"https:\/\/instantkarmamag.com\/es\/wp-json\/wp\/v2\/media?parent=26962"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/instantkarmamag.com\/es\/wp-json\/wp\/v2\/categories?post=26962"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/instantkarmamag.com\/es\/wp-json\/wp\/v2\/tags?post=26962"},{"taxonomy":"section","embeddable":true,"href":"https:\/\/instantkarmamag.com\/es\/wp-json\/wp\/v2\/section?post=26962"},{"taxonomy":"interest","embeddable":true,"href":"https:\/\/instantkarmamag.com\/es\/wp-json\/wp\/v2\/interest?post=26962"},{"taxonomy":"_magazine","embeddable":true,"href":"https:\/\/instantkarmamag.com\/es\/wp-json\/wp\/v2\/_magazine?post=26962"}],"curies":[{"name":"Gracias","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}<!-- This website is optimized by Airlift. Learn more: https://airlift.net. Template:. Learn more: https://airlift.net. Template: 6a3c9e6bc6af5a91495580da. Config Timestamp: 2026-06-25 03:19:51 UTC, Cached Timestamp: 2026-09-02 10:34:14 UTC -->