{"id":20497,"date":"2023-01-02T21:51:16","date_gmt":"2023-01-02T13:51:16","guid":{"rendered":"https:\/\/instantkarmamag.com\/?post_type=article&#038;p=20497"},"modified":"2024-02-05T02:37:00","modified_gmt":"2024-02-04T18:37:00","slug":"la-belleza-de-sulawesi","status":"publish","type":"article","link":"https:\/\/instantkarmamag.com\/es\/articulo\/la-belleza-de-sulawesi\/","title":{"rendered":"La belleza de Sulawesi"},"content":{"rendered":"<div id=\"bsf_rt_marker\"><\/div><p><span data-contrast=\"none\">La isla de Sulawesi, antes conocida como C\u00e9lebes, posee una excepcional diversidad de culturas y destinos acu\u00e1ticos (como el Parque Nacional Bunaken y las islas Wakatobi) y, sin embargo, todav\u00eda se mantiene relativamente intacta.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"none\">Pero quiz\u00e1s sea para bien. En cada rinc\u00f3n se esconden joyas ocultas, con playas pr\u00edstinas, monta\u00f1as majestuosas y selvas tropicales remotas que se extienden a lo largo de sus cuatro \u201ctent\u00e1culos\u201d.<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-20512 size-large\" src=\"https:\/\/instantkarmamag.com\/files\/2023\/01\/sulawesi-map-1024x724.png\" alt=\"Mapa de Sulawesi\" width=\"1024\" height=\"724\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/01\/sulawesi-map-1024x724.png 1024w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/01\/sulawesi-map-300x212.png 300w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/01\/sulawesi-map-768x543.png 768w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/01\/sulawesi-map-1536x1087.png 1536w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/01\/sulawesi-map.png 1750w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p><span data-contrast=\"none\">Los llamados tent\u00e1culos son las cuatro pen\u00ednsulas de la isla: la pen\u00ednsula de Minahasa en el norte de Sulawesi, la pen\u00ednsula oriental, la pen\u00ednsula sur y la pen\u00ednsula sureste.<\/span><\/p>\n<p><span data-contrast=\"none\">Cada pen\u00ednsula de Sulawesi tiene su propia cultura distintiva que todav\u00eda est\u00e1 fuertemente ligada a sus antiguas pr\u00e1cticas animistas, particularmente en el sur, como la incomparable procesi\u00f3n f\u00fanebre de la tribu Toraja.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"none\">Los habitantes de la isla tambi\u00e9n son famosos por su destreza marinera, como lo ejemplifica perfectamente el Patrimonio de la Humanidad reconocido por la UNESCO. <a href=\"\/es\/articulo\/pinisi\/\">Barco pinisi de la tribu Bugis<\/a>Tambi\u00e9n est\u00e1 la tribu Bajo que se gan\u00f3 su apodo como<\/span><i><span data-contrast=\"none\">gitanos del mar<\/span><\/i><span data-contrast=\"none\">Mientras viven en aldeas flotantes en la isla de Togean, en un mundo de mareas crecientes, resulta curioso ver c\u00f3mo se ver\u00e1n afectadas sus vidas en el futuro.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<h3>Las tribus de Sulawesi<\/h3>\n<h4>La tribu religiosa de Minahasa (C\u00e9lebes del Norte)<\/h4>\n<p><span data-contrast=\"none\">Manado; hogar del singular apellido (o<\/span><i><span data-contrast=\"none\">Marga<\/span><\/i><span data-contrast=\"none\">) como<\/span><i><span data-contrast=\"none\">Gerungan, Mandagi, Ratulangi, Umboh, Sondakh,<\/span><\/i><span data-contrast=\"none\">y muchos otros con los que luego podr\u00e1s discernir de qu\u00e9 pueblo son. <\/span><\/p>\n<p><span data-contrast=\"none\">Debido a la gran influencia de la colonizaci\u00f3n portuguesa, espa\u00f1ola y, finalmente, holandesa, Manado y sus alrededores tienen una educaci\u00f3n muy occidentalizada. Usaban la palabra \u201cfam\u201d para indicar el apellido, que deriva de la palabra holandesa \u201cvan\u201d. <\/span><\/p>\n<p><span data-contrast=\"none\">Seg\u00fan un residente de Manado, la ciudad en s\u00ed no tiene una \u201ccultura\u201d particular de la que hablar, y ser un cristiano fiel y religioso es la norma aqu\u00ed, ya que 67.41% de los manadoneses son protestantes. Las iglesias, como era de esperar, est\u00e1n a tiro de piedra aqu\u00ed.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"none\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-20503 size-full\" src=\"https:\/\/instantkarmamag.com\/files\/2023\/01\/Screenshot-2023-01-02-at-21-10-46-14-PRINT.pdf.png\" alt=\"Explorar Sulawesi\" width=\"930\" height=\"493\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/01\/Screenshot-2023-01-02-at-21-10-46-14-PRINT.pdf.png 930w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/01\/Screenshot-2023-01-02-at-21-10-46-14-PRINT.pdf-300x159.png 300w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/01\/Screenshot-2023-01-02-at-21-10-46-14-PRINT.pdf-768x407.png 768w\" sizes=\"auto, (max-width: 930px) 100vw, 930px\" \/><\/span><\/p>\n<h4><span data-contrast=\"none\">Pero eso no significa que no haya cultura en Manado en el sentido tradicional. <\/span><\/h4>\n<p><span data-contrast=\"none\">Algunas escuelas ense\u00f1an a sus estudiantes a tocar el<\/span><i><span data-contrast=\"none\">kulintang,<\/span><\/i><span data-contrast=\"none\">El tradicional instrumento de percusi\u00f3n Minahasan, que consiste en l\u00e1minas de madera dispuestas en fila y montadas sobre una tina de madera. Antes de la llegada de los colonizadores, los instrumentos se utilizaban como parte del culto a los esp\u00edritus ancestrales. <\/span><\/p>\n<h4><span data-contrast=\"none\">En 2013, el Ministerio de Educaci\u00f3n de Indonesia y Culture reconocieron<\/span><i><span data-contrast=\"none\">kulintang<\/span><\/i><span data-contrast=\"none\">como Patrimonio Cultural Inmaterial Nacional de Indonesia.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/h4>\n<figure id=\"attachment_20513\" aria-describedby=\"caption-attachment-20513\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-20513 size-medium\" src=\"https:\/\/instantkarmamag.com\/files\/2023\/01\/kulintang-300x212.png\" alt=\"sulawesi manado cultura\" width=\"300\" height=\"212\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/01\/kulintang-300x212.png 300w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/01\/kulintang-768x543.png 768w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/01\/kulintang-1024x724.png 1024w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/01\/kulintang.png 1500w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-20513\" class=\"wp-caption-text\"><em>Un instrumento tradicional t\u00edpico de manado kulintang.<\/em><\/figcaption><\/figure>\n<p><span data-contrast=\"none\">Otra tradici\u00f3n interesante de Minahasa se llama<em>METRO<\/em><\/span><i><span data-contrast=\"none\">apalo,<\/span><\/i><span data-contrast=\"none\">que es una forma de &#039;G<\/span><i><span data-contrast=\"none\">otro Royong&#039;<\/span><\/i><span data-contrast=\"none\">o servicio comunitario que se practica en toda Indonesia. <\/span><\/p>\n<p><span data-contrast=\"none\">La tradici\u00f3n tiene un origen agr\u00edcola en el que todos colaboran para cosechar los frutos de la naturaleza, pero gradualmente se ha ido implementando tambi\u00e9n en el ciclo de vida de una persona (nacimiento, boda, muerte). El esp\u00edritu comunitario de<em>METRO<\/em><\/span><i><span data-contrast=\"none\">apalo<\/span><\/i><span data-contrast=\"none\">Es ciertamente digno de elogio, ya que la vida moderna, especialmente en las grandes ciudades, carece de tal reciprocidad. <\/span><\/p>\n<p><span data-contrast=\"none\">Y uno de los lemas de Sulawesi del Norte lo dice todo:<\/span><\/p>\n<h3 style=\"text-align: center;\"><i><span data-contrast=\"none\">Para todos los que lo necesitan,<\/span><\/i><span data-contrast=\"none\">traducido como Todos somos familia.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-20504 size-full\" src=\"https:\/\/instantkarmamag.com\/files\/2023\/01\/Screenshot-2023-01-02-at-21-10-27-14-PRINT.pdf.png\" alt=\"Explorar Sulawesi\" width=\"738\" height=\"489\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/01\/Screenshot-2023-01-02-at-21-10-27-14-PRINT.pdf.png 738w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/01\/Screenshot-2023-01-02-at-21-10-27-14-PRINT.pdf-300x199.png 300w\" sizes=\"auto, (max-width: 738px) 100vw, 738px\" \/><\/p>\n<h4><\/h4>\n<h3>Los bugis del sur de Sulawesi, que se encuentran en el l\u00edmite del oc\u00e9ano<\/h3>\n<p><span data-contrast=\"none\">Hay un viejo dicho en indonesio:<\/span><\/p>\n<p><i><span data-contrast=\"none\">Nenek moyangku adalah seorang pelaut<\/span><\/i><span data-contrast=\"none\">(Mis antepasados son marineros), un dicho que podr\u00eda surgir de la tribu marinera Bugis del sur de Sulawesi.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-20501 size-large\" src=\"https:\/\/instantkarmamag.com\/files\/2023\/01\/Screenshot-2023-01-02-at-21-11-29-14-PRINT.pdf-1024x448.png\" alt=\"Explorar Sulawesi\" width=\"1024\" height=\"448\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/01\/Screenshot-2023-01-02-at-21-11-29-14-PRINT.pdf-1024x448.png 1024w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/01\/Screenshot-2023-01-02-at-21-11-29-14-PRINT.pdf-300x131.png 300w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/01\/Screenshot-2023-01-02-at-21-11-29-14-PRINT.pdf-768x336.png 768w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/01\/Screenshot-2023-01-02-at-21-11-29-14-PRINT.pdf.png 1222w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p><span data-contrast=\"none\">Los bugis son el grupo \u00e9tnico m\u00e1s numeroso de Sulawesi del Sur (seguidos de los makasar, los toraja y los mandares). Y aqu\u00ed hay un dato curioso: los bugis no estaban originalmente ligados al oc\u00e9ano: eran agricultores a partir del siglo XVIII. Reci\u00e9n en el siglo XIX empezaron a ser conocidos como marineros, cuando se vieron flotas de sus barcos pinisi que llegaban hasta Australia y \u00c1frica.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-20498 size-full\" src=\"https:\/\/instantkarmamag.com\/files\/2023\/01\/Screenshot-2023-01-02-at-21-12-41-14-PRINT.pdf1_.png\" alt=\"Explorar Sulawesi\" width=\"886\" height=\"470\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/01\/Screenshot-2023-01-02-at-21-12-41-14-PRINT.pdf1_.png 886w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/01\/Screenshot-2023-01-02-at-21-12-41-14-PRINT.pdf1_-300x159.png 300w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/01\/Screenshot-2023-01-02-at-21-12-41-14-PRINT.pdf1_-768x407.png 768w\" sizes=\"auto, (max-width: 886px) 100vw, 886px\" \/><\/p>\n<p><span data-contrast=\"none\">Tambi\u00e9n exist\u00eda la tradici\u00f3n de<em>S<\/em><\/span><i><span data-contrast=\"none\">Ompeq<\/span><\/i><span data-contrast=\"none\">y<em>PAG<\/em><\/span><i><span data-contrast=\"none\"><em>a<\/em>sompegg<\/span><\/i><span data-contrast=\"none\">El primero significa aproximadamente \u201cviajar\u201d y el segundo \u201cl\u00edmite oce\u00e1nico\u201d, lo que extiende la poblaci\u00f3n de la tribu Bugis por todo el archipi\u00e9lago indonesio, as\u00ed como en diferentes pa\u00edses.<\/span><\/p>\n<p><span data-contrast=\"none\">Incluso puedes encontrar un pueblo llamado<\/span><i><span data-contrast=\"none\">Macasar<\/span><\/i><span data-contrast=\"none\">en las afueras de Ciudad del Cabo, en Sud\u00e1frica. Tambi\u00e9n se les consideraba responsables de la proliferaci\u00f3n del comercio de especias en todo el mundo, ya que cargaban sus especias favoritas a bordo.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<h3>La literatura \u00e9pica de La Galigo<\/h3>\n<figure id=\"attachment_20514\" aria-describedby=\"caption-attachment-20514\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-20514 size-medium\" src=\"https:\/\/instantkarmamag.com\/files\/2023\/01\/la-galigo-e1672667004513-300x179.jpg\" alt=\"www.republika.co.id\" width=\"300\" height=\"179\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/01\/la-galigo-e1672667004513-300x179.jpg 300w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/01\/la-galigo-e1672667004513-768x459.jpg 768w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/01\/la-galigo-e1672667004513.jpg 798w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-20514\" class=\"wp-caption-text\">Foto cortes\u00eda de <a href=\"https:\/\/www.republika.co.id\/berita\/q7r6uh430\/pengaruh-islam-dalam-epos-i-la-galigo-1\" target=\"_blank\" rel=\"noopener\">www.republika.co.id<\/a><\/figcaption><\/figure>\n<p><span data-contrast=\"none\">La Galigo es como la biblia sagrada para los seguidores de las antiguas creencias de los Bugis llamadas &#039;<em>yo<\/em><\/span><i><span data-contrast=\"none\">el lotang&#039;.<\/span><\/i><span data-contrast=\"none\">Su gran volumen (6.000 p\u00e1ginas) supera incluso a otros textos sagrados como el Mahabharata de la India y el Homero de Grecia. Es de naturaleza epis\u00f3dica y aborda temas de moralidad y sabidur\u00eda envueltos en mitolog\u00edas que involucran a deidades celestiales.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><i><span data-contrast=\"none\">La Galigo<\/span><\/i><span data-contrast=\"none\">El manuscrito data del siglo XIV y se transmiti\u00f3 de forma oral antes de ser puesto por escrito entre los siglos XVIII y XX. En la actualidad, se considera que es la obra literaria m\u00e1s extensa del mundo, escrita en forma de poema en pent\u00e1metro.<\/span><\/p>\n<p><span data-contrast=\"none\">Las palabras de La Galigo se cantan e implican ciertos rituales (ofrendas, sacrificios de animales) antes de su lectura.<\/span><i><span data-contrast=\"none\">bis\u00fa,<\/span><\/i><span data-contrast=\"none\">La santa sacerdotisa Bugis, es la encargada del canto de La Galigo.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-20506 size-large\" src=\"https:\/\/instantkarmamag.com\/files\/2023\/01\/Screenshot-2023-01-02-at-21-09-47-14-PRINT.pdf-1024x452.png\" alt=\"Explorar Sulawesi\" width=\"1024\" height=\"452\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/01\/Screenshot-2023-01-02-at-21-09-47-14-PRINT.pdf-1024x452.png 1024w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/01\/Screenshot-2023-01-02-at-21-09-47-14-PRINT.pdf-300x132.png 300w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/01\/Screenshot-2023-01-02-at-21-09-47-14-PRINT.pdf-768x339.png 768w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/01\/Screenshot-2023-01-02-at-21-09-47-14-PRINT.pdf.png 1060w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<h3>En Sulawesi son Bissu<\/h3>\n<p><span data-contrast=\"none\">El<\/span><i><span data-contrast=\"none\">bis\u00fa<\/span><\/i><span data-contrast=\"none\">El pueblo Bugis es una figura fascinante en la historia de Bugis. Mucho antes de que el mundo actual reconociera lentamente la diversidad de g\u00e9nero (y de pronombres), la tribu Bugis reconoc\u00eda cinco g\u00e9neros:<\/span><i><span data-contrast=\"none\">oroano<\/span><\/i><span data-contrast=\"none\">(cis masculino),<\/span><i><span data-contrast=\"none\">makunrai<\/span><\/i><span data-contrast=\"none\">(cis mujer),<\/span><i><span data-contrast=\"none\">Calalai<\/span><\/i><span data-contrast=\"none\">(hembra con comportamiento masculino),<\/span><i><span data-contrast=\"none\">Calabaza<\/span><\/i><span data-contrast=\"none\">(masculino con comportamiento femenino) y, por \u00faltimo, el<\/span><i><span data-contrast=\"none\">bis\u00fa,<\/span><\/i><span data-contrast=\"none\">una figura intersexual que encarna tanto lo masculino como lo femenino.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"none\">En el<\/span><i><span data-contrast=\"none\">La Galigo<\/span><\/i><span data-contrast=\"none\">texto, el<\/span><i><span data-contrast=\"none\">bis\u00fa<\/span><\/i><span data-contrast=\"none\">Se menciona que descendi\u00f3 a la tierra junto con el primer hombre en la tierra (<\/span><i><span data-contrast=\"none\">Amanecer<\/span><\/i><span data-contrast=\"none\">), y fueron asignados como guardianes del reino y como enlace entre los humanos, el dios del cielo (<\/span><i><span data-contrast=\"none\">pero largo<\/span><\/i><span data-contrast=\"none\">) y el dios del mar (buri liung). De ah\u00ed su rango sagrado y reverenciado dentro de la tribu Bugis.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-20510 size-large\" src=\"https:\/\/instantkarmamag.com\/files\/2023\/01\/Sulawesi_08_come2indonesia_Indonesia-1024x720.jpg\" alt=\"Explorar Sulawesi\" width=\"1024\" height=\"720\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/01\/Sulawesi_08_come2indonesia_Indonesia-1024x720.jpg 1024w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/01\/Sulawesi_08_come2indonesia_Indonesia-300x211.jpg 300w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/01\/Sulawesi_08_come2indonesia_Indonesia-768x540.jpg 768w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/01\/Sulawesi_08_come2indonesia_Indonesia.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p><span data-contrast=\"none\">Lamentablemente, en el mundo moderno, el papel de<\/span><i><span data-contrast=\"none\">bis\u00fa<\/span><\/i><span data-contrast=\"none\">Ha sido minimizada y marginada significativamente, a partir de la islamizaci\u00f3n de la provincia por el movimiento rebelde Kahar Muzakar en 1965. <\/span><\/p>\n<p><span data-contrast=\"none\">Junto con el<\/span><i><span data-contrast=\"none\">Calabaza<\/span><\/i><span data-contrast=\"none\">g\u00e9nero, son ridiculizados y considerados antinaturales. Pero algunos<\/span><i><span data-contrast=\"none\">bis\u00fa<\/span><\/i><span data-contrast=\"none\">Las comunidades a\u00fan sobreviven hoy, dirigiendo y bendiciendo ceremonias nupciales, especialmente en regencias donde<\/span><i><span data-contrast=\"none\">A lotang<\/span><\/i><span data-contrast=\"none\">Todav\u00eda se practica, como en la regencia de Sidenreng Rappang.<\/span><\/p>\n<h3>Algunos puntos destacados de Sulawesi<\/h3>\n<h4>Danau Lago Tondano<\/h4>\n<p><span data-contrast=\"none\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-20500 size-full\" src=\"https:\/\/instantkarmamag.com\/files\/2023\/01\/Screenshot-2023-01-02-at-21-11-51-14-PRINT.pdf.png\" alt=\"Explorar Sulawesi\" width=\"820\" height=\"554\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/01\/Screenshot-2023-01-02-at-21-11-51-14-PRINT.pdf.png 820w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/01\/Screenshot-2023-01-02-at-21-11-51-14-PRINT.pdf-300x203.png 300w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/01\/Screenshot-2023-01-02-at-21-11-51-14-PRINT.pdf-768x519.png 768w\" sizes=\"auto, (max-width: 820px) 100vw, 820px\" \/>El lago Tondano, situado a unos 30 minutos de la ciudad de Manado, es un lugar fresco y pintoresco, aislado por tres majestuosas monta\u00f1as (Lembean, Kaweng y Masareng). Seg\u00fan el folclore local, el lago fue el resultado de un tormentoso encuentro entre dos tortolitos cuyos padres no aprobaban su relaci\u00f3n. Se escaparon al bosque y, as\u00ed, el volc\u00e1n Kaweng se abri\u00f3 y cre\u00f3 el lago. <\/span><\/p>\n<h5><span data-contrast=\"none\">\u00a1Y qu\u00e9 lago m\u00e1s bonito es! <\/span><\/h5>\n<p><span data-contrast=\"none\">En los alrededores hay algunos restaurantes modestos donde se puede probar la cocina local, en su mayor\u00eda picante. Tambi\u00e9n se puede ir a pie y experimentar la vida local del pueblo. <\/span><\/p>\n<p><span data-contrast=\"none\">Si tienes suerte, puedes ser invitado a una de las casas (especialmente si est\u00e1s con un gu\u00eda tur\u00edstico) y recibir una porci\u00f3n de bu\u00f1uelos de pl\u00e1tano con condimento de chile, as\u00ed como su licor local.<\/span><i><span data-contrast=\"none\">gorra tikus,<\/span><\/i><span data-contrast=\"none\">Un tipo de alcohol, similar al vodka 70%, elaborado a partir de az\u00facar de palma fermentada. Puedes beberlo si te atreves, pero sin duda es bueno para calentar el cuerpo.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<h4>Parque Nacional Bunaken<\/h4>\n<p><span data-contrast=\"none\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-20499 size-full\" src=\"https:\/\/instantkarmamag.com\/files\/2023\/01\/Screenshot-2023-01-02-at-21-12-22-14-PRINT.pdf.png\" alt=\"Explorar Sulawesi\" width=\"726\" height=\"387\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/01\/Screenshot-2023-01-02-at-21-12-22-14-PRINT.pdf.png 726w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/01\/Screenshot-2023-01-02-at-21-12-22-14-PRINT.pdf-300x160.png 300w\" sizes=\"auto, (max-width: 726px) 100vw, 726px\" \/><\/span><\/p>\n<p><span data-contrast=\"none\">Si buscas una experiencia submarina, no te pierdas el Parque Nacional Bunaken, un lugar que no debes perderte si est\u00e1s en el norte de Sulawesi. Se trata de un parque marino de 75.265 hect\u00e1reas que se compone de cinco islas: Bunaken, Manado Tua, Siladen, Mantehage y Naen. El parque, situado cerca del centro del Tri\u00e1ngulo de Coral, alberga 390 especies de corales coloridos y una gran variedad de vida marina.<\/span><\/p>\n<p><span data-contrast=\"none\">Entre los principales atractivos se encuentran los muros colgantes: una enorme pared de roca vertical que funciona como una especie de buf\u00e9 de comida para los peces. Las pr\u00e1cticas pesqueras irresponsables, como la pesca con explosivos, han afectado negativamente al entorno submarino, pero los esfuerzos de conservaci\u00f3n en curso han restaurado lentamente la belleza del parque.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>La isla de Sulawesi, antes conocida como C\u00e9lebes, posee una excepcional diversidad de culturas y destinos acu\u00e1ticos (como el Parque Nacional Bunaken y las Islas Wakatobi) y, sin embargo, a\u00fan se encuentra relativamente intacta. Pero quiz\u00e1s sea para bien. Joyas ocultas se esconden en cada rinc\u00f3n, con playas v\u00edrgenes, monta\u00f1as majestuosas y selvas tropicales remotas que se extienden a lo largo de [\u2026]<\/p>","protected":false},"author":46,"featured_media":20511,"comment_status":"open","ping_status":"closed","template":"","meta":{"footnotes":""},"categories":[271,270],"tags":[360,278],"section":[386,385],"interest":[199,377],"_magazine":[358],"class_list":["post-20497","article","type-article","status-publish","has-post-thumbnail","hentry","category-culture","category-explore","tag-360","tag-sulawesi","section-culture","section-explore","interest-expeditions","interest-sightseeing","_magazine-358"],"_links":{"self":[{"href":"https:\/\/instantkarmamag.com\/es\/wp-json\/wp\/v2\/article\/20497","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/instantkarmamag.com\/es\/wp-json\/wp\/v2\/article"}],"about":[{"href":"https:\/\/instantkarmamag.com\/es\/wp-json\/wp\/v2\/types\/article"}],"author":[{"embeddable":true,"href":"https:\/\/instantkarmamag.com\/es\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/instantkarmamag.com\/es\/wp-json\/wp\/v2\/comments?post=20497"}],"version-history":[{"count":0,"href":"https:\/\/instantkarmamag.com\/es\/wp-json\/wp\/v2\/article\/20497\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/instantkarmamag.com\/es\/wp-json\/wp\/v2\/media\/20511"}],"wp:attachment":[{"href":"https:\/\/instantkarmamag.com\/es\/wp-json\/wp\/v2\/media?parent=20497"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/instantkarmamag.com\/es\/wp-json\/wp\/v2\/categories?post=20497"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/instantkarmamag.com\/es\/wp-json\/wp\/v2\/tags?post=20497"},{"taxonomy":"section","embeddable":true,"href":"https:\/\/instantkarmamag.com\/es\/wp-json\/wp\/v2\/section?post=20497"},{"taxonomy":"interest","embeddable":true,"href":"https:\/\/instantkarmamag.com\/es\/wp-json\/wp\/v2\/interest?post=20497"},{"taxonomy":"_magazine","embeddable":true,"href":"https:\/\/instantkarmamag.com\/es\/wp-json\/wp\/v2\/_magazine?post=20497"}],"curies":[{"name":"Gracias","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}<!-- This website is optimized by Airlift. Learn more: https://airlift.net. Template:. Learn more: https://airlift.net. Template: 6a3c9e6bc6af5a91495580da. Config Timestamp: 2026-06-25 03:19:51 UTC, Cached Timestamp: 2026-09-02 07:04:44 UTC -->