{"id":13180,"date":"2022-07-01T17:55:24","date_gmt":"2022-07-01T09:55:24","guid":{"rendered":"https:\/\/instantkarmamag.com\/?post_type=article&#038;p=13180"},"modified":"2024-07-03T16:23:49","modified_gmt":"2024-07-03T08:23:49","slug":"balance","status":"publish","type":"article","link":"https:\/\/instantkarmamag.com\/es\/articulo\/balance\/","title":{"rendered":"Encontrar el equilibrio"},"content":{"rendered":"<div id=\"bsf_rt_marker\"><\/div><h3><strong>\u00bfPor qu\u00e9 uno viaja?<\/strong><\/h3>\n<p>\u00bfDecir que estuve en ese monumento, cascada, edificio, templo? \u00bfO simplemente es sentarse y observar lo que sucede a tu alrededor? \u00bfViajas en compa\u00f1\u00eda de otros o solo? Fue la decisi\u00f3n de salir y encontrar algo a lo que no est\u00e1s acostumbrado porque lo bonito de viajar es salir de la rutina y adentrarse en lo desconocido. Por eso, para muchos, viajar es encontrar el equilibrio interior.<\/p>\n<p>Viajar es un consumo constante, un gasto en alojamiento, comida y desplazamientos. Para muchos eres un loco que no piensa en el futuro, mientras que para otros eres el que hace todo bien.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-13186 size-full\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/07\/Screenshot-2022-07-01-at-17-44-26-11-OUTLINE_FINAL17june.pdf.png\" alt=\"bandita josefina encontrando el equilibrio articulo revista karma instantaneo\" width=\"353\" height=\"533\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/07\/Screenshot-2022-07-01-at-17-44-26-11-OUTLINE_FINAL17june.pdf.png 353w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/07\/Screenshot-2022-07-01-at-17-44-26-11-OUTLINE_FINAL17june.pdf-199x300.png 199w\" sizes=\"auto, (max-width: 353px) 100vw, 353px\" \/><\/p>\n<h3><b>Cada uno elige su propio camino<\/b><\/h3>\n<p>Soy de los que busca constantemente est\u00edmulos, y la mayor\u00eda de ellos son visuales. Me pierdo en calles laber\u00ednticas y camino siempre en sentido contrario.<\/p>\n<p>Intentar hacer contacto visual a veces es dif\u00edcil, pero es la mejor actuaci\u00f3n que se me ocurre cuando alguien te devuelve la sonrisa. Los ojos lo dicen todo. Muchos pueden mirar a los ojos y sonre\u00edr t\u00edmidamente, y otros pueden re\u00edr a carcajadas, mirar al suelo o a un lado. Pero capturar esa mirada en una foto es la parte gratificante, al menos para m\u00ed.<\/p>\n<p>Es el cambio de una ciudad de casas de bamb\u00fa con gallinas y cerdos jugando en el c\u00e1ntaro a una metr\u00f3polis rodeada de constante movimiento, durmiendo en lo que haya disponible por la noche, con la m\u00edstica de sentirse aventurero y no saber si despertar\u00e1s al lado de una rana, una lagartija o siendo comido por mosquitos.<\/p>\n<p>Apreciar una ducha caliente parece una frase cursi y en dos meses nadie encuentra la panacea. Sabes que vas a elegir la ducha caliente, pero aunque sea por un rato, te hace valorar algo que parece b\u00e1sico en la vida de las personas.<\/p>\n<p>\u00bfC\u00f3mo se vuelve de un viaje? No es la primera vez que decido hacer un viaje por mi cuenta a un nuevo destino, pero s\u00ed es la primera vez que no sigo un itinerario.<\/p>\n<p>Aunque todav\u00eda siento el cosquilleo que me hace moverme cada dos o tres d\u00edas, explorar cada rinc\u00f3n y encontrar la mejor foto del d\u00eda tambi\u00e9n es agotador, sobre todo cuando viajas con dos mochilas que suponen m\u00e1s de la mitad de tu peso.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-13185 size-full\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/07\/Screenshot-2022-07-01-at-17-44-46-11-OUTLINE_FINAL17june.pdf.png\" alt=\"bandita josefina encontrando el equilibrio articulo revista karma instantaneo\" width=\"523\" height=\"306\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/07\/Screenshot-2022-07-01-at-17-44-46-11-OUTLINE_FINAL17june.pdf.png 523w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/07\/Screenshot-2022-07-01-at-17-44-46-11-OUTLINE_FINAL17june.pdf-300x176.png 300w\" sizes=\"auto, (max-width: 523px) 100vw, 523px\" \/><\/p>\n<h3>El equilibrio<\/h3>\n<p>Encontrar el equilibrio es, como en la vida, la parte m\u00e1s desafiante.<\/p>\n<p>Viajar solo tiene esta ventaja: puedes elegir d\u00f3nde quieres estar, cu\u00e1ndo quieres estar, qui\u00e9n quieres ser y c\u00f3mo quieres ser. La alegr\u00eda de estar en tu propio mundo, donde puedes encontrar la independencia y la felicidad que nadie te puede dar.<\/p>\n<p>Escuchar las historias de las personas y aprender cosas nuevas puede ser maravilloso, pero \u00bftengo la paciencia para escucharlas cuando hablan y hacen ruidos cuando comen? \u00bfO cuando roncan?<\/p>\n<p>Compartes con estas personas por un momento y luego cada uno sigue su camino.<\/p>\n<h2 style=\"text-align: center;\">Y al final, la vida es as\u00ed, compartes un momento. Ese momento corto o largo, compartes mucho, compartes un poco, extra\u00f1as m\u00e1s, extra\u00f1as menos cuando se van.<\/h2>\n<p>Y vuelvo a la pregunta, \u00bfc\u00f3mo se vuelve de un viaje? \u00bfUno quiere volver a instalarse en un lugar? \u00bfEstablecer una rutina? \u00bfRodearse de las mismas personas una y otra vez? \u00bfO seguir viajando a nuevos lugares? \u00bfAhorrar para emprender un nuevo viaje?<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-13184 size-full\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/07\/Screenshot-2022-07-01-at-17-44-59-11-OUTLINE_FINAL17june.pdf.png\" alt=\"bandita josefina encontrando el equilibrio articulo revista karma instantaneo\" width=\"393\" height=\"325\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/07\/Screenshot-2022-07-01-at-17-44-59-11-OUTLINE_FINAL17june.pdf.png 393w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/07\/Screenshot-2022-07-01-at-17-44-59-11-OUTLINE_FINAL17june.pdf-300x248.png 300w\" sizes=\"auto, (max-width: 393px) 100vw, 393px\" \/><\/p>\n<h2 style=\"text-align: center;\">De un viaje no se vuelve. Uno elige a d\u00f3nde volver.<\/h2>\n<p>Cuando regresas a tu casa, a tu familia, a tu perro, a tu gato y a tu rutina, te quedas con la nostalgia y la alegr\u00eda que te regalaron esas fotos, s\u00f3lo para buscar un destino futuro.<\/p>\n<p>Si decides viajar y quedarte en otro lugar y empezar de nuevo, sigues adelante y buscas nuevos destinos. Nadie tiene la respuesta y cada uno elige su propio camino.<\/p>\n<p>Para m\u00ed viajar es un viaje interior. Equilibro mi vida con la fotograf\u00eda, eso es lo que hago.<\/p>\n<p>Entro en el lugar de los hechos, sea donde sea. Es el contacto con las personas, sus expresiones y su entorno donde capto ese momento m\u00e1gico y \u00fanico.<\/p>\n<p>No importa si la luz es perfecta o si la persona o el objeto est\u00e1n en una posici\u00f3n ideal. Si es la foto que quiero, esa es la foto que quiero. <a href=\"https:\/\/instantkarmamag.com\/es\/articulo\/ser-feliz\/\">Me hace feliz.<\/a><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-13183 size-full\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/07\/Screenshot-2022-07-01-at-17-45-11-11-OUTLINE_FINAL17june.pdf-1.png\" alt=\"bandita josefina encontrando el equilibrio articulo revista karma instantaneo\" width=\"310\" height=\"557\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/07\/Screenshot-2022-07-01-at-17-45-11-11-OUTLINE_FINAL17june.pdf-1.png 310w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/07\/Screenshot-2022-07-01-at-17-45-11-11-OUTLINE_FINAL17june.pdf-1-167x300.png 167w\" sizes=\"auto, (max-width: 310px) 100vw, 310px\" \/><\/p>\n<h4>\u00bfCuales son tus consejos y trucos para tomar fotograf\u00edas?<\/h4>\n<p>No necesitas las c\u00e1maras y lentes m\u00e1s caras para tomar buenas fotos. Alguien sabio me dijo una vez que cuando logras la foto que quieres, esa es la foto perfectamente equilibrada.<\/p>\n<p>El otro punto importante es la luz. Sin luz no hay fotograf\u00eda.<\/p>\n<p>Y por \u00faltimo, practica. Empieza a sacar fotos al azar, luego c\u00e9ntrate m\u00e1s en lo que m\u00e1s te guste y juega. Nunca sabes de lo que eres capaz hasta que empiezas.<\/p>\n<h4>\u00bfCuales son tus deseos para el futuro?<\/h4>\n<p>Nunca dejes de ser creativo.<\/p>\n<h4>\u00bfHas estado alguna vez en Bali?<\/h4>\n<p>Estuve en Bali hace 12 a\u00f1os con mi familia durante dos semanas, y siempre digo que cuando tengo un billete de ida al sur de Asia, Bali ser\u00e1 el lugar a explorar.<\/p>\n<h4>\u00bfPor qu\u00e9 volviste a Bali?<\/h4>\n<p>Viaj\u00e9 por el sur de Asia y quer\u00eda pasar mi cumplea\u00f1os en Bali. Pas\u00e9 dos semanas, viaj\u00e9 a Europa y volv\u00ed porque hay algo en Bali que no se puede explicar a menos que lo pruebes.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-13187 size-full\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/07\/Screenshot-2022-07-01-at-17-44-16-11-OUTLINE_FINAL17june.pdf.png\" alt=\"bandita josefina encontrando el equilibrio articulo revista karma instantaneo\" width=\"307\" height=\"384\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/07\/Screenshot-2022-07-01-at-17-44-16-11-OUTLINE_FINAL17june.pdf.png 307w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/07\/Screenshot-2022-07-01-at-17-44-16-11-OUTLINE_FINAL17june.pdf-240x300.png 240w\" sizes=\"auto, (max-width: 307px) 100vw, 307px\" \/><\/p>\n<h4>\u00bfQu\u00e9 te fascina de Bali?<\/h4>\n<p>Libertad y equilibrio. Bali es un lugar al que mucha gente llega con la idea de pasar unas vacaciones y eso hace que te quedes. La calidad de vida, y no me refiero a vivir en una lujosa villa con vistas a la playa, sino a la sencillez de olvidarte de la mayor\u00eda de los problemas y volver a tus ra\u00edces.<\/p>\n<h4>\u00bfEs Bali un destino de ensue\u00f1o?<\/h4>\n<p>Nunca te aburrir\u00e1s a menos que quieras aburrirte. Bali es enorme y tiene muchos lugares para visitar, desde playas hasta cascadas y <a href=\"https:\/\/instantkarmamag.com\/es\/articulo\/volcano-bali-beyond\/\">volcanes<\/a>. Pero lo que m\u00e1s me gusta es la generosidad y la humildad de la gente que vive en la isla, regalando una sonrisa cada d\u00eda aunque est\u00e9n pasando apuros, mostr\u00e1ndote lo esencial de la vida sin tener cosas caras.<\/p>\n<p><strong>Gracias, Josefina, por la entrevista.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<h4>Experimente usted mismo la fotograf\u00eda de Josefina<\/h4>\n<h4>Siguenos en Instagram: <a href=\"https:\/\/www.instagram.com\/baby_lemonadeph\/\" target=\"_blank\" rel=\"noopener\">@BABY_LEMONADEPH<\/a><\/h4>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>\u00bfPor qu\u00e9 viaja uno? \u00bfPara decir que estuvo en este monumento, cascada, edificio, templo? \u00bfO es simplemente para sentarse y observar lo que sucede a su alrededor? \u00bfViaja acompa\u00f1ado o solo? Fue la decisi\u00f3n de salir y encontrar algo a lo que no est\u00e1 acostumbrado, porque la belleza de [\u2026]<\/p>","protected":false},"author":214,"featured_media":13181,"comment_status":"open","ping_status":"closed","template":"","meta":{"footnotes":""},"categories":[],"tags":[353],"section":[317],"interest":[393,398],"_magazine":[354],"class_list":["post-13180","article","type-article","status-publish","has-post-thumbnail","hentry","tag-353","section-mindful","interest-philosphy","interest-self-help","_magazine-354"],"_links":{"self":[{"href":"https:\/\/instantkarmamag.com\/es\/wp-json\/wp\/v2\/article\/13180","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/instantkarmamag.com\/es\/wp-json\/wp\/v2\/article"}],"about":[{"href":"https:\/\/instantkarmamag.com\/es\/wp-json\/wp\/v2\/types\/article"}],"author":[{"embeddable":true,"href":"https:\/\/instantkarmamag.com\/es\/wp-json\/wp\/v2\/users\/214"}],"replies":[{"embeddable":true,"href":"https:\/\/instantkarmamag.com\/es\/wp-json\/wp\/v2\/comments?post=13180"}],"version-history":[{"count":0,"href":"https:\/\/instantkarmamag.com\/es\/wp-json\/wp\/v2\/article\/13180\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/instantkarmamag.com\/es\/wp-json\/wp\/v2\/media\/13181"}],"wp:attachment":[{"href":"https:\/\/instantkarmamag.com\/es\/wp-json\/wp\/v2\/media?parent=13180"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/instantkarmamag.com\/es\/wp-json\/wp\/v2\/categories?post=13180"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/instantkarmamag.com\/es\/wp-json\/wp\/v2\/tags?post=13180"},{"taxonomy":"section","embeddable":true,"href":"https:\/\/instantkarmamag.com\/es\/wp-json\/wp\/v2\/section?post=13180"},{"taxonomy":"interest","embeddable":true,"href":"https:\/\/instantkarmamag.com\/es\/wp-json\/wp\/v2\/interest?post=13180"},{"taxonomy":"_magazine","embeddable":true,"href":"https:\/\/instantkarmamag.com\/es\/wp-json\/wp\/v2\/_magazine?post=13180"}],"curies":[{"name":"Gracias","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}<!-- This website is optimized by Airlift. Learn more: https://airlift.net. Template:. Learn more: https://airlift.net. Template: 6a3c9e6bc6af5a91495580da. Config Timestamp: 2026-06-25 03:19:51 UTC, Cached Timestamp: 2026-09-02 02:29:00 UTC -->