{"id":21185,"date":"2024-06-08T19:10:05","date_gmt":"2024-06-08T11:10:05","guid":{"rendered":"https:\/\/instantkarmamag.com\/?page_id=21185"},"modified":"2024-10-30T22:27:53","modified_gmt":"2024-10-30T14:27:53","slug":"abonnieren","status":"publish","type":"page","link":"https:\/\/instantkarmamag.com\/de\/abonnieren\/","title":{"rendered":"Abonnieren"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"21185\" class=\"elementor elementor-21185\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6a925c8 e-flex e-con-boxed e-con e-parent\" data-id=\"6a925c8\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-c713d77 e-con-full e-flex e-con e-child\" data-id=\"c713d77\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e5d5fbc e-con-full e-flex e-con e-child\" data-id=\"e5d5fbc\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f2a24d4 elementor-widget elementor-widget-image\" data-id=\"f2a24d4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"178\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2024\/06\/Instant-Karma-logo-white-no-background-768x178.png\" class=\"attachment-medium_large size-medium_large wp-image-35135\" alt=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2024\/06\/Instant-Karma-logo-white-no-background-768x178.png 768w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2024\/06\/Instant-Karma-logo-white-no-background-300x69.png 300w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2024\/06\/Instant-Karma-logo-white-no-background-1024x237.png 1024w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2024\/06\/Instant-Karma-logo-white-no-background-1536x355.png 1536w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2024\/06\/Instant-Karma-logo-white-no-background-2048x474.png 2048w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2024\/06\/Instant-Karma-logo-white-no-background-18x4.png 18w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2024\/06\/Instant-Karma-logo-white-no-background-600x139.png 600w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-da4694f e-con-full e-flex e-con e-child\" data-id=\"da4694f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f600696 e-con-full notranslate e-flex e-con e-parent\" data-id=\"f600696\" data-element_type=\"container\" data-e-type=\"container\" data-no-translation=\"\" data-no-auto-translation=\"\">\n\t\t<div class=\"elementor-element elementor-element-de3664c e-con-full e-flex e-con e-child\" data-id=\"de3664c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7f6166b elementor-widget elementor-widget-heading\" data-id=\"7f6166b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Get unlimited access to<br><i>\nInstant Karma Magazine<\/i><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4d147a8 elementor-widget elementor-widget-text-editor\" data-id=\"4d147a8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Exclusive travel reports, guides &amp; mindful living tips<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b897329 elementor-widget elementor-widget-button\" data-id=\"b897329\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Plus, Karma Drops!<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9b9a048 e-con-full e-flex e-con e-child\" data-id=\"9b9a048\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a3a869e elementor-widget elementor-widget-image\" data-id=\"a3a869e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"450\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2024\/06\/mockup-instant-karma-mag-digital-no-back-1024x576.png\" class=\"attachment-large size-large wp-image-35133\" alt=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2024\/06\/mockup-instant-karma-mag-digital-no-back-1024x576.png 1024w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2024\/06\/mockup-instant-karma-mag-digital-no-back-300x169.png 300w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2024\/06\/mockup-instant-karma-mag-digital-no-back-768x432.png 768w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2024\/06\/mockup-instant-karma-mag-digital-no-back-1536x864.png 1536w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2024\/06\/mockup-instant-karma-mag-digital-no-back-18x10.png 18w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2024\/06\/mockup-instant-karma-mag-digital-no-back-600x338.png 600w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2024\/06\/mockup-instant-karma-mag-digital-no-back.png 1920w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9041d7a notranslate e-flex e-con-boxed e-con e-parent\" data-id=\"9041d7a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\" data-no-translation=\"\" data-no-auto-translation=\"\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-06a4edc e-con-full e-flex e-con e-child\" data-id=\"06a4edc\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-122a2b1 e-con-full e-flex e-con e-child\" data-id=\"122a2b1\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-43bf3b5 e-con-full e-flex e-con e-child\" data-id=\"43bf3b5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bef6124 elementor-widget elementor-widget-heading\" data-id=\"bef6124\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Monthly Print <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7568795 elementor-widget elementor-widget-text-editor\" data-id=\"7568795\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Monthly for only <span class=\"NA6bn BxUVEf ILfuVd\" lang=\"en\"><span class=\"hgKElc\">\u20ac5.90<\/span><\/span> (IDR 100.000)<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c6aaa0f e-con-full e-flex e-con e-child\" data-id=\"c6aaa0f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-72691cd elementor-widget elementor-widget-text-editor\" data-id=\"72691cd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>After one month, renews automatically for <span class=\"NA6bn BxUVEf ILfuVd\" lang=\"en\"><span class=\"hgKElc\">\u20ac6 <\/span><\/span>\/ year equivalent. <strong>Only in Indonesia.<\/strong><br \/>Cancel or pause anytime.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ec5ff4c elementor-align-start elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"ec5ff4c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-leanpub\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">get collectible print in Indonesia<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7cc285a elementor-align-center elementor-widget elementor-widget-button\" data-id=\"7cc285a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/karmakommunity.org\/signup\/print-reader\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Get Print in Indonesia<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-81c525e e-con-full e-flex e-con e-child\" data-id=\"81c525e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-f2931ea e-con-full e-flex e-con e-child\" data-id=\"f2931ea\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-62d8ee0 e-con-full e-flex e-con e-child\" data-id=\"62d8ee0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c1949a0 elementor-widget elementor-widget-heading\" data-id=\"c1949a0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Annual Digital<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-611e37f elementor-widget elementor-widget-text-editor\" data-id=\"611e37f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>1 Year for <s><span class=\"NA6bn BxUVEf ILfuVd\" lang=\"en\"><span class=\"hgKElc\">\u20ac<\/span><\/span>24.99<\/s> now only <span class=\"NA6bn BxUVEf ILfuVd\" lang=\"en\"><span class=\"hgKElc\">\u20ac<\/span><\/span>10<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9eff317 e-con-full e-flex e-con e-child\" data-id=\"9eff317\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3ec6705 elementor-widget elementor-widget-text-editor\" data-id=\"3ec6705\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>After one year, renews automatically for <span class=\"NA6bn BxUVEf ILfuVd\" lang=\"en\"><span class=\"hgKElc\">\u20ac10 <\/span><\/span>\/ year equivalent. <br \/>Cancel or pause anytime.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5ce1426 elementor-align-start elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"5ce1426\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-leanpub\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">all articles &amp; digital magazine<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3256dcd elementor-align-center elementor-widget elementor-widget-button\" data-id=\"3256dcd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/karmakommunity.org\/signup\/annual-digital\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Get Digital Access<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1e40b07 e-con-full e-flex e-con e-child\" data-id=\"1e40b07\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-e0a52b5 e-con-full e-flex e-con e-child\" data-id=\"e0a52b5\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-308ef81 e-con-full e-flex e-con e-child\" data-id=\"308ef81\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-79c6cc0 elementor-widget elementor-widget-heading\" data-id=\"79c6cc0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Global Print &amp; Digital<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-46aedda elementor-widget elementor-widget-text-editor\" data-id=\"46aedda\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span class=\"NA6bn BxUVEf ILfuVd\" lang=\"en\"><span class=\"hgKElc\">\u20ac8<\/span><\/span> per month &#8211; for one year<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-378a676 e-con-full e-flex e-con e-child\" data-id=\"378a676\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b7da04b elementor-widget elementor-widget-text-editor\" data-id=\"b7da04b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Billed at <span class=\"NA6bn BxUVEf ILfuVd\" lang=\"en\"><span class=\"hgKElc\">\u20ac96<\/span><\/span> equivalent at time of order. Renews automatically.<br \/>Cancel or pause anytime<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d18e089 elementor-align-start elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"d18e089\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-leanpub\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">get collectible print worldwide<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bcd40af elementor-align-center elementor-widget elementor-widget-button\" data-id=\"bcd40af\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/karmakommunity.org\/signup\/annual-print-digital\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Get Print &amp; Digital Access<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-491155f e-flex e-con-boxed e-con e-parent\" data-id=\"491155f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-5004a75 e-con-full e-flex e-con e-child\" data-id=\"5004a75\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a14dec8 e-con-full e-flex e-con e-child\" data-id=\"a14dec8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-8e2833b e-con-full e-flex e-con e-child\" data-id=\"8e2833b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-0dee457 e-con-full e-flex e-con e-child\" data-id=\"0dee457\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-9e54168 e-con-full e-flex e-con e-child\" data-id=\"9e54168\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cd3f26f elementor-widget elementor-widget-heading\" data-id=\"cd3f26f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Treten Sie der Karma Kommunity bei<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-637e620 elementor-widget elementor-widget-text-editor\" data-id=\"637e620\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>F\u00fcr immer kostenlos<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0e3db76 e-con-full e-flex e-con e-child\" data-id=\"0e3db76\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5124813 elementor-align-start elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"5124813\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-users\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Vernetzen Sie sich mit Gleichgesinnten weltweit<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1dab389 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"1dab389\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/karmakommunity.org\/signup\/member\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Kostenlos beitreten<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6fbf4a8 e-con-full e-flex e-con e-child\" data-id=\"6fbf4a8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-dda77fc notranslate e-flex e-con-boxed e-con e-parent\" data-id=\"dda77fc\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\" data-no-translation=\"\" data-no-auto-translation=\"\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3da64a8 elementor-widget elementor-widget-heading\" data-id=\"3da64a8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">What's included in Instant Karma<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ddda40f e-flex e-con-boxed e-con e-parent\" data-id=\"ddda40f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7faac11 e-n-tabs-mobile elementor-widget elementor-widget-n-tabs\" data-id=\"7faac11\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"nested-tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-tabs\" data-widget-number=\"133868561\" aria-label=\"Tabs. \u00d6ffnen Sie Elemente mit der Eingabetaste oder der Leertaste, schlie\u00dfen Sie sie mit Escape und navigieren Sie mit den Pfeiltasten.\">\n\t\t\t<div class=\"e-n-tabs-heading\" role=\"tablist\">\n\t\t\t\t\t<button id=\"e-n-tab-title-1338685611\" data-tab-title-id=\"e-n-tab-title-1338685611\" class=\"e-n-tab-title\" aria-selected=\"true\" data-tab-index=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"e-n-tab-content-1338685611\" style=\"--n-tabs-title-order: 1;\">\n\t\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\tUnbegrenzter Zugriff auf Inspiration, Reisef\u00fchrer und alle wichtigen Reiseutensilien.\t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t<button id=\"e-n-tab-title-1338685612\" data-tab-title-id=\"e-n-tab-title-1338685612\" class=\"e-n-tab-title\" aria-selected=\"false\" data-tab-index=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"e-n-tab-content-1338685612\" style=\"--n-tabs-title-order: 2;\">\n\t\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\tExklusive Artikel und \u00dcbungen von f\u00fchrenden Achtsamkeitslehrern und -experten.\t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t<button id=\"e-n-tab-title-1338685613\" data-tab-title-id=\"e-n-tab-title-1338685613\" class=\"e-n-tab-title\" aria-selected=\"false\" data-tab-index=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"e-n-tab-content-1338685613\" style=\"--n-tabs-title-order: 3;\">\n\t\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\tVollst\u00e4ndiger Archivzugriff auf das gesamte Archiv der digitalen Ausgaben des Instant Karma Magazine.\t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t<button id=\"e-n-tab-title-1338685614\" data-tab-title-id=\"e-n-tab-title-1338685614\" class=\"e-n-tab-title\" aria-selected=\"false\" data-tab-index=\"4\" role=\"tab\" tabindex=\"-1\" aria-controls=\"e-n-tab-content-1338685614\" style=\"--n-tabs-title-order: 4;\">\n\t\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\tInsider-Empfehlungen zu den besten umweltfreundlichen Hotels und angesagten Restaurants.\t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t<button id=\"e-n-tab-title-1338685615\" data-tab-title-id=\"e-n-tab-title-1338685615\" class=\"e-n-tab-title\" aria-selected=\"false\" data-tab-index=\"5\" role=\"tab\" tabindex=\"-1\" aria-controls=\"e-n-tab-content-1338685615\" style=\"--n-tabs-title-order: 5;\">\n\t\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\tExklusiver Zugang zu Karma Drops. Diese wertvollen Gutscheine sind nur f\u00fcr Abonnenten erh\u00e4ltlich!\t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t<button id=\"e-n-tab-title-1338685616\" data-tab-title-id=\"e-n-tab-title-1338685616\" class=\"e-n-tab-title\" aria-selected=\"false\" data-tab-index=\"6\" role=\"tab\" tabindex=\"-1\" aria-controls=\"e-n-tab-content-1338685616\" style=\"--n-tabs-title-order: 6;\">\n\t\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\tErweitern Sie Ihr Netzwerk. Treffen Sie Gleichgesinnte und vernetzen Sie sich mit ihnen!\t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t\t<\/div>\n\t\t\t<div class=\"e-n-tabs-content\">\n\t\t\t\t<div id=\"e-n-tab-content-1338685611\" role=\"tabpanel\" aria-labelledby=\"e-n-tab-title-1338685611\" data-tab-index=\"1\" style=\"--n-tabs-title-order: 1;\" class=\"e-active elementor-element elementor-element-4fa89e7 e-con-full e-flex e-con e-child\" data-id=\"4fa89e7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-e97bc4c e-flex e-con-boxed e-con e-child\" data-id=\"e97bc4c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div id=\"e-n-tab-content-1338685612\" role=\"tabpanel\" aria-labelledby=\"e-n-tab-title-1338685612\" data-tab-index=\"2\" style=\"--n-tabs-title-order: 2;\" class=\"elementor-element elementor-element-65551e8 e-con-full e-flex e-con e-child\" data-id=\"65551e8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-c410f2e e-flex e-con-boxed e-con e-child\" data-id=\"c410f2e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div id=\"e-n-tab-content-1338685613\" role=\"tabpanel\" aria-labelledby=\"e-n-tab-title-1338685613\" data-tab-index=\"3\" style=\"--n-tabs-title-order: 3;\" class=\"elementor-element elementor-element-cf304eb e-con-full e-flex e-con e-child\" data-id=\"cf304eb\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-e0b53bd e-flex e-con-boxed e-con e-child\" data-id=\"e0b53bd\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div id=\"e-n-tab-content-1338685614\" role=\"tabpanel\" aria-labelledby=\"e-n-tab-title-1338685614\" data-tab-index=\"4\" style=\"--n-tabs-title-order: 4;\" class=\"elementor-element elementor-element-c53ffe1 e-flex e-con-boxed e-con e-child\" data-id=\"c53ffe1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-4549bad e-con-full e-flex e-con e-child\" data-id=\"4549bad\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div id=\"e-n-tab-content-1338685615\" role=\"tabpanel\" aria-labelledby=\"e-n-tab-title-1338685615\" data-tab-index=\"5\" style=\"--n-tabs-title-order: 5;\" class=\"elementor-element elementor-element-7cacab1 e-flex e-con-boxed e-con e-child\" data-id=\"7cacab1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-48845e6 e-con-full e-flex e-con e-child\" data-id=\"48845e6\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div id=\"e-n-tab-content-1338685616\" role=\"tabpanel\" aria-labelledby=\"e-n-tab-title-1338685616\" data-tab-index=\"6\" style=\"--n-tabs-title-order: 6;\" class=\"elementor-element elementor-element-3a8a499 e-flex e-con-boxed e-con e-child\" data-id=\"3a8a499\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-5d06dd7 e-con-full e-flex e-con e-child\" data-id=\"5d06dd7\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-006a606 e-flex e-con-boxed e-con e-parent\" data-id=\"006a606\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-36188d3 e-con-full e-flex e-con e-child\" data-id=\"36188d3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c325d04 e-con-full e-flex e-con e-child\" data-id=\"c325d04\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9a2b9e0 elementor-widget elementor-widget-text-editor\" data-id=\"9a2b9e0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Schenken Sie <i>Instant Karma Magazin<br \/><\/i><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-94a6fa1 elementor-widget elementor-widget-button\" data-id=\"94a6fa1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/karmakommunity.org\/signup\/annual-print-digital\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-double-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Verschenken Sie ein Abonnement<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c00dfe7 e-con-full e-flex e-con e-child\" data-id=\"c00dfe7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-24023e3 e-flex e-con-boxed e-con e-parent\" data-id=\"24023e3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-decf302 e-con-full e-flex e-con e-child\" data-id=\"decf302\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-da50dbb e-con-full e-flex e-con e-child\" data-id=\"da50dbb\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2e13a6e elementor-widget elementor-widget-heading\" data-id=\"2e13a6e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><h2 style=\"font-weight:400;margin-bottom: -1px\">Was unsere<\/h2><h2 style=\"color:#FF7E79;margin-bottom: -1px;font-weight:700\">Leser sagen<h1><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-693a281 e-flex e-con-boxed e-con e-parent\" data-id=\"693a281\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-1c3a3d2 e-flex e-con-boxed e-con e-child\" data-id=\"1c3a3d2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-dd7f2d8 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"dd7f2d8\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-738d85c e-con-full e-flex e-con e-child\" data-id=\"738d85c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-51d7867 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"51d7867\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-quote-right\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fb3601c elementor-widget elementor-widget-text-editor\" data-id=\"fb3601c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ich habe gerade Ihre Ver\u00f6ffentlichung gefunden.<\/p><p>ICH LIEBE ES!<\/p><p>Es ist so unglaublich wertvoll. Ich mache die beschriebene Reise nach Flores und besuche auf jeden Fall einen Kochkurs bei Made Masak.<\/p><p>Ich kann es kaum erwarten, weiterzulesen!<\/p><p>Ich lebe auf Bali und kann in Canggu in meiner eigenen Routine stecken bleiben.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6bdb126 elementor-widget elementor-widget-rating\" data-id=\"6bdb126\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rating.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-rating\" itemtype=\"https:\/\/schema.org\/Rating\" itemscope=\"\" itemprop=\"reviewRating\">\n\t\t\t<meta itemprop=\"worstRating\" content=\"0\">\n\t\t\t<meta itemprop=\"bestRating\" content=\"5\">\n\t\t\t<div class=\"e-rating-wrapper\" itemprop=\"ratingValue\" content=\"5\" role=\"img\" aria-label=\"Bewertet mit 5 von 5\">\n\t\t\t\t\t\t\t<div class=\"e-icon\">\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-marked\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-star\"><\/i>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-unmarked\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-star\"><\/i>\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"e-icon\">\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-marked\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-star\"><\/i>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-unmarked\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-star\"><\/i>\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"e-icon\">\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-marked\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-star\"><\/i>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-unmarked\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-star\"><\/i>\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"e-icon\">\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-marked\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-star\"><\/i>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-unmarked\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-star\"><\/i>\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"e-icon\">\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-marked\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-star\"><\/i>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-unmarked\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-star\"><\/i>\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9a9081c elementor-widget elementor-widget-heading\" data-id=\"9a9081c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Ju<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-40e8c58 elementor-widget elementor-widget-heading\" data-id=\"40e8c58\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Expat<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-41f5491 e-con-full e-flex e-con e-child\" data-id=\"41f5491\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bbcd6a3 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"bbcd6a3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-quote-right\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-024bb42 elementor-widget elementor-widget-text-editor\" data-id=\"024bb42\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Es ist so sch\u00f6n, gleichgesinnte Reisende zu treffen und (einen kleinen Teil) dieser wachsenden, wertvollen und wunderbaren Bewegung zu spielen.<\/p><p>Die besten W\u00fcnsche f\u00fcr dieses Unterfangen und an alle mit \u00e4hnlichen Ambitionen f\u00fcr diese Welt und f\u00fcreinander!<\/p><p><br \/>PS Ich freue mich jetzt schon auf das Lesen meiner Zeitschrift \ud83d\ude0a<\/p><p>\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2f5ac49 elementor-widget elementor-widget-rating\" data-id=\"2f5ac49\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rating.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-rating\" itemtype=\"https:\/\/schema.org\/Rating\" itemscope=\"\" itemprop=\"reviewRating\">\n\t\t\t<meta itemprop=\"worstRating\" content=\"0\">\n\t\t\t<meta itemprop=\"bestRating\" content=\"5\">\n\t\t\t<div class=\"e-rating-wrapper\" itemprop=\"ratingValue\" content=\"5\" role=\"img\" aria-label=\"Bewertet mit 5 von 5\">\n\t\t\t\t\t\t\t<div class=\"e-icon\">\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-marked\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-star\"><\/i>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-unmarked\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-star\"><\/i>\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"e-icon\">\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-marked\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-star\"><\/i>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-unmarked\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-star\"><\/i>\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"e-icon\">\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-marked\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-star\"><\/i>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-unmarked\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-star\"><\/i>\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"e-icon\">\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-marked\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-star\"><\/i>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-unmarked\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-star\"><\/i>\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"e-icon\">\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-marked\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-star\"><\/i>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-unmarked\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-star\"><\/i>\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-38311e3 elementor-widget elementor-widget-heading\" data-id=\"38311e3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Tannis<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4ee7c32 elementor-widget elementor-widget-heading\" data-id=\"4ee7c32\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Reisender<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1dc0f9a e-con-full e-flex e-con e-child\" data-id=\"1dc0f9a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3dd8302 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"3dd8302\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-quote-right\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ce5b22e elementor-widget elementor-widget-text-editor\" data-id=\"ce5b22e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Liebe Freunde vom Instant Karma Magazine,<\/p><p>danke f\u00fcr die Gelegenheit, Ihre wunderbare Liebe zu mir zu teilen und mir die gute Nachricht zu \u00fcberbringen, dass wir die Ver\u00e4nderung sind, die wir in der Welt sehen wollen.<br \/>Es beginnt bei uns. WIR HABEN DIE MACHT!<\/p><p>Es war mir ein Vergn\u00fcgen und hoffentlich nur der Beginn einer neuen \u201eregenerativen\u201c Freundschaft!<br \/>Alles Liebe, Sil<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9f404d3 elementor-widget elementor-widget-rating\" data-id=\"9f404d3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rating.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-rating\" itemtype=\"https:\/\/schema.org\/Rating\" itemscope=\"\" itemprop=\"reviewRating\">\n\t\t\t<meta itemprop=\"worstRating\" content=\"0\">\n\t\t\t<meta itemprop=\"bestRating\" content=\"5\">\n\t\t\t<div class=\"e-rating-wrapper\" itemprop=\"ratingValue\" content=\"5\" role=\"img\" aria-label=\"Bewertet mit 5 von 5\">\n\t\t\t\t\t\t\t<div class=\"e-icon\">\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-marked\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-star\"><\/i>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-unmarked\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-star\"><\/i>\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"e-icon\">\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-marked\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-star\"><\/i>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-unmarked\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-star\"><\/i>\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"e-icon\">\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-marked\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-star\"><\/i>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-unmarked\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-star\"><\/i>\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"e-icon\">\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-marked\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-star\"><\/i>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-unmarked\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-star\"><\/i>\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"e-icon\">\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-marked\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-star\"><\/i>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"e-icon-wrapper e-icon-unmarked\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-star\"><\/i>\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-19bb12c elementor-widget elementor-widget-heading\" data-id=\"19bb12c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Sil<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e5b8d7a elementor-widget elementor-widget-heading\" data-id=\"e5b8d7a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Expat<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-499034c e-flex e-con-boxed e-con e-parent\" data-id=\"499034c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-9a4a258 e-con-full e-flex e-con e-child\" data-id=\"9a4a258\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-afb43a5 e-con-full e-flex e-con e-child\" data-id=\"afb43a5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-d1c6ab1 e-con-full e-flex e-con e-child\" data-id=\"d1c6ab1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4ed58fd elementor-widget elementor-widget-heading\" data-id=\"4ed58fd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">FAQ f\u00fcr<br>Neugierige K\u00f6pfe<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1647b93 elementor-widget-tablet__width-initial elementor-widget__width-inherit elementor-widget-mobile__width-initial elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-image\" data-id=\"1647b93\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation_mobile&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2024\/02\/Instant-karma-magazine-reader-bali-magazine-mindful-magazine-travel-magazine-reisemagazin.webp\" class=\"attachment-large size-large wp-image-31757\" alt=\"Instant Karma Magazin Leser Bali Magazin Mindful Magazin Reisemagazin Reisemagazin\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2024\/02\/Instant-karma-magazine-reader-bali-magazine-mindful-magazine-travel-magazine-reisemagazin.webp 1024w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2024\/02\/Instant-karma-magazine-reader-bali-magazine-mindful-magazine-travel-magazine-reisemagazin-250x250.webp 250w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2024\/02\/Instant-karma-magazine-reader-bali-magazine-mindful-magazine-travel-magazine-reisemagazin-300x300.webp 300w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2024\/02\/Instant-karma-magazine-reader-bali-magazine-mindful-magazine-travel-magazine-reisemagazin-768x768.webp 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ac45de2 e-con-full e-flex e-con e-child\" data-id=\"ac45de2\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-737adbb elementor-widget elementor-widget-toggle\" data-id=\"737adbb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h3 id=\"elementor-tab-title-1211\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1211\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-chevron-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-chevron-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Welche Art von Reisen decken Sie ab?<\/a>\n\t\t\t\t\t<\/h3>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1211\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1211\"><p>Wir decken verschiedene Aspekte des Reisens ab, von achtsamen Reisen, kulturellen Erlebnissen und Abenteuern bis hin zu Luxus, Wellness und \u00d6kotourismus.<\/p><p>Wir m\u00f6chten alle Arten von Reisenden inspirieren.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h3 id=\"elementor-tab-title-1212\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-1212\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-chevron-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-chevron-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Wie erhalte ich nach der Anmeldung Zugriff auf die Website?<\/a>\n\t\t\t\t\t<\/h3>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1212\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-1212\"><p>An <a href=\"https:\/\/instantkarmamag.com\/de\">: instantkarmamag.com<\/a> Klicken Sie auf \u201eAnmelden\u201c und geben Sie die mit Ihrem Abonnement verkn\u00fcpfte E-Mail-Adresse ein. Alternativ k\u00f6nnen Sie den Link in Ihrer Best\u00e4tigungs-E-Mail verwenden.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h3 id=\"elementor-tab-title-1213\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-1213\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-chevron-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-chevron-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Welchen Wert erhalte ich mit einem Abonnement?<\/a>\n\t\t\t\t\t<\/h3>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1213\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-1213\"><p>Sie erhalten Zugriff auf exklusive Artikel, Reisetipps von Experten, spannende kulturelle Einblicke, Sprachressourcen und eine unterst\u00fctzende Community. Unsere Mitgliedschaftspl\u00e4ne sind auf unterschiedliche Interessen und Vorlieben zugeschnitten und stellen sicher, dass Sie den besten Gegenwert f\u00fcr Ihr Abonnement erhalten.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h3 id=\"elementor-tab-title-1214\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-1214\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-chevron-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-chevron-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Ist es benutzerfreundlich und zug\u00e4nglich?<\/a>\n\t\t\t\t\t<\/h3>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1214\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-1214\"><p>Wir haben unsere Online-Plattform so gestaltet, dass sie intuitiv, benutzerfreundlich und auf verschiedenen Ger\u00e4ten leicht zug\u00e4nglich ist. Unsere Inhalte sind sowohl in digitaler als auch in gedruckter Form verf\u00fcgbar, sodass Sie das Instant Karma Magazine \u00fcberall und auf jede beliebige Art und Weise lesen k\u00f6nnen.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h3 id=\"elementor-tab-title-1215\" class=\"elementor-tab-title\" data-tab=\"5\" role=\"button\" aria-controls=\"elementor-tab-content-1215\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-chevron-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-chevron-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Wann kann ich mit der Lieferung meines Printmagazins rechnen?<\/a>\n\t\t\t\t\t<\/h3>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1215\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"5\" role=\"region\" aria-labelledby=\"elementor-tab-title-1215\"><p>Wenn Sie das Printmagazin abonnieren, erhalten Sie Ihr erstes Magazin ca. sechs Wochen nach dem Kauf.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<script type=\"application\/ld+json\">{\n    \"@context\": \"https:\\\/\\\/schema.org\",\n    \"@type\": \"FAQPage\",\n    \"mainEntity\": [\n        {\n            \"@type\": \"Question\",\n            \"name\": \"What kind of travel do you cover?\",\n            \"acceptedAnswer\": {\n                \"@type\": \"Answer\",\n                \"text\": \"<p>We cover various aspects of travel, from mindful journeys, cultural experiences, and adventures, to\\u00a0 luxury, wellness, and eco-tourism.<\\\/p><p>We strive to inspire all types of travellers.<\\\/p>\"\n            }\n        },\n        {\n            \"@type\": \"Question\",\n            \"name\": \"How do I access the website after subscribing?\",\n            \"acceptedAnswer\": {\n                \"@type\": \"Answer\",\n                \"text\": \"<p>On <a href=\\\"https:\\\/\\\/instantkarmamag.com\\\/\\\">instantkarmamag.com<\\\/a> click &#8220;Sign in,&#8221; and enter the email address associated with your subscription. Alternatively, use the link provided in your confirmation email.<\\\/p>\"\n            }\n        },\n        {\n            \"@type\": \"Question\",\n            \"name\": \"What value do I receive with a subscription?\",\n            \"acceptedAnswer\": {\n                \"@type\": \"Answer\",\n                \"text\": \"<p>You&#8217;ll enjoy access to exclusive articles, expert travel tips, engaging cultural insights, language resources, and a supportive community. Our membership plans are tailored to cater to different interests and preferences, ensuring that you receive the best value for your subscription.<\\\/p>\"\n            }\n        },\n        {\n            \"@type\": \"Question\",\n            \"name\": \"Is it user-friendly and accessible?\",\n            \"acceptedAnswer\": {\n                \"@type\": \"Answer\",\n                \"text\": \"<p>We have designed our online platform to be intuitive, user-friendly, and easily accessible on various devices. Our content is available in both digital and print formats, ensuring that you can enjoy Instant Karma Magazine wherever you are and however you prefer to read.<\\\/p>\"\n            }\n        },\n        {\n            \"@type\": \"Question\",\n            \"name\": \"When can I expect my print magazine to arrive?\",\n            \"acceptedAnswer\": {\n                \"@type\": \"Answer\",\n                \"text\": \"<p>If you subscribe to the print magazine, your first magazine will arrive approximately six weeks after purchase.<\\\/p>\"\n            }\n        }\n    ]\n}<\/script>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6a8506c e-flex e-con-boxed e-con e-parent\" data-id=\"6a8506c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-ad5a6cc e-con-full e-flex e-con e-child\" data-id=\"ad5a6cc\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-61fae29 e-con-full e-flex e-con e-child\" data-id=\"61fae29\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-532f118 elementor-widget elementor-widget-image\" data-id=\"532f118\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"178\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2024\/06\/Instant-Karma-logo-white-no-background-768x178.png\" class=\"attachment-medium_large size-medium_large wp-image-35135\" alt=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2024\/06\/Instant-Karma-logo-white-no-background-768x178.png 768w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2024\/06\/Instant-Karma-logo-white-no-background-300x69.png 300w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2024\/06\/Instant-Karma-logo-white-no-background-1024x237.png 1024w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2024\/06\/Instant-Karma-logo-white-no-background-1536x355.png 1536w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2024\/06\/Instant-Karma-logo-white-no-background-2048x474.png 2048w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2024\/06\/Instant-Karma-logo-white-no-background-18x4.png 18w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2024\/06\/Instant-Karma-logo-white-no-background-600x139.png 600w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-69fb0c4 elementor-widget elementor-widget-text-editor\" data-id=\"69fb0c4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"footer_legalese__c3UDb\"><p><i>Der Kundendienst ist per E-Mail erreichbar unter <a href=\"mailto:info@instantkarmamag.com\">info@instantkarmamag.com<\/a> und per WhatsApp\/Telefon unter (ID) +62-823-4087-9751.<\/i><\/p><p><i><a href=\"https:\/\/karmakommunity.org\/log-in\/\" target=\"_blank\" rel=\"noopener\">Melden Sie sich an, um Ihr Konto online zu verwalten<\/a><\/i><\/p><p><strong>Die regul\u00e4ren Jahrespreise betragen derzeit:<\/strong><\/p><p>In<strong> Indonesien<\/strong>, ein Jahres-Bundle-Printabonnement ist <br \/><em>1.200.000 Rupien ( <span class=\"NA6bn ILfuVd\" lang=\"en\"><span class=\"hgKElc\"><b>\u2248<\/b><\/span><\/span> <span class=\"NA6bn BxUVEf ILfuVd\" lang=\"en\"><span class=\"hgKElc\">EUR <\/span><\/span>67.50)<\/em><\/p><p>In <strong>alle anderen Ziele<\/strong>, ein j\u00e4hrliches Printabonnement ist <br \/><em>1.690.000 Rupien (\u00a0<span class=\"NA6bn ILfuVd\" lang=\"en\"><span class=\"hgKElc\"><b>\u2248<\/b><\/span><\/span> <span class=\"NA6bn BxUVEf ILfuVd\" lang=\"en\"><span class=\"hgKElc\">EUR<\/span><\/span> 96.00).<\/em><\/p><p>A <strong>nur digital<\/strong> Abonnement ist <em>175.000 Rupien (<span class=\"NA6bn ILfuVd\" lang=\"en\"><span class=\"hgKElc\"><b>\u2248<\/b><\/span><\/span> EUR<span class=\"NA6bn BxUVEf ILfuVd\" lang=\"en\"><span class=\"hgKElc\"> 10.00)<\/span><\/span><\/em>.<\/p><p><b><i>Das Instant Karma Magazine ver\u00f6ffentlicht 4 Ausgaben pro Jahr. <\/i><\/b><\/p><p>Die erste Ausgabe erfolgt per E-Mail innerhalb von 4 Wochen.<\/p><p>Dieses Angebot gilt nur f\u00fcr Kunden, die nicht abonniert haben <i>Sofortiges Karma <\/i>innerhalb der letzten 180 Tage.<\/p><p><strong>Alle Bestellungen m\u00fcssen genehmigt werden.<\/strong><\/p><p>Mit Ihrer Bestellung erkl\u00e4ren Sie sich damit einverstanden, keine auf dieser Site erworbenen Abonnements weiterzuverkaufen.<\/p><p>Bei Lieferungen au\u00dferhalb Indonesiens k\u00f6nnen Einfuhrgeb\u00fchren, Deklarationsgeb\u00fchren, Einfuhrz\u00f6lle und\/oder Steuern anfallen. Alle diese Geb\u00fchren gehen ausschlie\u00dflich zu Lasten des Kunden.<\/p><p>Mit Ihrer Bestellung erkl\u00e4ren Sie sich damit einverstanden, keine auf dieser Site erworbenen Abonnements weiterzuverkaufen.<\/p><p><strong>Abonnenten:<\/strong> Sollte Ihr Print-Abonnement nicht mehr zustellbar sein, bestehen f\u00fcr uns keine weiteren Verpflichtungen, sofern wir nicht innerhalb eines Jahres eine korrigierte Adresse und\/oder E-Mail erhalten.<\/p><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-16c39d3 elementor-icon-list--layout-inline elementor-align-center elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"16c39d3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/instantkarmamag.com\/de\/nutzungsbedingungen\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><u>Nutzungsbedingungen<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/instantkarmamag.com\/de\/datenschutzrichtlinie\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><u>Datenschutzrichtlinie<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9d489a2 e-con-full e-flex e-con e-child\" data-id=\"9d489a2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7a8ecee2 e-flex e-con-boxed e-con e-parent\" data-id=\"7a8ecee2\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-48a6b2b2 e-con-full e-flex e-con e-child\" data-id=\"48a6b2b2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4eab50 elementor-widget elementor-widget-heading\" data-id=\"4eab50\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/thekarmaworks.com\" target=\"_blank\" rel=\"noopener\">\u00a9 2024 - SOFORTIGES KARMA<\/a><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Erhalten Sie unbegrenzten Zugriff auf Instant Karma Magazine Exklusive Reiseberichte, Ratgeber und Tipps f\u00fcr ein achtsames Leben. Plus Karma Drops! Monatliche Printausgabe f\u00fcr nur 5,90 \u20ac (100.000 IDR). Nach einem Monat verl\u00e4ngert sich die Ausgabe automatisch um 6 \u20ac\/Jahr. Nur in Indonesien. Jederzeit k\u00fcndbar oder pausierbar. Holen Sie sich Sammlerst\u00fccke in Indonesien. Holen Sie sich Printausgaben in Indonesien. J\u00e4hrliche Digitalausgabe f\u00fcr 1 Jahr. [\u2026]<\/p>","protected":false},"author":1,"featured_media":31543,"parent":0,"menu_order":5,"comment_status":"closed","ping_status":"closed","template":"elementor_canvas","meta":{"footnotes":""},"class_list":["post-21185","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/instantkarmamag.com\/de\/wp-json\/wp\/v2\/pages\/21185","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/instantkarmamag.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/instantkarmamag.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/instantkarmamag.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/instantkarmamag.com\/de\/wp-json\/wp\/v2\/comments?post=21185"}],"version-history":[{"count":0,"href":"https:\/\/instantkarmamag.com\/de\/wp-json\/wp\/v2\/pages\/21185\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/instantkarmamag.com\/de\/wp-json\/wp\/v2\/media\/31543"}],"wp:attachment":[{"href":"https:\/\/instantkarmamag.com\/de\/wp-json\/wp\/v2\/media?parent=21185"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}<!-- This website is optimized by Airlift. Learn more: https://airlift.net. Template:. Learn more: https://airlift.net. Template: 6a3c9e6bc6af5a91495580da. Config Timestamp: 2026-06-25 03:19:51 UTC, Cached Timestamp: 2026-09-02 07:27:12 UTC -->