{"id":9705,"date":"2022-01-01T00:00:00","date_gmt":"2021-12-31T16:00:00","guid":{"rendered":"https:\/\/instantkarmamag.com\/article\/skate-like-a-bandita\/"},"modified":"2024-07-03T16:35:29","modified_gmt":"2024-07-03T08:35:29","slug":"skate-wie-eine-bandita","status":"publish","type":"article","link":"https:\/\/instantkarmamag.com\/de\/artikel\/skate-wie-eine-bandita\/","title":{"rendered":"Skate wie eine Bandita"},"content":{"rendered":"<div id=\"bsf_rt_marker\"><\/div><p><b><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-7709 alignright\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/01\/Screenshot-2022-01-01-at-12-23-00-8-FLIPBOOK2-pdf-128x300.png\" alt=\"\" width=\"128\" height=\"300\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/01\/Screenshot-2022-01-01-at-12-23-00-8-FLIPBOOK2-pdf-128x300.png 128w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/01\/Screenshot-2022-01-01-at-12-23-00-8-FLIPBOOK2-pdf.png 226w\" sizes=\"auto, (max-width: 128px) 100vw, 128px\" \/><\/b><\/p>\n<h2>Skate wie eine Bandita<\/h2>\n<p><b>Fr\u00fcher machten Skaterboys Witze \u00fcber Rodi und andere skatende M\u00e4dchen, aber heute haben sich die Zeiten ge\u00e4ndert. Frauen sind das neue Gesicht des Skateboardings, sowohl auf der Stra\u00dfe als auch in Skateparks. <\/b><\/p>\n<p><b>Wir trafen Rodi im Motion Skatepark, sie ist eine leidenschaftliche Skaterin, die urspr\u00fcnglich aus Deutschland kommt und seit 15 Jahren auf Bali lebt. Im Interview erz\u00e4hlte sie uns von ihren beiden Projekten Skatedukasi und GalsSkateBali, die sie w\u00e4hrend der Pandemie gestartet hat.<\/b><\/p>\n<p><strong>____________________<\/strong><\/p>\n<h3><b>Was war Ihre Inspiration f\u00fcr Ihre gro\u00dfartigen Projekte?<\/b><\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-7712 aligncenter\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/01\/Cover-photo-IK8-Sk8-image41.jpeg\" alt=\"skate wie eine Bandita Skateboarding\" width=\"358\" height=\"448\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/01\/Cover-photo-IK8-Sk8-image41.jpeg 683w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/01\/Cover-photo-IK8-Sk8-image41-240x300.jpeg 240w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/01\/Cover-photo-IK8-Sk8-image41-624x779.jpeg 624w\" sizes=\"auto, (max-width: 358px) 100vw, 358px\" \/><\/p>\n<p>Angefangen hat alles mit Corona. Str\u00e4nde, Sportanlagen, Schulen, alles war geschlossen. Sportunterricht, wie Ballett und Karate, musste eingestellt werden, Skateparks blieben jedoch ge\u00f6ffnet.<\/p>\n<p>Obwohl einige Schulen auf Online- und Zoom-Meetings umgestiegen sind, war dies f\u00fcr viele Kinder schwierig, da nicht jeder ein Mobiltelefon oder einen Laptop hat, geschweige denn Internetzugang oder Guthaben. Ich habe Kinder gesehen, die nicht zur Schule gingen, weil sie kein Ger\u00e4t hatten, um auf das Internet zuzugreifen oder ihre Schularbeiten per E-Mail zu erhalten.<\/p>\n<p>Also lud ich meinen Sohn und seine Freunde, die nicht weiter wussten, in den Skatepark ein, mit dem Motto: \u201eIch kann es ihnen beibringen\u201c \u2013 ich hatte bereits in Deutschland und der Schweiz Skate-Unterricht gegeben, es war f\u00fcr mich keine neue Erfahrung. Als aus einer Tochter zwei, dann drei wurden, begannen andere Eltern mich zu fragen, ob ich auch ihre Kinder unterrichten k\u00f6nnte. Das inspirierte mich dazu, eine Geb\u00fchr f\u00fcr den Skateboard-Unterricht zu verlangen, die ich bed\u00fcrftigen Kindern zugute kommen lassen konnte.<\/p>\n<p>Das war der Beginn von Skatedukasi, eine Kombination aus Skaten und Edukasi, dem indonesischen Wort f\u00fcr Bildung.<\/p>\n<p>Mit diesem Geld k\u00f6nnen wir monatlich das Schulgeld eines Waisenkindes unterst\u00fctzen, einen Lehrer f\u00fcr ein Stra\u00dfenkinder-Schulprojekt stellen, einen Schulbau auf Sumba mitfinanzieren sowie Skateboard-Events und -Aktivit\u00e4ten f\u00f6rdern.<\/p>\n<p>&nbsp;<\/p>\n<h3><b>Wie kamst du auf die Idee, eine Skate-Community f\u00fcr M\u00e4dchen zu gr\u00fcnden?<\/b><\/h3>\n<p>Viele M\u00e4dchen begannen eher zuf\u00e4llig mit mir Schlittschuh zu laufen und bald hatte ich eine gro\u00dfe Gruppe junger Damen, die alle Spa\u00df am Schlittschuhlaufen hatten.<\/p>\n<p>Ich habe versucht, die M\u00e4dchen mit der Idee zusammenzubringen, Freundschaften zu schlie\u00dfen und Tricks voneinander zu lernen. So entstand die Gals Skate Bali-Community.<\/p>\n<h3><b>Was lernst du au\u00dfer Skateboarden noch?<\/b><\/h3>\n<p>Skaten hilft Ihnen, wie andere Sportarten auch, Selbstvertrauen zu entwickeln. Geben Sie nicht auf. Manchmal f\u00e4llt man auf die Nase, aber man steht wieder auf und versucht es erneut. Es ist eine enorme Lektion f\u00fcrs Leben.<\/p>\n<p>Es erfordert auch viel Selbstvertrauen, eine neue F\u00e4higkeit zu erlernen, da viele Dinge \u00dcbung und Geduld erfordern. Die Dinge, die Sie lernen, sind auch in anderen Bereichen des Lebens wertvoll.<\/p>\n<p><b> <img loading=\"lazy\" decoding=\"async\" class=\"wp-image-7711 size-large aligncenter\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/01\/image31-1024x683.jpeg\" alt=\"skate wie eine Bandita Skateboarding\" width=\"1024\" height=\"683\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/01\/image31-1024x683.jpeg 1024w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/01\/image31-300x200.jpeg 300w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/01\/image31-768x512.jpeg 768w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/01\/image31-624x416.jpeg 624w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/01\/image31.jpeg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/b><\/p>\n<p><b>Warum sollten M\u00e4dchen Schlittschuh laufen?<\/b><\/p>\n<p>Weil es gro\u00dfen Spa\u00df macht, ein toller Sport ist und eine tolle M\u00f6glichkeit, neue Freunde kennenzulernen.<\/p>\n<p>Es gibt Ihnen Selbstvertrauen und Mut und ist f\u00fcr viele eine v\u00f6llig neue Erfahrung in einer v\u00f6llig anderen Welt.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-7713 aligncenter\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/01\/image22-702x1024.jpeg\" alt=\"skaten bali bandita\" width=\"478\" height=\"697\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/01\/image22-702x1024.jpeg 702w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/01\/image22-206x300.jpeg 206w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/01\/image22-768x1120.jpeg 768w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/01\/image22-624x910.jpeg 624w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2022\/01\/image22.jpeg 878w\" sizes=\"auto, (max-width: 478px) 100vw, 478px\" \/><\/p>\n<h3><b>Gibt es auf Bali viele Skateboarderinnen?<br \/>\n<\/b><\/h3>\n<p>Es gibt jetzt viele M\u00e4dchen, die skaten, vor allem junge. Das liegt nat\u00fcrlich daran, dass wir Unterricht geben und Aktivit\u00e4ten und Veranstaltungen organisieren. Ich denke, das liegt daran, dass die Skateparks (w\u00e4hrend der Pandemie) immer ge\u00f6ffnet waren und wir mit dem Aufbau dieser Community zu einem Zeitpunkt begonnen haben, als viele M\u00e4dchen zum Skaten kamen.<\/p>\n<p>Irgendwann folgten uns auch andere M\u00e4dchen an andere Orte und gr\u00fcndeten ihre eigenen Clubs, was fantastisch ist. M\u00e4dchen kommen in Skateparks immer h\u00e4ufiger vor \u2013 fr\u00fcher waren sie selten.<\/p>\n<h3><b>Was sind deine Lieblings-Skateboard-Spots auf Bali?<\/b><\/h3>\n<p>Zu meinen Lieblingsorten auf Bali geh\u00f6ren Keramas Fruit Bowl, Ubuds Titi Batu Club, Amplitude und Motion Skatepark.<\/p>\n<p>Ich glaube, dass es mir wichtiger ist, mit wem ich skate, als wo ich skate \u2013 Spa\u00df kann man \u00fcberall haben, sogar auf einem St\u00fcck Asphalt.<\/p>\n<p>&nbsp;<\/p>\n<h3><b>Wie haben die Skater-Jungs damals reagiert, als M\u00e4dels wie du skateten?\u00a0<\/b><\/h3>\n<p>Es gab immer viele dumme Kommentare oder die Skater-Jungs haben versucht, mich einzusch\u00fcchtern, aber das hat nicht geklappt, weil mir das Skaten zu viel Spa\u00df gemacht hat. Ich habe sie ignoriert und weil ich irgendwann besser war als viele Jungs, war das kein Thema mehr. Die Kommentare h\u00f6rten schnell auf und ich bekam mehr Respekt.<\/p>\n<h3><\/h3>\n<h3><b>Wie ist die Skateboard-Szene auf Bali?<\/b><\/h3>\n<p>Die Skateszene ist mittlerweile ziemlich gro\u00df. Es gibt viele Parks, vor allem im S\u00fcden der Insel. Es ist zwar nicht gerade ein Paradies f\u00fcr Streetskater, aber es gibt jede Menge Skateparks und Bowls. Die Leute sind super nett und man kennt sich. Da es so viele verschiedene Parks gibt, gibt es nat\u00fcrlich auch viele verschiedene Gruppen. Generell kann ich sagen, dass fast alle freundlich und h\u00f6flich sind.<\/p>\n<p>Die gro\u00dfe Neuigkeit ist, dass in Bangli ein riesiger Park gebaut wird \u2013 finanziert von der Regierung \u2013 was gro\u00dfartig ist. Nicht alle Parks sind kostenlos und nicht jeder kann sich den Eintritt leisten, daher ist es gro\u00dfartig, dass die Regierung jetzt \u00f6ffentliche Einrichtungen baut und den Sport unterst\u00fctzt.<\/p>\n<p><strong>Vielen Dank, Rodi, f\u00fcr dieses Interview<\/strong><\/p>\n<p><strong>____________________<\/strong><\/p>\n<p><strong>Fakten:<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>25 Jahre Leidenschaft. Trainer und Profi Rodi wurde von bekannten Marken gesponsert und nahm weltweit an Wettbewerben teil!<\/p>\n<p><strong>Ihre einzigartigen Projekte finden Sie auf Instagram<\/strong><\/p>\n<p><a href=\"https:\/\/www.instagram.com\/galsskatebali\/\" target=\"_blank\" rel=\"noopener\"><strong>@galsskatebali<\/strong><\/a><\/p>\n<p><a href=\"https:\/\/www.instagram.com\/skatedukasi\/\" target=\"_blank\" rel=\"noopener\"><strong>@skatedukasi<\/strong><\/a><\/p>\n<p><strong>____________________<\/strong><\/p>\n<p><em>Text von Myriam Speich<\/em><\/p>\n<p><em>Fotos von Gunandi Budiharjo <strong><a href=\"https:\/\/www.instagram.com\/gunandibudiharjo\/\" target=\"_blank\" rel=\"noopener\">@gunandibudiharjo<\/a><\/strong> &amp; Yosi Kastanja <a href=\"https:\/\/www.instagram.com\/yosi_kastanja\/\" target=\"_blank\" rel=\"noopener\"><strong>@yosi_kastanja<\/strong><\/a><\/em><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Fr\u00fcher machten Skaterboys Witze \u00fcber Rodi und andere skatende M\u00e4dchen, aber heute haben sich die Zeiten ge\u00e4ndert. Frauen sind das neue Gesicht des Skateboardings, sowohl auf der Stra\u00dfe als auch in Skateparks.<\/p>","protected":false},"author":214,"featured_media":10494,"comment_status":"open","ping_status":"closed","template":"","meta":{"footnotes":""},"categories":[273],"tags":[348],"section":[387,388],"interest":[381,378],"_magazine":[329],"class_list":["post-9705","article","type-article","status-publish","has-post-thumbnail","hentry","category-people","tag-348","section-impact","section-people","interest-empowerment","interest-social","_magazine-329"],"_links":{"self":[{"href":"https:\/\/instantkarmamag.com\/de\/wp-json\/wp\/v2\/article\/9705","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/instantkarmamag.com\/de\/wp-json\/wp\/v2\/article"}],"about":[{"href":"https:\/\/instantkarmamag.com\/de\/wp-json\/wp\/v2\/types\/article"}],"author":[{"embeddable":true,"href":"https:\/\/instantkarmamag.com\/de\/wp-json\/wp\/v2\/users\/214"}],"replies":[{"embeddable":true,"href":"https:\/\/instantkarmamag.com\/de\/wp-json\/wp\/v2\/comments?post=9705"}],"version-history":[{"count":0,"href":"https:\/\/instantkarmamag.com\/de\/wp-json\/wp\/v2\/article\/9705\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/instantkarmamag.com\/de\/wp-json\/wp\/v2\/media\/10494"}],"wp:attachment":[{"href":"https:\/\/instantkarmamag.com\/de\/wp-json\/wp\/v2\/media?parent=9705"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/instantkarmamag.com\/de\/wp-json\/wp\/v2\/categories?post=9705"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/instantkarmamag.com\/de\/wp-json\/wp\/v2\/tags?post=9705"},{"taxonomy":"section","embeddable":true,"href":"https:\/\/instantkarmamag.com\/de\/wp-json\/wp\/v2\/section?post=9705"},{"taxonomy":"interest","embeddable":true,"href":"https:\/\/instantkarmamag.com\/de\/wp-json\/wp\/v2\/interest?post=9705"},{"taxonomy":"_magazine","embeddable":true,"href":"https:\/\/instantkarmamag.com\/de\/wp-json\/wp\/v2\/_magazine?post=9705"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}<!-- This website is optimized by Airlift. Learn more: https://airlift.net. Template:. Learn more: https://airlift.net. Template: 6a3c9e6bc6af5a91495580da. Config Timestamp: 2026-06-25 03:19:51 UTC, Cached Timestamp: 2026-09-02 08:57:48 UTC -->