{"id":32260,"date":"2024-04-10T21:17:09","date_gmt":"2024-04-10T13:17:09","guid":{"rendered":"https:\/\/instantkarmamag.com\/?post_type=article&#038;p=32260"},"modified":"2024-07-02T17:35:10","modified_gmt":"2024-07-02T09:35:10","slug":"starkung-der-frauen-durch","status":"publish","type":"article","link":"https:\/\/instantkarmamag.com\/de\/artikel\/starkung-der-frauen-durch\/","title":{"rendered":"Die St\u00e4rke der Frauenf\u00f6rderung bei Via Via"},"content":{"rendered":"<div id=\"bsf_rt_marker\"><\/div><p><iframe loading=\"lazy\" title=\"Frauen st\u00e4rken - Janti &amp; Mie \u00fcber die Via Via World-Reise\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/7bBYFXbP78w?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<blockquote>\n<p style=\"text-align: center;\"><span data-contrast=\"auto\">Urspr\u00fcnglich von einer Gruppe junger Idealisten aus Belgien ins Leben gerufen, die sich f\u00fcr nachhaltigen Tourismus einsetzten, <\/span><\/p>\n<p style=\"text-align: center;\"><span data-contrast=\"auto\">ViaVia steht f\u00fcr famili\u00e4res und soziales Engagement. <\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<\/blockquote>\n<p><span data-contrast=\"auto\">Als Teil eines Reiseb\u00fcros, das sich sozialen, kulturellen und p\u00e4dagogischen Projekten widmet, konzentriert sich ViaVia auf echte Begegnungen zwischen Reisenden und Einheimischen. Es geht darum, Kulturen zu teilen und die Welt zu einem besseren Ort zu machen.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Geleitet von Menschen mit gro\u00dfen Visionen wie Mie, einer Fotografin, Grafikdesignerin und Mutter zweier Teenager, ist ViaVia ein Beispiel daf\u00fcr, wie kleine Taten Gro\u00dfes bewirken k\u00f6nnen.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">1995 f\u00fchlte sich Janti zu ViaVia hingezogen. Sie begann als Gast und ist seitdem ein wichtiger Teil von ViaVia Jogja. <\/span><span data-contrast=\"none\">2020<\/span><span data-contrast=\"auto\">. Janti hat sein Gl\u00fcck gefunden, weil es sich auf echte Verbindungen und den Umweltschutz konzentriert. <\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-32281 size-large\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2024\/04\/Via-Via-Jogja-DSC00375-1024x683.jpg\" alt=\"\" width=\"1024\" height=\"683\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2024\/04\/Via-Via-Jogja-DSC00375-1024x683.jpg 1024w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2024\/04\/Via-Via-Jogja-DSC00375-300x200.jpg 300w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2024\/04\/Via-Via-Jogja-DSC00375-768x512.jpg 768w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2024\/04\/Via-Via-Jogja-DSC00375-1536x1024.jpg 1536w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2024\/04\/Via-Via-Jogja-DSC00375-2048x1366.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<h2>Kraft und St\u00e4rke freisetzen<\/h2>\n<p><span data-contrast=\"auto\">Wenn es um Empowerment geht, glaubt Janti <\/span><span data-contrast=\"none\">Das <\/span><span data-contrast=\"auto\">alle <\/span><span data-contrast=\"none\">besitzt <\/span><span data-contrast=\"auto\">unbegrenztes Potenzial. Sie sagt, dass es der Schl\u00fcssel ist, sich selbst treu zu bleiben und engagiert zu bleiben, um <\/span><span data-contrast=\"none\">Erreichen<\/span><span data-contrast=\"auto\"> Ihre Ziele. Mie stimmt zu, <\/span><span data-contrast=\"none\">Betonung der Bedeutung pers\u00f6nlichen Wachstums f\u00fcr die Bew\u00e4ltigung von Herausforderungen und die Verwirklichung von Tr\u00e4umen.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\"> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-32286\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2024\/04\/Via-Via-Jogja-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1707\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2024\/04\/Via-Via-Jogja-scaled.jpg 2560w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2024\/04\/Via-Via-Jogja-2048x1365.jpg 2048w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2024\/04\/Via-Via-Jogja-300x200.jpg 300w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2024\/04\/Via-Via-Jogja-768x512.jpg 768w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2024\/04\/Via-Via-Jogja-1024x683.jpg 1024w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2024\/04\/Via-Via-Jogja-1536x1024.jpg 1536w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/span><\/p>\n<h3><b><span data-contrast=\"auto\">St\u00e4rkung der Rolle der Frau<\/span><\/b><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/h3>\n<p><span data-contrast=\"auto\">Von Anfang an besch\u00e4ftigte ViaVia bewusst ausschlie\u00dflich weibliche Mitarbeiter und Kundschaft und gab damit den Stimmen der Frauen Geh\u00f6r, was f\u00fcr die Tourismusbranche ein ungew\u00f6hnlicher Schritt war. Trotz Herausforderungen und Kritik blieb die St\u00e4rkung der Frauen und das Aufbrechen traditioneller Stereotypen eine Priorit\u00e4t. Bildungsprogramme, die durch ViaVias Gewinne finanziert wurden, haben zu bemerkenswerten Ver\u00e4nderungen gef\u00fchrt und gezeigt, wie wichtig Investitionen in die Bildung und St\u00e4rkung von Frauen sind. Durch die Bereitstellung von Chancen und Unterst\u00fctzung konnte ViaVia ein bemerkenswertes Wachstum und positive Ver\u00e4nderungen innerhalb seines Teams erleben. So hat beispielsweise eine ehemalige Reinigungskraft inzwischen einen Doktortitel in Bauingenieurwesen von einer japanischen Universit\u00e4t.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-32279 size-large\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2024\/04\/miecornoedus-768x1024.jpg\" alt=\"\" width=\"768\" height=\"1024\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2024\/04\/miecornoedus-768x1024.jpg 768w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2024\/04\/miecornoedus-225x300.jpg 225w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2024\/04\/miecornoedus-1152x1536.jpg 1152w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2024\/04\/miecornoedus-1536x2048.jpg 1536w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2024\/04\/miecornoedus-scaled.jpg 1920w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/p>\n<h3><b><span data-contrast=\"auto\">Wie bleiben Sie sich treu und wachsen?<\/span><\/b><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/h3>\n<p><span data-contrast=\"auto\">Janti betont, dass man dem Prozess vertrauen und aus jeder Erfahrung lernen sollte. Sie pl\u00e4diert f\u00fcr die Anpassung an unterschiedliche Situationen und daf\u00fcr, aus jeder einzelne Lehren zu ziehen. Mie stimmt dem zu und erkennt die Komplexit\u00e4t gesellschaftlicher Erwartungen an, insbesondere im Zeitalter der sozialen Medien. Sie schl\u00e4gt vor, Pausen von den sozialen Medien einzulegen, um sich auf pers\u00f6nliches Wachstum und Intuition zu konzentrieren und die Menschen zu ermutigen, sich selbst und ihren \u00dcberzeugungen treu zu bleiben.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<h3><b><span data-contrast=\"auto\">Wie beeinflussen Gemeinschaft und Zusammenarbeit Ihre Sichtweise auf die St\u00e4rkung der Rolle der Frau?<\/span><\/b><\/h3>\n<p><span data-contrast=\"none\">F\u00fcr Janti geht die Erfahrung \u00fcber pers\u00f6nliches Wachstum hinaus<\/span><span data-contrast=\"auto\">. Seit ihrem Umzug nach Jogja <\/span><span data-contrast=\"none\">hat<\/span><span data-contrast=\"auto\"> f\u00fchlte ein st\u00e4rkeres Gemeinschaftsgef\u00fchl.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">\u00a0\u201e<\/span><i><span data-contrast=\"auto\">Es ist, als w\u00fcrde ich in einem gro\u00dfen Dorf leben, wo ich mit lokalen Herstellern, Handwerkern und Kunsthandwerkern zusammenarbeite. Bei unseren Interaktionen geht es nicht nur um Geld, sondern auch um gegenseitige Unterst\u00fctzung. Ich brauche zum Beispiel Tempeh oder Gem\u00fcse von Bauern und sie brauchen einen Ort, an dem sie ihre Produkte verkaufen k\u00f6nnen. Durch die Organisation von Wochenendm\u00e4rkten profitieren wir alle.<\/span><\/i><span data-contrast=\"auto\">.\u201d\u00a0<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><b><span data-contrast=\"auto\">Mie f\u00fcgt hinzu:<\/span><\/b> <i><span data-contrast=\"auto\">\u201eManchmal f\u00fchlt es sich an, als w\u00fcrden wir gegen unsichtbare Hindernisse k\u00e4mpfen, aber die Verbindung mit\u00a0<\/span><\/i><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><i><span data-contrast=\"auto\">Gleichgesinnte zu treffen, macht alles lohnenswert. Es ist eine spannende Reise und die Zeit ist reif daf\u00fcr.\u201c<\/span><\/i><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-32275\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2024\/04\/IMG_3143-scaled.jpg\" alt=\"\" width=\"1707\" height=\"2560\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2024\/04\/IMG_3143-scaled.jpg 1707w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2024\/04\/IMG_3143-1365x2048.jpg 1365w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2024\/04\/IMG_3143-200x300.jpg 200w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2024\/04\/IMG_3143-768x1152.jpg 768w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2024\/04\/IMG_3143-683x1024.jpg 683w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2024\/04\/IMG_3143-1024x1536.jpg 1024w\" sizes=\"auto, (max-width: 1707px) 100vw, 1707px\" \/><\/p>\n<blockquote>\n<p style=\"text-align: center;\"><b><span data-contrast=\"auto\">In dem globalen Netzwerk, das Menschen und Kulturen verbindet, spielen Frauen eine entscheidende Rolle bei der St\u00e4rkung von Gemeinschaften und der F\u00f6rderung von Inklusivit\u00e4t.<\/span><\/b><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<\/blockquote>\n<p><span data-contrast=\"auto\">Mie betont, wie wichtig es ist, dass Frauen F\u00fchrungsrollen \u00fcbernehmen und bef\u00e4higt werden, zu f\u00fchren. Bei ViaVia haben Frauen in verschiedenen Bereichen F\u00fchrungspositionen inne, nicht unbedingt, weil sie daf\u00fcr ausgebildet wurden, sondern weil sie mit Unterst\u00fctzung und Ermutigung in diese Rollen hineingewachsen sind.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Janti betont das organische Wachstum der einzelnen Mitarbeiter bei ViaVia und hebt ihre Loyalit\u00e4t und Leistung im Laufe der Jahre hervor. Innerhalb des Teams werden Aufstiegsm\u00f6glichkeiten geboten, sodass die einzelnen Mitarbeiter aufsteigen und gr\u00f6\u00dfere und spannendere Aufgaben \u00fcbernehmen k\u00f6nnen.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Trotz m\u00f6glicher Bildungsbarrieren glaubt Janti an die Weisheit und die gemeinsamen Werte, die es Menschen erm\u00f6glichen, erfolgreich zu sein und sogar ein eigenes Unternehmen zu gr\u00fcnden. Dieser Ansatz f\u00f6rdert ein unterst\u00fctzendes Umfeld, in dem jeder die M\u00f6glichkeit hat, erfolgreich zu sein.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<h3><b><span data-contrast=\"auto\">\u00d6konomische, soziale, kulturelle und \u00f6kologische Faktoren ausbalancieren<\/span><\/b><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-32288 aligncenter\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2024\/04\/via-via-quote.png\" alt=\"Frauenf\u00f6rderung bei Viavia\" width=\"487\" height=\"592\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2024\/04\/via-via-quote.png 487w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2024\/04\/via-via-quote-247x300.png 247w\" sizes=\"auto, (max-width: 487px) 100vw, 487px\" \/><\/p>\n<h3><b><span data-contrast=\"auto\">ViaVias Fokus auf nachhaltigen Tourismus tr\u00e4gt zur Schaffung einer gerechten und offenen Welt bei<\/span><\/b><\/h3>\n<p><span data-contrast=\"none\">Mie erl\u00e4utert das Engagement von ViaVia f\u00fcr nachhaltigen Tourismus, das faire L\u00f6hne, gemeindenahe Initiativen, kulturell sensible Touren und Umweltaspekte wie Abfallmanagement und Plastikreduzierung umfasst. <\/span><\/p>\n<p><span data-contrast=\"none\">Die Zusammenarbeit mit Partnern wie der UNESCO f\u00f6rdert das interkulturelle Verst\u00e4ndnis und unterst\u00fctzt lokale Gemeinschaften. Mie betont die Bedeutung verantwortungsvoller F\u00fchrung bei der Schaffung einer gerechten und offenen Welt f\u00fcr alle.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><strong>Vielen Dank f\u00fcr das aufschlussreiche Interview! Seit seiner Er\u00f6ffnung am 15. Januar 2024 ist ViaVia Bali Sanur zu einem lebendigen Zentrum in Sanur geworden, das Gemeinschaft, Kultur und Nachhaltigkeit f\u00f6rdert. <\/strong><\/p>\n<p><strong>Ihr Engagement, Stereotypen zu durchbrechen und Bildung und Nachhaltigkeit zu f\u00f6rdern, ist wirklich lobenswert und stellt f\u00fcr uns alle ein starkes Beispiel dar.<\/strong><\/p>\n<p><strong><a href=\"https:\/\/viaviajogja.com\/\" target=\"_blank\" rel=\"noopener\">viaviajogja.com besuchen<\/a><\/strong><\/p>\n<p><strong>ICH G <a href=\"https:\/\/www.instagram.com\/viaviaworld\/\" target=\"_blank\" rel=\"noopener\">@viaviaworld<\/a><\/strong><\/p>\n<p><a href=\"https:\/\/viavia.world\/\" target=\"_blank\" rel=\"noopener\"><strong>Gehen Sie zu www.viavia.world<\/strong><\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Urspr\u00fcnglich von einer Gruppe junger Idealisten aus Belgien gegr\u00fcndet, die sich f\u00fcr nachhaltigen Tourismus einsetzen, steht VIAVIA f\u00fcr famili\u00e4res und soziales Engagement. <\/p>","protected":false},"author":214,"featured_media":32283,"comment_status":"open","ping_status":"closed","template":"","meta":{"footnotes":""},"categories":[273],"tags":[411],"section":[387,388],"interest":[381,378],"_magazine":[407],"class_list":["post-32260","article","type-article","status-publish","has-post-thumbnail","hentry","category-people","tag-readmore","section-impact","section-people","interest-empowerment","interest-social","_magazine-407"],"_links":{"self":[{"href":"https:\/\/instantkarmamag.com\/de\/wp-json\/wp\/v2\/article\/32260","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/instantkarmamag.com\/de\/wp-json\/wp\/v2\/article"}],"about":[{"href":"https:\/\/instantkarmamag.com\/de\/wp-json\/wp\/v2\/types\/article"}],"author":[{"embeddable":true,"href":"https:\/\/instantkarmamag.com\/de\/wp-json\/wp\/v2\/users\/214"}],"replies":[{"embeddable":true,"href":"https:\/\/instantkarmamag.com\/de\/wp-json\/wp\/v2\/comments?post=32260"}],"version-history":[{"count":0,"href":"https:\/\/instantkarmamag.com\/de\/wp-json\/wp\/v2\/article\/32260\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/instantkarmamag.com\/de\/wp-json\/wp\/v2\/media\/32283"}],"wp:attachment":[{"href":"https:\/\/instantkarmamag.com\/de\/wp-json\/wp\/v2\/media?parent=32260"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/instantkarmamag.com\/de\/wp-json\/wp\/v2\/categories?post=32260"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/instantkarmamag.com\/de\/wp-json\/wp\/v2\/tags?post=32260"},{"taxonomy":"section","embeddable":true,"href":"https:\/\/instantkarmamag.com\/de\/wp-json\/wp\/v2\/section?post=32260"},{"taxonomy":"interest","embeddable":true,"href":"https:\/\/instantkarmamag.com\/de\/wp-json\/wp\/v2\/interest?post=32260"},{"taxonomy":"_magazine","embeddable":true,"href":"https:\/\/instantkarmamag.com\/de\/wp-json\/wp\/v2\/_magazine?post=32260"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}<!-- This website is optimized by Airlift. Learn more: https://airlift.net. Template:. Learn more: https://airlift.net. Template: 6a3c9e6bc6af5a91495580da. Config Timestamp: 2026-06-25 03:19:51 UTC, Cached Timestamp: 2026-09-02 15:56:21 UTC -->