{"id":26413,"date":"2023-07-04T11:41:46","date_gmt":"2023-07-04T03:41:46","guid":{"rendered":"https:\/\/instantkarmamag.com\/?post_type=article&#038;p=26413"},"modified":"2024-07-03T16:15:21","modified_gmt":"2024-07-03T08:15:21","slug":"vervola-nachhaltige-mode","status":"publish","type":"article","link":"https:\/\/instantkarmamag.com\/de\/artikel\/vervola-nachhaltige-mode\/","title":{"rendered":"Vervola \u2013 Eine Geschichte nachhaltiger Mode"},"content":{"rendered":"<div id=\"bsf_rt_marker\"><\/div><p><span data-contrast=\"auto\">Susanne ist eine solch inspirierende Pers\u00f6nlichkeit, die es wagte, ihren eigenen Weg zu gehen und ihre Leidenschaft f\u00fcr Mode, Nachhaltigkeit und Yoga zu verbinden. Sie ist die Gr\u00fcnderin von vervola, einer Marke, die Yoga-Kleidung herstellt, die nicht nur funktional, sondern auch nachhaltig und einzigartig ist \u2013 genau wie Sie!<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Ihr Weg f\u00fchrte sie nach Bali, wo sie eine neue Heimat fand. Die Schweiz betrachtet sie als ihre Heimat und Bali als einen Ort, an dem sie zu Gast ist.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<h3 style=\"text-align: center;\">\u201eIch sch\u00e4tze die Freundlichkeit und die kulturelle Vielfalt Balis und Indonesiens.\u201c<\/h3>\n<p><span data-contrast=\"auto\">Im Alter von 53 Jahren wagten Susanne und ihr Mann den Schritt ins Ungewisse. <\/span><\/p>\n<p><span data-contrast=\"auto\">Nachdem sie jahrelang in verschiedenen L\u00e4ndern gelebt und gearbeitet hatten, entschieden sie sich neu. Ihr Mann engagiert sich aktiv bei einer Schweizer Stiftung, die den Vertrieb von auf Bali hergestellten Waren erleichtert und so die soziale Entwicklung und St\u00e4rkung einer l\u00e4ndlichen Region unterst\u00fctzt.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<h3>Welche Werte und Grunds\u00e4tze stehen f\u00fcr Dich bei der Produktion Deiner Yogabekleidung im Vordergrund?<\/h3>\n<p>Um das Wohlbefinden und Gl\u00fcck aller Beteiligten zu gew\u00e4hrleisten, habe ich f\u00fcr das Team einen Lebensraum geschaffen, der die Begriffe Kreativit\u00e4t und Leben vereint. Die Atmosph\u00e4re dort ist inspirierend und alle f\u00fchlen sich wohl.<\/p>\n<h2>Bei vervola leben wir nach dem Motto: \u201eHappy People \u2013 Happy Clothing.\u201c<\/h2>\n<p>Ein weiterer wichtiger Aspekt war f\u00fcr mich die Herkunft der Materialien. Um dies sicherzustellen, reiste ich nach Java und besuchte verschiedene Produktionsst\u00e4tten, um die beste Quelle f\u00fcr nachhaltige Materialien zu finden. Besonderes Augenmerk legte ich auf zertifizierte Materialien der renommierten Firma Lenzing.<\/p>\n<p>Dieser Aspekt ist sowohl in Europa als auch f\u00fcr mich pers\u00f6nlich ein wesentlicher Faktor f\u00fcr eine nachhaltige Produktion.<\/p>\n<p>Ich lege gro\u00dfen Wert darauf, dass meine Kundinnen nicht nur hochwertige Yogabekleidung erhalten, sondern auch wissen, dass diese unter fairen Bedingungen produziert und umweltfreundlich verpackt wird. Zudem werden Stoffreste f\u00fcr die Herstellung von Scrunchies und Stirnb\u00e4ndern verwendet, um den Abfall so gering wie m\u00f6glich zu halten.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-31918 size-large\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/07\/vervola-825x1024.jpg\" alt=\"vervola\" width=\"825\" height=\"1024\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/07\/vervola-825x1024.jpg 825w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/07\/vervola-242x300.jpg 242w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/07\/vervola-768x953.jpg 768w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/07\/vervola-1237x1536.jpg 1237w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/07\/vervola.jpg 1500w\" sizes=\"auto, (max-width: 825px) 100vw, 825px\" \/><\/p>\n<h3>Inwiefern hat dich deine Leidenschaft f\u00fcr Yoga dazu motiviert, vervola zu gr\u00fcnden?<\/h3>\n<p><span data-contrast=\"auto\">Meine Liebe zum Yoga und der Wunsch, nachhaltige Kleidung zu tragen, haben mich dazu inspiriert, Vervola zu gr\u00fcnden. Ich war auf der Suche nach nat\u00fcrlichen Materialien und T-Shirts, die beim Yoga nicht hochrutschen. Vor vier Jahren gab es auf dem Markt jedoch nur Polyester-Varianten, die meinen Anspr\u00fcchen nicht entsprachen. So kam ich auf die Idee, eine eigene Kollektion zu entwickeln.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Ich wollte nicht nur funktionelle Yoga-Kleidung entwerfen, sondern auch Teile, die bequem genug sind, um sie im Alltag oder beim Erledigen von Besorgungen zu tragen. Der urspr\u00fcngliche Gedanke war, T-Shirts zu entwerfen, die wirklich alltagstauglich sind. Doch dann entwickelte sich die Idee schnell weiter. Neben den T-Shirts wurden passende Hosen und Tops zu einem festen Bestandteil der Kollektion, da herk\u00f6mmliche Sport-BHs oft unbequem waren.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<blockquote>\n<h3 style=\"text-align: center;\"><span data-contrast=\"auto\"><em>F\u00fcr mich ist Vervola mehr als nur eine Modelinie. Es ist eine Leidenschaft, die mich antreibt, hochwertige, nachhaltige und bequeme Kleidung anzubieten.<\/em> <\/span><\/h3>\n<\/blockquote>\n<p style=\"text-align: left;\"><span data-contrast=\"auto\">Meine Vision ist es, Menschen dabei zu unterst\u00fctzen, sich in ihrer Kleidung wohlzuf\u00fchlen und gleichzeitig umweltbewusste Entscheidungen zu treffen. Durch Vervola habe ich die M\u00f6glichkeit, meine Liebe zum Yoga und meinen Wunsch nach nachhaltiger Mode zu vereinen und gleichzeitig andere zu motivieren, einen \u00e4hnlichen Weg einzuschlagen.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<h3>Wie manifestieren Sie Ihre Vision f\u00fcr Vervola?<\/h3>\n<p><span data-contrast=\"auto\">Meine Inspiration kommt aus der Natur und aus dem Umgang mit Menschen. Ich beobachte, wie Menschen Yoga praktizieren und sich durch die Stadt bewegen, um jedes Detail ihrer Kleidung zu verstehen. Sobald eine Idee in meinem Kopf Gestalt annimmt, setze ich sie in die Tat um, \u00fcbe sie und verfeinere sie, bis ich mit den Ergebnissen zufrieden bin. Um Frieden und Ruhe zu finden, wende ich mich der Aromatherapie und Meditation zu, bei der ich meine Vision visualisiere und manifestiere, und durch meine Gebete.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<h3>Welche Erfahrungen aus Ihrer Vergangenheit haben Ihr Leben gepr\u00e4gt?<\/h3>\n<p><span data-contrast=\"auto\">Ich habe Herausforderungen in der Vergangenheit mit Dankbarkeit und Vertrauen bew\u00e4ltigt. <\/span><\/p>\n<p><span data-contrast=\"auto\">Wenn es hart wird, bete ich und suche die Verbindung zur Natur.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Ich habe gelernt, dass das Leben sowohl positive als auch negative Aspekte hat, \u00e4hnlich wie die Natur selbst. Schwierige und schmerzhafte Momente durchzustehen und weiterzumachen, kann oft eine besondere Herausforderung sein.<\/span><\/p>\n<p><span data-contrast=\"auto\"> Doch gerade in diesen Momenten liegt die Chance f\u00fcr pers\u00f6nliches Wachstum und St\u00e4rke. Durch diese Erfahrungen habe ich gelernt, dass ich die Wahl habe, wie ich auf Herausforderungen reagiere. <\/span><\/p>\n<p><span data-contrast=\"auto\">Ich bewahre meine innere St\u00e4rke, indem ich mich auf das Positive konzentriere, mir selbst vertraue und nach vorne schaue. Das Leben ist ein st\u00e4ndiger Lernprozess und ich bin dankbar f\u00fcr jede Herausforderung, die mich gepr\u00e4gt hat.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<h3>Was motiviert Sie t\u00e4glich und was sind Ihre gr\u00f6\u00dften Leidenschaften im Leben?<\/h3>\n<p><span data-contrast=\"auto\">Das Gl\u00fcck meiner Familie und die Gewissheit, dass es meinen Kindern und meinem Mann gut geht, motivieren mich jeden Tag aufs Neue. Ihre Gesundheit und die gemeinsame Neugier sind mir sehr wichtig. Meine gr\u00f6\u00dfte Leidenschaft gilt jedoch der Beziehung zu meinem Mann \u2013 wir sind immer noch sehr verliebt.<\/span><\/p>\n<p><span data-contrast=\"auto\"> Dar\u00fcber hinaus liebe ich Yoga und Klangheilung und vertiefe mich leidenschaftlich in B\u00fccher, besonders Science-Fiction und spannende Geschichten. Ich entdecke die Welt mit Begeisterung auf Reisen. Diese Leidenschaften geben mir Energie und Freude und bereichern mein Leben auf vielf\u00e4ltige Weise.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-31919 size-large\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/07\/suzanne-vervola-1024x683.jpg\" alt=\"Suzanne Vervola\" width=\"1024\" height=\"683\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/07\/suzanne-vervola-1024x683.jpg 1024w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/07\/suzanne-vervola-300x200.jpg 300w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/07\/suzanne-vervola-768x512.jpg 768w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/07\/suzanne-vervola.jpg 1500w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<h3><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/h3>\n<h3><b><span data-contrast=\"auto\">Was sind Ihre Ziele und Tr\u00e4ume f\u00fcr die Zukunft und wie arbeiten Sie daran, diese zu verwirklichen?<\/span><\/b><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/h3>\n<p><span data-contrast=\"auto\">Meine Ziele und Tr\u00e4ume f\u00fcr die Zukunft sind klar: Ich m\u00f6chte, dass meine Kinder ihre Tr\u00e4ume verwirklichen k\u00f6nnen und dass mein Team in den Bali-Werkst\u00e4tten finanziell abgesichert ist. Gleichzeitig strebe ich danach, dass sich meine Marke Vervola fest etabliert.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Um diese Ziele zu erreichen, arbeite ich gewissenhaft und \u00fcberlegt. Meine Ertr\u00e4ge investiere ich strategisch und verzichte auf Fremdfinanzierung. Mein Fokus liegt auf nachhaltigem Wachstum und bewussten Entscheidungen.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Ich gehe meinen Weg zielstrebig und offen f\u00fcr neue Erfahrungen. Ich habe eine klare Vision meiner Tr\u00e4ume und arbeite hart daran, sie Wirklichkeit werden zu lassen \u2013 f\u00fcr meine Kinder, mein Team und mich selbst.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<h3><b><span data-contrast=\"auto\">Welche Dinge im Leben bereiten Ihnen die meiste Freude und wie integrieren Sie diese in Ihren Alltag, um ein erf\u00fclltes Leben zu f\u00fchren?<\/span><\/b><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/h3>\n<blockquote>\n<h2 style=\"text-align: center;\"><span data-contrast=\"auto\">Das Leben ist voller Freuden und ich integriere sie bewusst in meinen Alltag, um ein erf\u00fclltes Leben zu f\u00fchren.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/h2>\n<\/blockquote>\n<p><span data-contrast=\"auto\">Ein wichtiger Moment ist mein morgendliches Cappuccino-Ritual mit meinem Mann. Es gibt mir Energie und Freude f\u00fcr den bevorstehenden Tag.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Regelm\u00e4\u00dfige Pausen helfen mir, zu entspannen und neue Kraft zu tanken. K\u00f6rperliche Bet\u00e4tigung bei der Arbeit oder beim Sport st\u00e4rkt mich und verschafft mir Zufriedenheit. <\/span><\/p>\n<p><span data-contrast=\"auto\">Leckeres Essen und Kochen sind Freuden, die auch mein Leben bereichern.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">\u00dcber mich selbst zu lachen und Freude an den kleinen Dingen zu finden, erinnert mich an die Sch\u00f6nheit des Lebens.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Indem ich diesen freudigen Erlebnissen Priorit\u00e4t einr\u00e4ume und sie in meinen Alltag integriere, bin ich in der Lage, ein erf\u00fcllteres und freudvolleres Leben zu f\u00fchren.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-31920 size-large\" src=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/07\/suzanne-vervola-2-751x1024.jpg\" alt=\"\" width=\"751\" height=\"1024\" title=\"\" srcset=\"https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/07\/suzanne-vervola-2-751x1024.jpg 751w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/07\/suzanne-vervola-2-220x300.jpg 220w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/07\/suzanne-vervola-2-768x1048.jpg 768w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/07\/suzanne-vervola-2-1126x1536.jpg 1126w, https:\/\/instantkarmamag.com\/wp-content\/uploads\/2023\/07\/suzanne-vervola-2.jpg 1365w\" sizes=\"auto, (max-width: 751px) 100vw, 751px\" \/><\/p>\n<p>Vielen Dank, Susanne, f\u00fcr das Interview.<\/p>\n<p>Ihr Engagement f\u00fcr Nachhaltigkeit und Ihre Leidenschaft f\u00fcr Mode und Yoga sind wirklich inspirierend.<\/p>\n<p>&nbsp;<\/p>\n<h3>Hol dir vervola Yogakleidung: <a href=\"https:\/\/vervola.com\" target=\"_blank\" rel=\"noopener\"><b><span data-contrast=\"none\">www.vervola.com<\/span><\/b><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/a><\/h3>\n<h3>Folgen Sie uns auf Instagram <a href=\"https:\/\/www.instagram.com\/vervola_com\/\" target=\"_blank\" rel=\"noopener\">vervola_com<span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/a><\/h3>\n<p><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>Bei vervola leben wir nach dem Motto: \u201eHappy People \u2013 Happy Clothing.\u201c<\/p>","protected":false},"author":214,"featured_media":31915,"comment_status":"open","ping_status":"closed","template":"","meta":{"footnotes":""},"categories":[313],"tags":[365],"section":[387,388],"interest":[380,372,408],"_magazine":[366],"class_list":["post-26413","article","type-article","status-publish","has-post-thumbnail","hentry","category-review","tag-365","section-impact","section-people","interest-creative","interest-eco","interest-yoga","_magazine-366"],"_links":{"self":[{"href":"https:\/\/instantkarmamag.com\/de\/wp-json\/wp\/v2\/article\/26413","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/instantkarmamag.com\/de\/wp-json\/wp\/v2\/article"}],"about":[{"href":"https:\/\/instantkarmamag.com\/de\/wp-json\/wp\/v2\/types\/article"}],"author":[{"embeddable":true,"href":"https:\/\/instantkarmamag.com\/de\/wp-json\/wp\/v2\/users\/214"}],"replies":[{"embeddable":true,"href":"https:\/\/instantkarmamag.com\/de\/wp-json\/wp\/v2\/comments?post=26413"}],"version-history":[{"count":0,"href":"https:\/\/instantkarmamag.com\/de\/wp-json\/wp\/v2\/article\/26413\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/instantkarmamag.com\/de\/wp-json\/wp\/v2\/media\/31915"}],"wp:attachment":[{"href":"https:\/\/instantkarmamag.com\/de\/wp-json\/wp\/v2\/media?parent=26413"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/instantkarmamag.com\/de\/wp-json\/wp\/v2\/categories?post=26413"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/instantkarmamag.com\/de\/wp-json\/wp\/v2\/tags?post=26413"},{"taxonomy":"section","embeddable":true,"href":"https:\/\/instantkarmamag.com\/de\/wp-json\/wp\/v2\/section?post=26413"},{"taxonomy":"interest","embeddable":true,"href":"https:\/\/instantkarmamag.com\/de\/wp-json\/wp\/v2\/interest?post=26413"},{"taxonomy":"_magazine","embeddable":true,"href":"https:\/\/instantkarmamag.com\/de\/wp-json\/wp\/v2\/_magazine?post=26413"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}<!-- This website is optimized by Airlift. Learn more: https://airlift.net. Template:. Learn more: https://airlift.net. Template: 6a3c9e6bc6af5a91495580da. Config Timestamp: 2026-06-25 03:19:51 UTC, Cached Timestamp: 2026-09-02 04:54:32 UTC -->